{"id":39001,"date":"2024-02-22T17:44:13","date_gmt":"2024-02-22T20:44:13","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/22\/cinto-de-seguranca-nao-e-utilizado-por-41-dos-passageiros-no-banco-traseiro\/"},"modified":"2024-02-22T17:44:13","modified_gmt":"2024-02-22T20:44:13","slug":"cinto-de-seguranca-nao-e-utilizado-por-41-dos-passageiros-no-banco-traseiro","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/22\/cinto-de-seguranca-nao-e-utilizado-por-41-dos-passageiros-no-banco-traseiro\/","title":{"rendered":"Cinto de seguran\u00e7a n\u00e3o \u00e9 utilizado por 41% dos passageiros no banco traseiro"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p data-block-key=\"58dut\">No caso de caminh\u00f5es, tamb\u00e9m avaliados na pesquisa, a utiliza\u00e7\u00e3o do dispositivo \u00e9 ainda menos usual: 26,2% dos ocupantes deixam de fazer uso, ante 10,3% quando analisado entre motoristas e ocupantes de autom\u00f3veis de passeio.<\/p>\n<p data-block-key=\"4jfja\">Os resultados corroboram outras estat\u00edsticas da concession\u00e1ria. Em 2023, a empresa registrou tr\u00eas ocorr\u00eancias com mortes em que usu\u00e1rios foram ejetados para fora do ve\u00edculo, al\u00e9m de contabilizar outros acidentes que n\u00e3o resultam em \u00f3bito, mas que t\u00eam ind\u00edcios de que o cinto de seguran\u00e7a deixou de ser utilizado.<\/p>\n<p data-block-key=\"8muo\">Segundo dados da Associa\u00e7\u00e3o Brasileira de Medicina de Tr\u00e1fego (Abramet), o cinto de seguran\u00e7a pode reduzir o risco de morte em pelo menos 60% para ocupantes no banco da frente e em 44% para passageiros que se deslocam no banco traseiro. Cerca de 50% da efic\u00e1cia dos cintos de seguran\u00e7a se deve \u00e0 preven\u00e7\u00e3o da eje\u00e7\u00e3o de ocupantes de ve\u00edculos automotores. E, ainda segundo o estudo, n\u00e3o usar o cinto de seguran\u00e7a no banco de tr\u00e1s aumenta em cinco vezes o risco de morte do ocupante do banco da frente.<\/p>\n<p data-block-key=\"5tnad\"><strong>Metodologia<\/strong> \u2013 Os dados sobre o comportamento de motoristas e passageiros foram obtidos por meio de uma pesquisa de seguran\u00e7a vi\u00e1ria desenvolvida pela concession\u00e1ria, em outubro de 2023, nas onze pra\u00e7as de ped\u00e1gio que a empresa administra ao longo de 720 quil\u00f4metros, nas rodovias SP-255, SP-330, SP-334 e SP-318, nas regi\u00f5es de Franca, Ribeir\u00e3o Preto, Araraquara e Botucatu. Em seis dias foram abordados 6.950 ve\u00edculos e observado o comportamento de seguran\u00e7a de um total de 11.268 usu\u00e1rios, entre motoristas e passageiros de carro, utilit\u00e1rios, caminhonetes e caminh\u00f5es.<\/p>\n<p data-block-key=\"amp05\"><strong>Caracter\u00edsticas<\/strong> \u2013 A aus\u00eancia do equipamento tamb\u00e9m \u00e9 uma realidade observada entre ocupantes de ve\u00edculos comerciais. Apenas 75% dos motoristas de caminh\u00f5es utilizavam o cinto, de um total de 2.310 motoristas observados.<\/p>\n<p data-block-key=\"uljb\">A pesquisa tamb\u00e9m apontou outras caracter\u00edsticas no caso dos ve\u00edculos comerciais: o cinto \u00e9 menos usado aos finais de semana. Aos domingos, n\u00e3o foi utilizado em 28% dos casos. J\u00e1 durante a semana, essa m\u00e9dia \u00e9 de 23%.<\/p>\n<p data-block-key=\"6ps63\">Para a gerente de Opera\u00e7\u00f5es da ViaPaulista, Ana Gon\u00e7alves Caetano, as pesquisas ajudam a avaliar o h\u00e1bito de seguran\u00e7a do usu\u00e1rio, identificar o impacto das campanhas educativas e a definir novas estrat\u00e9gias operacionais.<\/p>\n<p data-block-key=\"4h4ng\">\u201cO cinto de seguran\u00e7a \u00e9 fundamental para evitar les\u00f5es, reduzir danos e evitar mortes. Temos um trabalho constante de educa\u00e7\u00e3o para conscientizar os usu\u00e1rios sobre essas e outras regras de tr\u00e2nsito, como por exemplo o Programa \u201cT\u00f4 de cinto, t\u00f4 seguro\u201d. Mas, ainda hoje, \u00e9 muito comum constatarmos acidentes graves com ind\u00edcios da falta dele.\u201d, afirma a gerente<\/p>\n<p data-block-key=\"1tieg\">Somente em 2023, foram realizadas 69 atividades de abordagem e conscientiza\u00e7\u00e3o sobre o cinto de seguran\u00e7a, com cerca de 6 mil usu\u00e1rios orientados na \u00e1rea da empresa.<\/p>\n<p data-block-key=\"9an8e\"><strong>Legisla\u00e7\u00e3o<\/strong> \u2013 A lei n\u00ba 9.503 do C\u00f3digo de Tr\u00e2nsito Brasileiro, de 23 de setembro de 1997, define no artigo 65 que \u00e9 obrigat\u00f3rio o uso do cinto de seguran\u00e7a para condutores e passageiros em todas as vias do territ\u00f3rio nacional, salvo em situa\u00e7\u00f5es regulamentadas pelo Conselho Nacional de Tr\u00e2nsito (Contran), e que a obrigatoriedade \u00e9 para todos os ocupantes do ve\u00edculo, inclusive os que andam no banco de tr\u00e1s. O descumprimento da regra \u00e9 considerado uma infra\u00e7\u00e3o grave e a multa \u00e9 de R$ 195,23 e 5 pontos na CNH.<\/p>\n<p data-block-key=\"3nku6\">Por meio do C\u00f3digo Brasileiro de Tr\u00e2nsito tamb\u00e9m \u00e9 considerada infra\u00e7\u00e3o o uso do cinto de seguran\u00e7a de forma irregular, ou com dispositivos que travem, afrouxem ou modifiquem o funcionamento normal do equipamento.<\/p>\n<\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/site\/cinto-de-seguranca-nao-e-utilizado-por-41-dos-passageiros-no-banco-traseiro\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] No caso de caminh\u00f5es, tamb\u00e9m avaliados na pesquisa, a utiliza\u00e7\u00e3o do dispositivo \u00e9 ainda menos usual: 26,2% dos ocupantes deixam de fazer uso, ante 10,3% quando analisado entre motoristas e ocupantes de autom\u00f3veis de passeio. Os resultados corroboram outras estat\u00edsticas da concession\u00e1ria. Em 2023, a empresa registrou tr\u00eas ocorr\u00eancias com mortes em que usu\u00e1rios &#8230; <a title=\"Cinto de seguran\u00e7a n\u00e3o \u00e9 utilizado por 41% dos passageiros no banco traseiro\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/22\/cinto-de-seguranca-nao-e-utilizado-por-41-dos-passageiros-no-banco-traseiro\/\" aria-label=\"Leia mais sobre Cinto de seguran\u00e7a n\u00e3o \u00e9 utilizado por 41% dos passageiros no banco traseiro\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":39002,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[578,4436,470,678,3048,134,1878,4438,4437],"class_list":["post-39001","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-banco","tag-cinto","tag-dos","tag-nao","tag-passageiros","tag-por","tag-seguranca","tag-traseiro","tag-utilizado"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/a61b7162-932e-47a8-9782-bca4aca583ce-scaled.jpg?fit=938%2C645&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/a61b7162-932e-47a8-9782-bca4aca583ce-scaled.jpg?fit=938%2C645&ssl=1",938,645,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/a61b7162-932e-47a8-9782-bca4aca583ce-scaled.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/a61b7162-932e-47a8-9782-bca4aca583ce-scaled.jpg?fit=300%2C206&ssl=1",300,206,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/a61b7162-932e-47a8-9782-bca4aca583ce-scaled.jpg?fit=768%2C528&ssl=1",768,528,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/a61b7162-932e-47a8-9782-bca4aca583ce-scaled.jpg?fit=938%2C645&ssl=1",938,645,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/a61b7162-932e-47a8-9782-bca4aca583ce-scaled.jpg?fit=938%2C645&ssl=1",938,645,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/a61b7162-932e-47a8-9782-bca4aca583ce-scaled.jpg?fit=938%2C645&ssl=1",938,645,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] No caso de caminh\u00f5es, tamb\u00e9m avaliados na pesquisa, a utiliza\u00e7\u00e3o do dispositivo \u00e9 ainda menos usual: 26,2% dos ocupantes deixam de fazer uso, ante 10,3% quando analisado entre motoristas e ocupantes de autom\u00f3veis de passeio. Os resultados corroboram outras estat\u00edsticas da concession\u00e1ria. Em 2023, a empresa registrou tr\u00eas ocorr\u00eancias com mortes em que usu\u00e1rios&hellip;","jetpack-related-posts":[{"id":25926,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/08\/homem-que-perdeu-a-vida-em-acidente-grave-apos-ser-ejetado-de-carro-e-identificado\/","url_meta":{"origin":39001,"position":0},"title":"Homem que perdeu a vida em acidente grave ap\u00f3s ser ejetado de carro \u00e9 identificado","author":"ismaelcolosi.com.br","date":"8 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Mais um grave acidente registrado uma das estradas que corta o estado de Santa Catarina, deixou outra v\u00edtima fatal. O caso esta sendo apurado pelas autoridades.De acordo com as primeiras informa\u00e7\u00f5es repassadas pelos agentes da Pol\u00edcia Rodovi\u00e1ria Federal (PRF), que foram acionados para atender a ocorr\u00eancia, a v\u00edtima fatal\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659c45ffc9e1f5667.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659c45ffc9e1f5667.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659c45ffc9e1f5667.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659c45ffc9e1f5667.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659c45ffc9e1f5667.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":78228,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/12\/03\/mais-um-morto-em-acidente-na-anhanguera\/","url_meta":{"origin":39001,"position":1},"title":"Mais um morto em acidente na Anhanguera","author":"ismaelcolosi.com.br","date":"3 de Dezembro de 2024","format":false,"excerpt":"[ad_1] Por: Adalberto Luque Uma pessoa morreu e duas ficaram feridas ap\u00f3s uma colis\u00e3o traseira, no in\u00edcio da manh\u00e3 desta ter\u00e7a-feira (3). O acidente ocorreu na Rodovia Anhanguera (SP-330), km 257, em Santa Rita do Passa Quatro, regi\u00e3o metropolitana. Um caminh\u00e3o Mercedes Benz 1113 estava parado no acostamento, na pista\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/03dez2024-acidentesantarita-scaled.jpg?fit=800%2C450&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/03dez2024-acidentesantarita-scaled.jpg?fit=800%2C450&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/03dez2024-acidentesantarita-scaled.jpg?fit=800%2C450&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/03dez2024-acidentesantarita-scaled.jpg?fit=800%2C450&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":78572,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/12\/06\/um-morto-e-cinco-feridos-em-acidente-no-trecho-critico-da-anhanguera\/","url_meta":{"origin":39001,"position":2},"title":"Um morto e cinco feridos em acidente no trecho cr\u00edtico da Anhanguera","author":"ismaelcolosi.com.br","date":"6 de Dezembro de 2024","format":false,"excerpt":"[ad_1] Em um per\u00edodo de 15 dias, cinco pessoas j\u00e1 perderam a vida na regi\u00e3o pr\u00f3xima \u00e0 Serra de Santa Rita 6 de dezembro de 20246 de dezembro de 202410 Compartilhar2 Por: Adalberto Luque Uma pessoa morreu e cinco ficaram feridas, na madrugada desta sexta-feira (6), ap\u00f3s um acidente envolvendo\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/06dez2024-morteserrinha-scaled.jpg?fit=651%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/06dez2024-morteserrinha-scaled.jpg?fit=651%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/06dez2024-morteserrinha-scaled.jpg?fit=651%2C500&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":23625,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/02\/um-morto-e-13-feridos-nas-estradas-da-regiao-durante-feriado\/","url_meta":{"origin":39001,"position":3},"title":"Um morto e 13 feridos nas estradas da regi\u00e3o durante feriado","author":"ismaelcolosi.com.br","date":"2 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Uma pessoa foi presa em flagrante por dirigir embriagada e outras 80 recusaram fazer o teste do baf\u00f4metro e foram autuadas 2 de janeiro de 2024 | 18:11 0Por: Adalberto LuqueA Pol\u00edcia Militar Rodovi\u00e1ria (PMRv) divulgou, na manh\u00e3 desta ter\u00e7a-feira (02), o balan\u00e7o da Opera\u00e7\u00e3o Feriado Ano Novo 2023\/2024\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/00-20-dez-2023-natal-nas-estradas-00-Foto-Divulgacao-scaled.jpg?fit=938%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/00-20-dez-2023-natal-nas-estradas-00-Foto-Divulgacao-scaled.jpg?fit=938%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/00-20-dez-2023-natal-nas-estradas-00-Foto-Divulgacao-scaled.jpg?fit=938%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/00-20-dez-2023-natal-nas-estradas-00-Foto-Divulgacao-scaled.jpg?fit=938%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":19031,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/21\/duas-irmas-perdem-a-vida-em-grave-acidente-na-lmg-754\/","url_meta":{"origin":39001,"position":4},"title":"Duas irm\u00e3s perdem a vida em grave acidente na LMG-754","author":"ismaelcolosi.com.br","date":"21 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Na madrugada desta quinta-feira (21), um grave acidente entre um carro e uma carreta ceifou a vida de duas irm\u00e3s. Duas irm\u00e3s, ambas na faixa et\u00e1ria de 65 e 70 anos, perderam a vida em um grave acidente.A batida envolveu um autom\u00f3vel e uma carreta na rodovia LMG-754, em\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658480337bb086849.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658480337bb086849.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658480337bb086849.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658480337bb086849.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658480337bb086849.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":28606,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/16\/gravissimo-acidente-entre-carro-e-caminhoes-deixa-tres-mortos-incluindo-duas-criancas\/","url_meta":{"origin":39001,"position":5},"title":"Grav\u00edssimo acidente entre carro e caminh\u00f5es deixa tr\u00eas mortos, incluindo duas crian\u00e7as","author":"ismaelcolosi.com.br","date":"16 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Um acidente devastador ocorreu na noite da \u00faltima segunda, dia 15 de janeiro, na Via Dutra, em S\u00e3o Paulo, resultando na morte de tr\u00eas pessoas, incluindo duas crian\u00e7as.O incidente, que aconteceu por volta das 22h, envolveu um ve\u00edculo de passeio e dois caminh\u00f5es, deixando tamb\u00e9m dois feridos.Durante um congestionamento\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a671d5e813c8893.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a671d5e813c8893.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a671d5e813c8893.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a671d5e813c8893.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a671d5e813c8893.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-a93","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/39001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=39001"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/39001\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/39002"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=39001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=39001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=39001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}