{"id":38827,"date":"2024-02-21T19:14:28","date_gmt":"2024-02-21T22:14:28","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/21\/veja-os-valores-dos-ingressos-para-o-ribeirao-rodeo-music\/"},"modified":"2024-02-21T19:14:28","modified_gmt":"2024-02-21T22:14:28","slug":"veja-os-valores-dos-ingressos-para-o-ribeirao-rodeo-music","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/21\/veja-os-valores-dos-ingressos-para-o-ribeirao-rodeo-music\/","title":{"rendered":"Veja os valores dos ingressos para o Ribeir\u00e3o Rodeo Music"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>Faltando <strong>dois<\/strong> <strong>meses<\/strong> para o <strong>Ribeir\u00e3o Rodeo Music<\/strong>, que acontece de 20 a 30 de abril, as <strong>vendas<\/strong> de <strong>ingressos<\/strong> para o <strong>evento<\/strong> j\u00e1 est\u00e3o acontecendo de forma <strong><a href=\"https:\/\/www.ribeiraorodeomusic.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">on-line<\/a><\/strong> e, desde ter\u00e7a-feira (20), come\u00e7ou tamb\u00e9m nas lojas <strong>Oscar Cal\u00e7ados<\/strong> do <strong>Novo Shopping<\/strong> e no <strong>Centro de Ribeir\u00e3o Preto<\/strong> (<strong>veja abaixo<\/strong>).<\/p>\n<p>Os <strong>pre\u00e7os<\/strong> dos <strong>ingressos <\/strong>para os quatro setores oferecidos no evento <strong>variam<\/strong> entre <strong>R$ 60 e R$ 1.299<\/strong>. Os valores alteram de acordo com o dia do evento.<\/p><div class='code-block code-block-8' style='margin: 8px auto; text-align: center; display: block; clear: both;'>\n<script>\n  atOptions = {\n    'key' : '66e2e2111ca34da796271819fc334058',\n    'format' : 'iframe',\n    'height' : 250,\n    'width' : 300,\n    'params' : {}\n  };\n<\/script>\n<script src=\"https:\/\/www.highperformanceformat.com\/66e2e2111ca34da796271819fc334058\/invoke.js\"><\/script>\n<\/div>\n\n<h4 class=\"wp-block-heading\"><strong>Confira os valores por setor e dia do evento:<\/strong><\/h4>\n<p><strong>Arena \u2013 <\/strong>espa\u00e7o com acesso aos shows do palco principal, provas e montarias em touros e cavalos<\/p>\n<p><strong>20\/04 \u2013 Ana Castela \/ Alok \/ Hugo &amp; Guilherme \/ Luan Pereira<br \/><\/strong>R$ 60 estudante<br \/>R$ 70 solid\u00e1ria<br \/>R$ 120 inteira<\/p>\n<p><strong>26\/04 \u2013 Z\u00e9 Neto &amp; Cristiano \/ C\u00e9sar Menotti &amp; Fabiano \/ Lauana Prado \/ Locos Dj<br \/><\/strong>R$ 60 estudante<br \/>R$ 70 solid\u00e1ria<br \/>R$ 120 inteira<\/p>\n<p><strong>27\/04 \u2013 Gusttavo Lima \/ Pedro Sampaio \/ Matheus &amp; Kauan \/ Fred &amp; Fabr\u00edcio<br \/><\/strong>R$ 70 estudante<br \/>R$ 80 solid\u00e1ria<br \/>R$ 140 inteira<\/p>\n<p><strong>30\/04 \u2013 Jorge &amp; Mateus \/ Zez\u00e9 di Camargo &amp; Luciano \/ Gustavo Mioto \/ \u00cdcaro &amp; Gilmar<br \/><\/strong>R$ 70 estudante<br \/>R$ 80 solid\u00e1ria<br \/>R$ 140 inteira<\/p>\n<p><strong>Passaporte para os quatro dias<br \/><\/strong>R$ 210<\/p>\n<p><strong>Camarote Ballantine\u2019s Black Lounge<\/strong> \u2013 espa\u00e7o Vip com acesso em frente ao palco principal e ao setor Arena<\/p>\n<p><strong>20\/04 \u2013 Ana Castela \/ Alok \/ Hugo &amp; Guilherme \/ Luan Pereira<br \/><\/strong>R$ 395 estudante (n\u00e3o open bar)<br \/>R$ 415 solid\u00e1rio (n\u00e3o open bar)<br \/>R$ 790 inteira (n\u00e3o open bar)<\/p>\n<p><strong>26\/04 \u2013 Z\u00e9 Neto &amp; Cristiano \/ C\u00e9sar Menotti &amp; Fabiano \/ Lauana Prado \/<br \/><\/strong>R$ 245 estudante (n\u00e3o open bar)<br \/>R$ 265 solid\u00e1rio (n\u00e3o open bar)<br \/>R$ 490 inteira (n\u00e3o open bar)<\/p>\n<p><strong>27\/04 \u2013 Gusttavo Lima \/ Pedro Sampaio \/ Matheus &amp; Kauan \/ Fred &amp;<br \/><\/strong>R$ 345 estudante (n\u00e3o open bar)<br \/>R$ 365 solid\u00e1rio (n\u00e3o open bar)<br \/>R$ 690 inteira (n\u00e3o open bar)<\/p>\n<p><strong>30\/04 \u2013 Jorge &amp; Mateus \/ Zez\u00e9 di Camargo &amp; Luciano \/ Gustavo Mioto \/ \u00cdcaro &amp; Gilmar<br \/><\/strong>R$ 325 estudante (n\u00e3o open bar)<br \/>R$ 345 solid\u00e1rio (n\u00e3o open bar)<br \/>R$ 650 inteira (n\u00e3o open bar)<\/p>\n<p><strong>Camarote Ballantines\u2019s Black Lounge Open Bar<\/strong> \u2013 espa\u00e7o Vip com acesso ao espa\u00e7o em frente ao palco principal, acesso ao setor Arena e camarote Black Lounge (n\u00e3o open bar)<\/p>\n<p><strong>20\/04 \u2013 Ana Castela \/ Alok \/ Hugo &amp; Guilherme \/ Luan Pereira<br \/><\/strong>R$ 660 Open Bar<\/p>\n<p><strong>26\/04 \u2013 Z\u00e9 Neto &amp; Cristiano \/ C\u00e9sar Menotti &amp; Fabiano \/ Lauana Prado \/<br \/><\/strong>R$ 490 Open Bar<\/p>\n<p><strong>27\/04 \u2013 Gusttavo Lima \/ Pedro Sampaio \/ Matheus &amp; Kauan \/ Fred &amp;<br \/><\/strong>R$ 730 Open Bar<\/p>\n<p><strong>30\/04 \u2013 Jorge &amp; Mateus \/ Zez\u00e9 di Camargo &amp; Luciano \/ Gustavo Mioto \/ \u00cdcaro &amp; Gilmar<br \/><\/strong>R$ 590 Open Bar<\/p>\n<p><strong>Camarote Brahma<\/strong> \u2013 espa\u00e7o open bar com chope Brahma e buffet exclusivo<\/p>\n<p><strong>20\/04 \u2013 Ana Castela \/ Alok \/ Hugo &amp; Guilherme \/ Luan Pereira<br \/><\/strong>R$ 939 meia<br \/>R$ 999 inteira<\/p>\n<p><strong>26\/04 \u2013 Z\u00e9 Neto &amp; Cristiano \/ C\u00e9sar Menotti &amp; Fabiano \/ Lauana Prado \/<br \/><\/strong>R$ 839 meia<br \/>R$ 899 inteira<\/p>\n<p><strong>27\/04 \u2013 Gusttavo Lima \/ Pedro Sampaio \/ Matheus &amp; Kauan \/ Fred &amp;<br \/><\/strong>R$ 1.129 meia<br \/>R$ 1.299 inteira<\/p>\n<p><strong>30\/04 \u2013 Jorge &amp; Mateus \/ Zez\u00e9 di Camargo &amp; Luciano \/ Gustavo Mioto \/ \u00cdcaro &amp; Gilmar<br \/><\/strong>R$ 879 meia<br \/>R$ 949 inteira<\/p>\n<h4 class=\"wp-block-heading\"><strong>Servi\u00e7o<\/strong><\/h4>\n<p><strong>Evento: <\/strong>Ribeir\u00e3o Rodeo Music<\/p>\n<p><strong>Data:<\/strong> 20, 26, 27 e 30 de abril de 2024<br \/><strong>Local: <\/strong>Parque Permanente de Exposi\u00e7\u00f5es de Ribeir\u00e3o Preto<br \/><strong>Venda de ingressos em pontos f\u00edsicos:<\/strong> <strong>Oscar Cal\u00e7ados<\/strong> | Rua \u00c1lvares Cabral, 470 (<strong>Centro<\/strong>) | Avenida Presidente Kennedy, 1500 \u2013 Ribeir\u00e2nia (<strong>Novo Shopping<\/strong>).<br \/><strong>Venda On-line:<\/strong>\u00a0<a href=\"https:\/\/www.ribeiraorodeomusic.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">www.ribeiraorodeomusic.com.br<\/a><\/p>\n<p>SAIBA MAIS<br \/>Veja a regi\u00e3o que concentra o maior n\u00famero de casos de dengue em Ribeir\u00e3o<\/p>\n<p><strong>FIQUE ON<\/strong><\/p>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do\u00a0<strong>acidade on\u00a0<\/strong>no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>\u00a0e no<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a0Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do\u00a0<strong>acidade on\u00a0<\/strong>no WhatsApp.\u00a0<a href=\"https:\/\/chat.whatsapp.com\/Bnv2w66ZT4VDyZW3oiZ69n\" target=\"_blank\" rel=\"noreferrer noopener\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<br \/>Qual foi o Pared\u00e3o com mais votos da hist\u00f3ria do BBB?<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/lazer-e-cultura\/veja-quanto-custa-ingressos-para-ribeirao-rodeo-music\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Faltando dois meses para o Ribeir\u00e3o Rodeo Music, que acontece de 20 a 30 de abril, as vendas de ingressos para o evento j\u00e1 est\u00e3o acontecendo de forma on-line e, desde ter\u00e7a-feira (20), come\u00e7ou tamb\u00e9m nas lojas Oscar Cal\u00e7ados do Novo Shopping e no Centro de Ribeir\u00e3o Preto (veja abaixo). Os pre\u00e7os dos ingressos &#8230; <a title=\"Veja os valores dos ingressos para o Ribeir\u00e3o Rodeo Music\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/21\/veja-os-valores-dos-ingressos-para-o-ribeirao-rodeo-music\/\" aria-label=\"Read more about Veja os valores dos ingressos para o Ribeir\u00e3o Rodeo Music\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":38828,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-38827","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/3-10.jpg?fit=1200%2C675&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/3-10.jpg?fit=1200%2C675&ssl=1",1200,675,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/3-10.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/3-10.jpg?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/3-10.jpg?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/3-10.jpg?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/3-10.jpg?fit=1200%2C675&ssl=1",1200,675,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/3-10.jpg?fit=1200%2C675&ssl=1",1200,675,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Faltando dois meses para o Ribeir\u00e3o Rodeo Music, que acontece de 20 a 30 de abril, as vendas de ingressos para o evento j\u00e1 est\u00e3o acontecendo de forma on-line e, desde ter\u00e7a-feira (20), come\u00e7ou tamb\u00e9m nas lojas Oscar Cal\u00e7ados do Novo Shopping e no Centro de Ribeir\u00e3o Preto (veja abaixo). Os pre\u00e7os dos ingressos&hellip;","jetpack-related-posts":[{"id":51581,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/28\/gusttavo-lima-se-apresenta-na-regiao-de-ribeirao-preto-ingressos-estao-disponiveis\/","url_meta":{"origin":38827,"position":0},"title":"Gusttavo Lima se apresenta na regi\u00e3o de Ribeir\u00e3o Preto; Ingressos est\u00e3o dispon\u00edveis","author":"ismaelcolosi.com.br","date":"28 de May de 2024","format":false,"excerpt":"[ad_1] Os ingressos para o show do cantor Gusttavo Lima em Pontal, cidade a aproximadamente 38 quil\u00f4metros de Ribeir\u00e3o Preto, ainda est\u00e3o dispon\u00edveis. A apresenta\u00e7\u00e3o acontece no dia 06 de junho, a partir das 21h, durante o Pontal Rodeo Music. O evento segue at\u00e9 o dia 8 de junho e\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__GL_III-e1714330490605.webp.webp?fit=900%2C692&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__GL_III-e1714330490605.webp.webp?fit=900%2C692&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__GL_III-e1714330490605.webp.webp?fit=900%2C692&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__GL_III-e1714330490605.webp.webp?fit=900%2C692&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":49441,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/10\/gusttavo-lima-faz-show-na-regiao-de-ribeirao-preto-veja-como-comprar-ingressos\/","url_meta":{"origin":38827,"position":1},"title":"Gusttavo Lima faz show na regi\u00e3o de Ribeir\u00e3o Preto; Veja como comprar ingressos","author":"ismaelcolosi.com.br","date":"10 de May de 2024","format":false,"excerpt":"[ad_1] O cantor Gusttavo Lima se apresenta em Pontal, cidade a cerca de 38 quil\u00f4metros de Ribeir\u00e3o Preto, no dia 06 de junho, a partir das 21h. A apresenta\u00e7\u00e3o faz parte do Pontal Rodeo Music, que acontece entre os dias 06 e 08 de junho, no Parque Permanente de Exposi\u00e7\u00f5es\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/InShot_20230728_093159520-scaled.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/InShot_20230728_093159520-scaled.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/InShot_20230728_093159520-scaled.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/InShot_20230728_093159520-scaled.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/InShot_20230728_093159520-scaled.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":38844,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/21\/veja-os-valores-dos-ingressos-para-o-ribeirao-rodeo-music-2\/","url_meta":{"origin":38827,"position":2},"title":"Veja os valores dos ingressos para o Ribeir\u00e3o Rodeo Music","author":"ismaelcolosi.com.br","date":"21 de February de 2024","format":false,"excerpt":"[ad_1] Faltando dois meses para o Ribeir\u00e3o Rodeo Music, que acontece de 20 a 30 de abril, as vendas de ingressos para o evento j\u00e1 est\u00e3o acontecendo de forma on-line e, desde ter\u00e7a-feira (20), come\u00e7ou tamb\u00e9m nas lojas Oscar Cal\u00e7ados do Novo Shopping e no Centro de Ribeir\u00e3o Preto (veja\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1708560717_3-10.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1708560717_3-10.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1708560717_3-10.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1708560717_3-10.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1708560717_3-10.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":39646,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/27\/confira-a-programacao-esportiva-do-ribeirao-rodeo-music\/","url_meta":{"origin":38827,"position":3},"title":"Confira a programa\u00e7\u00e3o esportiva do Ribeir\u00e3o Rodeo Music","author":"ismaelcolosi.com.br","date":"27 de February de 2024","format":false,"excerpt":"[ad_1] Foi divulgada a programa\u00e7\u00e3o esportiva do Ribeir\u00e3o Rodeo Music deste ano. Ao todo, s\u00e3o cinco modalidades que ser\u00e3o disputadas durante o evento, que acontece de 20 a 30 de abril, e que traz tamb\u00e9m atra\u00e7\u00f5es musicais de destaque nacional. As provas disputadas durante o RRM s\u00e3o: Team Penning, Montarias\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-16.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-16.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-16.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-16.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-16.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":33707,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/30\/veja-quando-comeca-a-venda-dos-ingressos-para-o-ribeirao-rodeo-music\/","url_meta":{"origin":38827,"position":4},"title":"Veja quando come\u00e7a a venda dos ingressos para o Ribeir\u00e3o Rodeo Music","author":"ismaelcolosi.com.br","date":"30 de January de 2024","format":false,"excerpt":"[ad_1] Come\u00e7a na pr\u00f3xima ter\u00e7a-feira (6) a venda dos ingressos para 18\u00aa edi\u00e7\u00e3o do Ribeir\u00e3o Rodeo Music. O evento est\u00e1 marcado para os dias 20, 26, 27 e 30 de abril de 2024 no Parque Permanente de Exposi\u00e7\u00f5es, em Ribeir\u00e3o Preto. No mesmo dia, a organiza\u00e7\u00e3o do evento tamb\u00e9m vai\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Ribeirao-Rodeo-Music.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Ribeirao-Rodeo-Music.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Ribeirao-Rodeo-Music.jpeg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Ribeirao-Rodeo-Music.jpeg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Ribeirao-Rodeo-Music.jpeg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":52032,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/03\/rodeio-na-regiao-de-ribeirao-preto-tem-shows-de-gusttavo-lima-e-leo-santana\/","url_meta":{"origin":38827,"position":5},"title":"Rodeio na regi\u00e3o de Ribeir\u00e3o Preto tem shows de Gusttavo Lima e L\u00e9o Santana","author":"ismaelcolosi.com.br","date":"3 de June de 2024","format":false,"excerpt":"[ad_1] Os cantores Gusttavo Lima e L\u00e9o Santana fazem shows em Pontal, na regi\u00e3o de Ribeir\u00e3o Preto, durante o \u201cPontal Rodeo Music\u201d. O evento, que acontece entre os dias 6 e 8 de junho, ser\u00e1 no Parque Permanente de Exposi\u00e7\u00f5es Isaura Moro Ferrante. Al\u00e9m de Gusttavo Lima e L\u00e9o Santana,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-3_2024-06-03_14-58-03_jpg_2024-06-03_14-58-03.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-3_2024-06-03_14-58-03_jpg_2024-06-03_14-58-03.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-3_2024-06-03_14-58-03_jpg_2024-06-03_14-58-03.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-3_2024-06-03_14-58-03_jpg_2024-06-03_14-58-03.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-3_2024-06-03_14-58-03_jpg_2024-06-03_14-58-03.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-a6f","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/38827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=38827"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/38827\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/38828"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=38827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=38827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=38827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}