{"id":38760,"date":"2024-02-21T15:04:59","date_gmt":"2024-02-21T18:04:59","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/21\/preco-de-repelente-aumenta-1578\/"},"modified":"2024-02-21T15:04:59","modified_gmt":"2024-02-21T18:04:59","slug":"preco-de-repelente-aumenta-1578","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/21\/preco-de-repelente-aumenta-1578\/","title":{"rendered":"Pre\u00e7o de repelente aumenta 15,78% \u00a0"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"\">\n<p> <span class=\"entry-meta-item penci-posted-on\"><i class=\"fa fa-clock-o\"\/><time class=\"entry-date published\" datetime=\"2024-02-21T15:00:57-03:00\">21 de fevereiro de 2024 | 15:00<\/time><time class=\"updated\" datetime=\"2024-02-21T09:40:17-03:00\">21 de fevereiro de 2024 | 9:40<\/time><\/span><\/p>\n<p> <span class=\"penci-social-buttons penci-social-share-footer\"><a href=\"#\" class=\"penci-post-like penci_post-meta_item  single-like-button penci-social-item like\" data-post_id=\"374437\" title=\"Like\" data-like=\"Like\" data-unlike=\"Unlike\"><i class=\"fa fa-thumbs-o-up\"\/><span class=\"penci-share-number\">0<\/span><\/a><i class=\"fa fa-facebook\"\/><a class=\"penci-social-item twitter\" target=\"_blank\" rel=\"noopener\" title=\"\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Pre\u00e7o%20de%20repelente%20aumenta%2015,78%20\u00a0%20-%20https:\/\/www.tribunaribeirao.com.br\/site\/preco-de-repelente-aumenta-1578\/\"><i class=\"fa fa-twitter\"\/><\/a><i class=\"fa fa-whatsapp\"\/><\/span><\/div>\n<div>\n<p><span class=\"TextRun SCXW84509393 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW84509393 BCX0\">Levantamento sobre pre\u00e7o de repelentes contra insetos, feito pela <\/span><\/span><span class=\"TextRun SCXW84509393 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW84509393 BCX0\">Funda\u00e7\u00e3o de Prote\u00e7\u00e3o e Defesa do Consumidor (<\/span><span class=\"NormalTextRun SCXW84509393 BCX0\">Funda\u00e7\u00e3o <\/span><span class=\"NormalTextRun SCXW84509393 BCX0\">Procon<\/span><span class=\"NormalTextRun SCXW84509393 BCX0\">-SP)<\/span><\/span><span class=\"TextRun SCXW84509393 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW84509393 BCX0\">, constatou aumento de 15,78% em m\u00e9dia, com diferen\u00e7as que chegaram a 84,19% para um mesmo produto em estabelecimentos diferentes, entre dezembro do ano passado e fevereiro deste ano.<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW84509393 BCX0\"><span class=\"SCXW84509393 BCX0\">\u00a0<\/span><br class=\"SCXW84509393 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW84509393 BCX0\"><span class=\"SCXW84509393 BCX0\">\u00a0<\/span><br class=\"SCXW84509393 BCX0\"\/><\/span><span class=\"TextRun SCXW84509393 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW84509393 BCX0\">A pesquisa foi realizada em cinco sites de drogarias, farm\u00e1cias e mercado. Foram <\/span><span class=\"NormalTextRun SCXW84509393 BCX0\">onze <\/span><span class=\"NormalTextRun SCXW84509393 BCX0\">itens com pre\u00e7os comparados. Segundo o <\/span><span class=\"NormalTextRun SCXW84509393 BCX0\">Procon<\/span><span class=\"NormalTextRun SCXW84509393 BCX0\">-SP, no mesmo per\u00edodo do levantamento, o \u00cdndice de Pre\u00e7os ao Consumidor (IPC-SP) da Funda\u00e7\u00e3o Instituto de Pesquisas Econ\u00f4micas (<\/span><span class=\"NormalTextRun SCXW84509393 BCX0\">Fipe<\/span><span class=\"NormalTextRun SCXW84509393 BCX0\">) teve varia\u00e7\u00e3o de 0,84%.<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW84509393 BCX0\"><span class=\"SCXW84509393 BCX0\">\u00a0<\/span><br class=\"SCXW84509393 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW84509393 BCX0\"><span class=\"SCXW84509393 BCX0\">\u00a0<\/span><br class=\"SCXW84509393 BCX0\"\/><\/span><span class=\"TextRun SCXW84509393 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW84509393 BCX0\">A alta dos pre\u00e7os de repelentes ocorre no momento de aumento de casos de dengue, transmitida pelo mosquito <\/span><span class=\"NormalTextRun SCXW84509393 BCX0\">Aedes<\/span> <span class=\"NormalTextRun SCXW84509393 BCX0\">aegypti<\/span><span class=\"NormalTextRun SCXW84509393 BCX0\">, que tamb\u00e9m \u00e9 vetor de transmiss\u00e3o da <\/span><span class=\"NormalTextRun SCXW84509393 BCX0\">zika<\/span><span class=\"NormalTextRun SCXW84509393 BCX0\"> e da <\/span><span class=\"NormalTextRun SCXW84509393 BCX0\">chikungunya<\/span><span class=\"NormalTextRun SCXW84509393 BCX0\">.<\/span> <span class=\"NormalTextRun SCXW84509393 BCX0\">Os casos de dengue no pa\u00eds j\u00e1 chegam a 653.656, conforme a atualiza\u00e7\u00e3o <\/span><span class=\"NormalTextRun SCXW84509393 BCX0\">na <\/span><span class=\"NormalTextRun SCXW84509393 BCX0\">segunda-feira, 19 de fevereiro, do painel de monitoramento de <\/span><span class=\"NormalTextRun SCXW84509393 BCX0\">arboviroses<\/span><span class=\"NormalTextRun SCXW84509393 BCX0\"> do Minist\u00e9rio da Sa\u00fade. <\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW84509393 BCX0\"><span class=\"SCXW84509393 BCX0\">\u00a0<\/span><br class=\"SCXW84509393 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW84509393 BCX0\"><span class=\"SCXW84509393 BCX0\">\u00a0<\/span><br class=\"SCXW84509393 BCX0\"\/><\/span><span class=\"TextRun SCXW84509393 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW84509393 BCX0\">S\u00e3o 321,9 casos por grupo de 100 mil habitantes.\u00a0 Desde 1\u00ba de janeiro, 113 pessoas morreram em decorr\u00eancia da doen\u00e7a transmitida pelo <\/span><span class=\"NormalTextRun SCXW84509393 BCX0\">Aedes<\/span> <span class=\"NormalTextRun SCXW84509393 BCX0\">aegypti<\/span><span class=\"NormalTextRun SCXW84509393 BCX0\">.\u00a0<\/span> <span class=\"NormalTextRun SCXW84509393 BCX0\">De acordo com o painel de monitoramento de <\/span><span class=\"NormalTextRun SCXW84509393 BCX0\">arboviroses<\/span><span class=\"NormalTextRun SCXW84509393 BCX0\"> do Minist\u00e9rio da Sa\u00fade, h\u00e1 ainda 438 mortes em investiga\u00e7\u00e3o para a doen\u00e7a.<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW84509393 BCX0\"><span class=\"SCXW84509393 BCX0\">\u00a0<\/span><br class=\"SCXW84509393 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW84509393 BCX0\"><span class=\"SCXW84509393 BCX0\">\u00a0<\/span><br class=\"SCXW84509393 BCX0\"\/><\/span><span class=\"TextRun SCXW84509393 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW84509393 BCX0\">\u201c<\/span><span class=\"NormalTextRun SCXW84509393 BCX0\">A grande diferen\u00e7a de pre\u00e7os entre estabelecimentos aponta para a necessidade de o consumidor pesquisar bastante antes de comprar seus produtos, ainda mais em um per\u00edodo de elevada demanda e considerando que n\u00e3o h\u00e1 tabelamento de pre\u00e7os no pa\u00eds\u201d, divulgou a entidade, em nota.<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW84509393 BCX0\"><span class=\"SCXW84509393 BCX0\">\u00a0<\/span><br class=\"SCXW84509393 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW84509393 BCX0\"><span class=\"SCXW84509393 BCX0\">\u00a0<\/span><br class=\"SCXW84509393 BCX0\"\/><\/span><span class=\"TextRun SCXW84509393 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW84509393 BCX0\">Ribeir\u00e3o Preto enfrenta mais uma epidemia de dengue, desta vez de n\u00edvel 2. J\u00e1 s\u00e3o 1.828 casos confirmados em 40 dias<\/span><span class=\"NormalTextRun SCXW84509393 BCX0\"> de 2024<\/span><span class=\"NormalTextRun SCXW84509393 BCX0\">, al\u00e9m de 5.462 sob investiga\u00e7\u00e3o. Uma semana atr\u00e1s eram 1.279. Em sete dias, o <\/span><span class=\"NormalTextRun SCXW84509393 BCX0\">Aedes<\/span> <span class=\"NormalTextRun SCXW84509393 BCX0\">aegypti<\/span><span class=\"NormalTextRun SCXW84509393 BCX0\"> \u2013 vetor da doen\u00e7a, do <\/span><span class=\"NormalTextRun SCXW84509393 BCX0\">zika<\/span><span class=\"NormalTextRun SCXW84509393 BCX0\"> v\u00edrus e da febre <\/span><span class=\"NormalTextRun SCXW84509393 BCX0\">chikungunya<\/span><span class=\"NormalTextRun SCXW84509393 BCX0\"> \u2013 fez mais 549 v\u00edtimas, aumento de 42,92%. <\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW84509393 BCX0\"><span class=\"SCXW84509393 BCX0\">\u00a0<\/span><br class=\"SCXW84509393 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW84509393 BCX0\"><span class=\"SCXW84509393 BCX0\">\u00a0<\/span><br class=\"SCXW84509393 BCX0\"\/><\/span><span class=\"TextRun SCXW84509393 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW84509393 BCX0\">Na semana anterior, a alta havia sido de 431,18%, de 975 para 1.279, com mais 304 v\u00edtimas do vetor. A m\u00e9dia di\u00e1ria neste ano \u00e9 de 47 ocorr\u00eancias, uma a cada 31 minutos, aproximadamente. Os dados s\u00e3o do per\u00edodo entre 1\u00ba de janeiro e <\/span><span class=\"NormalTextRun SCXW84509393 BCX0\">9<\/span><span class=\"NormalTextRun SCXW84509393 BCX0\"> de fevereiro. S\u00e3o 137 notifica\u00e7\u00f5es de casos suspeitos por dia. <\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW84509393 BCX0\"><span class=\"SCXW84509393 BCX0\">\u00a0<\/span><br class=\"SCXW84509393 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW84509393 BCX0\"><span class=\"SCXW84509393 BCX0\">\u00a0<\/span><br class=\"SCXW84509393 BCX0\"\/><\/span><span class=\"TextRun SCXW84509393 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW84509393 BCX0\">S\u00e3o 167 pacientes infectados em fevereiro, quase 19 por dia, um a cada \\uma hora e 16 minutos. S\u00e3o 1.661 em janeiro, ante 768 de dezembro, 893 a mais e alta de 116,28%. Na compara\u00e7\u00e3o com o primeiro m\u00eas de 2023, quando foram 402 pessoas pegaram dengue, o aumento chega a 313,18%. S\u00e3o 1.259 a mais<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW84509393 BCX0\"><span class=\"SCXW84509393 BCX0\">\u00a0<\/span><br class=\"SCXW84509393 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW84509393 BCX0\"><span class=\"SCXW84509393 BCX0\">\u00a0<\/span><br class=\"SCXW84509393 BCX0\"\/><\/span><span class=\"TextRun SCXW84509393 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW84509393 BCX0\">At\u00e9 agora, segundo a Secretaria Municipal da Sa\u00fade, n\u00e3o h\u00e1 nenhum \u00f3bito confirmado em 2024, mas h\u00e1 uma morte sob investiga\u00e7\u00e3o, de uma idosa que estava com a doen\u00e7a e faleceu.\u00a0 Foram oito falecimentos em decorr\u00eancia da doen\u00e7a em 2023, tr\u00eas em mar\u00e7o, duas em abril, duas em maio e uma em junho. Em 2022 ocorreu um \u00f3bito. <\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW84509393 BCX0\"><span class=\"SCXW84509393 BCX0\">\u00a0<\/span><br class=\"SCXW84509393 BCX0\"\/><\/span><\/p>\n<\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/site\/preco-de-repelente-aumenta-1578\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] 21 de fevereiro de 2024 | 15:0021 de fevereiro de 2024 | 9:40 0 Levantamento sobre pre\u00e7o de repelentes contra insetos, feito pela Funda\u00e7\u00e3o de Prote\u00e7\u00e3o e Defesa do Consumidor (Funda\u00e7\u00e3o Procon-SP), constatou aumento de 15,78% em m\u00e9dia, com diferen\u00e7as que chegaram a 84,19% para um mesmo produto em estabelecimentos diferentes, entre dezembro do &#8230; <a title=\"Pre\u00e7o de repelente aumenta 15,78% \u00a0\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/21\/preco-de-repelente-aumenta-1578\/\" aria-label=\"Leia mais sobre Pre\u00e7o de repelente aumenta 15,78% \u00a0\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":38761,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[2399,1850,4410],"class_list":["post-38760","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-aumenta","tag-preco","tag-repelente"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/8b57af96-718e-4883-b560-5086429ed06f.jpg?fit=640%2C427&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/8b57af96-718e-4883-b560-5086429ed06f.jpg?fit=640%2C427&ssl=1",640,427,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/8b57af96-718e-4883-b560-5086429ed06f.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/8b57af96-718e-4883-b560-5086429ed06f.jpg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/8b57af96-718e-4883-b560-5086429ed06f.jpg?fit=640%2C427&ssl=1",640,427,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/8b57af96-718e-4883-b560-5086429ed06f.jpg?fit=640%2C427&ssl=1",640,427,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/8b57af96-718e-4883-b560-5086429ed06f.jpg?fit=640%2C427&ssl=1",640,427,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/8b57af96-718e-4883-b560-5086429ed06f.jpg?fit=640%2C427&ssl=1",640,427,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] 21 de fevereiro de 2024 | 15:0021 de fevereiro de 2024 | 9:40 0 Levantamento sobre pre\u00e7o de repelentes contra insetos, feito pela Funda\u00e7\u00e3o de Prote\u00e7\u00e3o e Defesa do Consumidor (Funda\u00e7\u00e3o Procon-SP), constatou aumento de 15,78% em m\u00e9dia, com diferen\u00e7as que chegaram a 84,19% para um mesmo produto em estabelecimentos diferentes, entre dezembro do&hellip;","jetpack-related-posts":[{"id":37674,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/17\/precos-de-repelentes-tem-aumento-de-quase-16-diz-procon-sp\/","url_meta":{"origin":38760,"position":0},"title":"Pre\u00e7os de repelentes t\u00eam aumento de quase 16%, diz Procon-SP","author":"ismaelcolosi.com.br","date":"17 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] Um levantamento divulgado na sexta-feira (16) pelo Procon-SP apontou que os pre\u00e7os de repelentes tiveram um aumento de 15,78% em compara\u00e7\u00e3o com dezembro de 2023. A pesquisa foi realizada com o objetivo de contribuir com \u00e0 popula\u00e7\u00e3o para a preven\u00e7\u00e3o de combate \u00e0 dengue. De acordo com o \u00f3rg\u00e3o,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/mulher-em-close-up-desinfetando-maos_23-2148672882.jpg?fit=1060%2C596&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/mulher-em-close-up-desinfetando-maos_23-2148672882.jpg?fit=1060%2C596&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/mulher-em-close-up-desinfetando-maos_23-2148672882.jpg?fit=1060%2C596&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/mulher-em-close-up-desinfetando-maos_23-2148672882.jpg?fit=1060%2C596&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/mulher-em-close-up-desinfetando-maos_23-2148672882.jpg?fit=1060%2C596&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":79077,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/12\/12\/dia-d-contra-a-dengue-mobiliza-o-brasil-com-acoes-de-conscientizacao\/","url_meta":{"origin":38760,"position":1},"title":"Dia D Contra a Dengue Mobiliza o Brasil com A\u00e7\u00f5es de Conscientiza\u00e7\u00e3o","author":"ismaelcolosi.com.br","date":"12 de Dezembro de 2024","format":false,"excerpt":"[ad_1] O Brasil promove nesta semana o Dia D de Combate \u00e0 Dengue, com diversas a\u00e7\u00f5es de conscientiza\u00e7\u00e3o e mobiliza\u00e7\u00e3o em todo o territ\u00f3rio nacional. A iniciativa, liderada pelo Minist\u00e9rio da Sa\u00fade, visa alertar a popula\u00e7\u00e3o sobre a gravidade da doen\u00e7a e refor\u00e7ar medidas de preven\u00e7\u00e3o contra o mosquito Aedes\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/combate_dengue_14.webp.webp?fit=1170%2C700&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/combate_dengue_14.webp.webp?fit=1170%2C700&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/combate_dengue_14.webp.webp?fit=1170%2C700&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/combate_dengue_14.webp.webp?fit=1170%2C700&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/combate_dengue_14.webp.webp?fit=1170%2C700&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":40353,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/02\/voce-sabia-cuidados-com-dengue-devem-ser-maiores-na-gestacao\/","url_meta":{"origin":38760,"position":2},"title":"Voc\u00ea sabia? Cuidados com dengue devem ser maiores na gesta\u00e7\u00e3o","author":"ismaelcolosi.com.br","date":"2 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] O odor e o aumento do g\u00e1s carb\u00f4nico exalado pela pele das gestantes, aliados ao aumento da sua temperatura corporal, s\u00e3o fatores importantes para a atra\u00e7\u00e3o do mosquito Aedes aegypti. Al\u00e9m disso, as gr\u00e1vidas e pu\u00e9rperas est\u00e3o entre os grupos populacionais mais suscet\u00edveis a complica\u00e7\u00f5es e evolu\u00e7\u00e3o para as\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/gestante_mulher_1024x576_15022021172416.jpg?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/gestante_mulher_1024x576_15022021172416.jpg?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/gestante_mulher_1024x576_15022021172416.jpg?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/gestante_mulher_1024x576_15022021172416.jpg?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":39833,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/28\/previa-do-ipca-fecha-em-078\/","url_meta":{"origin":38760,"position":3},"title":"Pr\u00e9via do IPCA\u00a0fecha em 0,78% \u00a0","author":"ismaelcolosi.com.br","date":"28 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] O \u00cdndice Nacional de Pre\u00e7os ao Consumidor Amplo 15 \u2013 pr\u00e9via da infla\u00e7\u00e3o oficial no pa\u00eds \u2013 disparou 0,78% em fevereiro, ante alta de 0,31% em janeiro, avan\u00e7o de 0,40% em dezembro do ano passado. A \u00faltima defla\u00e7\u00e3o ocorreu em julho, de 0,07%. Com o resultado anunciado nesta ter\u00e7a-feira,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/IZa4lmensalidade-scaled.jpg?fit=968%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/IZa4lmensalidade-scaled.jpg?fit=968%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/IZa4lmensalidade-scaled.jpg?fit=968%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/IZa4lmensalidade-scaled.jpg?fit=968%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":58703,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/01\/interior-de-sp-confirma-dois-casos-de-febre-oropouche\/","url_meta":{"origin":38760,"position":4},"title":"Interior de SP confirma dois casos de Febre Oropouche","author":"ismaelcolosi.com.br","date":"1 de Agosto de 2024","format":false,"excerpt":"[ad_1] A Secretaria da Sa\u00fade de S\u00e3o Paulo confirmou dois casos de Febre Oropouche no interior paulista. A doen\u00e7a \u00e9 causada pela picada do mosquito-maruim infectado com o v\u00edrus, tamb\u00e9m conhecido como \u201cmosquito p\u00f3lvora\u201d. Os casos aut\u00f3ctones foram identificados em Cajati, munic\u00edpio da regi\u00e3o do Vale do Ribeira. Casos aut\u00f3ctones\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/febre-do-Oropouche_2024-07-26_18-02-20_jpg_2024-07-26_18-02-20.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/febre-do-Oropouche_2024-07-26_18-02-20_jpg_2024-07-26_18-02-20.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/febre-do-Oropouche_2024-07-26_18-02-20_jpg_2024-07-26_18-02-20.webp.webp?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/febre-do-Oropouche_2024-07-26_18-02-20_jpg_2024-07-26_18-02-20.webp.webp?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/febre-do-Oropouche_2024-07-26_18-02-20_jpg_2024-07-26_18-02-20.webp.webp?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":40072,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/29\/aluguel-tem-deflacao-de-052-em-fevereiro\/","url_meta":{"origin":38760,"position":5},"title":"Aluguel tem defla\u00e7\u00e3o\u00a0de 0,52% em fevereiro\u00a0","author":"ismaelcolosi.com.br","date":"29 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] 29 de fevereiro de 2024 | 18:0029 de fevereiro de 2024 | 11:59 0O \u00cdndice Geral de Pre\u00e7os \u2013 Mercado (IGP-M) caiu 0,52% em fevereiro, ap\u00f3s alta de 0,07% em janeiro, informou nesta quarta-feira, 28 de fevereiro, a Funda\u00e7\u00e3o Get\u00falio Vargas (FGV). Com esse resultado o \u00edndice acumula queda\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/AluguelRP-Alfredo-Risk-scaled.jpg?fit=1000%2C519&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/AluguelRP-Alfredo-Risk-scaled.jpg?fit=1000%2C519&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/AluguelRP-Alfredo-Risk-scaled.jpg?fit=1000%2C519&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/AluguelRP-Alfredo-Risk-scaled.jpg?fit=1000%2C519&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-a5a","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/38760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=38760"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/38760\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/38761"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=38760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=38760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=38760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}