{"id":38644,"date":"2024-02-20T22:11:29","date_gmt":"2024-02-21T01:11:29","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/20\/ex-prefeito-welson-gasparini-esta-internado-em-hospital-de-ribeirao-preto\/"},"modified":"2024-02-20T22:11:29","modified_gmt":"2024-02-21T01:11:29","slug":"ex-prefeito-welson-gasparini-esta-internado-em-hospital-de-ribeirao-preto","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/20\/ex-prefeito-welson-gasparini-esta-internado-em-hospital-de-ribeirao-preto\/","title":{"rendered":"Ex-prefeito Welson Gasparini est\u00e1 internado em hospital de Ribeir\u00e3o Preto"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_102\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p>O <strong>ex-prefeito de Ribeir\u00e3o Preto Welson Gasparini<\/strong>, de 87 anos, <strong>est\u00e1 internado no Hospital da Unimed, em Ribeir\u00e3o Preto.<\/strong> A informa\u00e7\u00e3o foi confirmada ao <strong>portal acidade on<\/strong>, na noite desta ter\u00e7a-feira (20), pelo filho dele, o <strong>vereador Mauricio Gasparini (UNI\u00c3O)<\/strong>.<\/p>\n<p>Durante sess\u00e3o na <strong>C\u00e2mara Municipal<\/strong> desta ter\u00e7a, o vereador <strong>Igor Oliveira (MDB)<\/strong>, disse que recebeu uma mensagem de Maur\u00edcio, <mark style=\"background-color:#fcb900\" class=\"has-inline-color\">informando que o ex-prefeito est\u00e1 <strong>internado na UTI (Unidade de Terapia Intensiva) do hospital<\/strong>.<\/mark><\/p>\n<p><strong>Welson Gasparini foi prefeito de Ribeir\u00e3o Preto quatro vezes<\/strong>, se tornando o pol\u00edtico que mais ocupou o cargo na cidade.<\/p>\n<p>Nasceu em dezembro de 1936, em <strong>Batatais<\/strong>, cidade a cerca de 43 quil\u00f4metros de <strong>Ribeir\u00e3o Preto<\/strong>. \u00c9 radialista, jornalista, professor e advogado. Al\u00e9m de prefeito, foi <strong>deputado estadual<\/strong> e <strong>deputado federal<\/strong>, ambos por S\u00e3o Paulo.<\/p>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<p>SAIBA MAIS<\/p>\n<p>Cinemas de Ribeir\u00e3o ter\u00e3o ingressos por R$ 12; Veja quando<\/p>\n<h4 class=\"wp-block-heading\"><strong><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">FIQUE ON<\/mark><\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do\u00a0<strong>acidade on<\/strong>\u00a0no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook.<\/a><\/p>\n<p>Receba not\u00edcias do acidade on no WhatsApp. Para entrar no grupo, basta\u00a0<a href=\"https:\/\/chat.whatsapp.com\/Bnv2w66ZT4VDyZW3oiZ69n\" target=\"_blank\" rel=\"noreferrer noopener\">clicar aqui<\/a>.<\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/politica\/ex-prefeito-welson-gasparini-esta-internado-em-hospital-de-ribeirao-preto\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] O ex-prefeito de Ribeir\u00e3o Preto Welson Gasparini, de 87 anos, est\u00e1 internado no Hospital da Unimed, em Ribeir\u00e3o Preto. A informa\u00e7\u00e3o foi confirmada ao portal acidade on, na noite desta ter\u00e7a-feira (20), pelo filho dele, o vereador Mauricio Gasparini (UNI\u00c3O). Durante sess\u00e3o na C\u00e2mara Municipal desta ter\u00e7a, o vereador Igor Oliveira (MDB), disse que &#8230; <a title=\"Ex-prefeito Welson Gasparini est\u00e1 internado em hospital de Ribeir\u00e3o Preto\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/20\/ex-prefeito-welson-gasparini-esta-internado-em-hospital-de-ribeirao-preto\/\" aria-label=\"Leia mais sobre Ex-prefeito Welson Gasparini est\u00e1 internado em hospital de Ribeir\u00e3o Preto\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":38645,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-38644","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-42.png?fit=1200%2C675&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-42.png?fit=1200%2C675&ssl=1",1200,675,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-42.png?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-42.png?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-42.png?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-42.png?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-42.png?fit=1200%2C675&ssl=1",1200,675,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-42.png?fit=1200%2C675&ssl=1",1200,675,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] O ex-prefeito de Ribeir\u00e3o Preto Welson Gasparini, de 87 anos, est\u00e1 internado no Hospital da Unimed, em Ribeir\u00e3o Preto. A informa\u00e7\u00e3o foi confirmada ao portal acidade on, na noite desta ter\u00e7a-feira (20), pelo filho dele, o vereador Mauricio Gasparini (UNI\u00c3O). Durante sess\u00e3o na C\u00e2mara Municipal desta ter\u00e7a, o vereador Igor Oliveira (MDB), disse que&hellip;","jetpack-related-posts":[{"id":38937,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/22\/saiba-o-estado-de-saude-do-ex-prefeito-de-ribeirao-preto-welson-gasparini\/","url_meta":{"origin":38644,"position":0},"title":"Saiba o estado de sa\u00fade do ex-prefeito de Ribeir\u00e3o Preto Welson Gasparini","author":"ismaelcolosi.com.br","date":"22 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] O ex-prefeito de Ribeir\u00e3o Preto Welson Gasparini, de 87 anos, segue internado no Hospital da Unimed, em Bonfim Paulista. De acordo com o vereador Maur\u00edcio Gasparini (Uni\u00e3o), filho do ex-prefeito, Welson est\u00e1 passando por \u201cv\u00e1rios exames\u201d. O parlamentar ainda informou que ainda n\u00e3o h\u00e1 previs\u00e3o de alta. O ex-prefeito\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/gasparini.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/gasparini.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/gasparini.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/gasparini.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/gasparini.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":40507,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/04\/morre-o-ex-prefeito-de-ribeirao-preto-welson-gasparini-aos-87-anos\/","url_meta":{"origin":38644,"position":1},"title":"Morre o ex-prefeito de Ribeir\u00e3o Preto Welson Gasparini, aos 87 anos","author":"ismaelcolosi.com.br","date":"4 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] Morreu nesta segunda-feira (4), o ex-prefeito de Ribeir\u00e3o Preto, Welson Gasparini, aos 87 anos. Gasparini estava internado no Hospital Unimed, em Bonfim Paulista, h\u00e1 duas semanas. A informa\u00e7\u00e3o foi confirmada pelo vereador Maur\u00edcio Gasparini (Uni\u00e3o), filho do ex-prefeito. Gasparini sofria de problemas card\u00edacos e chegou a passar por uma\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/gasparini.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/gasparini.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/gasparini.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/gasparini.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/gasparini.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":40526,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/04\/relembre-a-trajetoria-do-ex-prefeito-de-ribeirao-preto-welson-gasparini\/","url_meta":{"origin":38644,"position":2},"title":"Relembre a trajet\u00f3ria do ex-prefeito de Ribeir\u00e3o Preto Welson Gasparini","author":"ismaelcolosi.com.br","date":"4 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] O ex-prefeito de Ribeir\u00e3o Preto Welson Gasparini morreu nesta segunda-feira (4), aos 87 anos. Gasparini nasceu em Batatais em 1\u00ba de dezembro de 1937, filho de Vict\u00f3rio Gasparini e Deolinda Breguerilli. Al\u00e9m de pol\u00edtico, tamb\u00e9m foi jornalista, radialista, professor e advogado. De acordo com a Unimed Ribeir\u00e3o Preto, o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__gasparini-scaled.webp.webp?fit=1200%2C798&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__gasparini-scaled.webp.webp?fit=1200%2C798&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__gasparini-scaled.webp.webp?fit=1200%2C798&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__gasparini-scaled.webp.webp?fit=1200%2C798&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__gasparini-scaled.webp.webp?fit=1200%2C798&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":40573,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/04\/vice-presidente-alckmin-homenageia-ex-prefeito-de-ribeirao-welson-gasparini\/","url_meta":{"origin":38644,"position":3},"title":"Vice-presidente Alckmin homenageia ex-prefeito de Ribeir\u00e3o Welson Gasparini","author":"ismaelcolosi.com.br","date":"4 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] O vice-presidente Geraldo Alckmin homenageou na tarde desta segunda-feira (4) o ex-prefeito de Ribeir\u00e3o Preto Welson Gasparini, que morreu na manh\u00e3 de hoje. O prefeito de Ribeir\u00e3o Preto Duarte Nogueira, os deputados federais Baleia Rossi e Ricardo Silva, tamb\u00e9m homenagearam Welson Gasparini. Confira as homenagens ao ex-prefeito: \u201cO ex-prefeito\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-27.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-27.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-27.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-27.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-27.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":40537,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/04\/saiba-quando-sera-o-velorio-do-ex-prefeito-de-ribeirao-preto-welson-gasparini\/","url_meta":{"origin":38644,"position":4},"title":"Saiba quando ser\u00e1 o vel\u00f3rio do ex-prefeito de Ribeir\u00e3o Preto Welson Gasparini","author":"ismaelcolosi.com.br","date":"4 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] O vel\u00f3rio do ex-prefeito de Ribeir\u00e3o Preto Welson Gasparini, que morreu nesta segunda-feira (4), aos 87 anos, ser\u00e1 realizado a partir das 18h. De acordo com Hospital Unimed, Gasparini morreu de causas naturais. Gasparini estava internado desde o dia 16 de fevereiro e passou por um cateterismo e uma\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-42.png?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-42.png?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-42.png?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-42.png?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-42.png?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":40503,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/04\/morreu-nesta-segunda-welson-gasparini\/","url_meta":{"origin":38644,"position":5},"title":"Morre Welson Gasparini, ex-prefeito de Ribeir\u00e3o por 4 mandatos","author":"ismaelcolosi.com.br","date":"4 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] 4 de mar\u00e7o de 2024 | 11:454 de mar\u00e7o de 2024 | 11:56 0Morreu nesta segunda-feira (4), Welson Gasparini, aos 87 anos. Gasparini estava internado no\u00a0Hospital Unimed, em Bonfim Paulista, e passou por uma cirurgia card\u00edaca na semana passadaWelson Gasparini foi\u00a0prefeito de Ribeir\u00e3o Preto quatro vezes, se tornando o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/2-scaled.jpg?fit=325%2C450&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-a3i","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/38644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=38644"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/38644\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/38645"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=38644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=38644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=38644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}