{"id":37044,"date":"2024-02-14T06:23:43","date_gmt":"2024-02-14T09:23:43","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/14\/empreendedoras-precisam-aprender-a-cobrar-bem-forbes\/"},"modified":"2024-02-14T06:23:43","modified_gmt":"2024-02-14T09:23:43","slug":"empreendedoras-precisam-aprender-a-cobrar-bem-forbes","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/14\/empreendedoras-precisam-aprender-a-cobrar-bem-forbes\/","title":{"rendered":"empreendedoras-precisam-aprender-a-cobrar-bem Forbes"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<div id=\"attachment_475693\" class=\"wp-caption alignnone style=\" max-width:=\"\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-475693 size-medium\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2022\/06\/anafontes-redemulherempreendedora-forbesmulher-768x512.jpg?resize=678%2C452&#038;ssl=1\" http:=\"\" alt=\"Priscila Prade\" width=\"678\" height=\"452\" data-lazy-src=\"https:\/\/forbes.com.br\/wp-content\/uploads\/2022\/06\/anafontes-redemulherempreendedora-forbesmulher-768x512.jpg\"\/><noscript><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-475693 size-medium\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2022\/06\/anafontes-redemulherempreendedora-forbesmulher-768x512.jpg?resize=678%2C452&#038;ssl=1\" alt=\"Priscila Prade\" width=\"678\" height=\"452\"\/><\/noscript><\/p>\n<p>Priscila Prade<\/p>\n<p class=\"wp-caption-text\">\u201cNormalmente, os homens s\u00e3o ensinados a valorizar mais seu trabalho e seu tempo do que as mulheres\u201d, diz Ana Fontes, da Rede Mulher Empreendedora.<\/p>\n<\/div>\n<p>Fundadora da Rede Mulher Empreendedora, Ana Fontes circula entre milhares de empres\u00e1rias, de diferentes setores e realidades, e ouve relatos de sucessos, fracassos e da inseguran\u00e7a que rodeia as trajet\u00f3rias de muitas delas.<\/p>\n<ul>\n<li>\n<h3>Siga a <a href=\"https:\/\/whatsapp.com\/channel\/0029Va9gQKwBFLgM96cJnu0u\" target=\"_blank\" rel=\"noopener\">Forbes<\/a> no WhatsApp e receba as principais not\u00edcias sobre neg\u00f3cios, carreira, tecnologia e estilo de vida<\/h3>\n<\/li>\n<\/ul>\n<p>Mas isso n\u00e3o impediu que Ana e sua equipe ficassem surpresas quando, ao pedirem or\u00e7amentos para um servi\u00e7o de tradu\u00e7\u00e3o que precisavam contratar para a Rede, se depararam com o impacto da s\u00edndrome da impostora na pr\u00e1tica. \u201cOs or\u00e7amentos dos homens eram, em m\u00e9dia, 50% mais caros, e o tempo de execu\u00e7\u00e3o na proposta era maior\u201d, diz Ana Fontes, que recebeu 12 or\u00e7amentos \u2013 metade de homens e a outra de mulheres.<\/p>\n<p>Apesar da pequena amostra, a observa\u00e7\u00e3o da fundadora da Rede Mulher Empreendedora \u00e9 confirmada por outras pesquisas e ilustra um cen\u00e1rio mais amplo. Um estudo liderado por uma professora de Harvard mostra que, de fato, as mulheres pedem prazos mais curtos que os homens e t\u00eam menos probabilidade de negociar uma extens\u00e3o no deadline, acreditando que ser\u00e3o julgadas ou penalizadas.<\/p>\n<p>Para Ana, isso se deve a uma constru\u00e7\u00e3o social. \u201cNormalmente, os homens s\u00e3o ensinados a valorizar mais seu trabalho e seu tempo do que as mulheres.\u201d<\/p>\n<p><strong>Leia tamb\u00e9m:\u00a0<\/strong><\/p>\n<p>O problema vai al\u00e9m da quest\u00e3o financeira. A sensa\u00e7\u00e3o de ter muita coisa para entregar em pouco tempo tamb\u00e9m causa mais estresse e burnout, segundo a pesquisa. Al\u00e9m disso, as mulheres tamb\u00e9m s\u00e3o as principais respons\u00e1veis pelo trabalho de cuidado \u2013 com a casa, os filhos e outros parentes \u2013, e precisam enfrentar uma tripla jornada.<\/p>\n<h2>Por que as mulheres cobram menos?<\/h2>\n<p>As mulheres n\u00e3o t\u00eam menos capacidade que os homens ou entregam um servi\u00e7o inferior. \u201cMas por serem julgadas por tudo, acabam tendo a autoconfian\u00e7a abalada\u201d, diz Ana Fontes, que prioriza a contrata\u00e7\u00e3o de mulheres e de servi\u00e7os de empresas lideradas por empreendedoras.<\/p>\n<p>Pesquisas mostram que muitas mulheres acreditam que precisam cobrar menos para garantir e manter os clientes. A diferen\u00e7a salarial entre os g\u00eaneros, que ainda persiste no mundo corporativo, tamb\u00e9m existe no universo do empreendedorismo, mesmo em empresas do mesmo setor. \u201cMuitas profissionais oferecem servi\u00e7os de gra\u00e7a porque querem ser aceitas\u201d, diz a empreendedora. \u201cElas s\u00e3o muito rigorosas consigo mesmas.\u201d<\/p>\n<p>Ana Fontes deixa dicas para que empreendedoras e empreendedores valorizem seu trabalho e saibam cobrar pelos seus servi\u00e7os:<\/p>\n<ol>\n<li>Tenha no\u00e7\u00e3o de quanto vale seu trabalho e quanto custa a sua hora;<\/li>\n<li>Entenda qual foi o investimento feito no seu trabalho \u2013 ele precisa estar no seu pre\u00e7o (Por exemplo, n\u00e3o \u00e9 apenas o pre\u00e7o de uma tradu\u00e7\u00e3o, sua experi\u00eancia, seu curr\u00edculo e dedica\u00e7\u00e3o precisam ser contabilizados);<\/li>\n<li>Olhe para o mercado \u2013 veja o que outros profissionais (homens e mulheres) est\u00e3o oferecendo e por qual pre\u00e7o;<\/li>\n<li>Converse com profissionais da sua \u00e1rea e de outros setores;<\/li>\n<li>Deixe claro seu diferencial;<\/li>\n<li>N\u00e3o tenha vergonha de divulgar seu trabalho \u2013 muito menos de cobrar por ele;<\/li>\n<li>Tenha clareza do valor e do resultado que voc\u00ea est\u00e1 entregando \u2013 assim, dificilmente vai cobrar menos do que \u00e9 justo;<\/li>\n<li>Ajude outros empreendedores, especialmente mulheres, divulgando e consumindo seu trabalho;<\/li>\n<li>N\u00e3o pe\u00e7a desconto para outras empreendedoras, elas tamb\u00e9m merecem ter seu trabalho valorizado.<\/li>\n<\/ol>\n<\/div>\n<p><script type=\"rocketlazyloadscript\">\n\t\t\t\t(function(d, s, id){\n\t\t\t\t\tvar js, fjs = d.getElementsByTagName(s)[0];\n\t\t\t\t\tif (d.getElementById(id)) return;\n\t\t\t\t\tjs = d.createElement(s); js.id = id;\n\t\t\t\t\tjs.src = \"\/\/connect.facebook.net\/pt_BR\/sdk.js#xfbml=1&version=v2.9\";\n\t\t\t\t\tfjs.parentNode.insertBefore(js, fjs);\n\t\t\t\t}(document, 'script', 'facebook-jssdk'));\n\t\t\t<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/forbes.com.br\/carreira\/2024\/02\/empreendedoras-precisam-aprender-a-cobrar-bem\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Priscila Prade \u201cNormalmente, os homens s\u00e3o ensinados a valorizar mais seu trabalho e seu tempo do que as mulheres\u201d, diz Ana Fontes, da Rede Mulher Empreendedora. Fundadora da Rede Mulher Empreendedora, Ana Fontes circula entre milhares de empres\u00e1rias, de diferentes setores e realidades, e ouve relatos de sucessos, fracassos e da inseguran\u00e7a que rodeia &#8230; <a title=\"empreendedoras-precisam-aprender-a-cobrar-bem Forbes\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/14\/empreendedoras-precisam-aprender-a-cobrar-bem-forbes\/\" aria-label=\"Leia mais sobre empreendedoras-precisam-aprender-a-cobrar-bem Forbes\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":37045,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1964],"tags":[],"class_list":["post-37044","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carreira-e-sucesso-dicas-para-carreira"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/anafontes-redemulherempreendedora-forbesmulher-1024x683.jpg?fit=1024%2C683&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/anafontes-redemulherempreendedora-forbesmulher-1024x683.jpg?fit=1024%2C683&ssl=1",1024,683,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/anafontes-redemulherempreendedora-forbesmulher-1024x683.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/anafontes-redemulherempreendedora-forbesmulher-1024x683.jpg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/anafontes-redemulherempreendedora-forbesmulher-1024x683.jpg?fit=768%2C512&ssl=1",768,512,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/anafontes-redemulherempreendedora-forbesmulher-1024x683.jpg?fit=1024%2C683&ssl=1",1024,683,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/anafontes-redemulherempreendedora-forbesmulher-1024x683.jpg?fit=1024%2C683&ssl=1",1024,683,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/anafontes-redemulherempreendedora-forbesmulher-1024x683.jpg?fit=1024%2C683&ssl=1",1024,683,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Priscila Prade \u201cNormalmente, os homens s\u00e3o ensinados a valorizar mais seu trabalho e seu tempo do que as mulheres\u201d, diz Ana Fontes, da Rede Mulher Empreendedora. Fundadora da Rede Mulher Empreendedora, Ana Fontes circula entre milhares de empres\u00e1rias, de diferentes setores e realidades, e ouve relatos de sucessos, fracassos e da inseguran\u00e7a que rodeia&hellip;","jetpack-related-posts":[{"id":82563,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/02\/04\/quer-empreender-em-2025-veja-7-dicas-essenciais\/","url_meta":{"origin":37044,"position":0},"title":"Quer Empreender em 2025? Veja 7 Dicas Essenciais","author":"ismaelcolosi.com.br","date":"4 de Fevereiro de 2025","format":false,"excerpt":"[ad_1] \r Victor Affaro\r Ana Fontes \u00e9 fundadora e CEO da Rede Mulher Empreendedora e do Instituto RME, al\u00e9m de Presidente do W20, VP do Pacto Global da ONU no Brasil e conselheira \r Acessibilidade \r L\r L\r A-\r A+\r \r \u25d0\r \r \u00a0 \u00a0 Ter o pr\u00f3prio neg\u00f3cio \u00e9\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/mulher-empreendedora-ana-fontes-1200x675.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/mulher-empreendedora-ana-fontes-1200x675.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/mulher-empreendedora-ana-fontes-1200x675.jpeg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/mulher-empreendedora-ana-fontes-1200x675.jpeg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/02\/mulher-empreendedora-ana-fontes-1200x675.jpeg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":52312,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/05\/amazon-abre-programa-para-mulheres-empreendedoras\/","url_meta":{"origin":37044,"position":1},"title":"Amazon abre programa para mulheres empreendedoras","author":"ismaelcolosi.com.br","date":"5 de Junho de 2024","format":false,"excerpt":"[ad_1] \u00a0 Acessibilidade L L A- A+ \u25d0 A Amazon acaba de abrir as inscri\u00e7\u00f5es para a quarta edi\u00e7\u00e3o do Decola Garota, programa de acelera\u00e7\u00e3o para capacitar mulheres empreendedoras que querem expandir suas empresas nacional e internacionalmente. Ser\u00e3o selecionadas 30 participantes que tenham um neg\u00f3cio formalizado focado na venda de\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/mulheres-empreendedoras-amazon-1-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/mulheres-empreendedoras-amazon-1-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/mulheres-empreendedoras-amazon-1-1024x683.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/mulheres-empreendedoras-amazon-1-1024x683.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":86735,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/07\/23\/amazon-abre-vagas-para-programa-de-empreendedorismo-feminino\/","url_meta":{"origin":37044,"position":2},"title":"Amazon Abre Vagas Para Programa de Empreendedorismo Feminino","author":"ismaelcolosi.com.br","date":"23 de Julho de 2025","format":false,"excerpt":"[ad_1] \r Morsa Images\/Getty Images\r Desde sua cria\u00e7\u00e3o, em 2022, o Decola Garota j\u00e1 capacitou mais de 80 empreendedoras em quatro turmas\r Acessibilidade \r L\r L\r A-\r A+\r \r \u25d0\r \r A Amazon Brasil est\u00e1 com inscri\u00e7\u00f5es abertas para a 5\u00aa edi\u00e7\u00e3o do programa Decola Garota, realizado em parceria com\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/07\/Empreendedorismo-3-1-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/07\/Empreendedorismo-3-1-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/07\/Empreendedorismo-3-1-1200x675.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/07\/Empreendedorismo-3-1-1200x675.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/07\/Empreendedorismo-3-1-1200x675.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":86778,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/07\/25\/amazon-e-rme-tem-vagas-para-programa-de-empreendedorismo-feminino\/","url_meta":{"origin":37044,"position":3},"title":"Amazon e RME T\u00eam Vagas Para Programa de Empreendedorismo Feminino","author":"ismaelcolosi.com.br","date":"25 de Julho de 2025","format":false,"excerpt":"[ad_1] \r Morsa Images\/Getty Images\r Desde sua cria\u00e7\u00e3o, em 2022, o Decola Garota j\u00e1 capacitou mais de 80 empreendedoras em quatro turmas\r Acessibilidade \r L\r L\r A-\r A+\r \r \u25d0\r \r A Amazon Brasil est\u00e1 com inscri\u00e7\u00f5es abertas para a 5\u00aa edi\u00e7\u00e3o do programa Decola Garota, realizado em parceria com\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/07\/1753431405_Empreendedorismo-3-1-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/07\/1753431405_Empreendedorismo-3-1-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/07\/1753431405_Empreendedorismo-3-1-1200x675.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/07\/1753431405_Empreendedorismo-3-1-1200x675.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/07\/1753431405_Empreendedorismo-3-1-1200x675.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":66929,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/20\/quem-e-o-empresario-que-disse-deus-me-livre-de-mulher-ceo-e-pediu-desculpas-apos-reacoes\/","url_meta":{"origin":37044,"position":4},"title":"Quem \u00e9 o empres\u00e1rio que disse \u2018Deus me livre de mulher CEO\u2019 e pediu desculpas ap\u00f3s rea\u00e7\u00f5es","author":"ismaelcolosi.com.br","date":"20 de Setembro de 2024","format":false,"excerpt":"[ad_1] Da reda\u00e7\u00e3oi Da reda\u00e7\u00e3o 20\/09\/2024 - 2:44 Tallis Gomes fundou a Easy Taxi,\u00a0criou a plataforma Singu, definida como o \u201cUber da beleza\u201d, e atualmente \u00e9 presidente e s\u00f3cio da G4 Educa\u00e7\u00e3o, empresa que faturou R$ 200 milh\u00f5es em 2023. Mas n\u00e3o foi esse curr\u00edculo que deixou o empres\u00e1rio famoso,\u2026","rel":"","context":"In &quot;Empregos - Classificados&quot;","block_context":{"text":"Empregos - Classificados","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/singu.jpg?fit=860%2C484&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/singu.jpg?fit=860%2C484&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/singu.jpg?fit=860%2C484&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/singu.jpg?fit=860%2C484&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":79208,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/12\/13\/grupo-silvio-santos-nomeia-ana-karina-bortoni-como-nova-ceo\/","url_meta":{"origin":37044,"position":5},"title":"Grupo Silvio Santos nomeia Ana Karina Bortoni como nova CEO","author":"ismaelcolosi.com.br","date":"13 de Dezembro de 2024","format":false,"excerpt":"[ad_1] \r \r \r \r Executiva, que est\u00e1 na holding desde 2015, foi a primeira mulher CEO de um banco brasileiro \r \r \r \r Divulga\u00e7\u00e3o\/BMG\r Ana Karina Bortoni foi CEO do Banco BMG e capa da Forbes na edi\u00e7\u00e3o Mulheres de Sucesso em 2022\r \u00a0 Acessibilidade \r L\r L\r\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/Ana-Karina-Bortoni-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/Ana-Karina-Bortoni-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/Ana-Karina-Bortoni-1200x675.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/Ana-Karina-Bortoni-1200x675.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/Ana-Karina-Bortoni-1200x675.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-9Du","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/37044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=37044"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/37044\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/37045"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=37044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=37044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=37044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}