{"id":36954,"date":"2024-02-13T06:44:42","date_gmt":"2024-02-13T09:44:42","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/13\/conheca-10-bilionarios-que-fizeram-fortuna-apenas-trabalhando-para-os-outros-2\/"},"modified":"2024-02-13T06:44:42","modified_gmt":"2024-02-13T09:44:42","slug":"conheca-10-bilionarios-que-fizeram-fortuna-apenas-trabalhando-para-os-outros-2","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/13\/conheca-10-bilionarios-que-fizeram-fortuna-apenas-trabalhando-para-os-outros-2\/","title":{"rendered":"Conhe\u00e7a 10 bilion\u00e1rios que fizeram fortuna apenas trabalhando para os outros"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<div id=\"attachment_594422\" class=\"wp-caption alignnone style=\" max-width:=\"\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"alignnone alignnone size-medium wp-image-594422\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2024\/02\/Jonathan-Gray-Steve-Ballmer-Lisa-Su-Fotos-GUERIN-BLASK-RICK-DAHMS-JAMEL-TOPPIN-FORBES-768x512.png?resize=678%2C452&#038;ssl=1\" http:=\"\" alt=\"Os bilion\u00e1rios Jonathan Gray, Steve Ballmer e Lisa Su - Fotos: GUERIN BLASK - RICK DAHMS - JAMEL TOPPIN - FORBES\" width=\"678\" height=\"452\" data-lazy-src=\"https:\/\/forbes.com.br\/wp-content\/uploads\/2024\/02\/Jonathan-Gray-Steve-Ballmer-Lisa-Su-Fotos-GUERIN-BLASK-RICK-DAHMS-JAMEL-TOPPIN-FORBES-768x512.png\"\/><noscript><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"alignnone alignnone size-medium wp-image-594422\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2024\/02\/Jonathan-Gray-Steve-Ballmer-Lisa-Su-Fotos-GUERIN-BLASK-RICK-DAHMS-JAMEL-TOPPIN-FORBES-768x512.png?resize=678%2C452&#038;ssl=1\" alt=\"Os bilion\u00e1rios Jonathan Gray, Steve Ballmer e Lisa Su - Fotos: GUERIN BLASK - RICK DAHMS - JAMEL TOPPIN - FORBES\" width=\"678\" height=\"452\"\/><\/noscript><\/p>\n<p>Os bilion\u00e1rios Jonathan Gray, Steve Ballmer e Lisa Su &#8211; Fotos: GUERIN BLASK &#8211; RICK DAHMS &#8211; JAMEL TOPPIN &#8211; FORBES<\/p>\n<p class=\"wp-caption-text\">Os bilion\u00e1rios contratados<\/p>\n<\/div>\n<p>Ao pensar em um bilion\u00e1rio, provavelmente venha \u00e0 sua cabe\u00e7a a imagem de fundadores de grandes empresas, como \u00e9 o caso do CEO da Meta, Mark Zuckerberg, e o presidente da Amazon, Jeff Bezos. Al\u00e9m deles, existem os herdeiros, como Jacqueline Mars, neta do fundador da empresa de doces Mars, e Thomas Pritzker, cujos antepassados fundaram a cadeia de hot\u00e9is Hyatt, da qual ele \u00e9 CEO.<\/p>\n<ul>\n<li>\n<h3>Siga o canal da <a href=\"https:\/\/whatsapp.com\/channel\/0029Va9gQKwBFLgM96cJnu0u\" target=\"_blank\" rel=\"noopener\">Forbes<\/a> e de <a href=\"https:\/\/whatsapp.com\/channel\/0029VaAZk57JuyA9F4UwQc2I\" target=\"_blank\" rel=\"noopener\">Forbes Money<\/a> no WhatsApp e receba as principais not\u00edcias sobre neg\u00f3cios, carreira, tecnologia e estilo de vida<\/h3>\n<\/li>\n<\/ul>\n<p>Esse pensamento \u00e9 normal, j\u00e1 que aproximadamente 69% dos quase 760 bilion\u00e1rios nos Estados Unidos listados pela Forbes se enquadram na primeira categoria, enquanto um pouco mais de 27% herdaram uma grande fortuna. Ao todo, quase 97% dos bilion\u00e1rios americanos pertencem a essas duas categorias.<\/p>\n<p>Por\u00e9m, existe uma rara terceira op\u00e7\u00e3o, que enquadra aqueles que n\u00e3o s\u00e3o nem fundadores, nem herdeiros: eles s\u00e3o chamados de bilion\u00e1rios contratados, ou bilion\u00e1rios da escalada corporativa.<\/p>\n<p>A Forbes identificou apenas 26 pessoas que foram contratadas como executivos, funcion\u00e1rios juniores ou CEOs, e que se tornaram bilion\u00e1rias. Esses executivos ultra-ricos trabalham ou trabalharam em apenas 20 empresas, quase todas do setor de tecnologia ou private equity. Entre os mais not\u00e1veis est\u00e3o o CEO da Apple, Tim Cook; o CEO do JPMorgan Chase, Jamie Dimon; e Jonathan Gray, que foi contratado pela Blackstone em 1992 logo ap\u00f3s a faculdade e foi nomeado presidente e diretor de opera\u00e7\u00f5es da empresa em 2018.<\/p>\n<p>Nessa categoria, o mais rico entre os bilion\u00e1rios executivos \u00e9 Steve Ballmer, amigo de Harvard de Bill Gates, que ingressou na Microsoft em 1980 como funcion\u00e1rio n\u00famero 40 e liderou a empresa como CEO de 2000 a 2014. O membro mais recente deste grupo de elite \u00e9 Lisa Su, CEO da empresa de chips AMD, que recentemente se tornou bilion\u00e1ria devido ao aumento no pre\u00e7o das a\u00e7\u00f5es da companhia. Ela \u00e9 uma das cinco mulheres nesta lista.<\/p>\n<p>Outras nomes incluem Jayshree Ullal, da Arista Networks; a ex-COO da Meta, Sheryl Sandberg; e Meg Whitman, que como ex-CEO do eBay levou a empresa de uma receita de US$ 5,7 milh\u00f5es em 1998 para US$ 5 bilh\u00f5es em 2008, acumulando milh\u00f5es de a\u00e7\u00f5es no processo e se tornando bilion\u00e1ria em 2003.<\/p>\n<p>Aqui listamos as 10 pessoas mais ricas, que como funcion\u00e1rios se tornaram bilion\u00e1rios:<\/p>\n<div class=\"pksGallery\">\n<div class=\"stage\">\n<span class=\"back\"\/><br \/>\n<span class=\"next\"\/><\/p>\n<ul>\n<li>\n<div>\n<span><br \/>\n<img data-recalc-dims=\"1\" height=\"533\" width=\"800\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2024\/02\/Steve-Ballmer-1-800x533.jpg?resize=800%2C533&#038;ssl=1\" http:=\"\" data-lazy-src=\"https:\/\/forbes.com.br\/wp-content\/uploads\/2024\/02\/Steve-Ballmer-1-800x533.jpg\"\/><noscript><img data-recalc-dims=\"1\" height=\"533\" width=\"800\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2024\/02\/Steve-Ballmer-1-800x533.jpg?resize=800%2C533&#038;ssl=1\"\/><\/noscript><\/p>\n<article>\n<span class=\"credito\">Steve Ballmer &#8211; Foto: Getty Images<\/span><\/p>\n<h2>1. Steve Balmer<\/h2>\n<p>Fortuna: US$ 120,5 bilh\u00f5es<br \/>Empresa: Microsoft<br \/>Cargo: Ex-CEO<br \/>Ano de contrata\u00e7\u00e3o: 1980<\/p>\n<\/article>\n<p><\/span>\n<\/div>\n<\/li>\n<li>\n<div>\n<span><br \/>\n<img data-recalc-dims=\"1\" height=\"533\" width=\"800\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2023\/12\/Money_Eric-Schmidt_GettyImages-800x533.jpg?resize=800%2C533&#038;ssl=1\" http:=\"\" data-lazy-src=\"https:\/\/forbes.com.br\/wp-content\/uploads\/2023\/12\/Money_Eric-Schmidt_GettyImages-800x533.jpg\"\/><noscript><img data-recalc-dims=\"1\" height=\"533\" width=\"800\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2023\/12\/Money_Eric-Schmidt_GettyImages-800x533.jpg?resize=800%2C533&#038;ssl=1\"\/><\/noscript><\/p>\n<article>\n<span class=\"credito\">Eric Schmidt &#8211; Foto: Susan Walsh &#8211; AP<\/span><\/p>\n<h2>2. Eric Schmidt<\/h2>\n<p>Fortuna: US$ 20,7 bilh\u00f5es<br \/>Empresa: Google<br \/>Cargo: Ex-CEO<br \/>Ano de contrata\u00e7\u00e3o: 2001<\/p>\n<\/article>\n<p><\/span>\n<\/div>\n<\/li>\n<li>\n<div>\n<span><br \/>\n<img data-recalc-dims=\"1\" height=\"533\" width=\"800\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2024\/02\/Ramzi-Musallam-Fotos-Jamel-Toppin-Forbes-800x533.png?resize=800%2C533&#038;ssl=1\" http:=\"\" data-lazy-src=\"https:\/\/forbes.com.br\/wp-content\/uploads\/2024\/02\/Ramzi-Musallam-Fotos-Jamel-Toppin-Forbes-800x533.png\"\/><noscript><img data-recalc-dims=\"1\" height=\"533\" width=\"800\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2024\/02\/Ramzi-Musallam-Fotos-Jamel-Toppin-Forbes-800x533.png?resize=800%2C533&#038;ssl=1\"\/><\/noscript><\/p>\n<article>\n<span class=\"credito\">Ramzi Musallam &#8211; Foto: Jamel Toppin &#8211; Forbes<\/span><\/p>\n<h2>3. Ramzi Musallam<\/h2>\n<p>Fortuna: US$ 9 bilh\u00f5es<br \/>Empresa: Veritas Capital<br \/>Cargo: CEO<br \/>Ano de contrata\u00e7\u00e3o: 1997<\/p>\n<\/article>\n<p><\/span>\n<\/div>\n<\/li>\n<li>\n<div>\n<span><br \/>\n<img data-recalc-dims=\"1\" height=\"533\" width=\"800\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2024\/02\/John-Brown-Fotos-Divulgacao-Stryker-800x533.png?resize=800%2C533&#038;ssl=1\" http:=\"\" data-lazy-src=\"https:\/\/forbes.com.br\/wp-content\/uploads\/2024\/02\/John-Brown-Fotos-Divulgacao-Stryker-800x533.png\"\/><noscript><img data-recalc-dims=\"1\" height=\"533\" width=\"800\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2024\/02\/John-Brown-Fotos-Divulgacao-Stryker-800x533.png?resize=800%2C533&#038;ssl=1\"\/><\/noscript><\/p>\n<article>\n<span class=\"credito\">John Brown &#8211; Foto: Divulga\u00e7\u00e3o Stryker<\/span><\/p>\n<h2>4. John Brown<\/h2>\n<p>Fortuna: US$ 7,4 bilh\u00f5es<br \/>Empresa: Stryker Corp<br \/>Cargo: Ex-CEO<br \/>Ano de contrata\u00e7\u00e3o: 1977<\/p>\n<\/article>\n<p><\/span>\n<\/div>\n<\/li>\n<li>\n<\/li>\n<li>\n<div>\n<span><br \/>\n<img data-recalc-dims=\"1\" height=\"533\" width=\"800\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2024\/02\/Charles-Simonyi-Fotos-Reproducao-Forbes-800x533.png?resize=800%2C533&#038;ssl=1\" http:=\"\" data-lazy-src=\"https:\/\/forbes.com.br\/wp-content\/uploads\/2024\/02\/Charles-Simonyi-Fotos-Reproducao-Forbes-800x533.png\"\/><noscript><img data-recalc-dims=\"1\" height=\"533\" width=\"800\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2024\/02\/Charles-Simonyi-Fotos-Reproducao-Forbes-800x533.png?resize=800%2C533&#038;ssl=1\"\/><\/noscript><\/p>\n<article>\n<span class=\"credito\">Charles Simonyi &#8211; Foto: Reproducao &#8211; Forbes<\/span><\/p>\n<h2>5. Charles Simonyi<\/h2>\n<p>Fortuna: US$ 7,3 bilh\u00f5es<br \/>Empresa: Microsoft<br \/>Cargo: Ex- Chefe de arquitetura de software<br \/>Ano de contrata\u00e7\u00e3o: 1981<\/p>\n<\/article>\n<p><\/span>\n<\/div>\n<\/li>\n<li>\n<div>\n<span><br \/>\n<img data-recalc-dims=\"1\" height=\"533\" width=\"800\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2024\/02\/Jonathan-Gray-Fotos-getty-images-800x533.png?resize=800%2C533&#038;ssl=1\" http:=\"\" data-lazy-src=\"https:\/\/forbes.com.br\/wp-content\/uploads\/2024\/02\/Jonathan-Gray-Fotos-getty-images-800x533.png\"\/><noscript><img data-recalc-dims=\"1\" height=\"533\" width=\"800\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2024\/02\/Jonathan-Gray-Fotos-getty-images-800x533.png?resize=800%2C533&#038;ssl=1\"\/><\/noscript><\/p>\n<article>\n<span class=\"credito\">Jonathan Gray &#8211; Foto: Getty Images<\/span><\/p>\n<h2>6. Jonathan Gray<\/h2>\n<p>Fortuna: US$ 7,3 bilh\u00f5es<br \/>Empresa: Blackstone<br \/>Cargo: Presidente, COO<br \/>Ano de contrata\u00e7\u00e3o: 1992<\/p>\n<\/article>\n<p><\/span>\n<\/div>\n<\/li>\n<li>\n<div>\n<span><br \/>\n<img data-recalc-dims=\"1\" height=\"533\" width=\"800\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2024\/02\/Jeff-Rothschild-Fotos-Reproducao-Forbes-800x533.png?resize=800%2C533&#038;ssl=1\" http:=\"\" data-lazy-src=\"https:\/\/forbes.com.br\/wp-content\/uploads\/2024\/02\/Jeff-Rothschild-Fotos-Reproducao-Forbes-800x533.png\"\/><noscript><img data-recalc-dims=\"1\" height=\"533\" width=\"800\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2024\/02\/Jeff-Rothschild-Fotos-Reproducao-Forbes-800x533.png?resize=800%2C533&#038;ssl=1\"\/><\/noscript><\/p>\n<article>\n<span class=\"credito\">Jeff Rothschild &#8211; Fotos: Reprodu\u00e7\u00e3o &#8211; Forbes<\/span><\/p>\n<h2>7. Jeff Rothschild<\/h2>\n<p>Fortuna: US$ 5,7 bilh\u00f5es<br \/>Empresa: Facebook<br \/>Cargo: Ex-Vice Presidente<br \/>Ano de contrata\u00e7\u00e3o: 2005<\/p>\n<\/article>\n<p><\/span>\n<\/div>\n<\/li>\n<li>\n<div>\n<span><br \/>\n<img data-recalc-dims=\"1\" height=\"533\" width=\"800\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2024\/02\/Jeff-Skoll-Fotos-Getty-Images-800x533.png?resize=800%2C533&#038;ssl=1\" http:=\"\" data-lazy-src=\"https:\/\/forbes.com.br\/wp-content\/uploads\/2024\/02\/Jeff-Skoll-Fotos-Getty-Images-800x533.png\"\/><noscript><img data-recalc-dims=\"1\" height=\"533\" width=\"800\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2024\/02\/Jeff-Skoll-Fotos-Getty-Images-800x533.png?resize=800%2C533&#038;ssl=1\"\/><\/noscript><\/p>\n<article>\n<span class=\"credito\">Jeff Skoll &#8211; Foto: Getty Images<\/span><\/p>\n<h2>8. Jeff Skoll<\/h2>\n<p>Fortuna: US$ 4,3 bilh\u00f5es<br \/>Empresa: EBay<br \/>Cargo: Ex-Presidente<br \/>Ano de contrata\u00e7\u00e3o: 1995<\/p>\n<\/article>\n<p><\/span>\n<\/div>\n<\/li>\n<li>\n<div>\n<span><br \/>\n<img data-recalc-dims=\"1\" height=\"533\" width=\"800\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2024\/02\/Hamilton-Tony-James-Fotos-CHRISTOPHER-GOODNEY-BLOOMBERG-800x533.png?resize=800%2C533&#038;ssl=1\" http:=\"\" data-lazy-src=\"https:\/\/forbes.com.br\/wp-content\/uploads\/2024\/02\/Hamilton-Tony-James-Fotos-CHRISTOPHER-GOODNEY-BLOOMBERG-800x533.png\"\/><noscript><img data-recalc-dims=\"1\" height=\"533\" width=\"800\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2024\/02\/Hamilton-Tony-James-Fotos-CHRISTOPHER-GOODNEY-BLOOMBERG-800x533.png?resize=800%2C533&#038;ssl=1\"\/><\/noscript><\/p>\n<article>\n<span class=\"credito\">Hamilton &#8220;Tony&#8221; James &#8211; Foto: Christopher Goodney &#8211; Bloomberg<\/span><\/p>\n<h2>9. Hamilton \u201cTony\u201d James<\/h2>\n<p>Fortuna: US$ 4,1 bilh\u00f5es<br \/>Empresa: Blackstone<br \/>Cargo: Ex-Conselheiro Executivo<br \/>Ano de contrata\u00e7\u00e3o: 2002<\/p>\n<\/article>\n<p><\/span>\n<\/div>\n<\/li>\n<li>\n<div>\n<span><br \/>\n<img data-recalc-dims=\"1\" height=\"533\" width=\"800\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2024\/02\/Jayshree-Ullal-Fotos-CNBC-Getty-Images-800x533.png?resize=800%2C533&#038;ssl=1\" http:=\"\" data-lazy-src=\"https:\/\/forbes.com.br\/wp-content\/uploads\/2024\/02\/Jayshree-Ullal-Fotos-CNBC-Getty-Images-800x533.png\"\/><noscript><img data-recalc-dims=\"1\" height=\"533\" width=\"800\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2024\/02\/Jayshree-Ullal-Fotos-CNBC-Getty-Images-800x533.png?resize=800%2C533&#038;ssl=1\"\/><\/noscript><\/p>\n<article>\n<span class=\"credito\">Jayshree Ullal &#8211; Foto: CNBC &#8211; Getty Images<\/span><\/p>\n<h2>10. Jayshree Ullal<\/h2>\n<p>Fortuna: US$ 3,6 bilh\u00f5es<br \/>Empresa: Arista Networks<br \/>Cargo: CEO<br \/>Ano de contrata\u00e7\u00e3o: 2008<\/p>\n<\/article>\n<p><\/span>\n<\/div>\n<\/li>\n<li>\n<div>\n<span><br \/>\n<img data-recalc-dims=\"1\" height=\"533\" width=\"649\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2024\/02\/Captura-de-tela-2024-02-08-154739-649x533.png?resize=649%2C533&#038;ssl=1\" http:=\"\" data-lazy-src=\"https:\/\/forbes.com.br\/wp-content\/uploads\/2024\/02\/Captura-de-tela-2024-02-08-154739-649x533.png\"\/><noscript><img data-recalc-dims=\"1\" height=\"533\" width=\"649\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/forbes.com.br\/wp-content\/uploads\/2024\/02\/Captura-de-tela-2024-02-08-154739-649x533.png?resize=649%2C533&#038;ssl=1\"\/><\/noscript><\/p>\n<article>\n<span class=\"credito\"\/><\/p>\n<h2>Lista dos 26 bilion\u00e1rios<\/h2>\n<\/article>\n<p><\/span>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div class=\"description\">\n<span class=\"credito\">Steve Ballmer &#8211; Foto: Getty Images<\/span><\/p>\n<h2>1. Steve Balmer<\/h2>\n<p>Fortuna: US$ 120,5 bilh\u00f5es<br \/>Empresa: Microsoft<br \/>Cargo: Ex-CEO<br \/>Ano de contrata\u00e7\u00e3o: 1980<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p><script type=\"rocketlazyloadscript\">\n\t\t\t\t(function(d, s, id){\n\t\t\t\t\tvar js, fjs = d.getElementsByTagName(s)[0];\n\t\t\t\t\tif (d.getElementById(id)) return;\n\t\t\t\t\tjs = d.createElement(s); js.id = id;\n\t\t\t\t\tjs.src = \"\/\/connect.facebook.net\/pt_BR\/sdk.js#xfbml=1&version=v2.9\";\n\t\t\t\t\tfjs.parentNode.insertBefore(js, fjs);\n\t\t\t\t}(document, 'script', 'facebook-jssdk'));\n\t\t\t<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/forbes.com.br\/carreira\/2024\/02\/conheca-10-bilionarios-que-fizeram-fortuna-apenas-trabalhando-para-os-outros\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Os bilion\u00e1rios Jonathan Gray, Steve Ballmer e Lisa Su &#8211; Fotos: GUERIN BLASK &#8211; RICK DAHMS &#8211; JAMEL TOPPIN &#8211; FORBES Os bilion\u00e1rios contratados Ao pensar em um bilion\u00e1rio, provavelmente venha \u00e0 sua cabe\u00e7a a imagem de fundadores de grandes empresas, como \u00e9 o caso do CEO da Meta, Mark Zuckerberg, e o presidente &#8230; <a title=\"Conhe\u00e7a 10 bilion\u00e1rios que fizeram fortuna apenas trabalhando para os outros\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/13\/conheca-10-bilionarios-que-fizeram-fortuna-apenas-trabalhando-para-os-outros-2\/\" aria-label=\"Leia mais sobre Conhe\u00e7a 10 bilion\u00e1rios que fizeram fortuna apenas trabalhando para os outros\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":36955,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1964],"tags":[],"class_list":["post-36954","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carreira-e-sucesso-dicas-para-carreira"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707817487_Jonathan-Gray-Steve-Ballmer-Lisa-Su-Fotos-GUERIN-BLASK-RICK-DAHMS-JAMEL-TOPPIN-FORBES-1024x683.png?fit=1024%2C683&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707817487_Jonathan-Gray-Steve-Ballmer-Lisa-Su-Fotos-GUERIN-BLASK-RICK-DAHMS-JAMEL-TOPPIN-FORBES-1024x683.png?fit=1024%2C683&ssl=1",1024,683,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707817487_Jonathan-Gray-Steve-Ballmer-Lisa-Su-Fotos-GUERIN-BLASK-RICK-DAHMS-JAMEL-TOPPIN-FORBES-1024x683.png?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707817487_Jonathan-Gray-Steve-Ballmer-Lisa-Su-Fotos-GUERIN-BLASK-RICK-DAHMS-JAMEL-TOPPIN-FORBES-1024x683.png?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707817487_Jonathan-Gray-Steve-Ballmer-Lisa-Su-Fotos-GUERIN-BLASK-RICK-DAHMS-JAMEL-TOPPIN-FORBES-1024x683.png?fit=768%2C512&ssl=1",768,512,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707817487_Jonathan-Gray-Steve-Ballmer-Lisa-Su-Fotos-GUERIN-BLASK-RICK-DAHMS-JAMEL-TOPPIN-FORBES-1024x683.png?fit=1024%2C683&ssl=1",1024,683,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707817487_Jonathan-Gray-Steve-Ballmer-Lisa-Su-Fotos-GUERIN-BLASK-RICK-DAHMS-JAMEL-TOPPIN-FORBES-1024x683.png?fit=1024%2C683&ssl=1",1024,683,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707817487_Jonathan-Gray-Steve-Ballmer-Lisa-Su-Fotos-GUERIN-BLASK-RICK-DAHMS-JAMEL-TOPPIN-FORBES-1024x683.png?fit=1024%2C683&ssl=1",1024,683,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Os bilion\u00e1rios Jonathan Gray, Steve Ballmer e Lisa Su &#8211; Fotos: GUERIN BLASK &#8211; RICK DAHMS &#8211; JAMEL TOPPIN &#8211; FORBES Os bilion\u00e1rios contratados Ao pensar em um bilion\u00e1rio, provavelmente venha \u00e0 sua cabe\u00e7a a imagem de fundadores de grandes empresas, como \u00e9 o caso do CEO da Meta, Mark Zuckerberg, e o presidente&hellip;","jetpack-related-posts":[{"id":85205,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/05\/06\/conheca-15-bilionarios-sem-diploma-da-lista-da-forbes\/","url_meta":{"origin":36954,"position":0},"title":"Conhe\u00e7a 15 Bilion\u00e1rios sem Diploma da Lista da Forbes","author":"ismaelcolosi.com.br","date":"6 de Maio de 2025","format":false,"excerpt":"[ad_1] \r Getty Images\r Bill Gates, que ocupa a 13\u00aa posi\u00e7\u00e3o na lista de bilion\u00e1rios da Forbes, abandonou os cursos de matem\u00e1tica e direito na Universidade de Harvard \r Acessibilidade \r L\r L\r A-\r A+\r \r \u25d0\r \r \u00a0 A forma\u00e7\u00e3o acad\u00eamica \u00e9 frequentemente vista como uma das principais portas\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/forbes-bill-gates-bilionarios-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/forbes-bill-gates-bilionarios-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/forbes-bill-gates-bilionarios-1200x675.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/forbes-bill-gates-bilionarios-1200x675.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/forbes-bill-gates-bilionarios-1200x675.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":46336,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/11\/a-melhor-estrategia-de-carreira-para-se-tornar-bilionario\/","url_meta":{"origin":36954,"position":1},"title":"A melhor estrat\u00e9gia de carreira para se tornar bilion\u00e1rio","author":"ismaelcolosi.com.br","date":"11 de Abril de 2024","format":false,"excerpt":"[ad_1] Forbes USConhe\u00e7a as estrat\u00e9gias que fizeram Bill Gates, Jeff Bezos, Elon Musk (e tantos outros) se tornarem bilion\u00e1rios O que os 2.781 bilion\u00e1rios na lista da Forbes deste ano fizeram para alcan\u00e7ar fortunas estratosf\u00e9ricas? As hist\u00f3rias de Jeff Bezos, Elon Musk e Bill Gates se tornaram lendas modernas e\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/carreira-bilionarios-bill-gates-bezos-musk-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/carreira-bilionarios-bill-gates-bezos-musk-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/carreira-bilionarios-bill-gates-bezos-musk-1024x683.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/carreira-bilionarios-bill-gates-bezos-musk-1024x683.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":56057,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/09\/formula-dos-bilionarios-como-eles-construiram-fortuna\/","url_meta":{"origin":36954,"position":2},"title":"F\u00f3rmula dos bilion\u00e1rios: como eles constru\u00edram fortuna","author":"ismaelcolosi.com.br","date":"9 de Julho de 2024","format":false,"excerpt":"[ad_1] O interesse pelos bilion\u00e1rios \u00e9 t\u00e3o cativante quanto complexo. O que eles fizeram para alcan\u00e7ar alturas financeiras t\u00e3o estratosf\u00e9ricas? As hist\u00f3rias de bilion\u00e1rios como Jeff Bezos, Elon Musk e Bill Gates tornaram-se lendas modernas, despertando uma fascina\u00e7\u00e3o sobre como eles emergiram da obscuridade para vastas riquezas. Acessibilidade L L\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/carreira-bilionarios-elon-musk-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/carreira-bilionarios-elon-musk-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/carreira-bilionarios-elon-musk-1024x683.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/carreira-bilionarios-elon-musk-1024x683.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":36651,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/11\/conheca-10-bilionarios-que-fizeram-fortuna-apenas-trabalhando-para-os-outros\/","url_meta":{"origin":36954,"position":3},"title":"Conhe\u00e7a 10 bilion\u00e1rios que fizeram fortuna apenas trabalhando para os outros","author":"ismaelcolosi.com.br","date":"11 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] Os bilion\u00e1rios Jonathan Gray, Steve Ballmer e Lisa Su - Fotos: GUERIN BLASK - RICK DAHMS - JAMEL TOPPIN - FORBESOs bilion\u00e1rios contratados Ao pensar em um bilion\u00e1rio, provavelmente venha \u00e0 sua cabe\u00e7a a imagem de fundadores de grandes empresas, como \u00e9 o caso do CEO da Meta, Mark\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Jonathan-Gray-Steve-Ballmer-Lisa-Su-Fotos-GUERIN-BLASK-RICK-DAHMS-JAMEL-TOPPIN-FORBES-1024x683.png?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Jonathan-Gray-Steve-Ballmer-Lisa-Su-Fotos-GUERIN-BLASK-RICK-DAHMS-JAMEL-TOPPIN-FORBES-1024x683.png?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Jonathan-Gray-Steve-Ballmer-Lisa-Su-Fotos-GUERIN-BLASK-RICK-DAHMS-JAMEL-TOPPIN-FORBES-1024x683.png?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Jonathan-Gray-Steve-Ballmer-Lisa-Su-Fotos-GUERIN-BLASK-RICK-DAHMS-JAMEL-TOPPIN-FORBES-1024x683.png?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":53168,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/14\/as-10-faculdades-que-mais-formaram-bilionarios-nos-eua\/","url_meta":{"origin":36954,"position":4},"title":"As 10 faculdades que mais formaram bilion\u00e1rios nos EUA","author":"ismaelcolosi.com.br","date":"14 de Junho de 2024","format":false,"excerpt":"[ad_1] \u00a0 Acessibilidade L L A- A+ \u25d0 As pessoas mais ricas dos Estados Unidos estudaram em faculdades de todo o pa\u00eds \u2013 desde pequenas escolas de artes liberais como Hobart e William Smith Colleges, onde a CEO da Fidelity Investments, Abigail Johnson, estudou hist\u00f3ria da arte, at\u00e9 grandes universidades\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/SERVICOS-Harvard-chensiyuan-1024x683.png?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/SERVICOS-Harvard-chensiyuan-1024x683.png?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/SERVICOS-Harvard-chensiyuan-1024x683.png?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/SERVICOS-Harvard-chensiyuan-1024x683.png?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":85460,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/05\/21\/10-bilionarios-que-enriqueceram-trabalhando-para-outros\/","url_meta":{"origin":36954,"position":5},"title":"10 Bilion\u00e1rios que Enriqueceram Trabalhando para Outros","author":"ismaelcolosi.com.br","date":"21 de Maio de 2025","format":false,"excerpt":"[ad_1] \r Patrick T. Fallon\/Bloomberg, Justin Sullivan\/Getty Images, Sebastian Christoph Gollnow\/Getty Images\r Presidente e COO da SpaceX, Gwynne Shotwell; CEO da Apple, Tim Cook; e o presidente do conselho e CEO da Microsoft, Satya Nadella\r Acessibilidade \r L\r L\r A-\r A+\r \r \u25d0\r \r \u00a0 A maioria dos bilion\u00e1rios enriqueceu\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/forbes-bilionarios-1952025-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/forbes-bilionarios-1952025-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/forbes-bilionarios-1952025-1200x675.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/forbes-bilionarios-1952025-1200x675.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/05\/forbes-bilionarios-1952025-1200x675.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-9C2","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/36954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=36954"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/36954\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/36955"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=36954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=36954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=36954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}