{"id":36876,"date":"2024-02-12T18:19:19","date_gmt":"2024-02-12T21:19:19","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/12\/veja-a-programacao-do-ultimo-dia-do-carnaval-2024-em-ribeirao-preto\/"},"modified":"2024-02-12T18:19:19","modified_gmt":"2024-02-12T21:19:19","slug":"veja-a-programacao-do-ultimo-dia-do-carnaval-2024-em-ribeirao-preto","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/12\/veja-a-programacao-do-ultimo-dia-do-carnaval-2024-em-ribeirao-preto\/","title":{"rendered":"Veja a programa\u00e7\u00e3o do \u00faltimo dia do Carnaval 2024 em Ribeir\u00e3o Preto"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p><strong>Ribeir\u00e3o Preto<\/strong> oferece diversas op\u00e7\u00f5es para os foli\u00f5es de todas as idades nesta <strong>ter\u00e7a-feira (13)<\/strong> de <strong>Carnaval<\/strong>. \u00a0A <strong>programa\u00e7\u00e3o<\/strong> da cidade conta com <strong>blocos de ruas, apresenta\u00e7\u00f5es e matin\u00eas. Confira:<\/strong><\/p>\n<h4 class=\"wp-block-heading\"><strong>Clube Regatas<\/strong><\/h4>\n<p>O clube conta com seu <strong>\u00faltimo dia<\/strong> de <strong>programa\u00e7\u00e3o especial de Carnaval<\/strong> na <strong>ter\u00e7a-feira (13)<\/strong>. S\u00f3cios n\u00e3o pagam e n\u00e3o-s\u00f3cios precisa ser apresentado por um s\u00f3cio e o valor do\u00a0<strong>convite<\/strong>\u00a0\u00e9 de\u00a0<strong>R$ 100<\/strong>. Crian\u00e7as de 4 a 12 anos pagam meia-entrada.<\/p>\n<p>Das<strong> 12h30 \u00e0s 16h30<\/strong>, <strong>Eli Teixeira e Banda<\/strong> se apresentam. Das <strong>15h \u00e0s 18h<\/strong> tem matin\u00ea com <strong>Banda Classe A<\/strong>, que segue a apresenta\u00e7\u00e3o at\u00e9 <strong>as<\/strong> <strong>23h<\/strong>.<\/p>\n<h4 class=\"wp-block-heading\"><strong>Ipanema Clube<\/strong><\/h4>\n<p>O<strong> Ipanema Folia<\/strong> chega a seu <strong>\u00faltimo dia<\/strong>. Na secretaria do clube, \u00e9 poss\u00edvel que n\u00e3o-s\u00f3cios realizem a compra do <strong>convite<\/strong>. Crian\u00e7as at\u00e9 cinco anos n\u00e3o pagam. <strong>\u00c0s 12h<\/strong> acontece uma matin\u00ea com shows com<strong> Ax\u00e9 Bahia e Sidney Folia<\/strong>.<\/p>\n<h4 class=\"wp-block-heading\"><strong>Magic Gardens<\/strong><\/h4>\n<p>O <strong>Carna Magic<\/strong> tamb\u00e9m <strong>encerra suas atividades tem\u00e1ticas nesta ter\u00e7a-feira (13).<\/strong> Os <strong>convites<\/strong> podem ser adquiridos na bilheteria do clube. <strong>S\u00f3cios pagam R$ 20<\/strong>\u00a0(crian\u00e7as acima de 12 anos pagam),\u00a0<strong>n\u00e3o-s\u00f3cios R$ 50<\/strong>\u00a0(crian\u00e7as acima de 12 anos pagam) e crian\u00e7as s\u00f3cias ou n\u00e3o, de 7 a 12 anos, <strong>pagam R$ 10<\/strong>.<\/p>\n<p>Das <strong>13h15 at\u00e9 17h15 <\/strong>acontece a matin\u00ea na lanchonete das piscinas com a <strong>Banda Vingadores do Som<\/strong> e a <strong>Tenda Cultura<\/strong> do clube conta com uma roda de samba com <strong>Genilson Pessoa<\/strong>. E das <strong>15h \u00e0s 17h<\/strong> tem matin\u00ea infantil no <strong>Centro Kids<\/strong> com <strong>Ma Me Mi Mo M\u00fasica<\/strong>.<\/p>\n<h4 class=\"wp-block-heading\"><strong>Oficinas para personalizar m\u00e1scara de Carnaval e pinturas faciais de personagens no Shopping Iguatemi<\/strong><\/h4>\n<p>O evento conta com oficinas, matin\u00eas para crian\u00e7as e mais. As vagas s\u00e3o limitadas e crian\u00e7as de 0 a 2 anos n\u00e3o pagam, os ingressos podem ser adquiridos atrav\u00e9s do <a href=\"https:\/\/bilheteka.com.br\/comprar\/536\/bloquinho-tangerina\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">site (clique aqui)<\/a>.<\/p>\n<p>Dentre as atividades e atra\u00e7\u00f5es est\u00e3o DJs,<strong> Banda Tangerina<\/strong>, <strong>Camarim Kids<\/strong>, entre outras atra\u00e7\u00f5es. Al\u00e9m de barraquinhas de bebidas e comidas com consumo a parte. O evento acontece no Open Mall, piso superior do <strong>Shopping Iguatemi<\/strong>.<\/p>\n<h4 class=\"wp-block-heading\"><strong>21\u00aa Carnashopping no Novo Shoppping<\/strong><\/h4>\n<p>A tradicional matin\u00ea para crian\u00e7as no<strong>\u00a0Novo Shopping chega ao fim nesta ter\u00e7a-feira (13). O evento acontece das 16h \u00e0s 19h e conta com entrada gratuita<\/strong> para todas as crian\u00e7as de at\u00e9 10 anos.<\/p>\n<p>Para animar a folia haver\u00e1 um DJ e pintura facial. As primeiras crian\u00e7as que chegarem ganhar\u00e3o confetes. A folia fica na Pra\u00e7a de Eventos do Novo Shopping.<\/p>\n<p><strong>Blocos de Rua<\/strong><\/p>\n<p>A folia nas ruas da cidade segue agitada nesta ter\u00e7a-feira, confira as op\u00e7\u00f5es:<\/p>\n<ul>\n<li><strong>Cortejo C\u00eanico Sampalha\u00e7as<\/strong>: das 10h30 \u00e0s 12h \u2013 rua Visconde do Rio Branco 496 e 566<\/li>\n<\/ul>\n<ul>\n<li><strong>Escola de Samba dos Embaixadores: <\/strong>das 14h \u00e0s 20h \u2013 rua Ribeir\u00e3o Preto, 1.111 \u2013 Vila Carvalho <\/li>\n<\/ul>\n<ul>\n<li><strong>Um Amor Em Cada Bloco no Guadalupe: <\/strong>das 15h \u00e0s 21h \u2013 Guadalupe Caf\u00e9, rua Visconde do Rio Branco , 710<\/li>\n<\/ul>\n<ul>\n<li><strong>Carna Jo\u00e3o Rossi: <\/strong>das 15h \u00e0s 22h \u2013 Bar do Velho M\u00e1ximo, rua Mascimo Bernardes, 524<\/li>\n<\/ul>\n<ul>\n<li><strong>Bloco Purpurina: <\/strong>das 15h \u00e0s 22h \u2013 rua General Osorio, 1292<\/li>\n<\/ul>\n<ul>\n<li><strong>Carnaval de Rua com o Bloco do Fub\u00e1: <\/strong>das 15h \u00e0s 21h \u2013 rua Pedro Giroto, 1075<\/li>\n<\/ul>\n<ul>\n<li><strong>Tutubloco \u2013 Carnaval de Rua: <\/strong>das 17h \u00e0s 22h \u2013 pra\u00e7a Sete de Setembro, Centro<\/li>\n<\/ul>\n<p>SAIBA MAIS<br \/>Depois do Carnaval: Veja quais s\u00e3o os feriados em Ribeir\u00e3o Preto<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do<strong> acidade on<\/strong> no <a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Instagram<\/a> e no <a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do<strong> acidade on<\/strong> no WhatsApp. <a href=\"https:\/\/chat.whatsapp.com\/Bnv2w66ZT4VDyZW3oiZ69n\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<br \/>BBB 24: Wanessa Camargo recebeu amea\u00e7as?<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/lazer-e-cultura\/veja-a-programacao-do-ultimo-dia-do-carnaval-2024-em-ribeirao-preto\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Ribeir\u00e3o Preto oferece diversas op\u00e7\u00f5es para os foli\u00f5es de todas as idades nesta ter\u00e7a-feira (13) de Carnaval. \u00a0A programa\u00e7\u00e3o da cidade conta com blocos de ruas, apresenta\u00e7\u00f5es e matin\u00eas. Confira: Clube Regatas O clube conta com seu \u00faltimo dia de programa\u00e7\u00e3o especial de Carnaval na ter\u00e7a-feira (13). S\u00f3cios n\u00e3o pagam e n\u00e3o-s\u00f3cios precisa ser &#8230; <a title=\"Veja a programa\u00e7\u00e3o do \u00faltimo dia do Carnaval 2024 em Ribeir\u00e3o Preto\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/12\/veja-a-programacao-do-ultimo-dia-do-carnaval-2024-em-ribeirao-preto\/\" aria-label=\"Leia mais sobre Veja a programa\u00e7\u00e3o do \u00faltimo dia do Carnaval 2024 em Ribeir\u00e3o Preto\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":36877,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-36876","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/carnaval-1.jpg?fit=2000%2C1386&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/carnaval-1.jpg?fit=2000%2C1386&ssl=1",2000,1386,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/carnaval-1.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/carnaval-1.jpg?fit=300%2C208&ssl=1",300,208,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/carnaval-1.jpg?fit=768%2C532&ssl=1",768,532,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/carnaval-1.jpg?fit=1024%2C710&ssl=1",1024,710,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/carnaval-1.jpg?fit=1536%2C1064&ssl=1",1536,1064,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/carnaval-1.jpg?fit=2000%2C1386&ssl=1",2000,1386,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Ribeir\u00e3o Preto oferece diversas op\u00e7\u00f5es para os foli\u00f5es de todas as idades nesta ter\u00e7a-feira (13) de Carnaval. \u00a0A programa\u00e7\u00e3o da cidade conta com blocos de ruas, apresenta\u00e7\u00f5es e matin\u00eas. Confira: Clube Regatas O clube conta com seu \u00faltimo dia de programa\u00e7\u00e3o especial de Carnaval na ter\u00e7a-feira (13). S\u00f3cios n\u00e3o pagam e n\u00e3o-s\u00f3cios precisa ser&hellip;","jetpack-related-posts":[{"id":36114,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/08\/veja-a-programacao-de-carnaval-nos-clubes-de-ribeirao-preto\/","url_meta":{"origin":36876,"position":0},"title":"Veja a programa\u00e7\u00e3o de Carnaval nos clubes de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"8 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] Os clubes de Ribeir\u00e3o Preto est\u00e3o com programa\u00e7\u00e3o especial para o Carnaval. Em alguns locais as atra\u00e7\u00f5es come\u00e7am nesta sexta-feira (9). Para quem quiser participar e n\u00e3o \u00e9 s\u00f3cio, a programa\u00e7\u00e3o \u00e9 aberta com a venda de ingressos (veja abaixo). Clube de Regatas Nos dias 10, 11, 12 e\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1-3.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1-3.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1-3.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1-3.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1-3.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":36720,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/11\/carnaval-em-ribeirao-preto-veja-a-programacao-para-aproveitar-a-segunda-feira\/","url_meta":{"origin":36876,"position":1},"title":"Carnaval em Ribeir\u00e3o Preto: Veja a programa\u00e7\u00e3o para aproveitar a segunda-feira","author":"ismaelcolosi.com.br","date":"11 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] O Carnaval de Ribeir\u00e3o Preto segue com diversas op\u00e7\u00f5es para serem aproveitadas nesta segunda-feira (12). Tem bloco de rua, roda de samba, matin\u00ea com ax\u00e9 e marchinhas e programa\u00e7\u00e3o nos shoppings da cidade. Confira: Blocos em Ribeir\u00e3o Preto Com mais de 20 blocos de Carnaval, Ribeir\u00e3o Preto segue com\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/pessoa-feliz-no-carnaval.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/pessoa-feliz-no-carnaval.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/pessoa-feliz-no-carnaval.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/pessoa-feliz-no-carnaval.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/pessoa-feliz-no-carnaval.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":36624,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/10\/carnaval-em-ribeirao-confira-a-programacao-para-curtir-neste-domingo\/","url_meta":{"origin":36876,"position":2},"title":"Carnaval em Ribeir\u00e3o: Confira a programa\u00e7\u00e3o para curtir neste domingo","author":"ismaelcolosi.com.br","date":"10 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] Ribeir\u00e3o Preto segue com a programa\u00e7\u00e3o do Carnaval 2024 neste domingo (11). S\u00e3o diversas op\u00e7\u00f5es como blocos, festas tem\u00e1ticas e outros eventos para curtir pela cidade. Confira: CarnaRock O evento conta com mais de 10 horas de m\u00fasica, das 12h \u00e0s 22h, na rua Marcos Markarian, entre os n\u00fameros\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/carnaval-1024x699.png?fit=1024%2C699&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/carnaval-1024x699.png?fit=1024%2C699&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/carnaval-1024x699.png?fit=1024%2C699&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/carnaval-1024x699.png?fit=1024%2C699&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":34482,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/02\/pre-carnaval-agita-o-fim-de-semana-em-ribeirao-preto-confira-os-eventos\/","url_meta":{"origin":36876,"position":3},"title":"Pr\u00e9-carnaval agita o fim de semana em Ribeir\u00e3o Preto; Confira os eventos","author":"ismaelcolosi.com.br","date":"2 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] O fim de semana est\u00e1 repleto de eventos de pr\u00e9-carnaval em Ribeir\u00e3o Preto. S\u00e3o blocos, atividades tem\u00e1ticas, shows em bares e muito mais na programa\u00e7\u00e3o, que promete agitar a cidade antes do in\u00edcio oficial da maior festa popular do Brasil. Confira: Pr\u00e9-Carnaval Happy Hour do Ipanema Nesta sexta-feira (2),\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-1.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-1.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-1.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-1.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-1.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":35504,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/06\/confira-a-programacao-de-carnaval-em-shoppings-de-ribeirao-preto-e-franca\/","url_meta":{"origin":36876,"position":4},"title":"Confira a programa\u00e7\u00e3o de Carnaval em shoppings de Ribeir\u00e3o Preto e Franca","author":"ismaelcolosi.com.br","date":"6 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] Faltando poucos dias para o Carnaval, dois dos quatro shoppings de Ribeir\u00e3o Preto e o de Franca divulgaram as programa\u00e7\u00f5es para comemorar a data. As atividades culturais oferecidas pelos centros de compras s\u00e3o para toda fam\u00edlia e v\u00e3o desde oficinas, matin\u00eas at\u00e9 desfile de fantasias (veja abaixo). Shopping Iguatemi\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-6-1.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-6-1.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-6-1.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-6-1.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-6-1.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":35858,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/07\/mais-um-shopping-de-ribeirao-preto-tem-programacao-de-carnaval-confira\/","url_meta":{"origin":36876,"position":5},"title":"Mais um shopping de Ribeir\u00e3o Preto tem programa\u00e7\u00e3o de Carnaval; Confira","author":"ismaelcolosi.com.br","date":"7 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] O Shopping Santa \u00darsula, que fica na \u00e1rea Central de Ribeir\u00e3o Preto, divulgou nesta quarta-feira (7) a programa\u00e7\u00e3o de Carnaval. As atra\u00e7\u00f5es acontecem de 10 a 12 de fevereiro e s\u00e3o direcionadas para toda fam\u00edlia. Nos dias 10 e 12, as crian\u00e7as podem curtir o Bailinho de Carnaval do\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/linda-garota-com-peruca-de-palhaco-soprando-confete-scaled.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/linda-garota-com-peruca-de-palhaco-soprando-confete-scaled.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/linda-garota-com-peruca-de-palhaco-soprando-confete-scaled.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/linda-garota-com-peruca-de-palhaco-soprando-confete-scaled.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/linda-garota-com-peruca-de-palhaco-soprando-confete-scaled.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-9AM","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/36876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=36876"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/36876\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/36877"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=36876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=36876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=36876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}