{"id":36772,"date":"2024-02-12T08:29:36","date_gmt":"2024-02-12T11:29:36","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/12\/projeto-quer-capacitar-agentes-para-identificar-casos-de-violencia-domestica-em-rp\/"},"modified":"2024-02-12T08:29:36","modified_gmt":"2024-02-12T11:29:36","slug":"projeto-quer-capacitar-agentes-para-identificar-casos-de-violencia-domestica-em-rp","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/12\/projeto-quer-capacitar-agentes-para-identificar-casos-de-violencia-domestica-em-rp\/","title":{"rendered":"Projeto quer capacitar agentes para identificar casos de viol\u00eancia dom\u00e9stica em RP"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"post-373266\">\n<header class=\"entry-header penci-entry-header penci-title-center\">\n<p> <span class=\"entry-meta-item penci-posted-on\"><i class=\"fa fa-clock-o\"\/><time class=\"entry-date published\" datetime=\"2024-02-12T08:00:17-03:00\">12 de fevereiro de 2024 | 8:00<\/time><time class=\"updated\" datetime=\"2024-02-10T09:11:35-03:00\">10 de fevereiro de 2024 | 9:11<\/time><\/span><\/p>\n<p> <span class=\"penci-social-buttons penci-social-share-footer\"><a href=\"#\" class=\"penci-post-like penci_post-meta_item  single-like-button penci-social-item like\" data-post_id=\"373266\" title=\"Like\" data-like=\"Like\" data-unlike=\"Unlike\"><i class=\"fa fa-thumbs-o-up\"\/><span class=\"penci-share-number\">0<\/span><\/a><i class=\"fa fa-facebook\"\/><a class=\"penci-social-item twitter\" target=\"_blank\" rel=\"noopener\" title=\"\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Projeto%20quer%20capacitar%20agentes%20para%20identificar%20casos%20de%20viol\u00eancia%20dom\u00e9stica%20em%20RP%20-%20https:\/\/www.tribunaribeirao.com.br\/site\/projeto-quer-capacitar-agentes-para-identificar-casos-de-violencia-domestica-em-rp\/\"><i class=\"fa fa-twitter\"\/><\/a><i class=\"fa fa-whatsapp\"\/><\/span><\/header>\n<div class=\"penci-entry-content entry-content\">\n<p><span class=\"TextRun SCXW46501324 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW46501324 BCX0\">A C\u00e2mara <\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">de Ribeir\u00e3o Peto <\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">vai <\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">analisar projeto de lei que determina a capacita\u00e7\u00e3o de agentes comunit\u00e1rios de sa\u00fade para que identifiquem, acolham e encaminhem aos servi\u00e7os competentes as mulheres em situa\u00e7\u00e3o de viol\u00eancia dom\u00e9stica.<\/span> <\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW46501324 BCX0\"><span class=\"SCXW46501324 BCX0\">\u00a0<\/span><br class=\"SCXW46501324 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW46501324 BCX0\"><span class=\"SCXW46501324 BCX0\">\u00a0<\/span><br class=\"SCXW46501324 BCX0\"\/><\/span><span class=\"TextRun SCXW46501324 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW46501324 BCX0\">O <\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">a<\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">g<\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">e<\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">nte <\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">c<\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">omunit\u00e1rio de <\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">s<\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">a\u00fade (ACS) \u00e9 um dos profissionais que comp\u00f5em a equipe multiprofissional do Programa Sa\u00fade da Fam\u00edlia. Desenvolve a\u00e7\u00f5es de promo\u00e7\u00e3o da sa\u00fade e preven\u00e7\u00e3o de doen\u00e7as estabelecidas pelo Sistema \u00danico de Sa\u00fade (SUS). <\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW46501324 BCX0\"><span class=\"SCXW46501324 BCX0\">\u00a0<\/span><br class=\"SCXW46501324 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW46501324 BCX0\"><span class=\"SCXW46501324 BCX0\">\u00a0<\/span><br class=\"SCXW46501324 BCX0\"\/><\/span><span class=\"TextRun SCXW46501324 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW46501324 BCX0\">Atualmente Ribeir\u00e3o Preto tem 335 <\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">a<\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">gentes. Eles atuam nas Unidades B\u00e1sicas de Sa\u00fade (UBS) <\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">com <\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">modelo de Assist\u00eancia Estrat\u00e9gia Sa\u00fade da Fam\u00edlia. A cidade tem 22 <\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">postos deste tipo<\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">, localizad<\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">o<\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">s prioritariamente nas regi\u00f5es Norte e Oeste.<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW46501324 BCX0\"><span class=\"SCXW46501324 BCX0\">\u00a0<\/span><br class=\"SCXW46501324 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW46501324 BCX0\"><span class=\"SCXW46501324 BCX0\">\u00a0<\/span><br class=\"SCXW46501324 BCX0\"\/><\/span><span class=\"TextRun SCXW46501324 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW46501324 BCX0\">Denominado<\/span><span class=\"NormalTextRun SCXW46501324 BCX0\"> de Capacitando Quem Acolhe, o programa de treinamento \u00e9 de autoria do vereador Brando Veiga (Republicanos) e tem como objetivo instituir e sistematizar a atua\u00e7\u00e3o em conjunto com a rede de aten\u00e7\u00e3o e prote\u00e7\u00e3o social \u00e0s mulheres v\u00edtimas de viol\u00eancia dom\u00e9stica. <\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW46501324 BCX0\"><span class=\"SCXW46501324 BCX0\">\u00a0<\/span><br class=\"SCXW46501324 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW46501324 BCX0\"><span class=\"SCXW46501324 BCX0\">\u00a0<\/span><br class=\"SCXW46501324 BCX0\"\/><\/span><span class=\"TextRun SCXW46501324 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW46501324 BCX0\">Tamb\u00e9m prev\u00ea a elabora\u00e7\u00e3o do plano de educa\u00e7\u00e3o permanente para forma\u00e7\u00e3o, capacita\u00e7\u00e3o e sensibiliza\u00e7\u00e3o dos agentes de sa\u00fade envolvidos no atendimento as mulheres em situa\u00e7\u00e3o de viol\u00eancia dom\u00e9stica.<\/span> <span class=\"NormalTextRun SCXW46501324 BCX0\">A proposta \u00e9 semelhante ao programa do Coletivo de Mulheres do Brasil em A\u00e7\u00e3o (CMBA)<\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">.<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW46501324 BCX0\"><span class=\"SCXW46501324 BCX0\">\u00a0<\/span><br class=\"SCXW46501324 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW46501324 BCX0\"><span class=\"SCXW46501324 BCX0\">\u00a0<\/span><br class=\"SCXW46501324 BCX0\"\/><\/span><span class=\"TextRun SCXW46501324 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW46501324 BCX0\">Trata-se de <\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">uma organiza\u00e7\u00e3o civil de direito privado, localizada na cidade de Barra Velha, no <\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">E<\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">stado de Santa Catarina. Desde 2018 ela atua na prote\u00e7\u00e3o e atendimento \u00e0s mulheres v\u00edtimas de viol\u00eancia dom\u00e9stica e em vulnerabilidade social.<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW46501324 BCX0\"><span class=\"SCXW46501324 BCX0\">\u00a0<\/span><br class=\"SCXW46501324 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW46501324 BCX0\"><span class=\"SCXW46501324 BCX0\">\u00a0<\/span><br class=\"SCXW46501324 BCX0\"\/><\/span><span class=\"TextRun SCXW46501324 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW46501324 BCX0\">No projeto, o vereador argumenta que o n\u00famero de <\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">a<\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">gentes <\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">c<\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">omunit\u00e1rios de <\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">s<\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">a\u00fade tem crescido de forma acelerada, em todo <\/span><span class=\"NormalTextRun ContextualSpellingAndGrammarErrorV2Themed SCXW46501324 BCX0\">pais<\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">, devido \u00e0 necessidade dos servi\u00e7os na \u00e1rea de sa\u00fade p\u00fablica. Por\u00e9m muitos n\u00e3o possuem a forma\u00e7\u00e3o adequada em conformidade com a <\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">l<\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">ei <\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">f<\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">ederal n\u00b0 11.350\/2006, que regulamenta o cargo. <\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW46501324 BCX0\"><span class=\"SCXW46501324 BCX0\">\u00a0<\/span><br class=\"SCXW46501324 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW46501324 BCX0\"><span class=\"SCXW46501324 BCX0\">\u00a0<\/span><br class=\"SCXW46501324 BCX0\"\/><\/span><span class=\"TextRun SCXW46501324 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW46501324 BCX0\">\u201c<\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">Nesse contexto, o programa de <\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">c<\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">apacita\u00e7\u00e3o para <\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">a<\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">gente <\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">c<\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">omunit\u00e1rio de <\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">s<\/span><span class=\"NormalTextRun SCXW46501324 BCX0\">a\u00fade busca suprir a necessidade de forma\u00e7\u00e3o adequada em eixos de conhecimento b\u00e1sico para o atendimento e dos que j\u00e1 atuam como via de conex\u00e3o e integra\u00e7\u00e3o entre as unidades de sa\u00fade e a comunidade na qual est\u00e1 inserida\u201d, afirma. O projeto n\u00e3o tem data para ser votado em plen\u00e1rio.<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW46501324 BCX0\"><span class=\"SCXW46501324 BCX0\">\u00a0<\/span><br class=\"SCXW46501324 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW46501324 BCX0\"><span class=\"SCXW46501324 BCX0\">\u00a0<\/span><br class=\"SCXW46501324 BCX0\"\/><\/span><span class=\"EOP SCXW46501324 BCX0\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:200,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<\/div>\n<footer class=\"penci-entry-footer\"\/><\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/site\/projeto-quer-capacitar-agentes-para-identificar-casos-de-violencia-domestica-em-rp\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] 12 de fevereiro de 2024 | 8:0010 de fevereiro de 2024 | 9:11 0 A C\u00e2mara de Ribeir\u00e3o Peto vai analisar projeto de lei que determina a capacita\u00e7\u00e3o de agentes comunit\u00e1rios de sa\u00fade para que identifiquem, acolham e encaminhem aos servi\u00e7os competentes as mulheres em situa\u00e7\u00e3o de viol\u00eancia dom\u00e9stica. \u00a0\u00a0O agente comunit\u00e1rio de sa\u00fade&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":36773,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[4229,4228,996,3962,4230,71,685,796,1587],"class_list":["post-36772","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-agentes","tag-capacitar","tag-casos","tag-domestica","tag-identificar","tag-para","tag-projeto","tag-quer","tag-violencia"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1d497d9f-e1dc-456e-892c-83a8c0419a1b-scaled.jpg?fit=1000%2C598&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1d497d9f-e1dc-456e-892c-83a8c0419a1b-scaled.jpg?fit=1000%2C598&ssl=1",1000,598,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1d497d9f-e1dc-456e-892c-83a8c0419a1b-scaled.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1d497d9f-e1dc-456e-892c-83a8c0419a1b-scaled.jpg?fit=300%2C179&ssl=1",300,179,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1d497d9f-e1dc-456e-892c-83a8c0419a1b-scaled.jpg?fit=768%2C459&ssl=1",768,459,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1d497d9f-e1dc-456e-892c-83a8c0419a1b-scaled.jpg?fit=1000%2C598&ssl=1",1000,598,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1d497d9f-e1dc-456e-892c-83a8c0419a1b-scaled.jpg?fit=1000%2C598&ssl=1",1000,598,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1d497d9f-e1dc-456e-892c-83a8c0419a1b-scaled.jpg?fit=1000%2C598&ssl=1",1000,598,true],"neve-blog":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1d497d9f-e1dc-456e-892c-83a8c0419a1b-scaled.jpg?resize=930%2C598&ssl=1",930,598,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] 12 de fevereiro de 2024 | 8:0010 de fevereiro de 2024 | 9:11 0 A C\u00e2mara de Ribeir\u00e3o Peto vai analisar projeto de lei que determina a capacita\u00e7\u00e3o de agentes comunit\u00e1rios de sa\u00fade para que identifiquem, acolham e encaminhem aos servi\u00e7os competentes as mulheres em situa\u00e7\u00e3o de viol\u00eancia dom\u00e9stica. \u00a0\u00a0O agente comunit\u00e1rio de sa\u00fade&hellip;&nbsp;","jetpack-related-posts":[{"id":34033,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/31\/sp-bate-recorde-de-feminicidios-em-2023\/","url_meta":{"origin":36772,"position":0},"title":"SP bate recorde de\u00a0feminic\u00eddios em 2023\u00a0","author":"ismaelcolosi.com.br","date":"31 de Janeiro de 2024","format":false,"excerpt":"[ad_1] 31 de janeiro de 2024 | 18:0031 de janeiro de 2024 | 9:32 0O estado de S\u00e3o Paulo teve no ano passado o maior n\u00famero de feminic\u00eddios desde 2018, quando os dados passaram a ser divulgados separadamente das demais estat\u00edsticas de homic\u00eddio. Segundo a Secretaria de Estado da Seguran\u00e7a\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/feminicidio-psiquiatria-1.jpg?fit=800%2C534&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/feminicidio-psiquiatria-1.jpg?fit=800%2C534&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/feminicidio-psiquiatria-1.jpg?fit=800%2C534&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/feminicidio-psiquiatria-1.jpg?fit=800%2C534&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":34338,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/01\/fiscalizacao-do-nao-se-cale-tera-inicio-na-regiao\/","url_meta":{"origin":36772,"position":1},"title":"Fiscaliza\u00e7\u00e3o do \u2018N\u00e3o se Cale\u2019\u00a0ter\u00e1\u00a0in\u00edcio na regi\u00e3o \u00a0","author":"ismaelcolosi.com.br","date":"1 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] 1 de fevereiro de 2024 | 18:001 de fevereiro de 2024 | 9:10 0A ades\u00e3o de bares e restaurantes da regi\u00e3o de Ribeir\u00e3o Preto ao protocolo \u201cN\u00e3o se Cale\u201d come\u00e7ar\u00e1 a ser fiscalizada pela Funda\u00e7\u00e3o Procon de S\u00e3o Paulo (Procon-SP) \u2013 \u00f3rg\u00e3o ligado \u00e0 Secretaria de Estado de Justi\u00e7a\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Bares-Divulgacao-01.png?fit=513%2C263&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":39843,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/28\/somente-20-das-mulheres-brasileiras-conhecem-bem-a-lei-maria-da-penha\/","url_meta":{"origin":36772,"position":2},"title":"Somente 20% das mulheres brasileiras conhecem bem a Lei Maria da Penha","author":"ismaelcolosi.com.br","date":"28 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] Apenas duas em cada dez mulheres\u00a0se sentem bem informadas em rela\u00e7\u00e3o \u00e0 Lei\u00a0Maria da Penha, que criou mecanismos para coibir e prevenir a\u00a0viol\u00eancia dom\u00e9stica e familiar\u00a0contra a mulher e foi sancionada pelo presidente Luiz In\u00e1cio Lula da Silva em 2006.Os dados fazem parte da\u00a010\u00aa edi\u00e7\u00e3o da Pesquisa Nacional de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/ac80d7da-8633-4626-82e0-95169189e57a-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/ac80d7da-8633-4626-82e0-95169189e57a-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/ac80d7da-8633-4626-82e0-95169189e57a-scaled.jpg?fit=1000%2C598&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/ac80d7da-8633-4626-82e0-95169189e57a-scaled.jpg?fit=1000%2C598&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":67531,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/24\/fotografa-enfrentara-juri-popular-acusada-de-matar-o-namorado-a-facadas-em-ribeirao-preto-sp\/","url_meta":{"origin":36772,"position":3},"title":"Fot\u00f3grafa enfrentar\u00e1 j\u00fari popular acusada de matar o namorado a facadas em Ribeir\u00e3o Preto, SP","author":"ismaelcolosi.com.br","date":"24 de Setembro de 2024","format":false,"excerpt":"[ad_1] A fot\u00f3grafa de 29 anos acusada de assassinar o namorado em Ribeir\u00e3o Preto (SP) ir\u00e1 a j\u00fari popular, conforme decis\u00e3o judicial publicada nesta ter\u00e7a-feira (17). O crime aconteceu em 2022 e desde ent\u00e3o a mulher est\u00e1 sendo investigada pelo homic\u00eddio. A v\u00edtima, um homem de 32 anos, foi morta\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/O-IN-DUBIO-PRO-REO.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/O-IN-DUBIO-PRO-REO.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/O-IN-DUBIO-PRO-REO.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/O-IN-DUBIO-PRO-REO.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/O-IN-DUBIO-PRO-REO.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":14179,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/11\/vi-caminhada-pelo-fim-da-violencia-contra-mulheres-e-meninas-reuniu-cerca-de-200-pessoas-no-ultimo-domingo\/","url_meta":{"origin":36772,"position":4},"title":"VI Caminhada pelo fim da viol\u00eancia contra mulheres e meninas reuniu cerca de 200 pessoas no \u00faltimo domingo \u2013 Folha de Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"11 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Aconteceu no \u00faltimo domingo, 10 de dezembro, a VI Caminha Mulher Maravilha pelo fim da viol\u00eancia contra mulheres e meninas, realizada pela Prefeitura de Ribeir\u00e3o Preto, em parceria com o grupo Mulheres do Brasil. O evento, que teve sua concentra\u00e7\u00e3o no estacionamento da C\u00e2mara Municipal, contou com a presen\u00e7a\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/caminhada_mulher_maravilha_1.jpeg?fit=1200%2C903&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/caminhada_mulher_maravilha_1.jpeg?fit=1200%2C903&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/caminhada_mulher_maravilha_1.jpeg?fit=1200%2C903&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/caminhada_mulher_maravilha_1.jpeg?fit=1200%2C903&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/caminhada_mulher_maravilha_1.jpeg?fit=1200%2C903&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":42735,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/16\/abrasel-faz-parceria-para-o-nao-se-cale\/","url_meta":{"origin":36772,"position":5},"title":"Abrasel faz parceria para o \u2018N\u00e3o se cale\u2019\u00a0","author":"ismaelcolosi.com.br","date":"16 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] 16 de mar\u00e7o de 2024 | 14:0015 de mar\u00e7o de 2024 | 20:25 0A Associa\u00e7\u00e3o Brasileira de Bares e Restaurantes da Alta Mogiana (Abrasel) criou uma forma objetiva de aplicar a nova lei estadual que obriga funcion\u00e1rios de bares, restaurantes e casas noturnas a realizar o curso de aplica\u00e7\u00e3o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Abrasel-Divulgacao-01-scaled.jpg?fit=1000%2C606&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Abrasel-Divulgacao-01-scaled.jpg?fit=1000%2C606&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Abrasel-Divulgacao-01-scaled.jpg?fit=1000%2C606&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Abrasel-Divulgacao-01-scaled.jpg?fit=1000%2C606&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-9z6","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/36772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=36772"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/36772\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/36773"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=36772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=36772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=36772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}