{"id":34573,"date":"2024-02-02T15:10:01","date_gmt":"2024-02-02T18:10:01","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/02\/bloco-california-abre-o-carnaval\/"},"modified":"2024-02-02T15:10:01","modified_gmt":"2024-02-02T18:10:01","slug":"bloco-california-abre-o-carnaval","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/02\/bloco-california-abre-o-carnaval\/","title":{"rendered":"Bloco Calif\u00f3rnia\u00a0abre o carnaval\u00a0 &#8211; Jornal Tribuna Ribeir\u00e3o"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"\">\n<p> <span class=\"entry-meta-item penci-posted-on\"><i class=\"fa fa-clock-o\"\/><time class=\"entry-date published\" datetime=\"2024-02-02T15:00:35-03:00\">2 de fevereiro de 2024 | 15:00<\/time><time class=\"updated\" datetime=\"2024-02-01T17:46:22-03:00\">1 de fevereiro de 2024 | 17:46<\/time><\/span><\/p>\n<p> <span class=\"penci-social-buttons penci-social-share-footer\"><a href=\"#\" class=\"penci-post-like penci_post-meta_item  single-like-button penci-social-item like\" data-post_id=\"372313\" title=\"Like\" data-like=\"Like\" data-unlike=\"Unlike\"><i class=\"fa fa-thumbs-o-up\"\/><span class=\"penci-share-number\">0<\/span><\/a><i class=\"fa fa-facebook\"\/><a class=\"penci-social-item twitter\" target=\"_blank\" rel=\"noopener\" title=\"\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Bloco%20Calif\u00f3rnia\u00a0abre%20o%20carnaval\u00a0%20-%20https:\/\/www.tribunaribeirao.com.br\/site\/bloco-california-abre-o-carnaval\/\"><i class=\"fa fa-twitter\"\/><\/a><i class=\"fa fa-whatsapp\"\/><\/span><\/div>\n<div>\n<p><span data-contrast=\"none\">O Bloco Calif\u00f3rnia vai abrir o carnaval em Ribeir\u00e3o Preto, Ser\u00e1 neste s\u00e1bado, 3 de fevereiro, a partir das 15 horas, no Est\u00e1dio Palma Travassos. Com sucessos que marcaram a hist\u00f3ria dos grandes carnavais, Terra Samba desembarca em Ribeir\u00e3o Preto direto para a s\u00e9tima edi\u00e7\u00e3o do evento. <\/span><\/p>\n<p><span data-contrast=\"none\">O grupo celebrar\u00e1 com os foli\u00f5es seus 32 anos de trajet\u00f3ria e os 25 anos do hit \u201cCarrinho de M\u00e3o\u201d, sucesso que projetou a banda no pa\u00eds em 1998 e se tornou um fen\u00f4meno fonogr\u00e1fico com a venda de 2,5 milh\u00f5es de c\u00f3pias. O repert\u00f3rio foi preparado especialmente para o evento.<\/span><\/p>\n<p><span data-contrast=\"none\">Tamb\u00e9m est\u00e3o confirmados sucessos como, \u201cLibera Geral\u201d, \u201cBanho de Chuveiro\u201d e \u201cNa Manteiga\u201d, que proporcionar\u00e3o um momento nost\u00e1lgico principalmente para os foli\u00f5es dos anos 90, al\u00e9m das novas m\u00fasicas de trabalho, \u201cCarnavrau\u201d e \u201cZigue Zigue Za\u201d.<\/span><\/p>\n<p><b><span data-contrast=\"none\">Mais programa\u00e7\u00e3o <\/span><\/b><b><span data-contrast=\"auto\">\u2013 <\/span><\/b><span data-contrast=\"none\">Al\u00e9m do ax\u00e9 da banda baiana Terra Samba, o line-up ecl\u00e9tico do Bloco Calif\u00f3rnia contar\u00e1 ainda com o funk carioca de Tati Quebra Barraco e o balan\u00e7o da cantora Carla Cristina (que liderou o grupo As meninas \u2013 entre 1997 e 2002), o samba e o pagode do Grupo Presen\u00e7a, os hits do DJ Blakes (um dos principais nomes dos bailes de rua de S\u00e3o Paulo) e outras atra\u00e7\u00f5es. <\/span><\/p>\n<p><span data-contrast=\"none\">Ao todo, s\u00e3o previstas nove horas de evento. Mantendo a tradi\u00e7\u00e3o, a folia come\u00e7a com a apresenta\u00e7\u00e3o de tr\u00eas baterias universit\u00e1rias \u2013 Bates\u00e3o (Medicina USP), Dorot\u00e9ia (Farma USP) e Taquicardia (Medicina Unaerp). <\/span><\/p>\n<p><span data-contrast=\"none\">\u201cDesde o in\u00edcio, as baterias universit\u00e1rias ocupam um espa\u00e7o muito especial na programa\u00e7\u00e3o do nosso evento. Elas criam uma atmosfera \u00fanica, contagiante, deixando o p\u00fablico preparado para as atra\u00e7\u00f5es que assumem o circuito em seguida\u201d, afirma Mikhael Nakad, um dos organizadores do Bloco Calif\u00f3rnia.<\/span><\/p>\n<p><b><span data-contrast=\"none\">Ingressos <\/span><\/b><b><span data-contrast=\"auto\">\u2013<\/span><\/b> <span data-contrast=\"none\">Os ingressos do Bloco Calif\u00f3rnia est\u00e3o dispon\u00edveis atrav\u00e9s do site do evento, com pagamento via cart\u00e3o de cr\u00e9dito ou Pix.\u00a0 Para a pista custam R$ 100 (inteira), R$ 50 (meia-entrada) e R$ 60 o ingresso solid\u00e1rio (com a doa\u00e7\u00e3o de um quilo de alimento n\u00e3o perec\u00edvel na entrada do evento). <\/span><\/p>\n<p><b><span data-contrast=\"auto\">Abadas e clima de micareta \u2013 <\/span><\/b><span data-contrast=\"none\">O acesso ao camarote tem valor \u00fanico de R$ 180. Na p\u00e1gina do evento, o p\u00fablico tamb\u00e9m pode adquirir o tradicional abad\u00e1 da micareta por R$ 30 (uso n\u00e3o obrigat\u00f3rio). A retirada come\u00e7ar\u00e1 uma semana antes da folia.<\/span><br \/><b\/><\/p>\n<p><b><span data-contrast=\"auto\">Servi\u00e7o<\/span><\/b><br \/><b><span data-contrast=\"auto\">Evento:<\/span><\/b><span data-contrast=\"auto\"> Bloco <\/span><span data-contrast=\"auto\">Calif\u00f3rnia<\/span><br \/><b><span data-contrast=\"auto\">Quando:<\/span><\/b><span data-contrast=\"auto\"> s\u00e1bado,<\/span> <span data-contrast=\"auto\">3 de fevereiro<\/span><br \/><b><span data-contrast=\"auto\">Com:<\/span><\/b><span data-contrast=\"auto\"> Tati Quebra <\/span>\u00a0<span data-contrast=\"auto\">Barraco, Carla Cristina, <\/span>\u00a0<span data-contrast=\"auto\">Terra Samba, DJ Blakes <\/span>\u00a0<span data-contrast=\"auto\">e baterias universit\u00e1rias<\/span><br \/><b><span data-contrast=\"auto\">Baterias:<\/span><\/b> <span data-contrast=\"none\">Bates\u00e3o, <\/span>\u00a0<span data-contrast=\"none\">Dorot\u00e9ia e <\/span>\u00a0<span data-contrast=\"none\">Taquicardia<\/span><br \/><b><span data-contrast=\"auto\">Onde:<\/span><\/b><span data-contrast=\"auto\"> Est\u00e1dio Palma <\/span>\u00a0<span data-contrast=\"auto\">Travassos<\/span><br \/><b><span data-contrast=\"auto\">Endere\u00e7o:<\/span><\/b><span data-contrast=\"auto\"> avenida <\/span>\u00a0<span data-contrast=\"auto\">Doutor Pl\u00ednio de <\/span>\u00a0<span data-contrast=\"auto\">Castro Prado n\u00ba 1.000<\/span><br \/><b><span data-contrast=\"auto\">Ingressos<\/span><\/b><br \/><b><span data-contrast=\"auto\">Pista<\/span><\/b><br \/><b><span data-contrast=\"auto\">Inteira:<\/span><\/b><span data-contrast=\"auto\"> R$ 100<\/span> \u00a0<b><span data-contrast=\"auto\">Meia:<\/span><\/b><span data-contrast=\"auto\"> R$ 50<\/span><br \/><b><span data-contrast=\"auto\">Solid\u00e1rio:<\/span><\/b><span data-contrast=\"auto\"> R$ 60<\/span><br \/><b><span data-contrast=\"auto\">Camarote<\/span><\/b><br \/><b><span data-contrast=\"auto\">\u00danico:<\/span><\/b><span data-contrast=\"auto\"> R$ 180<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:200,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:200,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/site\/bloco-california-abre-o-carnaval\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] 2 de fevereiro de 2024 | 15:001 de fevereiro de 2024 | 17:46 0 O Bloco Calif\u00f3rnia vai abrir o carnaval em Ribeir\u00e3o Preto, Ser\u00e1 neste s\u00e1bado, 3 de fevereiro, a partir das 15 horas, no Est\u00e1dio Palma Travassos. Com sucessos que marcaram a hist\u00f3ria dos grandes carnavais, Terra Samba desembarca em Ribeir\u00e3o Preto &#8230; <a title=\"Bloco Calif\u00f3rnia\u00a0abre o carnaval\u00a0 &#8211; Jornal Tribuna Ribeir\u00e3o\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/02\/bloco-california-abre-o-carnaval\/\" aria-label=\"Leia mais sobre Bloco Calif\u00f3rnia\u00a0abre o carnaval\u00a0 &#8211; Jornal Tribuna Ribeir\u00e3o\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":34574,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[1673,4033,2688,785,26,786],"class_list":["post-34573","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-bloco","tag-californiaabre","tag-carnaval","tag-jornal","tag-ribeirao","tag-tribuna"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Bloco-Bat-Divulgacao-1-scaled.jpg?fit=968%2C645&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Bloco-Bat-Divulgacao-1-scaled.jpg?fit=968%2C645&ssl=1",968,645,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Bloco-Bat-Divulgacao-1-scaled.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Bloco-Bat-Divulgacao-1-scaled.jpg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Bloco-Bat-Divulgacao-1-scaled.jpg?fit=768%2C512&ssl=1",768,512,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Bloco-Bat-Divulgacao-1-scaled.jpg?fit=968%2C645&ssl=1",968,645,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Bloco-Bat-Divulgacao-1-scaled.jpg?fit=968%2C645&ssl=1",968,645,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Bloco-Bat-Divulgacao-1-scaled.jpg?fit=968%2C645&ssl=1",968,645,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] 2 de fevereiro de 2024 | 15:001 de fevereiro de 2024 | 17:46 0 O Bloco Calif\u00f3rnia vai abrir o carnaval em Ribeir\u00e3o Preto, Ser\u00e1 neste s\u00e1bado, 3 de fevereiro, a partir das 15 horas, no Est\u00e1dio Palma Travassos. Com sucessos que marcaram a hist\u00f3ria dos grandes carnavais, Terra Samba desembarca em Ribeir\u00e3o Preto&hellip;","jetpack-related-posts":[{"id":11892,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/07\/bloco-california-em-ribeirao-preto-confirma-as-primeiras-atracoes\/","url_meta":{"origin":34573,"position":0},"title":"Bloco Calif\u00f3rnia, em Ribeir\u00e3o Preto, confirma as primeiras atra\u00e7\u00f5es","author":"ismaelcolosi.com.br","date":"7 de Dezembro de 2023","format":false,"excerpt":"[ad_1] O Bloco Calif\u00f3rnia, em Ribeir\u00e3o Preto, confirmou as primeira atra\u00e7\u00f5es: Tati Quebra Barraco, Carla Cristina e o DJ Blakes. A 7\u00b0 edi\u00e7\u00e3o do evento de pr\u00e9-carnaval acontece em 3 de fevereiro de 2024, no est\u00e1dio Palma Travassos. \u00a0 Segundo a organiza\u00e7\u00e3o do evento j\u00e1 divulgou, o Bloco Calif\u00f3rnia ter\u00e1\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/346244465_1227185564598648_4087334571733265628_n.jpg?fit=1079%2C935&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/346244465_1227185564598648_4087334571733265628_n.jpg?fit=1079%2C935&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/346244465_1227185564598648_4087334571733265628_n.jpg?fit=1079%2C935&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/346244465_1227185564598648_4087334571733265628_n.jpg?fit=1079%2C935&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/346244465_1227185564598648_4087334571733265628_n.jpg?fit=1079%2C935&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":17218,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/17\/bloco-california-ja-tem-atracoes\/","url_meta":{"origin":34573,"position":1},"title":"Bloco Calif\u00f3rnia j\u00e1 tem atra\u00e7\u00f5es\u00a0","author":"ismaelcolosi.com.br","date":"17 de Dezembro de 2023","format":false,"excerpt":"[ad_1] 17 de dezembro de 2023 | 17:0015 de dezembro de 2023 | 17:09 0Abrindo alas para a chegada de sua s\u00e9tima edi\u00e7\u00e3o, o Bloco Calif\u00f3rnia confirmou uma animada mistura de ritmos em seu line-up principal. A folia \u2013 que antecede o Reinado de Momo \u2013 acontece em 3 de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Bloco-Divulgacao-02.png?fit=396%2C645&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":24843,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/05\/bloco-de-carnaval-de-ribeirao-preto-anuncia-terra-samba-e-grupo-presenca\/","url_meta":{"origin":34573,"position":2},"title":"Bloco de Carnaval de Ribeir\u00e3o Preto anuncia Terra Samba e Grupo Presen\u00e7a","author":"ismaelcolosi.com.br","date":"5 de Janeiro de 2024","format":false,"excerpt":"[ad_1] O Bloco Calif\u00f3rnia, que agita o pr\u00e9-carnaval de Ribeir\u00e3o Preto, anunciou a banda baiana Terra Samba e o Grupo Presen\u00e7a. O evento acontece no dia 3 de fevereiro (s\u00e1bado), a partir das 15h, no Est\u00e1dio Palma Travassos. Na segunda-feira (8), o Bloco Calif\u00f3rnia reabre a venda de ingressos para\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-05-at-10.25.32.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-05-at-10.25.32.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-05-at-10.25.32.jpeg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-05-at-10.25.32.jpeg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-05-at-10.25.32.jpeg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":24864,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/05\/bloco-de-carnaval-de-ribeirao-preto-anuncia-terra-samba-e-grupo-presenca-2\/","url_meta":{"origin":34573,"position":3},"title":"Bloco de Carnaval de Ribeir\u00e3o Preto anuncia Terra Samba e Grupo Presen\u00e7a","author":"ismaelcolosi.com.br","date":"5 de Janeiro de 2024","format":false,"excerpt":"[ad_1] O Bloco Calif\u00f3rnia, que agita o pr\u00e9-carnaval de Ribeir\u00e3o Preto, anunciou a banda baiana Terra Samba e o Grupo Presen\u00e7a. O evento acontece no dia 3 de fevereiro (s\u00e1bado), a partir das 15h, no Est\u00e1dio Palma Travassos. Na segunda-feira (8), o Bloco Calif\u00f3rnia reabre a venda de ingressos para\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1704466124_WhatsApp-Image-2024-01-05-at-10.25.32.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1704466124_WhatsApp-Image-2024-01-05-at-10.25.32.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1704466124_WhatsApp-Image-2024-01-05-at-10.25.32.jpeg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1704466124_WhatsApp-Image-2024-01-05-at-10.25.32.jpeg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1704466124_WhatsApp-Image-2024-01-05-at-10.25.32.jpeg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":37432,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/16\/baile-do-copa\/","url_meta":{"origin":34573,"position":4},"title":"Baile do Copa &#8211; Jornal Tribuna Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"16 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] 16 de fevereiro de 2024 | 9:0314 de fevereiro de 2024 | 10:59 0O Copacabana Palace, A Belmond Hotel, apresentou mais uma edi\u00e7\u00e3o de seu tradicional baile de carnaval, o aclamado \u2018Baile do Copa\u2019, uma experi\u00eancia inigual\u00e1vel no hotel mais ic\u00f4nico do Rio de Janeiro. O \u2018Copa\u2019, como \u00e9\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Narcisa-Tamborindeguy_Credito-Castro-Filmes-scaled.jpg?fit=667%2C1000&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Narcisa-Tamborindeguy_Credito-Castro-Filmes-scaled.jpg?fit=667%2C1000&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Narcisa-Tamborindeguy_Credito-Castro-Filmes-scaled.jpg?fit=667%2C1000&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":1115,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/10\/bloco-california-em-ribeirao-preto-anuncia-a-data-da-folia-em-2024\/","url_meta":{"origin":34573,"position":5},"title":"Bloco Calif\u00f3rnia em Ribeir\u00e3o Preto anuncia a data da folia em 2024\u00a0","author":"ismaelcolosi.com.br","date":"10 de Novembro de 2023","format":false,"excerpt":"[ad_1] A 7\u00b0 edi\u00e7\u00e3o do Bloco Calif\u00f3rnia, festa de pr\u00e9-carnaval de Ribeir\u00e3o Preto, est\u00e1 prevista para acontecer no dia 3 de fevereiro de 2024, no est\u00e1dio Palma Travassos, na zona Leste. \u00a0 Segundo a organiza\u00e7\u00e3o do evento, a programa\u00e7\u00e3o ter\u00e1 novidades e, uma delas, a estreia de um camarote no\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/bloco-california-credito-divulgacao.jpeg?fit=800%2C534&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/bloco-california-credito-divulgacao.jpeg?fit=800%2C534&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/bloco-california-credito-divulgacao.jpeg?fit=800%2C534&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/bloco-california-credito-divulgacao.jpeg?fit=800%2C534&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-8ZD","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/34573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=34573"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/34573\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/34574"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=34573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=34573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=34573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}