{"id":34440,"date":"2024-02-02T02:30:21","date_gmt":"2024-02-02T05:30:21","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/02\/rp-tem-nove-presos-em-operacao-nacional-contra-trafico\/"},"modified":"2024-02-02T02:30:21","modified_gmt":"2024-02-02T05:30:21","slug":"rp-tem-nove-presos-em-operacao-nacional-contra-trafico","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/02\/rp-tem-nove-presos-em-operacao-nacional-contra-trafico\/","title":{"rendered":"RP tem nove presos em opera\u00e7\u00e3o nacional contra tr\u00e1fico"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>Por: Adalberto Luque e Alfredo Risk<\/p>\n<p>Pol\u00edcias Civil e Militar deflagraram, no final da madrugada desta quinta-feira (01), uma megaopera\u00e7\u00e3o contra organiza\u00e7\u00e3o criminosa. O grupo \u00e9 investigado por tr\u00e1fico de drogas e lavagem de dinheiro. A opera\u00e7\u00e3o \u201cHades\u201d foi realizada em diversos estados brasileiros.<\/p>\n<p>Para a a\u00e7\u00e3o foram mobilizadas equipes da Divis\u00e3o Especial de Investiga\u00e7\u00f5es Criminais (DEIC) e Grupo de Opera\u00e7\u00f5es Especiais (GOE), ambos da Pol\u00edcia Civil; Batalh\u00e3o de Opera\u00e7\u00f5es Especiais de Pol\u00edcia (BAEP) e policiais do 3\u00ba Batalh\u00e3o e 51\u00ba Batalh\u00e3o, todos da Pol\u00edcia Militar. O Canil do BAEP tamb\u00e9m ficou \u00e0 disposi\u00e7\u00e3o em caso de necessidade de buscas de drogas.<\/p>\n<figure id=\"attachment_372276\" aria-describedby=\"caption-attachment-372276\" style=\"width: 1000px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" decoding=\"async\" alt=\"\" width=\"1000\" height=\"563\" srcset=\"https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-02-foto-divulgacao-scaled.jpg 1000w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-02-foto-divulgacao-300x169.jpg 300w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-02-foto-divulgacao-1024x576.jpg 1024w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-02-foto-divulgacao-768x432.jpg 768w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-02-foto-divulgacao-1536x864.jpg 1536w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-02-foto-divulgacao-960x540.jpg 960w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-02-foto-divulgacao-711x400.jpg 711w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-02-foto-divulgacao-585x329.jpg 585w\" src=\"https:\/\/i0.wp.com\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-02-foto-divulgacao-scaled.jpg?resize=1000%2C563&#038;ssl=1\" data-sizes=\"(max-width: 1000px) 100vw, 1000px\" class=\"size-full wp-image-372276 lazyload\"\/><noscript><img data-recalc-dims=\"1\" decoding=\"async\" class=\"size-full wp-image-372276\" src=\"https:\/\/i0.wp.com\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-02-foto-divulgacao-scaled.jpg?resize=1000%2C563&#038;ssl=1\" alt=\"\" width=\"1000\" height=\"563\" srcset=\"https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-02-foto-divulgacao-scaled.jpg 1000w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-02-foto-divulgacao-300x169.jpg 300w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-02-foto-divulgacao-1024x576.jpg 1024w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-02-foto-divulgacao-768x432.jpg 768w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-02-foto-divulgacao-1536x864.jpg 1536w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-02-foto-divulgacao-960x540.jpg 960w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-02-foto-divulgacao-711x400.jpg 711w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-02-foto-divulgacao-585x329.jpg 585w\" sizes=\"(max-width: 1000px) 100vw, 1000px\"\/><\/noscript><figcaption id=\"caption-attachment-372276\" class=\"wp-caption-text\">Empresas de Ribeir\u00e3o Preto realizavam movimenta\u00e7\u00e3o incompat\u00edvel e foram alvo dos mandados de busca e apreens\u00e3o (Foto: Pol\u00edcia Civil\/Divulga\u00e7\u00e3o)<\/figcaption><\/figure>\n<p>Segundo o diretor da DEIC, Kleber de Oliveira Granja, a opera\u00e7\u00e3o foi realizada a partir da investiga\u00e7\u00e3o feita pela Pol\u00edcia Civil de Macei\u00f3 (AL). \u201cTrata-se de criteriosa e complexa investiga\u00e7\u00e3o de tr\u00eas anos, coordenada pela Pol\u00edcia Civil do Estado de Alagoas, por meio do DRACO [Departamento de Repress\u00e3o ao Crime Organizado]\u201d, disse o delegado.<\/p>\n<p>Foram mobilizados 180 policiais civis e militares em 56 viaturas. A opera\u00e7\u00e3o contou tamb\u00e9m com apoio a\u00e9reo do helic\u00f3ptero \u00c1guia da PM. Os agentes cumpriram 27 mandados de busca e apreens\u00e3o e sete de pris\u00e3o tempor\u00e1ria, expedidos pela Justi\u00e7a de Alagoas.<\/p>\n<figure id=\"attachment_372275\" aria-describedby=\"caption-attachment-372275\" style=\"width: 1000px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" decoding=\"async\" alt=\"\" width=\"1000\" height=\"563\" srcset=\"https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-01-foto-divulgacao-scaled.jpg 1000w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-01-foto-divulgacao-300x169.jpg 300w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-01-foto-divulgacao-1024x576.jpg 1024w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-01-foto-divulgacao-768x432.jpg 768w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-01-foto-divulgacao-960x540.jpg 960w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-01-foto-divulgacao-711x400.jpg 711w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-01-foto-divulgacao-585x329.jpg 585w\" src=\"https:\/\/i0.wp.com\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-01-foto-divulgacao-scaled.jpg?resize=1000%2C563&#038;ssl=1\" data-sizes=\"(max-width: 1000px) 100vw, 1000px\" class=\"size-full wp-image-372275 lazyload\"\/><noscript><img data-recalc-dims=\"1\" decoding=\"async\" class=\"size-full wp-image-372275\" src=\"https:\/\/i0.wp.com\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-01-foto-divulgacao-scaled.jpg?resize=1000%2C563&#038;ssl=1\" alt=\"\" width=\"1000\" height=\"563\" srcset=\"https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-01-foto-divulgacao-scaled.jpg 1000w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-01-foto-divulgacao-300x169.jpg 300w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-01-foto-divulgacao-1024x576.jpg 1024w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-01-foto-divulgacao-768x432.jpg 768w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-01-foto-divulgacao-960x540.jpg 960w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-01-foto-divulgacao-711x400.jpg 711w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-01-foto-divulgacao-585x329.jpg 585w\" sizes=\"(max-width: 1000px) 100vw, 1000px\"\/><\/noscript><figcaption id=\"caption-attachment-372275\" class=\"wp-caption-text\">Objetivo foi cumprir 27 mandados de busca e apreens\u00e3o e sete de pris\u00e3o preventiva (Foto: Pol\u00edcia Civil\/Divulga\u00e7\u00e3o)<\/figcaption><\/figure>\n<p><span style=\"color: #008000\"><em><strong>Balan\u00e7o<\/strong><\/em><\/span><\/p>\n<p>Na entrevista coletiva, foi divulgado que nove pessoas foram presas. Destas, seis eram alvo dos sete mandados de pris\u00e3o e outras tr\u00eas foram presas em flagrante. Foram apreendidas quatro armas de fogo, cinco ve\u00edculos e uma moto (avaliados em R$ 343 mil), celulares, notebooks, computadores e chip de celular, entre outros itens.<\/p>\n<p>Segundo o diretor da DEIC, a log\u00edstica da opera\u00e7\u00e3o foi coordenada pela intelig\u00eancia dos policiais civis de Alagoas, de Ribeir\u00e3o Preto e dos policiais militares de Ribeir\u00e3o Preto. \u201cFoi um trabalho in\u00e9dito. Buscamos n\u00e3o apenas a pris\u00e3o desses indiv\u00edduos, mas principalmente a recupera\u00e7\u00e3o de ativos. O trabalho n\u00e3o \u00e9 s\u00f3 captura do procurado, mas principalmente trabalhar com inqu\u00e9ritos policiais na lavagem de dinheiro, na intelig\u00eancia financeira, para tornar o crime mais oneroso e recuperar ativos para repara\u00e7\u00e3o dos danos\u201d, disse Granja.<\/p>\n<figure id=\"attachment_372289\" aria-describedby=\"caption-attachment-372289\" style=\"width: 875px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" decoding=\"async\" alt=\"\" width=\"875\" height=\"645\" srcset=\"https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-07-foto-divulgacao-scaled.jpg 875w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-07-foto-divulgacao-300x221.jpg 300w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-07-foto-divulgacao-1024x755.jpg 1024w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-07-foto-divulgacao-768x566.jpg 768w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-07-foto-divulgacao-960x707.jpg 960w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-07-foto-divulgacao-543x400.jpg 543w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-07-foto-divulgacao-585x431.jpg 585w\" src=\"https:\/\/i0.wp.com\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-07-foto-divulgacao-scaled.jpg?resize=875%2C645&#038;ssl=1\" data-sizes=\"(max-width: 875px) 100vw, 875px\" class=\"size-full wp-image-372289 lazyload\"\/><noscript><img data-recalc-dims=\"1\" decoding=\"async\" class=\"size-full wp-image-372289\" src=\"https:\/\/i0.wp.com\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-07-foto-divulgacao-scaled.jpg?resize=875%2C645&#038;ssl=1\" alt=\"\" width=\"875\" height=\"645\" srcset=\"https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-07-foto-divulgacao-scaled.jpg 875w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-07-foto-divulgacao-300x221.jpg 300w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-07-foto-divulgacao-1024x755.jpg 1024w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-07-foto-divulgacao-768x566.jpg 768w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-07-foto-divulgacao-960x707.jpg 960w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-07-foto-divulgacao-543x400.jpg 543w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-07-foto-divulgacao-585x431.jpg 585w\" sizes=\"(max-width: 875px) 100vw, 875px\"\/><\/noscript><figcaption id=\"caption-attachment-372289\" class=\"wp-caption-text\">Condom\u00ednio de luxo na zona Sul foi um dos alvos da opera\u00e7\u00e3o que contou com apoio do \u00c1guia da PM (Foto: Pol\u00edcia Civil\/Divulga\u00e7\u00e3o)<\/figcaption><\/figure>\n<p>O delegado tamb\u00e9m disse que as condutas dos presos ser\u00e3o individualizadas, de acordo com os elementos encontrados durante as pris\u00f5es. Todos estavam sendo interrogados na presen\u00e7a de advogados, mas a Pol\u00edcia Civil n\u00e3o divulgou o nome de nenhum envolvido.<\/p>\n<p><span style=\"color: #008000\"><em><strong>R$ 300 milh\u00f5es<\/strong><\/em><\/span><\/p>\n<p>Segundo o delegado Jo\u00e3o Marcelo Almeida, da Pol\u00edcia Civil de Alagoas, o grupo teria movimentado R$ 300 milh\u00f5es em menos de tr\u00eas anos. As investiga\u00e7\u00f5es come\u00e7aram em Macei\u00f3 em 2021, mirando dois casais, um do Par\u00e1 e outro de Alagoas, que seriam respons\u00e1veis pelo tr\u00e1fico na regi\u00e3o norte do Pa\u00eds. O cabe\u00e7a do grupo fica no Rio de Janeiro.<\/p>\n<figure id=\"attachment_372288\" aria-describedby=\"caption-attachment-372288\" style=\"width: 748px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" decoding=\"async\" alt=\"\" width=\"748\" height=\"812\" srcset=\"https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-06-foto-divulgacao.jpg 594w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-06-foto-divulgacao-276x300.jpg 276w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-06-foto-divulgacao-368x400.jpg 368w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-06-foto-divulgacao-585x635.jpg 585w\" src=\"https:\/\/i0.wp.com\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-06-foto-divulgacao.jpg?resize=748%2C812&#038;ssl=1\" data-sizes=\"(max-width: 748px) 100vw, 748px\" class=\" wp-image-372288 lazyload\"\/><noscript><img data-recalc-dims=\"1\" decoding=\"async\" class=\" wp-image-372288\" src=\"https:\/\/i0.wp.com\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-06-foto-divulgacao.jpg?resize=748%2C812&#038;ssl=1\" alt=\"\" width=\"748\" height=\"812\" srcset=\"https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-06-foto-divulgacao.jpg 594w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-06-foto-divulgacao-276x300.jpg 276w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-06-foto-divulgacao-368x400.jpg 368w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-06-foto-divulgacao-585x635.jpg 585w\" sizes=\"(max-width: 748px) 100vw, 748px\"\/><\/noscript><figcaption id=\"caption-attachment-372288\" class=\"wp-caption-text\">Objetos como notebooks e celulares ser\u00e3o periciados (Foto: Pol\u00edcia Civil\/Divulga\u00e7\u00e3o)<\/figcaption><\/figure>\n<p>Almeida informou que o n\u00facleo de Ribeir\u00e3o Preto, que era ligado ao casal de Macei\u00f3, seria respons\u00e1vel apenas pela lavagem de dinheiro, embora a droga viesse do Mato Grosso do Sul para Ribeir\u00e3o Preto, onde era distribu\u00edda para o Nordeste e para a cidade de S\u00e3o Paulo.<\/p>\n<p>Os presos s\u00e3o empres\u00e1rios com empresas como loja de celular, lava-r\u00e1pido, estacionamento, loja de autope\u00e7as, entre outros. Um dos empres\u00e1rios movimentou R$ 19 milh\u00f5es em menos de dois anos. Outro movimentou R$ 15 milh\u00f5es no mesmo per\u00edodo. De acordo com o delegado alagoano, o montante movimentado \u00e9 incompat\u00edvel com o porte das empresas investigadas.<\/p>\n<figure id=\"attachment_372270\" aria-describedby=\"caption-attachment-372270\" style=\"width: 1000px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" decoding=\"async\" alt=\"\" width=\"1000\" height=\"562\" srcset=\"https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-03-foto-divulgacao-scaled.jpg 1000w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-03-foto-divulgacao-300x169.jpg 300w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-03-foto-divulgacao-1024x576.jpg 1024w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-03-foto-divulgacao-768x432.jpg 768w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-03-foto-divulgacao-1536x864.jpg 1536w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-03-foto-divulgacao-960x540.jpg 960w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-03-foto-divulgacao-711x400.jpg 711w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-03-foto-divulgacao-585x329.jpg 585w\" src=\"https:\/\/i0.wp.com\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-03-foto-divulgacao-scaled.jpg?resize=1000%2C562&#038;ssl=1\" data-sizes=\"(max-width: 1000px) 100vw, 1000px\" class=\"size-full wp-image-372270 lazyload\"\/><noscript><img data-recalc-dims=\"1\" decoding=\"async\" class=\"size-full wp-image-372270\" src=\"https:\/\/i0.wp.com\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-03-foto-divulgacao-scaled.jpg?resize=1000%2C562&#038;ssl=1\" alt=\"\" width=\"1000\" height=\"562\" srcset=\"https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-03-foto-divulgacao-scaled.jpg 1000w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-03-foto-divulgacao-300x169.jpg 300w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-03-foto-divulgacao-1024x576.jpg 1024w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-03-foto-divulgacao-768x432.jpg 768w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-03-foto-divulgacao-1536x864.jpg 1536w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-03-foto-divulgacao-960x540.jpg 960w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-03-foto-divulgacao-711x400.jpg 711w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-03-foto-divulgacao-585x329.jpg 585w\" sizes=\"(max-width: 1000px) 100vw, 1000px\"\/><\/noscript><figcaption id=\"caption-attachment-372270\" class=\"wp-caption-text\">Armas, joias, rel\u00f3gios e outros objetos foram apreendidos pelos agentes (Foto: Pol\u00edcia Civil\/Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p>A opera\u00e7\u00e3o Hades foi realizada, simultaneamente, em diversos estados brasileiros. No total, foram 229 mandados de busca e apreens\u00e3o e 79 mandados de pris\u00e3o para serem cumpridos em 17 estados. Almeida n\u00e3o soube informar se o chefe do esquema, no Rio de Janeiro, havia sido capturado.<\/p>\n<p>Os presos em Ribeir\u00e3o Preto devem passar por audi\u00eancia de cust\u00f3dia nesta sexta-feira (02). Se a pris\u00e3o for convertida em preventiva, eles devem ser transferidos para a capital alagoana. O inqu\u00e9rito segue para Macei\u00f3, onde as investiga\u00e7\u00f5es foram originadas.<\/p>\n<figure id=\"attachment_372271\" aria-describedby=\"caption-attachment-372271\" style=\"width: 1000px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" decoding=\"async\" alt=\"\" width=\"1000\" height=\"563\" srcset=\"https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-04-foto-divulgacao-scaled.jpg 1000w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-04-foto-divulgacao-300x169.jpg 300w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-04-foto-divulgacao-1024x576.jpg 1024w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-04-foto-divulgacao-768x432.jpg 768w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-04-foto-divulgacao-960x540.jpg 960w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-04-foto-divulgacao-711x400.jpg 711w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-04-foto-divulgacao-585x329.jpg 585w\" src=\"https:\/\/i0.wp.com\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-04-foto-divulgacao-scaled.jpg?resize=1000%2C563&#038;ssl=1\" data-sizes=\"(max-width: 1000px) 100vw, 1000px\" class=\"size-full wp-image-372271 lazyload\"\/><noscript><img data-recalc-dims=\"1\" decoding=\"async\" class=\"size-full wp-image-372271\" src=\"https:\/\/i0.wp.com\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-04-foto-divulgacao-scaled.jpg?resize=1000%2C563&#038;ssl=1\" alt=\"\" width=\"1000\" height=\"563\" srcset=\"https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-04-foto-divulgacao-scaled.jpg 1000w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-04-foto-divulgacao-300x169.jpg 300w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-04-foto-divulgacao-1024x576.jpg 1024w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-04-foto-divulgacao-768x432.jpg 768w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-04-foto-divulgacao-960x540.jpg 960w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-04-foto-divulgacao-711x400.jpg 711w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-04-foto-divulgacao-585x329.jpg 585w\" sizes=\"(max-width: 1000px) 100vw, 1000px\"\/><\/noscript><figcaption id=\"caption-attachment-372271\" class=\"wp-caption-text\">Durante a opera\u00e7\u00e3o, seis ve\u00edculos e uma moto, avaliados em R$ 343 mil, foram apreendidos (Foto: Pol\u00edcia Civil\/Divulga\u00e7\u00e3o)<\/figcaption><\/figure>\n<p>Em Ribeir\u00e3o Preto, os mandados foram cumpridos em diversos bairros e regi\u00f5es, inclusive em um condom\u00ednio de alto padr\u00e3o na zona Sul da cidade. As investiga\u00e7\u00f5es prosseguem.<\/p>\n<p><span style=\"color: #008000\"><em><strong>Mandados cumpridos por estado<\/strong><\/em><\/span><\/p>\n<p><strong>Alagoas<\/strong> \u2013 27 mandados, sendo sete de pris\u00e3o e 20 de busca e apreens\u00e3o;<br \/><strong>Amazonas<\/strong> \u2013 29 mandados, sendo tr\u00eas de pris\u00e3o e 26 de busca e apreens\u00e3o;<br \/><strong>Bahia<\/strong> \u2013 dois mandados de busca e apreens\u00e3o;<br \/><strong>Cear\u00e1<\/strong> \u2013 11 mandados, sendo tr\u00eas de pris\u00e3o e oito de busca e apreens\u00e3o;<br \/><strong>Goi\u00e1s<\/strong> \u2013 10 mandados de busca e apreens\u00e3o;<br \/><strong>Mato Grosso<\/strong> \u2013 13 mandados, sendo tr\u00eas de pris\u00e3o e 10 de busca e apreens\u00e3o;<br \/><strong>Mato Grosso do Sul<\/strong> \u2013 61 mandados, sendo 19 de pris\u00e3o e 42 de busca e apreens\u00e3o;<br \/><strong>Minas Gerais<\/strong> \u2013 cinco mandados, sendo um de pris\u00e3o e quatro de busca e apreens\u00e3o;<br \/><strong>Par\u00e1<\/strong> \u2013 40 mandados, sendo 14 de pris\u00e3o e 26 de busca e apreens\u00e3o;<br \/><strong>Paran\u00e1<\/strong> \u2013 um mandado de pris\u00e3o;<br \/><strong>Pernambuco<\/strong> \u2013 tr\u00eas mandados, sendo dois de pris\u00e3o e um de busca e apreens\u00e3o;<br \/><strong>Piau\u00ed<\/strong> \u2013 dois mandados, sendo um de pris\u00e3o e um de busca e apreens\u00e3o;<br \/><strong>Rio de Janeiro<\/strong> \u2013 11 mandados, sendo quatro de pris\u00e3o e sete de busca e apreens\u00e3o;<br \/><strong>Rio Grande do Norte<\/strong> \u2013 um mandado de busca e apreens\u00e3o;<br \/><strong>Roraima<\/strong> \u2013 04 mandados, sendo um de pris\u00e3o e dois de busca e apreens\u00e3o;<br \/><strong>Santa Catarina<\/strong> \u2013 quatro mandados, sendo um de pris\u00e3o e tr\u00eas de busca e apreens\u00e3o;<br \/><strong>S\u00e3o Paulo<\/strong> \u2013 84 mandados, sendo 19 de pris\u00e3o e 65 de busca e apreens\u00e3o.<\/p>\n<\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/site\/rp-tem-nove-presos-em-operacao-nacional-contra-trafico\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Por: Adalberto Luque e Alfredo Risk Pol\u00edcias Civil e Militar deflagraram, no final da madrugada desta quinta-feira (01), uma megaopera\u00e7\u00e3o contra organiza\u00e7\u00e3o criminosa. O grupo \u00e9 investigado por tr\u00e1fico de drogas e lavagem de dinheiro. A opera\u00e7\u00e3o \u201cHades\u201d foi realizada em diversos estados brasileiros. Para a a\u00e7\u00e3o foram mobilizadas equipes da Divis\u00e3o Especial de &#8230; <a title=\"RP tem nove presos em opera\u00e7\u00e3o nacional contra tr\u00e1fico\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/02\/rp-tem-nove-presos-em-operacao-nacional-contra-trafico\/\" aria-label=\"Leia mais sobre RP tem nove presos em opera\u00e7\u00e3o nacional contra tr\u00e1fico\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":34441,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[109,721,1228,1130,1490,162,1570],"class_list":["post-34440","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-contra","tag-nacional","tag-nove","tag-operacao","tag-presos","tag-tem","tag-trafico"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-05-foto-Alfredo-Risk-scaled.jpg?fit=967%2C645&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-05-foto-Alfredo-Risk-scaled.jpg?fit=967%2C645&ssl=1",967,645,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-05-foto-Alfredo-Risk-scaled.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-05-foto-Alfredo-Risk-scaled.jpg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-05-foto-Alfredo-Risk-scaled.jpg?fit=768%2C512&ssl=1",768,512,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-05-foto-Alfredo-Risk-scaled.jpg?fit=967%2C645&ssl=1",967,645,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-05-foto-Alfredo-Risk-scaled.jpg?fit=967%2C645&ssl=1",967,645,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-crime-org-alagoas-05-foto-Alfredo-Risk-scaled.jpg?fit=967%2C645&ssl=1",967,645,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Por: Adalberto Luque e Alfredo Risk Pol\u00edcias Civil e Militar deflagraram, no final da madrugada desta quinta-feira (01), uma megaopera\u00e7\u00e3o contra organiza\u00e7\u00e3o criminosa. O grupo \u00e9 investigado por tr\u00e1fico de drogas e lavagem de dinheiro. A opera\u00e7\u00e3o \u201cHades\u201d foi realizada em diversos estados brasileiros. Para a a\u00e7\u00e3o foram mobilizadas equipes da Divis\u00e3o Especial de&hellip;","jetpack-related-posts":[{"id":32882,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/26\/utm_sourcerssutm_mediumrssutm_campaigngaeco-e-baep-realizam-operacao-contra-faccao-criminosa\/","url_meta":{"origin":34440,"position":0},"title":"GAECO e BAEP realizam opera\u00e7\u00e3o contra fac\u00e7\u00e3o criminosa \u2013 X Tudo Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"26 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Uma grande opera\u00e7\u00e3o foi deflagrada, no in\u00edcio da manh\u00e3 desta sexta-feira (26), pelo Grupo de Atua\u00e7\u00e3o Especial de Combate ao Crime Organizado (GAECO), do Minist\u00e9rio P\u00fablico de S\u00e3o Paulo (MPSP). A \u201cOpera\u00e7\u00e3o Paralelo 16\u201d contou com apoio do Batalh\u00e3o de A\u00e7\u00f5es Especiais de Pol\u00edcia (BAEP). Segundo informa\u00e7\u00f5es, o objetivo\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/BAEP.jpg?fit=585%2C701&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/BAEP.jpg?fit=585%2C701&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/BAEP.jpg?fit=585%2C701&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":8607,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/30\/utm_sourcerssutm_mediumrssutm_campaignpf-gaeco-e-baep-realizam-operacao-em-rp\/","url_meta":{"origin":34440,"position":1},"title":"PF, GAECO e BAEP realizam opera\u00e7\u00e3o em RP \u2013 X Tudo Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"30 de Novembro de 2023","format":false,"excerpt":"[ad_1] Uma opera\u00e7\u00e3o envolvendo Pol\u00edcia Federal (PF) e Grupo de Atua\u00e7\u00e3o Especial de Combate ao Crime Organizado (GAECO), com apoio do Batalh\u00e3o de A\u00e7\u00f5es Especiais de Pol\u00edcia (BAEP) foi realizada em Ribeir\u00e3o Preto, na manh\u00e3 desta quinta-feira (30). A opera\u00e7\u00e3o, denominada \u201cCar Wash\u201d, teve por objetivo desarticular uma quadrilha ligada\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/c3b841d5-889f-42b4-9cb9-72db0b22e4ea.jpeg?fit=1200%2C788&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/c3b841d5-889f-42b4-9cb9-72db0b22e4ea.jpeg?fit=1200%2C788&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/c3b841d5-889f-42b4-9cb9-72db0b22e4ea.jpeg?fit=1200%2C788&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/c3b841d5-889f-42b4-9cb9-72db0b22e4ea.jpeg?fit=1200%2C788&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/c3b841d5-889f-42b4-9cb9-72db0b22e4ea.jpeg?fit=1200%2C788&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":43972,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/25\/grupo-e-preso-transportando-cocaina-em-compartimento-de-caminhonete\/","url_meta":{"origin":34440,"position":2},"title":"Grupo \u00e9 preso transportando coca\u00edna em compartimento de caminhonete","author":"ismaelcolosi.com.br","date":"25 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] Fundo falso foi localizado com apoio de c\u00e3o de faro; um homem e tr\u00eas mulheres foram presos e encaminhados \u00e0 PF 25 de mar\u00e7o de 2024 | 7:1124 de mar\u00e7o de 2024 | 20:07 1 Por: Adalberto Luque Um grupo de quatro pessoas foi preso neste domingo (24) por\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-25-mar-2024-apreensao-maconha-01-foto-baep.jpg?fit=1200%2C822&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-25-mar-2024-apreensao-maconha-01-foto-baep.jpg?fit=1200%2C822&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-25-mar-2024-apreensao-maconha-01-foto-baep.jpg?fit=1200%2C822&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-25-mar-2024-apreensao-maconha-01-foto-baep.jpg?fit=1200%2C822&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-25-mar-2024-apreensao-maconha-01-foto-baep.jpg?fit=1200%2C822&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":34326,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/01\/utm_sourcerssutm_mediumrssutm_campaignbaep-prende-traficante-no-quintino-facci-ii\/","url_meta":{"origin":34440,"position":3},"title":"BAEP prende traficante no Quintino Facci II \u2013 X Tudo Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"1 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] Um traficante foi preso com uma sacola de drogas pela equipe do 11\u00ba BAEP (Batalh\u00e3o de A\u00e7\u00f5es Especiais de Pol\u00edcia), no bairro Quintino Facci II, na zona Norte de Ribeir\u00e3o Preto Segundo informa\u00e7\u00f5es da Pol\u00edcia, durante o patrulhamento ostensivo pela regi\u00e3o, os PMs depararam com acusado com uma sacola\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-apreensao-baep-foto-divulgacao-1024x768-1.jpg?fit=1024%2C768&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-apreensao-baep-foto-divulgacao-1024x768-1.jpg?fit=1024%2C768&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-apreensao-baep-foto-divulgacao-1024x768-1.jpg?fit=1024%2C768&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/00-01-fev-2024-apreensao-baep-foto-divulgacao-1024x768-1.jpg?fit=1024%2C768&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":34199,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/01\/utm_sourcerssutm_mediumrssutm_campaignoperacao-hades-em-ribeirao-preto-cumpre-mandados-contra-organizacao-criminosa-investigada-pela-policia-de-alagoas\/","url_meta":{"origin":34440,"position":4},"title":"Opera\u00e7\u00e3o Hades em Ribeir\u00e3o Preto cumpre mandados contra organiza\u00e7\u00e3o criminosa investigada pela Pol\u00edcia de Alagoas \u2013 X Tudo Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"1 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] A Pol\u00edcia Civil atrav\u00e9s do DEIC do Deinter 3 com apoio da PM cumpre na manh\u00e3 desta quinta-feira (1\/2), mandados de buscas e de pris\u00f5es contra uma organiza\u00e7\u00e3o criminosa investigada no estado de Alagoas.\u00a0 Segundo informa\u00e7\u00f5es da Pol\u00edcia, Opera\u00e7\u00e3o batizada como \u201cHades\u201d, chefiada pelo Departamento de Repress\u00e3o ao Crime\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-01-at-07.36.56.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-01-at-07.36.56.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-01-at-07.36.56.jpeg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-01-at-07.36.56.jpeg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-01-at-07.36.56.jpeg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":42378,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/14\/baep-apreende-25-kg-de-drogas-na-zona-norte\/","url_meta":{"origin":34440,"position":5},"title":"BAEP apreende 25 kg de drogas na zona Norte","author":"ismaelcolosi.com.br","date":"14 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] A\u00e7\u00f5es ocorreram nos bairros Jardim Salgado Filho 1 e 2 14 de mar\u00e7o de 2024 | 11:16 0Por: Adalberto LuqueEm duas a\u00e7\u00f5es distintas, realizadas nesta quarta-feira (13), o Batalh\u00e3o de A\u00e7\u00f5es Especiais de Pol\u00edcia (BAEP) apreendeu quase 25 quilos de drogas em duas opera\u00e7\u00f5es. As a\u00e7\u00f5es ocorreram em bairros\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-14-mar-2024-Drogas-Salgado-Filho-02-foto-baep-scaled.jpg?fit=1000%2C573&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-14-mar-2024-Drogas-Salgado-Filho-02-foto-baep-scaled.jpg?fit=1000%2C573&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-14-mar-2024-Drogas-Salgado-Filho-02-foto-baep-scaled.jpg?fit=1000%2C573&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-14-mar-2024-Drogas-Salgado-Filho-02-foto-baep-scaled.jpg?fit=1000%2C573&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-8Xu","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/34440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=34440"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/34440\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/34441"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=34440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=34440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=34440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}