{"id":34380,"date":"2024-02-01T21:19:17","date_gmt":"2024-02-02T00:19:17","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/01\/muro-de-escola-desaba-na-zona-oeste-de-ribeirao-preto-durante-temporal\/"},"modified":"2024-02-01T21:19:17","modified_gmt":"2024-02-02T00:19:17","slug":"muro-de-escola-desaba-na-zona-oeste-de-ribeirao-preto-durante-temporal","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/01\/muro-de-escola-desaba-na-zona-oeste-de-ribeirao-preto-durante-temporal\/","title":{"rendered":"Muro de escola desaba na zona Oeste de Ribeir\u00e3o Preto durante temporal"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_104\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p>Devido a<strong> forte chuva<\/strong> registrada nesta quinta-feira (1\u00ba), uma \u00e1rvore caiu e <strong>provocou a queda do muro da Escola Estadual Santos Dumont<\/strong>, no bairro Sumarezinho, na zona Oeste de <strong>Ribeir\u00e3o Preto<\/strong>.<\/p>\n<p>De acordo com o <strong>Centro Nacional de Monitoramento e Alertas de Desastres Naturais(Cemaden) choveu cerca de 68 mil\u00edmetros<\/strong> no Centro, o que causou diversos transtornos na cidade.<\/p>\n<p>Ap\u00f3s o ocorrido, a \u00e1rea foi isolada pelo<strong> Corpo de Bombeiros<\/strong> e por uma equipe de agentes de tr\u00e2nsito da <strong>RP Mobi<\/strong>. Por sorte, n\u00e3o houve feridos.<\/p>\n<h4 class=\"wp-block-heading\"><strong>Outro lado<\/strong><\/h4>\n<p>Em nota, a <strong>Secretaria da Educa\u00e7\u00e3o do Estado de S\u00e3o Paulo (Seduc-SP)<\/strong> informou que, devido ao temporal na tarde desta quinta, parte do muro da escola cedeu ap\u00f3s a queda de uma \u00e1rvore e que o local j\u00e1 foi vistoriado para avalia\u00e7\u00e3o de danos.<\/p>\n<p>Ainda de acordo com a <strong>Seduc-SP<\/strong>, <mark style=\"background-color:#fcb900\" class=\"has-inline-color\">os reparos dever\u00e3o ser iniciados nesta sexta (2)<\/mark>. A queda do muro <strong>n\u00e3o impactar\u00e1 o funcionamento da escola no retorno do ano letivo<\/strong>, j\u00e1 que as aulas est\u00e3o previstas para o dia 15 de fevereiro.<\/p>\n<p>O \u00f3rg\u00e3o tamb\u00e9m informou que a <strong>Prefeitura de Ribeir\u00e3o Preto<\/strong> j\u00e1 foi acionada pela Diretoria de Ensino para apoio na retirada da \u00e1rvore.<\/p>\n<p>SAIBA MAIS<\/p>\n<p>Chuva causa alagamentos em Ribeir\u00e3o Preto; Veja os pontos<\/p>\n<h4 class=\"wp-block-heading\"><strong><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">FIQUE ON<\/mark><\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do<strong>\u00a0acidade on\u00a0<\/strong>no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do<strong>\u00a0acidade on\u00a0<\/strong>no WhatsApp.<a href=\"https:\/\/chat.whatsapp.com\/Bnv2w66ZT4VDyZW3oiZ69n\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a0Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Fim de semana de Pr\u00e9-Carnaval vai ter chuva em SP?<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/muro-de-escola-desaba-na-zona-oeste-de-ribeirao-preto-durante-temporal\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Devido a forte chuva registrada nesta quinta-feira (1\u00ba), uma \u00e1rvore caiu e provocou a queda do muro da Escola Estadual Santos Dumont, no bairro Sumarezinho, na zona Oeste de Ribeir\u00e3o Preto. De acordo com o Centro Nacional de Monitoramento e Alertas de Desastres Naturais(Cemaden) choveu cerca de 68 mil\u00edmetros no Centro, o que causou &#8230; <a title=\"Muro de escola desaba na zona Oeste de Ribeir\u00e3o Preto durante temporal\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/01\/muro-de-escola-desaba-na-zona-oeste-de-ribeirao-preto-durante-temporal\/\" aria-label=\"Leia mais sobre Muro de escola desaba na zona Oeste de Ribeir\u00e3o Preto durante temporal\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":34381,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-34380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-28.png?fit=1200%2C675&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-28.png?fit=1200%2C675&ssl=1",1200,675,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-28.png?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-28.png?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-28.png?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-28.png?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-28.png?fit=1200%2C675&ssl=1",1200,675,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-28.png?fit=1200%2C675&ssl=1",1200,675,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Devido a forte chuva registrada nesta quinta-feira (1\u00ba), uma \u00e1rvore caiu e provocou a queda do muro da Escola Estadual Santos Dumont, no bairro Sumarezinho, na zona Oeste de Ribeir\u00e3o Preto. De acordo com o Centro Nacional de Monitoramento e Alertas de Desastres Naturais(Cemaden) choveu cerca de 68 mil\u00edmetros no Centro, o que causou&hellip;","jetpack-related-posts":[{"id":70669,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/11\/temporal-provoca-quedas-de-arvores-e-interdicoes-em-ribeirao-preto\/","url_meta":{"origin":34380,"position":0},"title":"Temporal provoca quedas de \u00e1rvores e interdi\u00e7\u00f5es em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"11 de Outubro de 2024","format":false,"excerpt":"[ad_1] O temporal que atingiu Ribeir\u00e3o Preto, na tarde desta sexta-feira (11), n\u00e3o durou muito tempo, mas foi o suficiente para causas danos e interdi\u00e7\u00f5es em alguns pontos da cidade. Na avenida Pio XII, zona Oeste da cidade, uma \u00e1rvore caiu e derrubou o muro da CEMEI Eduardo Romualdo de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-15_2024-10-11_21-01-48_png_2024-10-11_21-01-48.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-15_2024-10-11_21-01-48_png_2024-10-11_21-01-48.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-15_2024-10-11_21-01-48_png_2024-10-11_21-01-48.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-15_2024-10-11_21-01-48_png_2024-10-11_21-01-48.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Copia-de-Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-15_2024-10-11_21-01-48_png_2024-10-11_21-01-48.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":34374,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/01\/apos-temporal-veja-como-fica-o-tempo-no-final-de-semana-em-ribeirao-preto\/","url_meta":{"origin":34380,"position":1},"title":"Ap\u00f3s temporal, veja como fica o tempo no final de semana em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"1 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] Ap\u00f3s os estragos provocados pelo temporal que atingiu a regi\u00e3o Central de Ribeir\u00e3o Preto, no final da tarde desta quinta-feira (1\u00ba), ainda h\u00e1 previs\u00e3o de chuva para cidade neste final de semana. Vale lembrar que todo o estado de S\u00e3o Paulo, inclusive o interior, est\u00e1 sob alerta amarelo de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-29.png?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-29.png?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-29.png?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-29.png?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-29.png?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":70734,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/12\/bosque-de-ribeirao-preto-fica-fechado-por-conta-da-queda-de-arvores\/","url_meta":{"origin":34380,"position":2},"title":"Bosque de Ribeir\u00e3o Preto fica fechado por conta da queda de \u00e1rvores","author":"ismaelcolosi.com.br","date":"12 de Outubro de 2024","format":false,"excerpt":"[ad_1] O Bosque Zool\u00f3gico F\u00e1bio Barreto, em Ribeir\u00e3o Preto, n\u00e3o abrir\u00e1 neste s\u00e1bado (12). Segundo a prefeitura, a decis\u00e3o foi motivada pela queda de duas \u00e1rvores durante a forte chuva da tarde de sexta-feira (11). Em nota, a Administra\u00e7\u00e3o Municipal informa que as atividades no bosque voltam ao normal neste\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/queda-arvore-bosque_2024-10-12_13-23-15_jpg_2024-10-12_13-23-15.webp.webp?fit=843%2C470&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/queda-arvore-bosque_2024-10-12_13-23-15_jpg_2024-10-12_13-23-15.webp.webp?fit=843%2C470&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/queda-arvore-bosque_2024-10-12_13-23-15_jpg_2024-10-12_13-23-15.webp.webp?fit=843%2C470&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/queda-arvore-bosque_2024-10-12_13-23-15_jpg_2024-10-12_13-23-15.webp.webp?fit=843%2C470&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":34478,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/02\/tempestade-causa-mais-transtornos-em-rp\/","url_meta":{"origin":34380,"position":3},"title":"Tempestade causa mais transtornos em RP","author":"ismaelcolosi.com.br","date":"2 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] 2 de fevereiro de 2024 | 8:22 0O temporal que caiu em Ribeir\u00e3o Preto, no final da tarde desta quinta-feira, 1\u00ba de novembro, causou mais transtornos \u00e0 popula\u00e7\u00e3o. A tempestade durou numa hora, veio acompanhada de rajadas de vento de at\u00e9 70 quil\u00f4metros por hora e derrubou \u00e1rvores em\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/content_d2741f76-a8e0-46d3-8cf6-2bab16790ef6.jpg?fit=600%2C338&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/content_d2741f76-a8e0-46d3-8cf6-2bab16790ef6.jpg?fit=600%2C338&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/content_d2741f76-a8e0-46d3-8cf6-2bab16790ef6.jpg?fit=600%2C338&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":25724,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/08\/predio-e-interditado-apos-temporal-em-ribeirao-preto-transito-conta-com-bloqueios\/","url_meta":{"origin":34380,"position":4},"title":"Pr\u00e9dio \u00e9 interditado ap\u00f3s temporal em Ribeir\u00e3o Preto; Tr\u00e2nsito conta com bloqueios","author":"ismaelcolosi.com.br","date":"8 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Um pr\u00e9dio no Parque dos Lagos, na zona Leste de Ribeir\u00e3o Preto, foi interditado pela Defesa Civil na madrugada desta segunda-feira (8) ap\u00f3s o temporal que atingiu a cidade no final da tarde de domingo (7). Segundo a Prefeitura de Ribeir\u00e3o Preto, engenheiros ser\u00e3o enviados ao local para vistoriar\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/queda-de-arvore-ribeirao-preto.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/queda-de-arvore-ribeirao-preto.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/queda-de-arvore-ribeirao-preto.jpeg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/queda-de-arvore-ribeirao-preto.jpeg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/queda-de-arvore-ribeirao-preto.jpeg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":55032,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/29\/carro-desgovernado-so-para-entre-muro-e-arvore-na-regiao-de-ribeirao-veja-o-video\/","url_meta":{"origin":34380,"position":5},"title":"Carro desgovernado s\u00f3 para entre muro e \u00e1rvore na regi\u00e3o de Ribeir\u00e3o; Veja o v\u00eddeo","author":"ismaelcolosi.com.br","date":"29 de Junho de 2024","format":false,"excerpt":"[ad_1] Um carro desgovernado bateu contra tr\u00eas ve\u00edculos estacionados e s\u00f3 parou ap\u00f3s ficar preso na cal\u00e7ada, entre o muro de uma casa e uma \u00e1rvore (veja o v\u00eddeo). O acidente aconteceu na manh\u00e3 deste s\u00e1bado (29), na rua Jos\u00e9 Bonif\u00e1cio, na Vila Nic\u00e1cio em Franca, cidade na regi\u00e3o de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-29_2024-06-29_21-44-02_jpg_2024-06-29_21-44-02.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-29_2024-06-29_21-44-02_jpg_2024-06-29_21-44-02.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-29_2024-06-29_21-44-02_jpg_2024-06-29_21-44-02.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-29_2024-06-29_21-44-02_jpg_2024-06-29_21-44-02.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-29_2024-06-29_21-44-02_jpg_2024-06-29_21-44-02.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-8Ww","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/34380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=34380"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/34380\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/34381"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=34380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=34380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=34380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}