{"id":33985,"date":"2024-01-31T14:03:13","date_gmt":"2024-01-31T17:03:13","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/31\/ana-castela-esta-confirmada-na-festa-do-peao-de-barretos\/"},"modified":"2024-01-31T14:03:13","modified_gmt":"2024-01-31T17:03:13","slug":"ana-castela-esta-confirmada-na-festa-do-peao-de-barretos","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/31\/ana-castela-esta-confirmada-na-festa-do-peao-de-barretos\/","title":{"rendered":"Ana Castela est\u00e1 confirmada na Festa do Pe\u00e3o de Barretos"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_104\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p>A cantora sertaneja <strong>Ana Castela<\/strong>, conhecida como <strong>\u201cBoiadeira\u201d<\/strong> est\u00e1 <strong>confirmada<\/strong> na programa\u00e7\u00e3o musical da <strong>Festa do Pe\u00e3o de Barretos<\/strong> deste ano, que acontece de <strong>15 a 25 de agosto<\/strong>.<\/p>\n<p>A<strong> apresenta\u00e7\u00e3o<\/strong> da \u201cBoiadeira\u201d ser\u00e1 no <strong>dia 17<\/strong>, mesmo dia em que as<strong> duplas sertanejas Jorge e Mateus<\/strong> e os <strong>embaixadores do rodeio C\u00e9sar Menotti e Fabiano<\/strong> subir\u00e3o ao <strong>palco principal<\/strong> do evento.<\/p>\n<p><strong>Ana Castela<\/strong> se apresenta pela <strong>terceira vez<\/strong> durante a festa.<\/p>\n<p>Al\u00e9m das apresenta\u00e7\u00f5es sertanejas, o<strong> cantor Cody Johnson <\/strong>tamb\u00e9m tem data definida na programa\u00e7\u00e3o. O <strong>\u00eddolo country norte-americano<\/strong> subir\u00e1 no dia <strong>24 de agosto<\/strong>.<\/p>\n<p><strong>Veja como comprar seu ingresso<\/strong><\/p>\n<p>Os <strong>ingressos<\/strong> para a <strong>Festa do Pe\u00e3o de Barretos<\/strong> est\u00e3o sendo <strong>vendidos<\/strong> exclusivamente pelo <strong><a href=\"https:\/\/barretos.totalacesso.com\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">site<\/a><\/strong>. \u00a0<\/p>\n<p>Est\u00e3o <strong>dispon\u00edveis<\/strong> lotes para <strong>todos os setores<\/strong> do evento, que incluem o parque, o rodeio, shows, \u00e1rea vip, pistas e camarotes. Os pacotes para a \u00e1rea do camping tamb\u00e9m j\u00e1 est\u00e3o sendo vendidos.<\/p>\n<p>SAIBA MAIS<\/p>\n<p>Ribeir\u00e3o tem feira pr\u00e9-Carnaval com cerveja artesanal, food trucks e m\u00fasica; Veja quando<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do acidade on no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do acidade on no WhatsApp. Para entrar no grupo, basta\u00a0<a href=\"https:\/\/chat.whatsapp.com\/Bnv2w66ZT4VDyZW3oiZ69n\" target=\"_blank\" rel=\"noreferrer noopener\">clicar aqui<\/a>.<\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Rodovia Mogi-Bertioga \u00e9 liberada nesta ter\u00e7a-feira<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/lazer-e-cultura\/ana-castela-esta-confirmada-na-festa-do-peao-de-barretos\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] A cantora sertaneja Ana Castela, conhecida como \u201cBoiadeira\u201d est\u00e1 confirmada na programa\u00e7\u00e3o musical da Festa do Pe\u00e3o de Barretos deste ano, que acontece de 15 a 25 de agosto. A apresenta\u00e7\u00e3o da \u201cBoiadeira\u201d ser\u00e1 no dia 17, mesmo dia em que as duplas sertanejas Jorge e Mateus e os embaixadores do rodeio C\u00e9sar Menotti &#8230; <a title=\"Ana Castela est\u00e1 confirmada na Festa do Pe\u00e3o de Barretos\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/31\/ana-castela-esta-confirmada-na-festa-do-peao-de-barretos\/\" aria-label=\"Leia mais sobre Ana Castela est\u00e1 confirmada na Festa do Pe\u00e3o de Barretos\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":33986,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-33985","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-31-at-12.25.44.jpeg?fit=1600%2C1066&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-31-at-12.25.44.jpeg?fit=1600%2C1066&ssl=1",1600,1066,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-31-at-12.25.44.jpeg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-31-at-12.25.44.jpeg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-31-at-12.25.44.jpeg?fit=768%2C512&ssl=1",768,512,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-31-at-12.25.44.jpeg?fit=1024%2C682&ssl=1",1024,682,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-31-at-12.25.44.jpeg?fit=1536%2C1023&ssl=1",1536,1023,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-31-at-12.25.44.jpeg?fit=1600%2C1066&ssl=1",1600,1066,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] A cantora sertaneja Ana Castela, conhecida como \u201cBoiadeira\u201d est\u00e1 confirmada na programa\u00e7\u00e3o musical da Festa do Pe\u00e3o de Barretos deste ano, que acontece de 15 a 25 de agosto. A apresenta\u00e7\u00e3o da \u201cBoiadeira\u201d ser\u00e1 no dia 17, mesmo dia em que as duplas sertanejas Jorge e Mateus e os embaixadores do rodeio C\u00e9sar Menotti&hellip;","jetpack-related-posts":[{"id":42283,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/13\/bruno-marrone-voltam-ao-palco-da-festa-do-peao-de-barretos\/","url_meta":{"origin":33985,"position":0},"title":"Bruno &#038; Marrone voltam ao palco da Festa do Pe\u00e3o de Barretos","author":"ismaelcolosi.com.br","date":"13 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] A dupla sertaneja Bruno & Marrone volta se apresentar no palco da Festa do Pe\u00e3o de Barretos, que acontece de 15 a 25 de agosto. A confirma\u00e7\u00e3o dos cantores na programa\u00e7\u00e3o do evento foi divulgada pela organiza\u00e7\u00e3o na tarde desta quarta-feira (13). O show dos cantores sertanejos, conhecidos pelas\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-46.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-46.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-46.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-46.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-46.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":39638,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/27\/lauana-prado-e-mais-uma-atracao-confirmada-na-festa-do-peao-de-barretos\/","url_meta":{"origin":33985,"position":1},"title":"Lauana Prado \u00e9 mais uma atra\u00e7\u00e3o confirmada na Festa do Pe\u00e3o de Barretos","author":"ismaelcolosi.com.br","date":"27 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] Foi confirmada nesta ter\u00e7a-feira (27) mais uma atra\u00e7\u00e3o para a 69\u00aa Festa do Pe\u00e3o de Boiadeiro de Barretos, cidade a cerca de 120 quil\u00f4metros de Ribeir\u00e3o Preto. Desta vez, quem se apresenta, pelo segundo ano consecutivo, \u00e9 a cantora Lauana Prado. O show \u201cRaiz Arena\u201d, que faz releituras de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-15.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-15.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-15.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-15.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-15.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":46085,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/09\/festa-do-peao-de-barretos-confirma-show-de-edson-hudson\/","url_meta":{"origin":33985,"position":2},"title":"Festa do Pe\u00e3o de Barretos confirma show de Edson &#038; Hudson","author":"ismaelcolosi.com.br","date":"9 de Abril de 2024","format":false,"excerpt":"[ad_1] Festa do Pe\u00e3o de Barretos confirma show de Edson & HudsonDupla com mais de tr\u00eas d\u00e9cadas de hist\u00f3ria apresentar\u00e1 seus maiores sucessos no dia 18 de agosto, domingo. A Festa acontece de 15 a 25 de agosto, no Parque do Pe\u00e3o, e ingressos j\u00e1 est\u00e3o \u00e0 venda. A 69\u00aa\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/85f68e21cdfeac1b8cca92eadc410ba7-1.jpeg?fit=1200%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/85f68e21cdfeac1b8cca92eadc410ba7-1.jpeg?fit=1200%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/85f68e21cdfeac1b8cca92eadc410ba7-1.jpeg?fit=1200%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/85f68e21cdfeac1b8cca92eadc410ba7-1.jpeg?fit=1200%2C645&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/85f68e21cdfeac1b8cca92eadc410ba7-1.jpeg?fit=1200%2C645&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":45214,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/03\/festa-do-peao-de-barretos-tera-show-de-ze-neto-cristiano\/","url_meta":{"origin":33985,"position":3},"title":"Festa do Pe\u00e3o de Barretos ter\u00e1 show de Z\u00e9 Neto &#038; Cristiano","author":"ismaelcolosi.com.br","date":"3 de Abril de 2024","format":false,"excerpt":"[ad_1] Festa do Pe\u00e3o de Barretos ter\u00e1 show de Z\u00e9 Neto & CristianoA dupla Z\u00e9 Neto & Cristiano, uma das mais aclamadas e ouvidas do pa\u00eds, est\u00e1 confirmada na grade musical da 69\u00aa Festa do Pe\u00e3o de Boiadeiro de Barretos (15 a 25 de agosto). Os cantores far\u00e3o show no\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/78896df7ff9867b582066d0c653570be.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/78896df7ff9867b582066d0c653570be.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/78896df7ff9867b582066d0c653570be.jpeg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/78896df7ff9867b582066d0c653570be.jpeg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/78896df7ff9867b582066d0c653570be.jpeg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":43012,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/18\/veja-a-programacao-musical-da-festa-do-peao-de-barretos-2024\/","url_meta":{"origin":33985,"position":4},"title":"Veja a programa\u00e7\u00e3o musical da Festa do Pe\u00e3o de Barretos 2024","author":"ismaelcolosi.com.br","date":"18 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] A Festa do Pe\u00e3o de Barretos, que acontece de 15 a 25 de agosto, tem mais uma atra\u00e7\u00e3o musical confirmada. Desta vez, \u00e9 a dupla Zez\u00e9 Di Camargo & Luciano que confirmou presen\u00e7a no dia 23 de agosto. No mesmo dia em que a dupla sertaneja, que faz sucesso\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-64.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-64.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-64.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-64.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-64.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":45492,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/04\/show-de-daniel-e-confirmado-na-festa-do-peao-de-barretos\/","url_meta":{"origin":33985,"position":5},"title":"Show de Daniel \u00e9 confirmado na Festa do Pe\u00e3o de Barretos","author":"ismaelcolosi.com.br","date":"4 de Abril de 2024","format":false,"excerpt":"[ad_1] Show de Daniel \u00e9 confirmado na Festa do Pe\u00e3o de BarretosArtista com 40 anos de carreira, integra a grade musical de 22 de agosto. No mesmo dia, evento tamb\u00e9m ter\u00e1 shows de Matogrosso & Mathias, Victor & L\u00e9o e Pedro Paulo & Alex. Festa acontece de 15 a 25\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Cantor-Daniel-celebra-40-anos-de-carreira-com-show-inedito.webp.webp?fit=1200%2C856&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Cantor-Daniel-celebra-40-anos-de-carreira-com-show-inedito.webp.webp?fit=1200%2C856&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Cantor-Daniel-celebra-40-anos-de-carreira-com-show-inedito.webp.webp?fit=1200%2C856&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Cantor-Daniel-celebra-40-anos-de-carreira-com-show-inedito.webp.webp?fit=1200%2C856&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Cantor-Daniel-celebra-40-anos-de-carreira-com-show-inedito.webp.webp?fit=1200%2C856&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-8Q9","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/33985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=33985"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/33985\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/33986"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=33985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=33985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=33985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}