{"id":33938,"date":"2024-01-31T11:18:49","date_gmt":"2024-01-31T14:18:49","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/31\/cidades-na-regiao-de-ribeirao-tem-concursos-publicos-com-salarios-de-r-4-mil\/"},"modified":"2024-01-31T11:18:49","modified_gmt":"2024-01-31T14:18:49","slug":"cidades-na-regiao-de-ribeirao-tem-concursos-publicos-com-salarios-de-r-4-mil","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/31\/cidades-na-regiao-de-ribeirao-tem-concursos-publicos-com-salarios-de-r-4-mil\/","title":{"rendered":"Cidades na regi\u00e3o de Ribeir\u00e3o t\u00eam concursos p\u00fablicos com sal\u00e1rios de R$ 4 mil"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_104\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p>As prefeituras de<a href=\"https:\/\/www.guatapara.sp.gov.br\/site\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"> <strong>Guatapar\u00e1<\/strong><\/a><strong> <\/strong>e <strong><a href=\"https:\/\/www.santoantoniodaalegria.sp.gov.br\/site\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Santo Ant\u00f4nio da Alegria<\/a><\/strong>, na regi\u00e3o de <strong>Ribeir\u00e3o Preto<\/strong>, contam com <strong>concursos p\u00fablicos <\/strong>para o cadastro de reserva e vagas para contrata\u00e7\u00e3o imediata. As oportunidades s\u00e3o de n\u00edvel fundamental, m\u00e9dio, t\u00e9cnico e superior e os sal\u00e1rios variam entre R$ 1,4 mil e R$ 4,2 mil.<\/p>\n<h4 class=\"wp-block-heading\"><strong>Confira os concursos p\u00fablicos<\/strong><\/h4>\n<h4 class=\"wp-block-heading\"><strong>Prefeitura de Guatapar\u00e1<\/strong><\/h4>\n<p><strong>Ensino fundamental<\/strong><\/p>\n<ul>\n<li>Ajudante de servi\u00e7os gerais, motorista e operador de m\u00e1quinas<\/li>\n<\/ul>\n<p><strong>Ensino m\u00e9dio e t\u00e9cnico<\/strong><\/p>\n<ul>\n<li>Agente comunit\u00e1rio de sa\u00fade, agente sanit\u00e1rio, auxiliar administrativo, auxiliar de campo, auxiliar de enfermagem, auxiliar de recep\u00e7\u00e3o, t\u00e9cnico em radiologia<\/li>\n<\/ul>\n<p><strong>Ensino superior<\/strong><\/p>\n<ul>\n<li>Assistente social, contador, enfermeiro, m\u00e9dico cl\u00ednico geral, geriatra, ginecologista, ortopedista, pediatra, m\u00e9dico plantonista cl\u00ednico geral, professor de educa\u00e7\u00e3o infantil I, professor PEB II \u2013 educa\u00e7\u00e3o f\u00edsica, tesoureiro<\/li>\n<\/ul>\n<p><mark style=\"background-color:#fcb900\" class=\"has-inline-color has-black-color\">As inscri\u00e7\u00f5es devem ser realizadas pela internet (<a href=\"https:\/\/institutoindec.org.br\/concursos\/publicacoes\/PREFEITURA+MUNICIPAL+DE+GUATAPAR%C3%81\/94\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">clique aqui<\/a>) at\u00e9 o dia 29 de fevereiro<\/mark>. A taxa de inscri\u00e7\u00e3o custa entre R$ 60 e R$ 85.<\/p>\n<p>As provas objetivas est\u00e3o previstas para o dia 24 de mar\u00e7o de 2024. O edital completo pode ser conferido <a href=\"https:\/\/institutoindec.org.br\/concursos\/publicacoes\/PREFEITURA+MUNICIPAL+DE+GUATAPAR%C3%81\/94\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">clicando aqui<\/a>.<\/p>\n<h4 class=\"wp-block-heading\"><strong>Prefeitura de Santo Ant\u00f4nio da Alegria<\/strong><\/h4>\n<p><strong>Ensino fundamental<\/strong><\/p>\n<p><strong>Ensino m\u00e9dio e t\u00e9cnico<\/strong><\/p>\n<ul>\n<li>Auxiliar de cirurgi\u00e3o dentista (1 vaga), escritur\u00e1rio e Guarda Municipal (1 vaga)<\/li>\n<\/ul>\n<p><strong>Ensino superior<\/strong><\/p>\n<ul>\n<li>Fonoaudi\u00f3logo e psic\u00f3logo (1 vaga)<\/li>\n<\/ul>\n<p><mark style=\"background-color:#fcb900\" class=\"has-inline-color has-black-color\">As inscri\u00e7\u00f5es devem ser realizadas pela internet <a href=\"https:\/\/institutoindec.org.br\/concursos\/publicacoes\/PREFEITURA+MUNICIPAL+DE+SANTO+ANT%C3%94NIO+DA+ALEGRIA\/95\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">(clique aqui)<\/a> at\u00e9 o dia 29 de fevereiro<\/mark>. A taxa de inscri\u00e7\u00e3o custa entre R$ 55 e R$ 85.<\/p>\n<p>As provas objetivas est\u00e3o previstas para o dia 24 de mar\u00e7o de 2024. O edital completo pode ser conferido<a href=\"https:\/\/institutoindec.org.br\/concursos\/publicacoes\/PREFEITURA+MUNICIPAL+DE+SANTO+ANT%C3%94NIO+DA+ALEGRIA\/95\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"> clicando aqui.<\/a><\/p>\n<p>SAIBA MAIS<br \/>Inmet emite alerta de tempestade para o estado de SP a partir desta quarta<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do <strong>acidade on <\/strong>no <a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Instagram<\/a> e no <a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do <strong>acidade on<\/strong> no WhatsApp. <a href=\"https:\/\/chat.whatsapp.com\/Bnv2w66ZT4VDyZW3oiZ69n\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<br \/>BBB 24: Rodriguinho chama Yasmin Brunet de \u201cvice-prefeita\u201d de Wanessa Camargo<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/economia\/cidades-na-regiao-de-ribeirao-tem-concursos-publicos-com-salarios-de-r-4-mil\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] As prefeituras de Guatapar\u00e1 e Santo Ant\u00f4nio da Alegria, na regi\u00e3o de Ribeir\u00e3o Preto, contam com concursos p\u00fablicos para o cadastro de reserva e vagas para contrata\u00e7\u00e3o imediata. As oportunidades s\u00e3o de n\u00edvel fundamental, m\u00e9dio, t\u00e9cnico e superior e os sal\u00e1rios variam entre R$ 1,4 mil e R$ 4,2 mil. Confira os concursos p\u00fablicos &#8230; <a title=\"Cidades na regi\u00e3o de Ribeir\u00e3o t\u00eam concursos p\u00fablicos com sal\u00e1rios de R$ 4 mil\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/31\/cidades-na-regiao-de-ribeirao-tem-concursos-publicos-com-salarios-de-r-4-mil\/\" aria-label=\"Leia mais sobre Cidades na regi\u00e3o de Ribeir\u00e3o t\u00eam concursos p\u00fablicos com sal\u00e1rios de R$ 4 mil\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":33939,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-33938","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1706710734_concurso-publico.jpg?fit=1200%2C800&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1706710734_concurso-publico.jpg?fit=1200%2C800&ssl=1",1200,800,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1706710734_concurso-publico.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1706710734_concurso-publico.jpg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1706710734_concurso-publico.jpg?fit=768%2C512&ssl=1",768,512,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1706710734_concurso-publico.jpg?fit=1024%2C683&ssl=1",1024,683,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1706710734_concurso-publico.jpg?fit=1200%2C800&ssl=1",1200,800,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1706710734_concurso-publico.jpg?fit=1200%2C800&ssl=1",1200,800,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] As prefeituras de Guatapar\u00e1 e Santo Ant\u00f4nio da Alegria, na regi\u00e3o de Ribeir\u00e3o Preto, contam com concursos p\u00fablicos para o cadastro de reserva e vagas para contrata\u00e7\u00e3o imediata. As oportunidades s\u00e3o de n\u00edvel fundamental, m\u00e9dio, t\u00e9cnico e superior e os sal\u00e1rios variam entre R$ 1,4 mil e R$ 4,2 mil. Confira os concursos p\u00fablicos&hellip;","jetpack-related-posts":[{"id":34961,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/04\/regiao-oferece-concursos-para-varias-areas\/","url_meta":{"origin":33938,"position":0},"title":"Regi\u00e3o oferece concursos para v\u00e1rias \u00e1reas\u00a0","author":"ismaelcolosi.com.br","date":"4 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] O ano de 2024 come\u00e7ou com concursos abertos em v\u00e1rias cidades da regi\u00e3o. Est\u00e3o com processos abertos as prefeituras de Ribeir\u00e3o Preto, Guatapar\u00e1, Santo Ant\u00f4nio de Alegria e Barrinha para cargos que v\u00e3o do ensino fundamental ao n\u00edvel superior. Al\u00e9m dos concursos de prefeituras, o governo federal est\u00e1 com\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/foto.png?fit=629%2C414&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/foto.png?fit=629%2C414&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/foto.png?fit=629%2C414&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":32826,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/26\/confira-sete-concursos-publicos-em-sp-com-565-vagas-e-salarios-de-r-12-mil\/","url_meta":{"origin":33938,"position":1},"title":"Confira sete concursos p\u00fablicos em SP com 565 vagas e sal\u00e1rios de R$ 12 mil","author":"ismaelcolosi.com.br","date":"26 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Al\u00e9m do \u201cEnem dos Concursos\u201d, quem se interessa por oportunidades em concursos p\u00fablicos pode se candidatar por oportunidades em prefeituras do Estado de S\u00e3o Paulo. S\u00e3o 565 vagas dispon\u00edveis em sete editais em cidades como Ribeir\u00e3o Preto, Campinas, Piracicaba e S\u00e3o Bernardo do Campo. Veja os concursos p\u00fablicos Prefeitura\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/concurso-publico-8.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/concurso-publico-8.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/concurso-publico-8.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/concurso-publico-8.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/concurso-publico-8.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":49791,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/13\/prefeitura-no-interior-de-sp-abre-concurso-publico-com-salarios-de-r-8-mil\/","url_meta":{"origin":33938,"position":2},"title":"Prefeitura no interior de SP abre concurso p\u00fablico com sal\u00e1rios de R$ 8 mil","author":"ismaelcolosi.com.br","date":"13 de Maio de 2024","format":false,"excerpt":"[ad_1] A Prefeitura de Jaboticabal, no interior de S\u00e3o Paulo, abriu as inscri\u00e7\u00f5es de concurso p\u00fablico para o cadastro de reserva em 20 cargos. As vagas s\u00e3o de n\u00edvel fundamental, m\u00e9dio, t\u00e9cnico e superior e os sal\u00e1rios variam entre R$ 1,8 mil e R$ 8,8 mil. As inscri\u00e7\u00f5es devem ser\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__concurso-publico-5.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__concurso-publico-5.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__concurso-publico-5.webp.webp?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__concurso-publico-5.webp.webp?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__concurso-publico-5.webp.webp?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":52823,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/11\/inscricoes-para-concurso-publico-em-prefeitura-do-interior-de-sp-terminam-nesta-terca-feira\/","url_meta":{"origin":33938,"position":3},"title":"Inscri\u00e7\u00f5es para concurso p\u00fablico em prefeitura do interior de SP terminam nesta ter\u00e7a-feira","author":"ismaelcolosi.com.br","date":"11 de Junho de 2024","format":false,"excerpt":"[ad_1] As inscri\u00e7\u00f5es para o concurso p\u00fablico da Prefeitura de Jaboticabal, no interior de S\u00e3o Paulo, terminam \u00e0s 23h59 desta ter\u00e7a-feira (11). Com 20 vagas para cadastro reserva, os sal\u00e1rios s\u00e3o de R$ 1,8 mil a R$ 8,8 mil. Os interessados nos cargos oferecidos que s\u00e3o de n\u00edvel fundamental, m\u00e9dio,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-6_2024-06-11_13-40-15_jpg_2024-06-11_13-40-15.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-6_2024-06-11_13-40-15_jpg_2024-06-11_13-40-15.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-6_2024-06-11_13-40-15_jpg_2024-06-11_13-40-15.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-6_2024-06-11_13-40-15_jpg_2024-06-11_13-40-15.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-6_2024-06-11_13-40-15_jpg_2024-06-11_13-40-15.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":55880,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/06\/prefeitura-no-interior-de-sp-abre-concurso-publico-com-salarios-de-ate-r-33-mil\/","url_meta":{"origin":33938,"position":4},"title":"Prefeitura no interior de SP abre concurso p\u00fablico com sal\u00e1rios de at\u00e9 R$ 3,3 mil","author":"ismaelcolosi.com.br","date":"6 de Julho de 2024","format":false,"excerpt":"[ad_1] A Prefeitura de Brodowski, no interior de S\u00e3o Paulo, publicou o edital para inscri\u00e7\u00f5es em concurso p\u00fablico para o cadastro de reserva. As vagas s\u00e3o de n\u00edvel fundamental, m\u00e9dio e superior e os sal\u00e1rios variam entre R$ 1,5 mil e R$ 3,3 mil. Para a fun\u00e7\u00e3o de m\u00e9dico o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__concurso-publico-5.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__concurso-publico-5.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__concurso-publico-5.webp.webp?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__concurso-publico-5.webp.webp?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__concurso-publico-5.webp.webp?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":37070,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/14\/prefeitura-no-interior-de-sp-tem-concurso-publico-com-53-vagas-e-salarios-de-r-3-mil\/","url_meta":{"origin":33938,"position":5},"title":"Prefeitura no interior de SP tem concurso p\u00fablico com 53 vagas e sal\u00e1rios de R$ 3 mil","author":"ismaelcolosi.com.br","date":"14 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] A Prefeitura de Terra Roxa, no interior de S\u00e3o Paulo, tem concurso p\u00fablico com 53 vagas e sal\u00e1rios de at\u00e9 R$ 3,2 mil. As oportunidades s\u00e3o de n\u00edvel fundamental, m\u00e9dio e superior. As inscri\u00e7\u00f5es devem ser realizadas at\u00e9 o dia 25 de fevereiro pela internet (clique aqui). O valor\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707915946_concurso-publico-13.jpg?fit=1200%2C801&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707915946_concurso-publico-13.jpg?fit=1200%2C801&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707915946_concurso-publico-13.jpg?fit=1200%2C801&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707915946_concurso-publico-13.jpg?fit=1200%2C801&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/1707915946_concurso-publico-13.jpg?fit=1200%2C801&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-8Po","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/33938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=33938"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/33938\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/33939"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=33938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=33938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=33938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}