{"id":33721,"date":"2024-01-30T15:43:23","date_gmt":"2024-01-30T18:43:23","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/30\/ribeirao-tem-feira-pre-carnaval-com-cerveja-artesanal-food-trucks-e-musica-veja-quando\/"},"modified":"2024-01-30T15:43:23","modified_gmt":"2024-01-30T18:43:23","slug":"ribeirao-tem-feira-pre-carnaval-com-cerveja-artesanal-food-trucks-e-musica-veja-quando","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/30\/ribeirao-tem-feira-pre-carnaval-com-cerveja-artesanal-food-trucks-e-musica-veja-quando\/","title":{"rendered":"Ribeir\u00e3o tem feira pr\u00e9-Carnaval com cerveja artesanal, food trucks e m\u00fasica; Veja quando"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p><strong>Ribeir\u00e3o Preto<\/strong> recebe, neste domingo (4), a <strong>Feira do Coletivo<\/strong> em <strong>edi\u00e7\u00e3o especial de Carnaval<\/strong>, na pra\u00e7a 7 de Setembro, no Centro da cidade. O evento \u00e9 <strong>gratuito <\/strong>e <strong>aberto ao p\u00fablico<\/strong>.<\/p>\n<p>A feira acontece das <strong>15h<\/strong> \u00e0s <strong>21h <\/strong>e conta com cervejas e chopes artesanais, foodtrucks, expositores, oficinas, feira de ado\u00e7\u00e3o e muita m\u00fasica ao som de <strong>marchinhas de Carnaval<\/strong>, <strong>samba <\/strong>e <strong>brasilidades<\/strong>.<\/p>\n<figure class=\"wp-block-pullquote\">\n<blockquote>\n<p>\u00a0\u201cA Feira do Coletivo tem o intuito de ocupar e revitalizar espa\u00e7os p\u00fablicos e gerar na popula\u00e7\u00e3o uma maior sensa\u00e7\u00e3o de pertencimento \u00e0 cidade\u201d, contou Bruna Lapenta, organizadora do evento.<\/p>\n<\/blockquote>\n<\/figure>\n<h4 class=\"wp-block-heading\"><strong>Programa\u00e7\u00e3o<\/strong><\/h4>\n<p>Na programa\u00e7\u00e3o do evento est\u00e3o aulas de yoga, viv\u00eancia sobre abelhas sem ferr\u00e3o, roda de conversa e viv\u00eancia, leitura de tar\u00f4, oficinas para todas as idades e feira de ado\u00e7\u00e3o de animais.<\/p>\n<p>Al\u00e9m disso, as crian\u00e7as ainda ter\u00e3o oficinas especiais, pula-pula, brinquedos infl\u00e1veis e pintura facial. <mark style=\"background-color:#fcb900\" class=\"has-inline-color\"><strong>Mais de 40 marcas autorais<\/strong> tamb\u00e9m fazem parte do encontro, j\u00e1 que a feira promove a <strong>economia criativa <\/strong>em <strong>Ribeir\u00e3o Preto<\/strong> e <strong>regi\u00e3o<\/strong>.<\/mark><\/p>\n<p>O evento vai receber a cantora <strong>Nanna Siqueira<\/strong>, \u00e0s <strong>15h30<\/strong>, e, na sequ\u00eancia, a banda <strong>\u201cDe Quinta! O Bloco\u201d<\/strong>, composta por <strong>Manga Moraes<\/strong> e <strong>Fernanda Marx<\/strong>. As atra\u00e7\u00f5es v\u00e3o alegrar os visitantes com marchinhas de Carnaval, samba e brasilidades.<\/p>\n<h4 class=\"wp-block-heading\"><strong>SERVI\u00c7O<\/strong><\/h4>\n<p><em>Feira do Coletivo \u2013 edi\u00e7\u00e3o de Carnaval<\/em><\/p>\n<p>Data: 04 de fevereiro \u2013 domingo<\/p>\n<p>Hor\u00e1rio: das 15h \u00e0s 21h<\/p>\n<p>Entrada: gratuita<\/p>\n<p>Local: Pra\u00e7a 7 de Setembro \u2013 Rua Sete de Setembro, 579, Centro<\/p>\n<p><a href=\"https:\/\/www.instagram.com\/cole_tivo\/\" target=\"_blank\" rel=\"noreferrer noopener\">Clique aqui <\/a>para saber mais<\/p>\n<p>SAIBA MAIS<\/p>\n<p>Veja quando come\u00e7a a venda dos ingressos para o Ribeir\u00e3o Rodeo Music<\/p>\n<h4 class=\"wp-block-heading\"><strong><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">FIQUE ON<\/mark><\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do\u00a0<strong>acidade on<\/strong>\u00a0no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do\u00a0<strong>acidade on\u00a0<\/strong>no WhatsApp.<a href=\"https:\/\/chat.whatsapp.com\/Bnv2w66ZT4VDyZW3oiZ69n\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a0Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Caf\u00e9 gelado cremoso com chocolate; confira o passo a passo<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/lazer-e-cultura\/ribeirao-tem-feira-pre-carnaval-com-cerveja-artesanal-food-trucks-e-musica-veja-quando\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Ribeir\u00e3o Preto recebe, neste domingo (4), a Feira do Coletivo em edi\u00e7\u00e3o especial de Carnaval, na pra\u00e7a 7 de Setembro, no Centro da cidade. O evento \u00e9 gratuito e aberto ao p\u00fablico. A feira acontece das 15h \u00e0s 21h e conta com cervejas e chopes artesanais, foodtrucks, expositores, oficinas, feira de ado\u00e7\u00e3o e muita &#8230; <a title=\"Ribeir\u00e3o tem feira pr\u00e9-Carnaval com cerveja artesanal, food trucks e m\u00fasica; Veja quando\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/30\/ribeirao-tem-feira-pre-carnaval-com-cerveja-artesanal-food-trucks-e-musica-veja-quando\/\" aria-label=\"Leia mais sobre Ribeir\u00e3o tem feira pr\u00e9-Carnaval com cerveja artesanal, food trucks e m\u00fasica; Veja quando\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":33722,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-33721","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Leo-Gallo_Coletivo.jpeg?fit=1143%2C761&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Leo-Gallo_Coletivo.jpeg?fit=1143%2C761&ssl=1",1143,761,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Leo-Gallo_Coletivo.jpeg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Leo-Gallo_Coletivo.jpeg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Leo-Gallo_Coletivo.jpeg?fit=768%2C511&ssl=1",768,511,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Leo-Gallo_Coletivo.jpeg?fit=1024%2C682&ssl=1",1024,682,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Leo-Gallo_Coletivo.jpeg?fit=1143%2C761&ssl=1",1143,761,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Leo-Gallo_Coletivo.jpeg?fit=1143%2C761&ssl=1",1143,761,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Ribeir\u00e3o Preto recebe, neste domingo (4), a Feira do Coletivo em edi\u00e7\u00e3o especial de Carnaval, na pra\u00e7a 7 de Setembro, no Centro da cidade. O evento \u00e9 gratuito e aberto ao p\u00fablico. A feira acontece das 15h \u00e0s 21h e conta com cervejas e chopes artesanais, foodtrucks, expositores, oficinas, feira de ado\u00e7\u00e3o e muita&hellip;","jetpack-related-posts":[{"id":46408,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/11\/ribeirao-preto-tem-feira-com-cerveja-artesanal-food-trucks-e-musica-ao-vivo-no-final-de-semana\/","url_meta":{"origin":33721,"position":0},"title":"Ribeir\u00e3o Preto tem feira com cerveja artesanal, food trucks e m\u00fasica ao vivo no final de semana","author":"ismaelcolosi.com.br","date":"11 de Abril de 2024","format":false,"excerpt":"[ad_1] Ribeir\u00e3o Preto recebe mais uma edi\u00e7\u00e3o da Feira do Coletivo, neste domingo (14), na pra\u00e7a 7 de Setembro, no Centro da cidade. O evento \u00e9 gratuito e aberto ao p\u00fablico. A feira vai acontecer das 15h \u00e0s 21h e conta com cervejas e chopes artesanais, food trucks, expositores, oficinas,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-09-at-18.23.00-e1712858091814.webp.webp?fit=1050%2C700&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-09-at-18.23.00-e1712858091814.webp.webp?fit=1050%2C700&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-09-at-18.23.00-e1712858091814.webp.webp?fit=1050%2C700&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-09-at-18.23.00-e1712858091814.webp.webp?fit=1050%2C700&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-09-at-18.23.00-e1712858091814.webp.webp?fit=1050%2C700&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":52894,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/11\/ribeirao-preto-tem-edicao-especial-de-feira-com-cerveja-artesanal-food-trucks-e-musica\/","url_meta":{"origin":33721,"position":1},"title":"Ribeir\u00e3o Preto tem edi\u00e7\u00e3o especial de feira com cerveja artesanal, food trucks e m\u00fasica","author":"ismaelcolosi.com.br","date":"11 de Junho de 2024","format":false,"excerpt":"[ad_1] Ribeir\u00e3o Preto recebe, neste domingo (16), a Feira do Coletivo em edi\u00e7\u00e3o especial de Festa Junina, na pra\u00e7a 7 de Setembro, no Centro da cidade. O evento \u00e9 gratuito e aberto ao p\u00fablico. A feira acontece das 15h \u00e0s 21h e conta com cervejas e chopes artesanais, comidas t\u00edpicas,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-09-at-18.23.00-e1712858091814.webp.webp?fit=1050%2C700&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-09-at-18.23.00-e1712858091814.webp.webp?fit=1050%2C700&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-09-at-18.23.00-e1712858091814.webp.webp?fit=1050%2C700&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-09-at-18.23.00-e1712858091814.webp.webp?fit=1050%2C700&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/AnyConv.com__WhatsApp-Image-2024-04-09-at-18.23.00-e1712858091814.webp.webp?fit=1050%2C700&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":34482,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/02\/pre-carnaval-agita-o-fim-de-semana-em-ribeirao-preto-confira-os-eventos\/","url_meta":{"origin":33721,"position":2},"title":"Pr\u00e9-carnaval agita o fim de semana em Ribeir\u00e3o Preto; Confira os eventos","author":"ismaelcolosi.com.br","date":"2 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] O fim de semana est\u00e1 repleto de eventos de pr\u00e9-carnaval em Ribeir\u00e3o Preto. S\u00e3o blocos, atividades tem\u00e1ticas, shows em bares e muito mais na programa\u00e7\u00e3o, que promete agitar a cidade antes do in\u00edcio oficial da maior festa popular do Brasil. Confira: Pr\u00e9-Carnaval Happy Hour do Ipanema Nesta sexta-feira (2),\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-1.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-1.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-1.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-1.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-1.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":14376,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/12\/ribeirao-preto-tem-feira-com-cerveja-artesanal-food-trucks-e-musica\/","url_meta":{"origin":33721,"position":3},"title":"Ribeir\u00e3o Preto tem feira com cerveja artesanal, food trucks e m\u00fasica","author":"ismaelcolosi.com.br","date":"12 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Ribeir\u00e3o Preto recebe, no dia 17 de dezembro, a Feira do Coletivo em edi\u00e7\u00e3o especial de Natal, na Pra\u00e7a 7 de Setembro, no Centro da cidade. O evento \u00e9 gratuito e aberto ao p\u00fablico. \u00a0 A feira acontece das 14h \u00e0s 21h e conta com cerveja artesanal, foodtrucks, expositores,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-11-at-11.28.049.jpeg?fit=1150%2C614&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-11-at-11.28.049.jpeg?fit=1150%2C614&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-11-at-11.28.049.jpeg?fit=1150%2C614&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-11-at-11.28.049.jpeg?fit=1150%2C614&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-11-at-11.28.049.jpeg?fit=1150%2C614&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":46721,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/13\/feira-com-musica-ao-vivo-cerveja-e-food-trucks-acontece-neste-domingo-em-ribeirao-preto\/","url_meta":{"origin":33721,"position":4},"title":"Feira com m\u00fasica ao vivo, cerveja e food trucks acontece neste domingo em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"13 de Abril de 2024","format":false,"excerpt":"[ad_1] Neste domingo (14) acontece mais uma edi\u00e7\u00e3o da Feira do Coletivo na pra\u00e7a 7 de Setembro, no\u00a0Centro\u00a0de Ribeir\u00e3o Preto. O evento \u00e9 gratuito e aberto ao p\u00fablico. O evento acontece das 15h \u00e0s 21h e conta com cervejas e chopes artesanais, food trucks, expositores, oficinas, feira de ado\u00e7\u00e3o de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-09-at-18.23.00-1.webp.webp?fit=1200%2C863&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-09-at-18.23.00-1.webp.webp?fit=1200%2C863&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-09-at-18.23.00-1.webp.webp?fit=1200%2C863&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-09-at-18.23.00-1.webp.webp?fit=1200%2C863&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-09-at-18.23.00-1.webp.webp?fit=1200%2C863&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":46537,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/12\/agenda-cultural-veja-o-que-fazer-neste-fim-de-semana-em-ribeirao-preto\/","url_meta":{"origin":33721,"position":5},"title":"Agenda cultural: Veja o que fazer neste fim de semana em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"12 de Abril de 2024","format":false,"excerpt":"[ad_1] Ribeir\u00e3o Preto conta com uma\u00a0agenda cultural\u00a0cheia de op\u00e7\u00f5es para diferentes gostos e idades neste fim de semana.\u00a0Entre as op\u00e7\u00f5es, h\u00e1 pe\u00e7as de teatro, shows, feiras e at\u00e9 encontro de carros. Confira a programa\u00e7\u00e3o: Um Amor a Cada Bloco Ribeir\u00e3o Preto\u00a0recebe a primeira edi\u00e7\u00e3o p\u00f3s-carnaval do \u2018Um Amor em Cada\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Orquestra.jpg?fit=1071%2C518&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Orquestra.jpg?fit=1071%2C518&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Orquestra.jpg?fit=1071%2C518&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Orquestra.jpg?fit=1071%2C518&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/Orquestra.jpg?fit=1071%2C518&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-8LT","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/33721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=33721"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/33721\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/33722"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=33721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=33721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=33721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}