{"id":33208,"date":"2024-01-28T15:23:52","date_gmt":"2024-01-28T18:23:52","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/28\/aviao-se-desintegra-no-ar-em-cai-no-sul-de-minas\/"},"modified":"2024-01-28T15:23:52","modified_gmt":"2024-01-28T18:23:52","slug":"aviao-se-desintegra-no-ar-em-cai-no-sul-de-minas","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/28\/aviao-se-desintegra-no-ar-em-cai-no-sul-de-minas\/","title":{"rendered":"Avi\u00e3o se desintegra no ar em cai no Sul de Minas"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"post-371838\">\n<header class=\"entry-header penci-entry-header penci-title-center\">\n<p> <span class=\"entry-meta-item penci-posted-on\"><i class=\"fa fa-clock-o\"\/><time class=\"entry-date published updated\" datetime=\"2024-01-28T15:12:44-03:00\">28 de janeiro de 2024 | 15:12<\/time><\/span><\/p>\n<p> <span class=\"penci-social-buttons penci-social-share-footer\"><a href=\"#\" class=\"penci-post-like penci_post-meta_item  single-like-button penci-social-item like\" data-post_id=\"371838\" title=\"Like\" data-like=\"Like\" data-unlike=\"Unlike\"><i class=\"fa fa-thumbs-o-up\"\/><span class=\"penci-share-number\">0<\/span><\/a><i class=\"fa fa-facebook\"\/><a class=\"penci-social-item twitter\" target=\"_blank\" rel=\"noopener\" title=\"\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Avi\u00e3o%20se%20desintegra%20no%20ar%20em%20cai%20no%20Sul%20de%20Minas%20-%20https:\/\/www.tribunaribeirao.com.br\/site\/aviao-se-desintegra-no-ar-em-cai-no-sul-de-minas\/\"><i class=\"fa fa-twitter\"\/><\/a><i class=\"fa fa-whatsapp\"\/><\/span><\/header>\n<div class=\"penci-entry-content entry-content\">\n<p>Uma aeronave caiu no Bairro Monjolinho, uma \u00e1rea rural de Itapeva, Sul de Minas, na manh\u00e3 deste domingo (28). O Corpo de Bombeiros relatou que cinco indiv\u00edduos perderam a vida e outros dois, incluindo uma crian\u00e7a, est\u00e3o desaparecidos.<\/p>\n<p>O acidente ocorreu por volta das 10h36. Antes de atingir o solo, o avi\u00e3o se desintegrou no ar. Foi informado que o piloto \u00e9 origin\u00e1rio de Belo Horizonte (MG).<\/p>\n<p>Os residentes locais relataram que houve uma forte chuva em Itapeva pela manh\u00e3.<\/p>\n<p>De acordo com a Ag\u00eancia Nacional de Avia\u00e7\u00e3o Civil (ANAC), o avi\u00e3o, de matr\u00edcula PS-MTG, foi produzido em 1996 pela Piper Aircraft. Ele \u00e9 registrado como uma aeronave de servi\u00e7o a\u00e9reo privado e n\u00e3o tem autoriza\u00e7\u00e3o para operar como t\u00e1xi a\u00e9reo. A aeronave estava em condi\u00e7\u00f5es normais de navegabilidade.<\/p>\n<p>A Pol\u00edcia Civil est\u00e1 no local realizando os procedimentos padr\u00e3o. O Centro de Investiga\u00e7\u00e3o e Preven\u00e7\u00e3o de Acidentes Aeron\u00e1uticos (CENIPA) foi notificado e deve liderar as investiga\u00e7\u00f5es. At\u00e9 agora, n\u00e3o h\u00e1 detalhes exatos sobre as circunst\u00e2ncias do acidente e as v\u00edtimas.<\/p>\n<\/div>\n<footer class=\"penci-entry-footer\"\/><\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/site\/aviao-se-desintegra-no-ar-em-cai-no-sul-de-minas\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] 28 de janeiro de 2024 | 15:12 0 Uma aeronave caiu no Bairro Monjolinho, uma \u00e1rea rural de Itapeva, Sul de Minas, na manh\u00e3 deste domingo (28). O Corpo de Bombeiros relatou que cinco indiv\u00edduos perderam a vida e outros dois, incluindo uma crian\u00e7a, est\u00e3o desaparecidos. O acidente ocorreu por volta das 10h36. Antes &#8230; <a title=\"Avi\u00e3o se desintegra no ar em cai no Sul de Minas\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/28\/aviao-se-desintegra-no-ar-em-cai-no-sul-de-minas\/\" aria-label=\"Leia mais sobre Avi\u00e3o se desintegra no ar em cai no Sul de Minas\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":33209,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[2589,634,3939,1109,420],"class_list":["post-33208","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-aviao","tag-cai","tag-desintegra","tag-minas","tag-sul"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/aviaoqueda.jpg?fit=730%2C425&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/aviaoqueda.jpg?fit=730%2C425&ssl=1",730,425,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/aviaoqueda.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/aviaoqueda.jpg?fit=300%2C175&ssl=1",300,175,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/aviaoqueda.jpg?fit=730%2C425&ssl=1",730,425,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/aviaoqueda.jpg?fit=730%2C425&ssl=1",730,425,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/aviaoqueda.jpg?fit=730%2C425&ssl=1",730,425,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/aviaoqueda.jpg?fit=730%2C425&ssl=1",730,425,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] 28 de janeiro de 2024 | 15:12 0 Uma aeronave caiu no Bairro Monjolinho, uma \u00e1rea rural de Itapeva, Sul de Minas, na manh\u00e3 deste domingo (28). O Corpo de Bombeiros relatou que cinco indiv\u00edduos perderam a vida e outros dois, incluindo uma crian\u00e7a, est\u00e3o desaparecidos. O acidente ocorreu por volta das 10h36. Antes&hellip;","jetpack-related-posts":[{"id":41181,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/06\/aviao-da-pf-cai-e-deixa-dois-mortos-em-belo-horizonte\/","url_meta":{"origin":33208,"position":0},"title":"Avi\u00e3o da PF cai e deixa dois mortos em Belo Horizonte","author":"ismaelcolosi.com.br","date":"6 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] 6 de mar\u00e7o de 2024 | 18:05 0Um avi\u00e3o monomotor caiu pr\u00f3ximo ao Aeroporto da Pampulha, em Belo Horizonte, na tarde desta quarta-feira (6). Segundo dados do Registro Aeron\u00e1utico Brasileiro, a aeronave, um Cessna 208B prefixo PR-AAB, fabricada\u00a0em 2001, pertence \u00e0 Pol\u00edcia Federal (PF).De acordo com o Corpo de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/d59f994c-dab9-476c-8703-6750f6206e5f-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/d59f994c-dab9-476c-8703-6750f6206e5f-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/d59f994c-dab9-476c-8703-6750f6206e5f-scaled.jpg?fit=1000%2C598&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/d59f994c-dab9-476c-8703-6750f6206e5f-scaled.jpg?fit=1000%2C598&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":25104,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/05\/ator-e-duas-filhas-morrem-em-acidente-de-aviao-video-mostra-momento-que-aeronave-cai-no-mar\/","url_meta":{"origin":33208,"position":1},"title":"Ator e duas filhas morrem em acidente de avi\u00e3o; v\u00eddeo mostra momento que aeronave cai no mar","author":"ismaelcolosi.com.br","date":"5 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Os f\u00e3s de um querido ator foram surpreendidos nesta sexta-feira (05\/01) com uma triste not\u00edcia a seu respeito. Christian Oliver, que tinha 51 anos, acabou perdendo a vida depois de ser v\u00edtima de um grave acidente de avi\u00e3o.No momento da trag\u00e9dia, Christian estava com as suas dias filhas, Madita,\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-6598903f3e69e9620.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-6598903f3e69e9620.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-6598903f3e69e9620.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-6598903f3e69e9620.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-6598903f3e69e9620.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":32175,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/24\/aviao-que-levava-65-prisioneiros-de-guerra-ucranianos-cai-na-russia\/","url_meta":{"origin":33208,"position":2},"title":"Avi\u00e3o que levava 65 prisioneiros de guerra ucranianos cai na R\u00fassia","author":"ismaelcolosi.com.br","date":"24 de Janeiro de 2024","format":false,"excerpt":"[ad_1] 24 de janeiro de 2024 | 10:34 0Um avi\u00e3o de transporte militar da R\u00fassia que transportava 65 prisioneiros de guerra ucranianos, seis tripulantes e tr\u00eas acompanhantes caiu na manh\u00e3 desta quarta-feira, 24, na regi\u00e3o russa de Belgorod, perto da Ucr\u00e2nia, informou o Minist\u00e9rio da Defesa russo. O acidente ocorreu\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/aviao-russo-scaled.jpg?fit=1000%2C563&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/aviao-russo-scaled.jpg?fit=1000%2C563&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/aviao-russo-scaled.jpg?fit=1000%2C563&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/aviao-russo-scaled.jpg?fit=1000%2C563&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":19875,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/23\/aviao-cai-em-praca-de-sp-e-deixa-5-vitimas-fatais-uma-delas-era-empresario-conhecido\/","url_meta":{"origin":33208,"position":3},"title":"Avi\u00e3o cai em pra\u00e7a de SP e deixa 5 v\u00edtimas fatais; uma delas era empres\u00e1rio conhecido","author":"ismaelcolosi.com.br","date":"23 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Um avi\u00e3o de pequeno porte caiu na manh\u00e3 deste s\u00e1bado (23\/12) e deixou v\u00e1rias v\u00edtimas. O monomotor despencou em cima da Pra\u00e7a das Jaboticabeiras, que fica situada no bairro Jardim Universit\u00e1rio, em Jaboticabal, no interior de S\u00e3o Paulo.Uma das v\u00edtimas da trag\u00e9dia foi o empres\u00e1rio Delcides Menezes Tiago, que\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6587176b535d75024.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6587176b535d75024.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6587176b535d75024.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6587176b535d75024.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6587176b535d75024.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":5579,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/23\/aviao-cai-em-shopping-pega-fogo-ao-bater-em-carro-e-obito-e-confirmado\/","url_meta":{"origin":33208,"position":4},"title":"avi\u00e3o cai em shopping, pega fogo ao bater em carro e \u00f3bito \u00e9 confirmado","author":"ismaelcolosi.com.br","date":"23 de Novembro de 2023","format":false,"excerpt":"[ad_1] Um avi\u00e3o assustou moradores da cidade de Plano, no estado do Texas, nos Estados Unidos, ao cair em um shopping. O tr\u00e1gico epis\u00f3dio ocorreu na \u00faltima ter\u00e7a-feira (21), e virou manchete em diversos portais de not\u00edcias americanos.A aeronave despencou dentro do estacionamento do shopping. O avi\u00e3o em quest\u00e3o pegou\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655ffa9c800d95901.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655ffa9c800d95901.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655ffa9c800d95901.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655ffa9c800d95901.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655ffa9c800d95901.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":33424,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/29\/aviao-de-cantor-sertanejo-e-pai-do-filho-de-marilia-mendonca-cai-em-vala-e-o-pior-acontece-ele-ver-mais\/","url_meta":{"origin":33208,"position":5},"title":"Avi\u00e3o de cantor sertanejo e pai do filho de MAR\u00cdLIA MENDON\u00c7A ca\u00ed em VALA e o PIOR ACONTECE: &#8220;Ele&#8230;Ver mais","author":"ismaelcolosi.com.br","date":"29 de Janeiro de 2024","format":false,"excerpt":"[ad_1] O avi\u00e3o do cantor sertanejo Murilo Huff sofreu problemas e caiu em uma vala nesta segunda (29) e o acidente deixou muitas pessoas preocupadas com o estado de sa\u00fade do cantor. O caso aconteceu no Aeroporto Santa Genoveva, localizado em Goi\u00e2nia e atrav\u00e9s do Instagram a equipe de Murillo\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Apresentacao-sem-titulo-1.png?fit=960%2C540&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Apresentacao-sem-titulo-1.png?fit=960%2C540&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Apresentacao-sem-titulo-1.png?fit=960%2C540&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Apresentacao-sem-titulo-1.png?fit=960%2C540&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-8DC","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/33208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=33208"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/33208\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/33209"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=33208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=33208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=33208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}