{"id":32669,"date":"2024-01-26T00:03:06","date_gmt":"2024-01-26T03:03:06","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/26\/acusado-por-morte-de-engenheiro-em-ribeirao-preto-diz-que-crime-foi-acidental\/"},"modified":"2024-01-26T00:03:06","modified_gmt":"2024-01-26T03:03:06","slug":"acusado-por-morte-de-engenheiro-em-ribeirao-preto-diz-que-crime-foi-acidental","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/26\/acusado-por-morte-de-engenheiro-em-ribeirao-preto-diz-que-crime-foi-acidental\/","title":{"rendered":"Acusado por morte de engenheiro em Ribeir\u00e3o Preto diz que crime foi acidental"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>O segundo acusado pelo envolvimento na morte do engenheiro <strong>Paulo Roberto Carvalho Pena Braga Filho<\/strong>, disse ao chegar na delegacia em <strong>Ribeir\u00e3o Preto<\/strong> que o crime foi acidental.<strong> <\/strong><strong>Marcelo Fernandes da Fonseca<\/strong> foi preso em <strong>Diadema<\/strong>, na<strong> Grande S\u00e3o Paulo<\/strong>, na manh\u00e3 desta quinta-feira (25).<\/p>\n<p>Ao chegar na<strong> CPJ (Central de Pol\u00edcia Judici\u00e1ria) de Ribeir\u00e3o Preto<\/strong>, o acusado <mark style=\"background-color:#fcb900\" class=\"has-inline-color has-black-color\">afirmou que n\u00e3o houve briga<\/mark> e que teria sido contratado para servi\u00e7os sexuais. \u201cSimplesmente foi uma fatalidade. Em nenhum momento tivemos inten\u00e7\u00e3o de tirar a vida de ningu\u00e9m\u201d, disse.<\/p>\n<p>O que contradiz o que o outro acusado de participa\u00e7\u00e3o no crime, <mark style=\"background-color:#fcb900\" class=\"has-inline-color has-black-color\"><strong>Gabriel Souza Brito<\/strong>, disse em entrevista na segunda-feira (22)<\/mark><mark style=\"background-color:#fcb900\" class=\"has-inline-color has-black-color\">, que teria discutido com a v\u00edtima<\/mark>. Segundo a <strong>Pol\u00edcia Civil<\/strong>, laudo aponta que Paulo Roberto Braga foi <mark style=\"background-color:#fcb900\" class=\"has-inline-color has-black-color\">morto por <strong>estrangulamento<\/strong>.<\/mark><\/p>\n<h4 class=\"wp-block-heading\"><strong>O crime<\/strong><\/h4>\n<p>O engenheiro Paulo Roberto Carvalho Pena Braga Filho foi morto no final de dezembro de 2023. Segundo a pol\u00edcia, ele teria marcado um encontro por aplicativo, quando desapareceu.<\/p>\n<p>O engenheiro, que morava nos<strong> Estados Unidos<\/strong>, passava as festas de final de ano com a fam\u00edlia. No dia do desaparecimento, Paulo Roberto tinha avisado os familiares que iria se encontrar com amigos.<\/p>\n<p>Contudo, ele n\u00e3o retornou para casa. A m\u00e3e da v\u00edtima chegou a receber mensagens de uma pessoa que estaria com o celular de Paulo Roberto, afirmando que iria devolver o aparelho.<\/p>\n<p>No entanto, essa pessoa n\u00e3o apareceu no local marcado e come\u00e7ou a pedir as senhas de acesso. No dia 30 de dezembro, a v\u00edtima foi encontrada morta em um im\u00f3vel na <strong>avenida do Caf\u00e9<\/strong>, em Ribeir\u00e3o Preto.<\/p>\n<p>SAIBA MAIS<br \/>Sebrae-SP abre processo seletivo com sal\u00e1rios de R$ 8 mil; Veja como participar<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do<strong> acidade on <\/strong>no <a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Instagram<\/a> e no<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"> Facebook.<\/a><\/p>\n<p>Receba not\u00edcias do <strong>acidade on<\/strong> no WhatsApp. <a href=\"https:\/\/chat.whatsapp.com\/Bnv2w66ZT4VDyZW3oiZ69n\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<br \/>Querid\u00f4metro do BBB 24: participantes reagem a emojis pol\u00eamicos nesta quinta-feira<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/acusado-por-morte-de-engenheiro-em-ribeirao-preto-diz-que-crime-foi-acidental\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] O segundo acusado pelo envolvimento na morte do engenheiro Paulo Roberto Carvalho Pena Braga Filho, disse ao chegar na delegacia em Ribeir\u00e3o Preto que o crime foi acidental. Marcelo Fernandes da Fonseca foi preso em Diadema, na Grande S\u00e3o Paulo, na manh\u00e3 desta quinta-feira (25). Ao chegar na CPJ (Central de Pol\u00edcia Judici\u00e1ria) de &#8230; <a title=\"Acusado por morte de engenheiro em Ribeir\u00e3o Preto diz que crime foi acidental\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/26\/acusado-por-morte-de-engenheiro-em-ribeirao-preto-diz-que-crime-foi-acidental\/\" aria-label=\"Leia mais sobre Acusado por morte de engenheiro em Ribeir\u00e3o Preto diz que crime foi acidental\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":32670,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[3884,637,88,1498,2946,654,558,134,27,26],"class_list":["post-32669","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-acidental","tag-acusado","tag-crime","tag-diz","tag-engenheiro","tag-foi","tag-morte","tag-por","tag-preto","tag-ribeirao"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/marcelo-fernandes-scaled.jpeg?fit=2560%2C1920&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/marcelo-fernandes-scaled.jpeg?fit=2560%2C1920&ssl=1",2560,1920,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/marcelo-fernandes-scaled.jpeg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/marcelo-fernandes-scaled.jpeg?fit=300%2C225&ssl=1",300,225,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/marcelo-fernandes-scaled.jpeg?fit=768%2C576&ssl=1",768,576,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/marcelo-fernandes-scaled.jpeg?fit=1024%2C768&ssl=1",1024,768,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/marcelo-fernandes-scaled.jpeg?fit=1536%2C1152&ssl=1",1536,1152,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/marcelo-fernandes-scaled.jpeg?fit=2048%2C1536&ssl=1",2048,1536,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] O segundo acusado pelo envolvimento na morte do engenheiro Paulo Roberto Carvalho Pena Braga Filho, disse ao chegar na delegacia em Ribeir\u00e3o Preto que o crime foi acidental. Marcelo Fernandes da Fonseca foi preso em Diadema, na Grande S\u00e3o Paulo, na manh\u00e3 desta quinta-feira (25). Ao chegar na CPJ (Central de Pol\u00edcia Judici\u00e1ria) de&hellip;","jetpack-related-posts":[{"id":34532,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/02\/acusados-participam-de-reconstituicao-da-morte-de-engenheiro-em-ribeirao\/","url_meta":{"origin":32669,"position":0},"title":"Acusados participam de reconstitui\u00e7\u00e3o da morte de engenheiro em Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"2 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] A Pol\u00edcia Civil realiza na manh\u00e3 desta sexta-feira (2) a reconstitui\u00e7\u00e3o da morte do engenheiro Paulo Roberto Carvalho Pena Braga Filho, morto em Ribeir\u00e3o Preto no final de 2023. Os dois acusados, presos pela morte do engenheiro, participam da reconstitui\u00e7\u00e3o, no im\u00f3vel da avenida do Caf\u00e9. \u201c\u00c9 uma esp\u00e9cie\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/reconstituicao-beto-braga-scaled.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/reconstituicao-beto-braga-scaled.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/reconstituicao-beto-braga-scaled.jpeg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/reconstituicao-beto-braga-scaled.jpeg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/reconstituicao-beto-braga-scaled.jpeg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":31540,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/22\/policia-investiga-participacao-de-terceira-pessoa-em-morte-de-engenheiro-em-ribeirao\/","url_meta":{"origin":32669,"position":1},"title":"Pol\u00edcia investiga participa\u00e7\u00e3o de terceira pessoa em morte de engenheiro em Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"22 de Janeiro de 2024","format":false,"excerpt":"[ad_1] A Pol\u00edcia Civil investiga a participa\u00e7\u00e3o de uma terceira pessoa no envolvimento da morte do engenheiro Paulo Roberto Carvalho Pena Braga Filho, que aconteceu em um im\u00f3vel na avenida do Caf\u00e9, em Ribeir\u00e3o Preto, no final de dezembro de 2023. Nesta segunda-feira (22), o delegado Targino Os\u00f3rio, respons\u00e1vel pelo\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/gabriel-souza-brito-1-scaled.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/gabriel-souza-brito-1-scaled.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/gabriel-souza-brito-1-scaled.jpeg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/gabriel-souza-brito-1-scaled.jpeg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/gabriel-souza-brito-1-scaled.jpeg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":46119,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/09\/justica-aceita-denuncia-contra-acusados-pela-morte-de-engenheiro-em-ribeirao-preto\/","url_meta":{"origin":32669,"position":2},"title":"Justi\u00e7a aceita den\u00fancia contra acusados pela morte de engenheiro em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"9 de Abril de 2024","format":false,"excerpt":"[ad_1] A Justi\u00e7a recebeu a den\u00fancia contra os acusados de terem matado o engenheiro Paulo Roberto de Carvalho Braga Filho, em Ribeir\u00e3o Preto. Isso significa que o juiz respons\u00e1vel pelo caso aceitou que eles sejam processados pelos crimes apresentados pelo MP-SP (Minist\u00e9rio P\u00fablico de S\u00e3o Paulo) e os suspeitos passam\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__beto-braga.webp.webp?fit=979%2C610&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__beto-braga.webp.webp?fit=979%2C610&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__beto-braga.webp.webp?fit=979%2C610&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__beto-braga.webp.webp?fit=979%2C610&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":33002,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/27\/policia-reconstitui-morte-de-engenheiro-da-regiao-de-ribeirao-que-comprou-carro-furtado-sem-saber\/","url_meta":{"origin":32669,"position":3},"title":"Pol\u00edcia reconstitui morte de engenheiro da regi\u00e3o de Ribeir\u00e3o que comprou carro furtado sem saber","author":"ismaelcolosi.com.br","date":"27 de Janeiro de 2024","format":false,"excerpt":"[ad_1] A Pol\u00edcia Civil realizou nesta sexta-feira (26), a reconstitui\u00e7\u00e3o da morte do engenheiro C\u00e9sar Henrique Rinhel, de 50 anos, assassinado em dezembro de 2023, em uma oficina da zona Norte de Ribeir\u00e3o Preto. A v\u00edtima, que morava em Batatais, morreu ap\u00f3s ser baleada e foi enterrada em um canavial\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/rECONSTITUICAO.png?fit=1117%2C603&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/rECONSTITUICAO.png?fit=1117%2C603&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/rECONSTITUICAO.png?fit=1117%2C603&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/rECONSTITUICAO.png?fit=1117%2C603&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/rECONSTITUICAO.png?fit=1117%2C603&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":41783,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/11\/acusados-de-matar-engenheiro-em-ribeirao-preto-vao-a-juri-popular\/","url_meta":{"origin":32669,"position":4},"title":"Acusados de matar engenheiro em Ribeir\u00e3o Preto v\u00e3o a j\u00fari popular","author":"ismaelcolosi.com.br","date":"11 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] O juiz da 3\u00aa Vara Criminal de Ribeir\u00e3o Preto Guacy Sibille Leite, acatou o pedido do Minist\u00e9rio P\u00fablico de S\u00e3o Paulo e os acusados de matar o engenheiro Paulo Roberto de Carvalho Braga Filho, morto em 29 de dezembro do ano passado, v\u00e3o a j\u00fari popular. A decis\u00e3o aconteceu\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__beto-braga.webp.webp?fit=979%2C610&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__beto-braga.webp.webp?fit=979%2C610&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__beto-braga.webp.webp?fit=979%2C610&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__beto-braga.webp.webp?fit=979%2C610&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":67145,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/21\/mp-pede-pena-maxima-para-acusados-de-assassinar-engenheiro-beto-braga-em-ribeirao-preto\/","url_meta":{"origin":32669,"position":5},"title":"MP pede pena m\u00e1xima para acusados de assassinar engenheiro Beto Braga em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"21 de Setembro de 2024","format":false,"excerpt":"[ad_1] O Minist\u00e9rio P\u00fablico de S\u00e3o Paulo (MP) solicitou nesta ter\u00e7a-feira (17) a aplica\u00e7\u00e3o da pena m\u00e1xima para os acusados de assassinar o engenheiro Beto Braga, crime que chocou Ribeir\u00e3o Preto (SP) em 2023. A promotoria apresentou a argumenta\u00e7\u00e3o final ao juiz do caso, classificando o assassinato como uma \u201cconduta\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-8uV","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/32669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=32669"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/32669\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/32670"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=32669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=32669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=32669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}