{"id":32374,"date":"2024-01-25T00:45:58","date_gmt":"2024-01-25T03:45:58","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/25\/familias-de-ribeirao-preto-enfrentam-dificuldades-para-manter-filhos-com-autismo-na-ama-entenda\/"},"modified":"2024-01-25T00:45:58","modified_gmt":"2024-01-25T03:45:58","slug":"familias-de-ribeirao-preto-enfrentam-dificuldades-para-manter-filhos-com-autismo-na-ama-entenda","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/25\/familias-de-ribeirao-preto-enfrentam-dificuldades-para-manter-filhos-com-autismo-na-ama-entenda\/","title":{"rendered":"Fam\u00edlias de Ribeir\u00e3o Preto enfrentam dificuldades para manter filhos com autismo na AMA; Entenda"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>Fam\u00edlias de <strong>Ribeir\u00e3o Preto<\/strong>, que possuem filhos com <strong>espectro autista<\/strong>, est\u00e3o com dificuldades para continuar o tratamento na cidade, <strong>devido \u00e0 falta do transporte gratuito, que foi suspenso desde o final de 2023.<\/strong><\/p>\n<p>A dona de casa Leila da Silva Melo e sua filha Jennifer s\u00e3o exemplos de pessoas que foram afetadas devido \u00e0 suspens\u00e3o. A garota realizava <strong>v\u00e1rias atividades que contribuem para o desenvolvimento na AMA (Associa\u00e7\u00e3o de Amigos do Autista).<\/strong><\/p>\n<p>Sem a van que efetuava o transporte de m\u00e3e e filha, <mark style=\"background-color:#fcb900\" class=\"has-inline-color\">elas precisam pegar dois \u00f4nibus para ir e dois \u00f4nibus para voltar da associa\u00e7\u00e3o<\/mark>, no entanto, al\u00e9m de ser do espectro autista, Jennifer tamb\u00e9m uma s\u00edndrome que vai <strong>atrofiando os m\u00fasculos do corpo, o que dificulta a sua locomo\u00e7\u00e3o.<\/strong><\/p>\n<figure class=\"wp-block-pullquote\">\n<blockquote>\n<p>\u201cO que nos resta agora \u00e9 \u00f4nibus e a dificuldade que a gente vai enfrentar que \u00e9 muito grande, porque s\u00e3o dois \u00f4nibus pra ir e dois pra voltar. Ela tem que levantar bem cedinho pra enfrentar dois \u00f4nibus e voltar. Judia muito dela\u201d, disse Leila, em entrevista a EPTV.<\/p>\n<\/blockquote>\n<\/figure>\n<h4 class=\"wp-block-heading\"><strong>Suspens\u00e3o do servi\u00e7o<\/strong><\/h4>\n<p>A associa\u00e7\u00e3o atende<strong> 126 fam\u00edlias<\/strong> e <strong>45 est\u00e3o com dificuldades em ir at\u00e9 o local<\/strong>, devido \u00e0 falta de transporte. De acordo com essas pessoas, a suspens\u00e3o do servi\u00e7o foi comunicada pela <strong>AMA <\/strong>no final de 2023, isso depois de anos com as vans fazendo o transporte desses alunos.<\/p>\n<p><strong>A associa\u00e7\u00e3o alega que faltam recursos para manter esse servi\u00e7o, e que o gasto estimado seria de R$ 25 mil a R$ 45 mil por m\u00eas.<\/strong><\/p>\n<p>Em dezembro, a <strong>AMA <\/strong>chegou a publicar um edital para credenciar duas vans para fazer o transporte. O servi\u00e7o seria para at\u00e9 40 passageiros semanais, em dois turnos, de segunda a sexta-feira, e cada contrato seria no valor de R$ 6,5 mil, no entanto, <strong>nenhuma empresa se interessou.<\/strong><\/p>\n<h4 class=\"wp-block-heading\"><strong>O que dizem os envolvidos?<\/strong><\/h4>\n<p>Em nota enviada a <em>EPTV<\/em>, a <strong>Secretaria Municipal de Educa\u00e7\u00e3o<\/strong> informou que repassa, por ano, mais de R$ 740 mil para a AMA e que o transporte \u00e9 de responsabilidade da associa\u00e7\u00e3o.<\/p>\n<p>A pasta tamb\u00e9m disse que a institui\u00e7\u00e3o entregou o plano de trabalho de 2024 e que nele constava o transporte para alunos, portanto, entrar\u00e1 em contato com a AMA.<\/p>\n<p>J\u00e1 a associa\u00e7\u00e3o informou que fez reuni\u00f5es com os pais dos alunos para explicar a situa\u00e7\u00e3o e que esta a disposi\u00e7\u00e3o para conversar novamente com a prefeitura de Ribeir\u00e3o Preto.<\/p>\n<p><em>*Com informa\u00e7\u00f5es da EPTV<\/em><\/p>\n<p>SAIBA MAIS<\/p>\n<p>Monobloco agita pr\u00e9-carnaval em Ribeir\u00e3o neste final de semana; Ingressos ainda est\u00e3o dispon\u00edveis<\/p>\n<p><strong><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">FIQUE ON<\/mark><\/strong><\/p>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do<strong>\u00a0acidade on<\/strong>\u00a0no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram\u00a0<\/a>e no<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a0Facebook.<\/a><\/p>\n<p>Receba not\u00edcias do\u00a0<strong>acidade on<\/strong>\u00a0no WhatsApp.<a href=\"https:\/\/chat.whatsapp.com\/Bnv2w66ZT4VDyZW3oiZ69n\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a0Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Bot\u00e3o da desist\u00eancia toca outra vez no BBB 24; entenda<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/familias-de-ribeirao-preto-enfrentam-dificuldades-para-manter-filhos-com-autismo-na-ama-entenda\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Fam\u00edlias de Ribeir\u00e3o Preto, que possuem filhos com espectro autista, est\u00e3o com dificuldades para continuar o tratamento na cidade, devido \u00e0 falta do transporte gratuito, que foi suspenso desde o final de 2023. A dona de casa Leila da Silva Melo e sua filha Jennifer s\u00e3o exemplos de pessoas que foram afetadas devido \u00e0&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":32375,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[3859,3858,3518,3546,33,1454,1899,3857,71,27,26],"class_list":["post-32374","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-ama","tag-autismo","tag-dificuldades","tag-enfrentam","tag-entenda","tag-familias","tag-filhos","tag-manter","tag-para","tag-preto","tag-ribeirao"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-19.png?fit=1200%2C675&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-19.png?fit=1200%2C675&ssl=1",1200,675,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-19.png?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-19.png?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-19.png?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-19.png?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-19.png?fit=1200%2C675&ssl=1",1200,675,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-19.png?fit=1200%2C675&ssl=1",1200,675,true],"neve-blog":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-19.png?resize=930%2C620&ssl=1",930,620,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Fam\u00edlias de Ribeir\u00e3o Preto, que possuem filhos com espectro autista, est\u00e3o com dificuldades para continuar o tratamento na cidade, devido \u00e0 falta do transporte gratuito, que foi suspenso desde o final de 2023. A dona de casa Leila da Silva Melo e sua filha Jennifer s\u00e3o exemplos de pessoas que foram afetadas devido \u00e0&hellip;&nbsp;","jetpack-related-posts":[{"id":16992,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/17\/desafios-na-cobertura-de-tratamento-para-autistas-e-as-negativas-de-plano-de-saude\/","url_meta":{"origin":32374,"position":0},"title":"Desafios na cobertura de tratamento para autistas e as negativas de plano de sa\u00fade\u00a0","author":"ismaelcolosi.com.br","date":"17 de Dezembro de 2023","format":false,"excerpt":"[ad_1] 17 de dezembro de 2023 | 8:2016 de dezembro de 2023 | 13:43 0Jos\u00e9 dos Santos Santana J\u00fanior*\u00a0\u00c9 crescente a preocupa\u00e7\u00e3o em rela\u00e7\u00e3o as negativas de tratamento para indiv\u00edduos autistas por parte dos planos de sa\u00fade. Essa problem\u00e1tica levanta quest\u00f5es essenciais sobre a equidade no acesso aos cuidados de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Jose-dos-Santos-Santana-Junior-scaled.jpg?fit=444%2C645&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":26568,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/10\/dentista-tira-a-vida-do-proprio-filho-diagnosticado-com-autismo-e-depois-atenta-contra-si-mesma\/","url_meta":{"origin":32374,"position":1},"title":"dentista tira a vida do pr\u00f3prio filho, diagnosticado com autismo, e depois atenta contra si mesma","author":"ismaelcolosi.com.br","date":"10 de Janeiro de 2024","format":false,"excerpt":"[ad_1] A regi\u00e3o de \u00c1guas Claras, no Distrito Federal, est\u00e1 abalada por uma trag\u00e9dia chocante que ocorreu na noite de ter\u00e7a-feira, dia 9 de janeiro, ap\u00f3s uma idosa de 63 anos de idade ter tirado a pr\u00f3pria vida e a de seu filho, de 27 anos, que tinha o diagn\u00f3stico\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659ea019337b91460.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659ea019337b91460.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659ea019337b91460.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659ea019337b91460.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659ea019337b91460.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":41258,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/07\/mae-e-presa-acusada-de-agressoes-contra-filha-de-apenas-3-anos-em-ribeirao-preto\/","url_meta":{"origin":32374,"position":2},"title":"M\u00e3e \u00e9 presa acusada de agress\u00f5es contra filha de apenas 3 anos em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"7 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] Uma m\u00e3e de duas crian\u00e7as foi presa em flagrante em Ribeir\u00e3o Preto acusada de agredir a filha de apenas 3 anos \u2013 a menina foi diagnosticada como portadora do transtorno do espectro autista. A pris\u00e3o aconteceu na tarde da \u00faltima quarta-feira (6), ap\u00f3s a Pol\u00edcia Militar ter sido acionada\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/HomemmorreapscairdeandaimeenquantotrabalhavaemRibeiroPreto_Tamanho_2_image.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/HomemmorreapscairdeandaimeenquantotrabalhavaemRibeiroPreto_Tamanho_2_image.jpg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/HomemmorreapscairdeandaimeenquantotrabalhavaemRibeiroPreto_Tamanho_2_image.jpg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/HomemmorreapscairdeandaimeenquantotrabalhavaemRibeiroPreto_Tamanho_2_image.jpg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/HomemmorreapscairdeandaimeenquantotrabalhavaemRibeiroPreto_Tamanho_2_image.jpg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":41532,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/08\/o-que-se-sabe-sobre-mae-acusada-de-agredir-filha-de-3-anos-em-ribeirao-preto\/","url_meta":{"origin":32374,"position":3},"title":"O que se sabe sobre m\u00e3e acusada de agredir filha de 3 anos em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"8 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] A mulher que foi presa ap\u00f3s agredir uma das filhas de apenas tr\u00eas anos de idade recebeu liberdade provis\u00f3ria na quinta-feira (7), ap\u00f3s passar por audi\u00eancia de cust\u00f3dia realizada pelo Tribunal de Justi\u00e7a de S\u00e3o Paulo. Mesmo em liberdade, a m\u00e3e de duas crian\u00e7as ter\u00e1 que cumprir algumas medidas\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2023-12-09-at-13.55.44.jpeg?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2023-12-09-at-13.55.44.jpeg?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2023-12-09-at-13.55.44.jpeg?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2023-12-09-at-13.55.44.jpeg?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":45017,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/01\/dia-mundial-de-conscientizacao-sobre-o-transtorno-do-espectro-autista-tea-e-celebrado-nesta-terca\/","url_meta":{"origin":32374,"position":4},"title":"\u201cDia Mundial de Conscientiza\u00e7\u00e3o sobre o Transtorno do Espectro Autista &#8211; TEA\u201d \u00e9 celebrado nesta ter\u00e7a","author":"ismaelcolosi.com.br","date":"1 de Abril de 2024","format":false,"excerpt":"[ad_1] A Secretaria Municipal da Sa\u00fade celebra nesta ter\u00e7a-feira, 2 de abril, o \u201cDia Mundial de Conscientiza\u00e7\u00e3o do Transtorno do Espectro Autista \u2013 TEA\u201d, com o objetivo de promover o conhecimento sobre o transtorno, bem como sobre as necessidades e os direitos das pessoas com TEA. O TEA \u00e9 uma\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/tea_3.jpg?fit=722%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/tea_3.jpg?fit=722%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/tea_3.jpg?fit=722%2C500&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/tea_3.jpg?fit=722%2C500&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":17123,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/17\/mp-garante-reducao-de-jornada-para-funcionaria-publica-cuidar-de-filho-autista-na-regiao-de-ribeirao\/","url_meta":{"origin":32374,"position":5},"title":"MP garante redu\u00e7\u00e3o de jornada para funcion\u00e1ria p\u00fablica cuidar de filho autista na regi\u00e3o de Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"17 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Uma funcion\u00e1ria p\u00fablica de Batatais, cidade a cerca de 43 quil\u00f4metros de Ribeir\u00e3o Preto, conseguiu por decis\u00e3o do Minist\u00e9rio P\u00fablico do Trabalho (MPT) de Campinas, o direito de reduzir em 50% sua jornada de trabalho, para cuidar do filho com Transtorno do Espectro Autista (TEA). A decis\u00e3o, concedida em\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/news_3055_570_370_202310111615513990480.png?fit=570%2C370&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/news_3055_570_370_202310111615513990480.png?fit=570%2C370&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/news_3055_570_370_202310111615513990480.png?fit=570%2C370&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-8qa","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/32374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=32374"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/32374\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/32375"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=32374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=32374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=32374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}