{"id":32175,"date":"2024-01-24T10:50:03","date_gmt":"2024-01-24T13:50:03","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/24\/aviao-que-levava-65-prisioneiros-de-guerra-ucranianos-cai-na-russia\/"},"modified":"2024-01-24T10:50:03","modified_gmt":"2024-01-24T13:50:03","slug":"aviao-que-levava-65-prisioneiros-de-guerra-ucranianos-cai-na-russia","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/24\/aviao-que-levava-65-prisioneiros-de-guerra-ucranianos-cai-na-russia\/","title":{"rendered":"Avi\u00e3o que levava 65 prisioneiros de guerra ucranianos cai na R\u00fassia"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"post-371390\">\n<header class=\"entry-header penci-entry-header penci-title-center\">\n<p> <span class=\"entry-meta-item penci-posted-on\"><i class=\"fa fa-clock-o\"\/><time class=\"entry-date published updated\" datetime=\"2024-01-24T10:34:36-03:00\">24 de janeiro de 2024 | 10:34<\/time><\/span><\/p>\n<p> <span class=\"penci-social-buttons penci-social-share-footer\"><a href=\"#\" class=\"penci-post-like penci_post-meta_item  single-like-button penci-social-item like\" data-post_id=\"371390\" title=\"Like\" data-like=\"Like\" data-unlike=\"Unlike\"><i class=\"fa fa-thumbs-o-up\"\/><span class=\"penci-share-number\">0<\/span><\/a><i class=\"fa fa-facebook\"\/><a class=\"penci-social-item twitter\" target=\"_blank\" rel=\"noopener\" title=\"\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Avi\u00e3o%20que%20levava%2065%20prisioneiros%20de%20guerra%20ucranianos%20cai%20na%20R\u00fassia%20-%20https:\/\/www.tribunaribeirao.com.br\/site\/aviao-que-levava-65-prisioneiros-de-guerra-ucranianos-cai-na-russia\/\"><i class=\"fa fa-twitter\"\/><\/a><i class=\"fa fa-whatsapp\"\/><\/span><\/header>\n<div class=\"penci-entry-content entry-content\">\n<div id=\"Corpo\">Um avi\u00e3o de transporte militar da R\u00fassia que transportava 65 prisioneiros de guerra ucranianos, seis tripulantes e tr\u00eas acompanhantes caiu na manh\u00e3 desta quarta-feira, 24, na regi\u00e3o russa de Belgorod, perto da Ucr\u00e2nia, informou o Minist\u00e9rio da Defesa russo. O acidente ocorreu por volta de 11h, hor\u00e1rio local, e sua causa ainda n\u00e3o foi divulgada. As autoridades n\u00e3o divulgaram se h\u00e1 sobreviventes.<\/p>\n<p>As autoridades locais est\u00e3o investigando a causa do acidente e uma comiss\u00e3o militar especial estava a caminho do local da queda do avi\u00e3o, informou o Minist\u00e9rio da Defesa.<\/p>\n<p><b>Drones<\/b><\/p>\n<p>O Presidente da C\u00e2mara de Oryol, na R\u00fassia, Yuri Parakhin, afirmou que v\u00e1rios drones foram abatidos sobre a cidade, sem registro de v\u00edtimas. Outro drone ucraniano foi abatido na manh\u00e3 de quarta-feira sobre a regi\u00e3o fronteiri\u00e7a de Belgorod, informou o governador regional Vyacheslav Gladkov, tamb\u00e9m sem v\u00edtimas.<\/p>\n<p>Os aliados da Ucr\u00e2nia comprometeram-se a continuar enviando pacotes de ajuda militares. O Minist\u00e9rio da Defesa alem\u00e3o anunciou nesta quarta que planeja enviar seis helic\u00f3pteros SEA KING Mk41 da Bundeswehr para a Ucr\u00e2nia.<\/p>\n<p>Desde o in\u00edcio da guerra, a Alemanha enviou cerca de 6 bilh\u00f5es de euros (US$ 6,52 bilh\u00f5es) em equipamento militar, incluindo grandes sistemas antia\u00e9reos, de acordo com o governo. Associated Press.<\/p>\n<\/div>\n<\/div>\n<footer class=\"penci-entry-footer\"\/><\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/site\/aviao-que-levava-65-prisioneiros-de-guerra-ucranianos-cai-na-russia\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] 24 de janeiro de 2024 | 10:34 0 Um avi\u00e3o de transporte militar da R\u00fassia que transportava 65 prisioneiros de guerra ucranianos, seis tripulantes e tr\u00eas acompanhantes caiu na manh\u00e3 desta quarta-feira, 24, na regi\u00e3o russa de Belgorod, perto da Ucr\u00e2nia, informou o Minist\u00e9rio da Defesa russo. O acidente ocorreu por volta de 11h, &#8230; <a title=\"Avi\u00e3o que levava 65 prisioneiros de guerra ucranianos cai na R\u00fassia\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/24\/aviao-que-levava-65-prisioneiros-de-guerra-ucranianos-cai-na-russia\/\" aria-label=\"Leia mais sobre Avi\u00e3o que levava 65 prisioneiros de guerra ucranianos cai na R\u00fassia\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":32176,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[2589,634,1200,3840,3841,3843,3842],"class_list":["post-32175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-aviao","tag-cai","tag-guerra","tag-levava","tag-prisioneiros","tag-russia","tag-ucranianos"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/aviao-russo-scaled.jpg?fit=1000%2C563&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/aviao-russo-scaled.jpg?fit=1000%2C563&ssl=1",1000,563,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/aviao-russo-scaled.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/aviao-russo-scaled.jpg?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/aviao-russo-scaled.jpg?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/aviao-russo-scaled.jpg?fit=1000%2C563&ssl=1",1000,563,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/aviao-russo-scaled.jpg?fit=1000%2C563&ssl=1",1000,563,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/aviao-russo-scaled.jpg?fit=1000%2C563&ssl=1",1000,563,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] 24 de janeiro de 2024 | 10:34 0 Um avi\u00e3o de transporte militar da R\u00fassia que transportava 65 prisioneiros de guerra ucranianos, seis tripulantes e tr\u00eas acompanhantes caiu na manh\u00e3 desta quarta-feira, 24, na regi\u00e3o russa de Belgorod, perto da Ucr\u00e2nia, informou o Minist\u00e9rio da Defesa russo. O acidente ocorreu por volta de 11h,&hellip;","jetpack-related-posts":[{"id":7542,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/28\/tregua-entre-israel-e-hamas-chega-ao-quinto-dia-e-mais-refens-devem-ser-libertados-nesta-terca\/","url_meta":{"origin":32175,"position":0},"title":"Tr\u00e9gua entre Israel e Hamas chega ao quinto dia e mais ref\u00e9ns devem ser libertados nesta ter\u00e7a","author":"ismaelcolosi.com.br","date":"28 de Novembro de 2023","format":false,"excerpt":"[ad_1] Entrou em vigor nesta ter\u00e7a-feira, 28, a extens\u00e3o da tr\u00e9gua entre Israel e o grupo terrorista Hamas, depois que ambos os lados concordaram em prolongar o seu cessar-fogo por mais dois dias na segunda-feira, 27. Com a medida, mais ref\u00e9ns israelenses devem ser libertados em troca de palestinos que\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/familiagaza.jpg?fit=848%2C477&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/familiagaza.jpg?fit=848%2C477&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/familiagaza.jpg?fit=848%2C477&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/familiagaza.jpg?fit=848%2C477&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":44665,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/29\/european-crossroads-encruzilhada-europeia\/","url_meta":{"origin":32175,"position":1},"title":"European Crossroads (Encruzilhada europeia)\u00a0 &#8211; Jornal Tribuna Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"29 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] 29 de mar\u00e7o de 2024 | 8:2028 de mar\u00e7o de 2024 | 18:13 0 Luiz Paulo Tupynamb\u00e1 *\u00a0blog: www.tupyweb.com\u00a0\u00a0Parlamento Europeu: 704 cadeiras. Elei\u00e7\u00f5es (todas as cadeiras em disputa) de 6 a 9 de junho.\u00a0\u00a0Hoje, a Uni\u00e3o Europeia tem 27 pa\u00edses-membros, com diferen\u00e7as lingu\u00edsticas, culturais, hist\u00f3ricas e econ\u00f4micas significativas. Essas\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1711720560_luizpaulotupynamba-1-scaled.jpg?fit=1000%2C625&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1711720560_luizpaulotupynamba-1-scaled.jpg?fit=1000%2C625&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1711720560_luizpaulotupynamba-1-scaled.jpg?fit=1000%2C625&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1711720560_luizpaulotupynamba-1-scaled.jpg?fit=1000%2C625&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":26515,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/10\/ex-ceo-do-google-tem-projeto-secreto-de-drones-militares\/","url_meta":{"origin":32175,"position":2},"title":"Ex-CEO do Google tem projeto secreto de drones militares","author":"ismaelcolosi.com.br","date":"10 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Foto: Getty Images \/ Ilustra\u00e7\u00e3o: ForbesBilion\u00e1rio, Eric Schmidt deixou a lideran\u00e7a do Google em 2017 O ex-CEO do Google Eric Schmidt vem planejando discretamente um novo empreendimento de tecnologia de defesa: um projeto de drones militares, segundo fontes com conhecimento do assunto disseram \u00e0 Forbes. O projeto ainda n\u00e3o\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/carreira-Eric-Schmidt-ex-ceo-google-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/carreira-Eric-Schmidt-ex-ceo-google-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/carreira-Eric-Schmidt-ex-ceo-google-1024x683.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/carreira-Eric-Schmidt-ex-ceo-google-1024x683.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":43572,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/22\/direita-volver-parte-2\/","url_meta":{"origin":32175,"position":3},"title":"Direita, volver &#8211; parte 2\u00a0","author":"ismaelcolosi.com.br","date":"22 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] 22 de mar\u00e7o de 2024 | 8:1322 de mar\u00e7o de 2024 | 8:12 0 Luiz Paulo Tupynamb\u00e1 *\u00a0www.tupyweb.com\u00a0\u00a0\u201cA esperan\u00e7a dan\u00e7a \/ Na corda bamba de sombrinha\/ E em cada passo dessa linha\/Pode se machucar\u2026\u201d Trecho da can\u00e7\u00e3o \u201cO b\u00eabado e a equilibrista\u201d \u2013 de Aldir Blanc e Jo\u00e3o Bosco\u00a0\u00a0Semana\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/luizpaulotupynamba-1-scaled.jpg?fit=1000%2C625&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/luizpaulotupynamba-1-scaled.jpg?fit=1000%2C625&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/luizpaulotupynamba-1-scaled.jpg?fit=1000%2C625&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/luizpaulotupynamba-1-scaled.jpg?fit=1000%2C625&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":48686,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/05\/harry-potter-e-o-prisioneiro-de-azkaban-retorna-as-telonas-com-exibicoes-exclusivas-no-dia-4-de-junho\/","url_meta":{"origin":32175,"position":4},"title":"Harry Potter e o Prisioneiro de Azkaban retorna \u00e0s telonas com exibi\u00e7\u00f5es exclusivas no dia 4 de junho","author":"ismaelcolosi.com.br","date":"5 de Maio de 2024","format":false,"excerpt":"[ad_1] Harry Potter e o Prisioneiro de Azkaban retorna \u00e0s telonas com exibi\u00e7\u00f5es exclusivas no dia 4 de junhoAl\u00e9m de assistir ao filme, que este ano completa 20 anos desde sua estreia nas telonas, os Potterheads poder\u00e3o conferir a nova exposi\u00e7\u00e3o tem\u00e1tica que celebra a saga e chega ao Brasil\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/39388397_605.jpg?fit=1199%2C674&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/39388397_605.jpg?fit=1199%2C674&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/39388397_605.jpg?fit=1199%2C674&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/39388397_605.jpg?fit=1199%2C674&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/39388397_605.jpg?fit=1199%2C674&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":52964,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/12\/harry-potter-e-o-prisioneiro-de-azkaban-tem-novas-sessoes-veja-como-comprar-ingressos\/","url_meta":{"origin":32175,"position":5},"title":"\u2018Harry Potter e o Prisioneiro de Azkaban\u2019 tem novas sess\u00f5es; Veja como comprar ingressos","author":"ismaelcolosi.com.br","date":"12 de Junho de 2024","format":false,"excerpt":"[ad_1] Terceiro filme da franquia, \u201cHarry Potter e o Prisioneiro de Azkaban\u201d t\u00eam novas sess\u00f5es nos cinemas brasileiros. A reexibi\u00e7\u00e3o do filme acontece no dia 29 de junho, \u00faltimo s\u00e1bado do m\u00eas, e a pr\u00e9-venda ser\u00e1 iniciada no pr\u00f3ximo dia 21 de junho. O anuncio das novas sess\u00f5es foi feito\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-10_2024-06-12_15-21-26_jpg_2024-06-12_15-21-26.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-10_2024-06-12_15-21-26_jpg_2024-06-12_15-21-26.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-10_2024-06-12_15-21-26_jpg_2024-06-12_15-21-26.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-10_2024-06-12_15-21-26_jpg_2024-06-12_15-21-26.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-10_2024-06-12_15-21-26_jpg_2024-06-12_15-21-26.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-8mX","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/32175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=32175"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/32175\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/32176"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=32175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=32175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=32175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}