{"id":31535,"date":"2024-01-22T16:14:18","date_gmt":"2024-01-22T19:14:18","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/22\/os-10-discos-preferidos-de-steve-harris-baixista-do-iron-maiden\/"},"modified":"2024-01-22T16:14:18","modified_gmt":"2024-01-22T19:14:18","slug":"os-10-discos-preferidos-de-steve-harris-baixista-do-iron-maiden","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/22\/os-10-discos-preferidos-de-steve-harris-baixista-do-iron-maiden\/","title":{"rendered":"Os 10 discos preferidos de Steve Harris, baixista do Iron Maiden"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<div class=\"td-post-featured-image\">\n<figure><picture class=\"entry-thumb td-modal-image\" title=\"Steve Harris do Iron Maiden no Rock In Rio 2019\"><source type=\"image\/webp\" srcset=\"https:\/\/www.tenhomaisdiscosqueamigos.com\/wp-content\/uploads\/2019\/10\/iron-maiden-foto-rock-rio-2019-696x464.jpg.webp 696w, https:\/\/www.tenhomaisdiscosqueamigos.com\/wp-content\/uploads\/2019\/10\/iron-maiden-foto-rock-rio-2019-300x200.jpg.webp 300w, https:\/\/www.tenhomaisdiscosqueamigos.com\/wp-content\/uploads\/2019\/10\/iron-maiden-foto-rock-rio-2019-768x512.jpg.webp 768w, https:\/\/www.tenhomaisdiscosqueamigos.com\/wp-content\/uploads\/2019\/10\/iron-maiden-foto-rock-rio-2019.jpg.webp 1000w\" sizes=\"(max-width: 696px) 100vw, 696px\"\/><img data-recalc-dims=\"1\" decoding=\"async\" width=\"696\" height=\"464\" src=\"https:\/\/i0.wp.com\/www.tenhomaisdiscosqueamigos.com\/wp-content\/uploads\/2019\/10\/iron-maiden-foto-rock-rio-2019-696x464.jpg?resize=696%2C464&#038;ssl=1\" srcset=\"https:\/\/www.tenhomaisdiscosqueamigos.com\/wp-content\/uploads\/2019\/10\/iron-maiden-foto-rock-rio-2019-696x464.jpg 696w, https:\/\/www.tenhomaisdiscosqueamigos.com\/wp-content\/uploads\/2019\/10\/iron-maiden-foto-rock-rio-2019-300x200.jpg 300w, https:\/\/www.tenhomaisdiscosqueamigos.com\/wp-content\/uploads\/2019\/10\/iron-maiden-foto-rock-rio-2019-768x512.jpg 768w, https:\/\/www.tenhomaisdiscosqueamigos.com\/wp-content\/uploads\/2019\/10\/iron-maiden-foto-rock-rio-2019.jpg 1000w\" sizes=\"(max-width: 696px) 100vw, 696px\" alt=\"Steve Harris do Iron Maiden no Rock In Rio 2019\"\/>\n<\/picture><figcaption class=\"wp-caption-text\">Foto por Diego Padilha<\/figcaption><\/figure>\n<\/div>\n<p>            <!-- echo $td_mod_single->get_content(); --><\/p>\n<p><strong>Steve Harris<\/strong> \u00e9 considerado uma lenda por seu trabalho impec\u00e1vel em destacar o baixo no Metal atrav\u00e9s das m\u00fasicas do\u00a0<strong>Iron Maiden<\/strong>, banda que fundou no Natal de 1975.<\/p>\n<p>O ic\u00f4nico baixista fez a estreia do grupo, que recebeu seu nome inspirado no romance <strong><em>O Homem da M\u00e1scara de Ferro<\/em><\/strong>, de Alexandre Dumas, em 1\u00ba de Maio de 1976. Desde o in\u00edcio da banda, a trajet\u00f3ria foi marcada por muitas refer\u00eancias de trabalhos de Hard Rock e Heavy Metal, al\u00e9m de um pouco de Punk, que est\u00e3o sempre ligadas a Harris.<\/p>\n<p>Ao longo de sua jornada de quase 48 anos, e com a contribui\u00e7\u00e3o de membros como o vocalista <strong>Bruce Dickinson<\/strong>, o Iron Maiden ficou conhecido no mundo inteiro por conta de seus temas sombrios, que tamb\u00e9m contam muito com a contribui\u00e7\u00e3o de Steve Harris como compositor \u2014 ou seja, n\u00e3o \u00e9 de se estranhar que a banda deixe transparecer v\u00e1rias de suas influ\u00eancias.<\/p>\n<p>Em 1985, depois do grupo j\u00e1 ter lan\u00e7ado discos como <strong><em>The Number of the Beast<\/em><\/strong> (1982), <strong><em>Piece of Mind<\/em><\/strong> (1983) e <strong><em>Powerslave<\/em> <\/strong>(1984), a revista Metal (via <em><a href=\"https:\/\/www.ironmaiden666.com.br\/2013\/08\/os-dez-discos-favoritos-de-steve-harris.html\" target=\"_blank\" rel=\"noopener\">Iron Maiden 666<\/a><\/em>), publica\u00e7\u00e3o brasileira popular na d\u00e9cada de 80, compartilhou em uma de suas edi\u00e7\u00f5es uma curiosidade que ajuda a entender toda essa sonoridade: as prefer\u00eancias musicais do baixista Steve Harris.<\/p>\n<p>Confira a seguir quais discos foram citados pelo baixista do Iron Maiden como os seus preferidos naquela \u00e9poca!<\/p>\n<h3>Os 10 discos preferidos de Steve Harris, do Iron Maiden<\/h3>\n<h4>Genesis \u2013 <em>Foxtrot<\/em> (1972)<\/h4>\n<p><iframe title=\"Genesis - Supper&amp;apos;s Ready [Full Song]\" width=\"1200\" height=\"900\" src=\"https:\/\/www.youtube.com\/embed\/szJq1lwnkNw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<h4>Todd Rundgren \u2013 <em>A Wizard \/ A True Star<\/em> (1973)<\/h4>\n<p><iframe title=\"Todd Rundgren - International Feel [Single Version]\" width=\"1200\" height=\"900\" src=\"https:\/\/www.youtube.com\/embed\/-1A5WBf1EFQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<h4>Nektar \u2013 <em>Recycled<\/em> (1975)<\/h4>\n<p><iframe title=\"Recycle\" width=\"1200\" height=\"900\" src=\"https:\/\/www.youtube.com\/embed\/gV9pxgkBIHI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<h4>UFO \u2013 <em>Strangers in the Night<\/em> (1979)<\/h4>\n<p><iframe title=\"Only You Can Rock Me (2008 Remaster)\" width=\"1200\" height=\"900\" src=\"https:\/\/www.youtube.com\/embed\/1HH_aWDGu58?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<h4>Judas Priest \u2013 <em>Sad Wings of Destiny<\/em> (1976)<\/h4>\n<p><iframe title=\"Victim of Changes\" width=\"1200\" height=\"900\" src=\"https:\/\/www.youtube.com\/embed\/ME2PT1bxUJA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<h4>Van Halen \u2013 <em>Van Halen II<\/em> ( 1979)<\/h4>\n<p><iframe title=\"Dance the Night Away (2015 Remaster)\" width=\"1200\" height=\"900\" src=\"https:\/\/www.youtube.com\/embed\/E-rTKd-Alk8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<h4>Scorpions \u2013 <em>Lovedrive<\/em> (1979)<\/h4>\n<p><iframe title=\"Scorpions - Always Somewhere (Visualizer)\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/AepjLbcLrJE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<h4>Beckett \u2013 <em>Beckett<\/em> (1974)<\/h4>\n<p><iframe title=\"Beckett - Life&amp;apos;s Shadow\" width=\"1200\" height=\"900\" src=\"https:\/\/www.youtube.com\/embed\/hTBmLmYz6A0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<h4>Golden Earring \u2013 <em>Contraband<\/em> (1976)<\/h4>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=QeRK97iUyME\" target=\"_blank\" rel=\"noopener\">https:\/\/www.youtube.com\/watch?v=QeRK97iUyME<\/a><\/p>\n<h4>Jethro Tull \u2013 <em>Thick as a Brick<\/em> (1972)<\/h4>\n<p><iframe title=\"Jethro Tull - Thick As A Brick\" width=\"1200\" height=\"900\" src=\"https:\/\/www.youtube.com\/embed\/u9bk2MrMGaA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<div class=\"td-a-rec td-a-rec-id-content_bottom  tdi_3 td_block_template_1\">\n<h3>OU\u00c7A AGORA MESMO A PLAYLIST TMDQA! CHARTS<\/h3>\n<p>               Hits, sucessos e novidades quentes est\u00e3o te esperando agora mesmo na <strong>Playlist TMDQA! Charts<\/strong>; aproveite e <a href=\"https:\/\/open.spotify.com\/playlist\/05jyAgzDISm9DyKJt4WUj1?si=fa5ec8e47e7f49da\" target=\"_blank\" rel=\"noopener\">siga o TMDQA! no Spotify!<\/a><\/p>\n<p>                <iframe style=\"border-radius:12px\" src=\"https:\/\/open.spotify.com\/embed\/playlist\/05jyAgzDISm9DyKJt4WUj1?utm_source=generator\" width=\"100%\" height=\"352\" frameborder=\"0\" allowfullscreen=\"\" allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\"><\/iframe><\/p>\n<\/div>\n<p>                <!-- YOUR ARTICLE BOTTOM AD --><br \/>\n                <!-- \n\n<h3>NOT&Iacute;CIAS MAIS QUENTES no RESUMO DA SEMANA<\/h3>\n\n\n                Fique por dentro das not&iacute;cias mais quentes do mundo da m&uacute;sica, bem como dos lan&ccedil;amentos nacionais, ouvindo o <strong>Resumo da Semana<\/strong>, programa do <strong>Podcast Tenho Mais Discos Que Amigos!<\/strong>\n\n                <iframe style=\"border-radius:12px\" src=\"https:\/\/open.spotify.com\/embed-podcast\/episode\/77gyOc7Ern5hPOH93li1xi?utm_source=generator\" width=\"100%\" height=\"232\" frameBorder=\"0\" allowfullscreen=\"\" allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\"><\/iframe>\n\n                &nbsp;\n\n                \n\n<div id=\"taboola-below-article-thumbnails\"><\/div>\n\n\n                 --><br \/>\n                <!-- .YOUR ARTICLE BOTTOM AD --><\/p><\/div>\n<p><script>\n        (function(d, s, id) {\n        var js, fjs = d.getElementsByTagName(s)[0];\n        if (d.getElementById(id)) return;\n        js = d.createElement(s);\n        js.id = id;\n        js.src = \"\/\/connect.facebook.net\/pt_BR\/sdk.js#xfbml=1&version=v2.8&appId=578941478929256\";\n        fjs.parentNode.insertBefore(js, fjs);\n        }(document, 'script', 'facebook-jssdk'));\n    <\/script><script>(function(d, s, id) {\n  var js, fjs = d.getElementsByTagName(s)[0];\n  if (d.getElementById(id)) return;\n  js = d.createElement(s); js.id = id;\n  js.src = \"\/\/connect.facebook.net\/en_US\/sdk.js#xfbml=1&appId=120335281773834&version=v2.3\";\n  fjs.parentNode.insertBefore(js, fjs);\n}(document, 'script', 'facebook-jssdk'));<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tenhomaisdiscosqueamigos.com\/2024\/01\/22\/discos-preferidos-steve-harris\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Foto por Diego Padilha Steve Harris \u00e9 considerado uma lenda por seu trabalho impec\u00e1vel em destacar o baixo no Metal atrav\u00e9s das m\u00fasicas do\u00a0Iron Maiden, banda que fundou no Natal de 1975. O ic\u00f4nico baixista fez a estreia do grupo, que recebeu seu nome inspirado no romance O Homem da M\u00e1scara de Ferro, de &#8230; <a title=\"Os 10 discos preferidos de Steve Harris, baixista do Iron Maiden\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/22\/os-10-discos-preferidos-de-steve-harris-baixista-do-iron-maiden\/\" aria-label=\"Leia mais sobre Os 10 discos preferidos de Steve Harris, baixista do Iron Maiden\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":31536,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-31535","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/iron-maiden-foto-rock-rio-2019.jpg?fit=1000%2C667&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/iron-maiden-foto-rock-rio-2019.jpg?fit=1000%2C667&ssl=1",1000,667,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/iron-maiden-foto-rock-rio-2019.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/iron-maiden-foto-rock-rio-2019.jpg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/iron-maiden-foto-rock-rio-2019.jpg?fit=768%2C512&ssl=1",768,512,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/iron-maiden-foto-rock-rio-2019.jpg?fit=1000%2C667&ssl=1",1000,667,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/iron-maiden-foto-rock-rio-2019.jpg?fit=1000%2C667&ssl=1",1000,667,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/iron-maiden-foto-rock-rio-2019.jpg?fit=1000%2C667&ssl=1",1000,667,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Foto por Diego Padilha Steve Harris \u00e9 considerado uma lenda por seu trabalho impec\u00e1vel em destacar o baixo no Metal atrav\u00e9s das m\u00fasicas do\u00a0Iron Maiden, banda que fundou no Natal de 1975. O ic\u00f4nico baixista fez a estreia do grupo, que recebeu seu nome inspirado no romance O Homem da M\u00e1scara de Ferro, de&hellip;","jetpack-related-posts":[{"id":48171,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/01\/bruce-dickinson-do-iron-maiden-se-apresenta-em-ribeirao-preto-nesta-quinta\/","url_meta":{"origin":31535,"position":0},"title":"Bruce Dickinson, do Iron Maiden, se apresenta em Ribeir\u00e3o Preto nesta quinta","author":"ismaelcolosi.com.br","date":"1 de Maio de 2024","format":false,"excerpt":"[ad_1] O vocalista do Iron Maiden, Bruce Dickinson, traz seu show solo para Ribeir\u00e3o Preto nesta quinta-feira (2), no Quinta Linda Centro de Eventos. O hor\u00e1rio de abertura dos port\u00f5es foi alterado, sendo agora \u00e0s 19h e o show come\u00e7a \u00e0s 21h. O artista traz para os palcos do interior\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__bruce-dickinson.webp.webp?fit=1078%2C812&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__bruce-dickinson.webp.webp?fit=1078%2C812&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__bruce-dickinson.webp.webp?fit=1078%2C812&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__bruce-dickinson.webp.webp?fit=1078%2C812&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__bruce-dickinson.webp.webp?fit=1078%2C812&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":41604,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/09\/dire-straits-legacy-confirma-show-em-ribeirao-preto\/","url_meta":{"origin":31535,"position":1},"title":"Dire Straits Legacy confirma show em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"9 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] Ap\u00f3s bem sucedida turn\u00ea pelo Brasil, a banda DIRE STRAITS LEGACY volta ao pa\u00eds e confirma show em Ribeir\u00e3o Preto com a turn\u00ea For You South America Tour 2024. Formada por m\u00fasicos que fizeram parte de diferentes fases da carreira do Dire Straits, a banda apresenta um show \u00fanico\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1710004276_DSL-Band-Credit-RON-ELKAM-USA-TODAY-NETWORK-scaled.jpg?fit=1000%2C573&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1710004276_DSL-Band-Credit-RON-ELKAM-USA-TODAY-NETWORK-scaled.jpg?fit=1000%2C573&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1710004276_DSL-Band-Credit-RON-ELKAM-USA-TODAY-NETWORK-scaled.jpg?fit=1000%2C573&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/1710004276_DSL-Band-Credit-RON-ELKAM-USA-TODAY-NETWORK-scaled.jpg?fit=1000%2C573&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":48317,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/02\/ribeirao-tomato-bruce-dickinson-grava-video-sobre-show-na-cidade-assista\/","url_meta":{"origin":31535,"position":2},"title":"\u2018Ribeir\u00e3o Tomato\u2019? Bruce Dickinson grava v\u00eddeo sobre show na cidade; Assista","author":"ismaelcolosi.com.br","date":"2 de Maio de 2024","format":false,"excerpt":"[ad_1] O vocalista Bruce Dickinson, do Iron Maiden, gravou um v\u00eddeo para os ribeir\u00e3o-pretanos. O astro do heavy metal se apresenta em show solo nesta quinta-feira (2), no Quinta Linda Centro de Eventos, em Ribeir\u00e3o Preto. Assista o v\u00eddeo abaixo: Os port\u00f5es do local abrem \u00e0s 19h e a apresenta\u00e7\u00e3o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__bruce-dickinson-1_2024-05-02_14-07-07.webp.webp?fit=1200%2C674&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__bruce-dickinson-1_2024-05-02_14-07-07.webp.webp?fit=1200%2C674&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__bruce-dickinson-1_2024-05-02_14-07-07.webp.webp?fit=1200%2C674&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__bruce-dickinson-1_2024-05-02_14-07-07.webp.webp?fit=1200%2C674&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/AnyConv.com__bruce-dickinson-1_2024-05-02_14-07-07.webp.webp?fit=1200%2C674&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":28078,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/14\/veja-quais-sao-os-shows-confirmados-para-2024-em-ribeirao-preto\/","url_meta":{"origin":31535,"position":3},"title":"Veja quais s\u00e3o os shows nacionais e internacionais confirmados para 2024 em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"14 de Janeiro de 2024","format":false,"excerpt":"[ad_1] O ano de 2024 come\u00e7ou a pouco tempo mas Ribeir\u00e3o Preto j\u00e1 possui diversos shows nacionais e internacionais confirmados para o primeiro semestre do ano. H\u00e1 op\u00e7\u00f5es para todos os estilos musicais, como rock, sertanejo, pop e tecnobrega. O portal acidade on preparou uma lista com as atra\u00e7\u00f5es confirmadas\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-10.png?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-10.png?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-10.png?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-10.png?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-10.png?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1045,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/10\/po-de-cafe-sexteto-lanca-novo-album\/","url_meta":{"origin":31535,"position":4},"title":"P\u00f3 de Caf\u00e9: sexteto lan\u00e7a novo \u00e1lbum\u00a0","author":"ismaelcolosi.com.br","date":"10 de Novembro de 2023","format":false,"excerpt":"[ad_1] 10 de novembro de 2023 | 9:039 de novembro de 2023 | 16:10 0O grupo de jazz brasileiro P\u00f3 de Caf\u00e9 lan\u00e7a nesta sexta-feira, 10 de novembro, o quinto \u00e1lbum \u201cSu\u00edte do Caf\u00e9\u201d, gravado juntamente com a orquestra USP Filarm\u00f4nica, de Ribeir\u00e3o Preto. O \u00e1lbum est\u00e1 dispon\u00edvel em todas\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/sexteto-scaled.jpg?fit=1000%2C561&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/sexteto-scaled.jpg?fit=1000%2C561&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/sexteto-scaled.jpg?fit=1000%2C561&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/sexteto-scaled.jpg?fit=1000%2C561&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":1395,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/12\/bandolinista-e-violonista-de-sp-e-convidado-especial-do-choro-na-esquina\/","url_meta":{"origin":31535,"position":5},"title":"Bandolinista e violonista de SP \u00e9 convidado especial do Choro na esquina\u00a0","author":"ismaelcolosi.com.br","date":"12 de Novembro de 2023","format":false,"excerpt":"[ad_1] 12 de novembro de 2023 | 16:0012 de novembro de 2023 | 11:32 0No pr\u00f3ximo domingo, dia 19, v\u00e9spera de feriado, a Cia. Minaz promove mais uma edi\u00e7\u00e3o da s\u00e9rie \u201cChoro na Esquina\u201d, no Teatro Minaz.\u00a0\u00a0Nesta edi\u00e7\u00e3o, o bandolinista e violonista Lu\u00eds Passos, de S\u00e3o Paulo, ser\u00e1 o convidado.\u00a0A\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/choro-scaled.jpeg?fit=968%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/choro-scaled.jpeg?fit=968%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/choro-scaled.jpeg?fit=968%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/choro-scaled.jpeg?fit=968%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-8cD","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/31535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=31535"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/31535\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/31536"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=31535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=31535"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=31535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}