{"id":31511,"date":"2024-01-22T14:56:29","date_gmt":"2024-01-22T17:56:29","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/22\/concurso-publico-tem-salarios-de-r-5-mil-e-vagas-no-interior-de-sp\/"},"modified":"2024-01-22T14:56:29","modified_gmt":"2024-01-22T17:56:29","slug":"concurso-publico-tem-salarios-de-r-5-mil-e-vagas-no-interior-de-sp","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/22\/concurso-publico-tem-salarios-de-r-5-mil-e-vagas-no-interior-de-sp\/","title":{"rendered":"Concurso p\u00fablico tem sal\u00e1rios de R$ 5 mil e vagas no interior de SP"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_104\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p>O <strong>Cress-SP (Conselho Regional de Servi\u00e7o Social de S\u00e3o Paulo) <\/strong>da 9\u00aa Regi\u00e3o publicou edital de concurso p\u00fablico com oportunidades para diversas \u00e1reas e vagas no <strong>interior de S\u00e3o Paulo<\/strong>. Os sal\u00e1rios variam entre R$ 2,6 mil e R$ 5 mil.<\/p>\n<p>As inscri\u00e7\u00f5es devem ser realizadas no per\u00edodo entre 29 de janeiro e 7 de mar\u00e7o de 2024 no site do <strong>Instituto Mais <\/strong>(<a href=\"https:\/\/www.institutomais.org.br\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">clique aqui<\/a>). A taxa de inscri\u00e7\u00e3o custa entre R$ 63 e R$ 75.<\/p><div class='code-block code-block-8' style='margin: 8px auto; text-align: center; display: block; clear: both;'>\n<script>\n  atOptions = {\n    'key' : '66e2e2111ca34da796271819fc334058',\n    'format' : 'iframe',\n    'height' : 250,\n    'width' : 300,\n    'params' : {}\n  };\n<\/script>\n<script src=\"https:\/\/www.highperformanceformat.com\/66e2e2111ca34da796271819fc334058\/invoke.js\"><\/script>\n<\/div>\n\n<h4 class=\"wp-block-heading\"><strong>Veja as vagas dispon\u00edveis<\/strong><\/h4>\n<ul>\n<li>Agente Fiscal (1 vaga + Cadastro Reserva), Analista de administra\u00e7\u00e3o e servi\u00e7os (Cadastro Reserva), Analista de comunica\u00e7\u00e3o (Cadastro Reserva), Analista de RH (Cadastro Reserva), Analista de Tecnologia da Informa\u00e7\u00e3o (Cadastro Reserva), analista jur\u00eddico (Cadastro Reserva), Assistente de Administra\u00e7\u00e3o e Servi\u00e7os (Cadastro Reserva), Auxiliar de servi\u00e7os gerais (Cadastro Reserva), Bibliotec\u00e1rio (1 vaga), Agente fiscal (Cadastro Reserva), \u00a0Assistente de administra\u00e7\u00e3o e servi\u00e7os (Cadastro Reserva).<\/li>\n<\/ul>\n<p>As vagas dispon\u00edveis s\u00e3o para <strong>Ribeir\u00e3o Preto<\/strong>, <strong>Ara\u00e7atuba<\/strong>, <strong>Bauru<\/strong>,<strong> Campinas<\/strong>, <strong>Mar\u00edlia<\/strong>, <strong>Presidente Prudente<\/strong>,<strong> Santo Andr\u00e9<\/strong>, <strong>Santos<\/strong>, <strong>S\u00e3o Jos\u00e9 do Rio Preto<\/strong>, <strong>S\u00e3o Jos\u00e9 dos Campos<\/strong>, <strong>Sorocaba<\/strong>, al\u00e9m da <strong>capital<\/strong>.<\/p>\n<p>O edital completo pode ser conferido na edi\u00e7\u00e3o desta segunda-feira (22) do<strong> Di\u00e1rio Oficial da Uni\u00e3o <\/strong>(<a href=\"https:\/\/www.in.gov.br\/web\/dou\/-\/edital-n-1-de-18-de-janeiro-de-2024-concurso-publico-538775022\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">clique aqui<\/a>).<\/p>\n<p>SAIBA MAIS<br \/>PAT de Ribeir\u00e3o Preto conta com 58 vagas de emprego; Veja como participar<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do <strong>acidade on <\/strong>no <a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Instagram<\/a> e no <a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do <strong>acidade on<\/strong> no WhatsApp. <a href=\"https:\/\/chat.whatsapp.com\/Bnv2w66ZT4VDyZW3oiZ69n\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<br \/>Quem canta a m\u00fasica de abertura de \u201cRenascer\u201d?<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/economia\/concurso-publico-tem-salarios-de-r-5-mil-e-vagas-no-interior-de-sp\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] O Cress-SP (Conselho Regional de Servi\u00e7o Social de S\u00e3o Paulo) da 9\u00aa Regi\u00e3o publicou edital de concurso p\u00fablico com oportunidades para diversas \u00e1reas e vagas no interior de S\u00e3o Paulo. Os sal\u00e1rios variam entre R$ 2,6 mil e R$ 5 mil. As inscri\u00e7\u00f5es devem ser realizadas no per\u00edodo entre 29 de janeiro e 7 &#8230; <a title=\"Concurso p\u00fablico tem sal\u00e1rios de R$ 5 mil e vagas no interior de SP\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/22\/concurso-publico-tem-salarios-de-r-5-mil-e-vagas-no-interior-de-sp\/\" aria-label=\"Read more about Concurso p\u00fablico tem sal\u00e1rios de R$ 5 mil e vagas no interior de SP\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":31512,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[567,237,402,282,768,162,143],"class_list":["post-31511","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-concurso","tag-interior","tag-mil","tag-publico","tag-salarios","tag-tem","tag-vagas"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1705946192_concurso-publico-nacional-unificado-cesgranrio.jpg?fit=1200%2C798&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1705946192_concurso-publico-nacional-unificado-cesgranrio.jpg?fit=1200%2C798&ssl=1",1200,798,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1705946192_concurso-publico-nacional-unificado-cesgranrio.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1705946192_concurso-publico-nacional-unificado-cesgranrio.jpg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1705946192_concurso-publico-nacional-unificado-cesgranrio.jpg?fit=768%2C511&ssl=1",768,511,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1705946192_concurso-publico-nacional-unificado-cesgranrio.jpg?fit=1024%2C681&ssl=1",1024,681,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1705946192_concurso-publico-nacional-unificado-cesgranrio.jpg?fit=1200%2C798&ssl=1",1200,798,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1705946192_concurso-publico-nacional-unificado-cesgranrio.jpg?fit=1200%2C798&ssl=1",1200,798,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] O Cress-SP (Conselho Regional de Servi\u00e7o Social de S\u00e3o Paulo) da 9\u00aa Regi\u00e3o publicou edital de concurso p\u00fablico com oportunidades para diversas \u00e1reas e vagas no interior de S\u00e3o Paulo. Os sal\u00e1rios variam entre R$ 2,6 mil e R$ 5 mil. As inscri\u00e7\u00f5es devem ser realizadas no per\u00edodo entre 29 de janeiro e 7&hellip;","jetpack-related-posts":[{"id":46806,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/15\/camara-no-interior-de-sp-abre-concurso-publico-com-salarios-de-r-5-mil\/","url_meta":{"origin":31511,"position":0},"title":"C\u00e2mara no interior de SP abre concurso p\u00fablico com sal\u00e1rios de R$ 5 mil","author":"ismaelcolosi.com.br","date":"15 de April de 2024","format":false,"excerpt":"[ad_1] A C\u00e2mara Municipal de Cajuru, no interior de S\u00e3o Paulo, abriu concurso p\u00fablico com sal\u00e1rios que variam entre R$ 2 mil e R$ 5 mil. S\u00e3o quatro vagas de n\u00edvel fundamental, m\u00e9dio e superior, al\u00e9m de oportunidades para o cadastro de reserva. As inscri\u00e7\u00f5es devem ser realizadas no per\u00edodo\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/1713191118_concurso-publico.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/1713191118_concurso-publico.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/1713191118_concurso-publico.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/1713191118_concurso-publico.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/1713191118_concurso-publico.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":70828,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/13\/veja-cinco-concursos-publicos-com-mais-de-110-vagas-no-interior-de-sp\/","url_meta":{"origin":31511,"position":1},"title":"Veja cinco concursos p\u00fablicos com mais de 110 vagas no interior de SP","author":"ismaelcolosi.com.br","date":"13 de October de 2024","format":false,"excerpt":"[ad_1] Os interessados em concorrer a uma vaga em concurso p\u00fablico contam com mais de 110 oportunidades em cinco editais dispon\u00edveis no interior de S\u00e3o Paulo. As oportunidades s\u00e3o para cargos de n\u00edvel m\u00e9dio, t\u00e9cnico e superior. Os sal\u00e1rios variam entre R$ 2,1 mil e R$ 12,6 mil. Confira a\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-22_2024-07-24_20-00-55_jpg_2024-07-24_20-00-55.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-22_2024-07-24_20-00-55_jpg_2024-07-24_20-00-55.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-22_2024-07-24_20-00-55_jpg_2024-07-24_20-00-55.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-22_2024-07-24_20-00-55_jpg_2024-07-24_20-00-55.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-22_2024-07-24_20-00-55_jpg_2024-07-24_20-00-55.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":52649,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/09\/prefeitura-no-interior-de-sp-tem-20-vagas-em-concurso-publico-veja-como-se-inscrever\/","url_meta":{"origin":31511,"position":2},"title":"Prefeitura no interior de SP tem 20 vagas em concurso p\u00fablico; Veja como se inscrever","author":"ismaelcolosi.com.br","date":"9 de June de 2024","format":false,"excerpt":"[ad_1] A Prefeitura de Colina, cidade no interior de S\u00e3o Paulo, est\u00e1 com as inscri\u00e7\u00f5es abertas para concurso com 20 vagas, al\u00e9m de oportunidades para cadastro de reserva. As vagas s\u00e3o de n\u00edvel fundamental, m\u00e9dio e superior. Os sal\u00e1rios variam entre R$ 1,5 mil e R$ 2,8 mil. Para os\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/concuso-publico.jpg?fit=1200%2C801&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/concuso-publico.jpg?fit=1200%2C801&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/concuso-publico.jpg?fit=1200%2C801&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/concuso-publico.jpg?fit=1200%2C801&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/concuso-publico.jpg?fit=1200%2C801&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":66151,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/16\/camara-no-interior-de-sp-abre-concurso-publico-com-salarios-de-r-7-mil\/","url_meta":{"origin":31511,"position":3},"title":"C\u00e2mara no interior de SP abre concurso p\u00fablico com sal\u00e1rios de R$ 7 mil","author":"ismaelcolosi.com.br","date":"16 de September de 2024","format":false,"excerpt":"[ad_1] A C\u00e2mara Municipal de S\u00e3o Sim\u00e3o, no interior de S\u00e3o Paulo, abriu concurso p\u00fablico com quatro vagas de n\u00edvel m\u00e9dio e superior, al\u00e9m de oportunidades para cadastro de reserva. Os sal\u00e1rios para as fun\u00e7\u00f5es variam entre R$ 3 mil e R$ 7 mil. As inscri\u00e7\u00f5es devem ser realizadas pela\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/concurso-publico-ribeirao-preto_2024-08-13_10-44-40_jpg_2024-08-13_10-44-40.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/concurso-publico-ribeirao-preto_2024-08-13_10-44-40_jpg_2024-08-13_10-44-40.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/concurso-publico-ribeirao-preto_2024-08-13_10-44-40_jpg_2024-08-13_10-44-40.webp.webp?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/concurso-publico-ribeirao-preto_2024-08-13_10-44-40_jpg_2024-08-13_10-44-40.webp.webp?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/concurso-publico-ribeirao-preto_2024-08-13_10-44-40_jpg_2024-08-13_10-44-40.webp.webp?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":67327,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/22\/veja-sete-concursos-publicos-com-mais-de-200-vagas-no-interior-de-sp\/","url_meta":{"origin":31511,"position":4},"title":"Veja sete concursos p\u00fablicos com mais de 200 vagas no interior de SP","author":"ismaelcolosi.com.br","date":"22 de September de 2024","format":false,"excerpt":"[ad_1] Voc\u00ea procura por uma oportunidade de emprego no servi\u00e7o p\u00fablico? O acidade on Ribeir\u00e3o separou uma lista com sete concursos p\u00fablico que t\u00eam, somados, mais de 200 vagas dispon\u00edveis no interior de S\u00e3o Paulo. As vagas nos concursos p\u00fablicos s\u00e3o de n\u00edvel fundamental, m\u00e9dio, t\u00e9cnico e superior com sal\u00e1rios\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-33_2024-05-23_13-39-05_jpg_2024-05-23_13-39-05.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-33_2024-05-23_13-39-05_jpg_2024-05-23_13-39-05.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-33_2024-05-23_13-39-05_jpg_2024-05-23_13-39-05.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-33_2024-05-23_13-39-05_jpg_2024-05-23_13-39-05.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-33_2024-05-23_13-39-05_jpg_2024-05-23_13-39-05.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":48728,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/06\/com-provas-no-interior-de-sp-justica-federal-abre-concurso-publico-com-salarios-de-r-13-mil\/","url_meta":{"origin":31511,"position":5},"title":"Com provas no interior de SP, Justi\u00e7a Federal abre concurso p\u00fablico com sal\u00e1rios de R$ 13 mil","author":"ismaelcolosi.com.br","date":"6 de May de 2024","format":false,"excerpt":"[ad_1] O TRF-3 (Tribunal Regional Federal da 3\u00aa Regi\u00e3o) abriu as inscri\u00e7\u00f5es para concurso p\u00fablico com 269 vagas de n\u00edvel superior para os estados de S\u00e3o Paulo e Mato Grosso do Sul. Os sal\u00e1rios variam entre R$ 8.529,65 e R$ 13.994,78. As inscri\u00e7\u00f5es devem ser realizadas at\u00e9 o dia 28\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/concurso-publico.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/concurso-publico.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/concurso-publico.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/concurso-publico.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/concurso-publico.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-8cf","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/31511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=31511"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/31511\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/31512"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=31511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=31511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=31511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}