{"id":29449,"date":"2024-01-18T11:55:06","date_gmt":"2024-01-18T14:55:06","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/18\/empresario-e-preso-por-dirigir-embriagado-e-discutir-com-policial-em-ribeirao\/"},"modified":"2024-01-18T11:55:06","modified_gmt":"2024-01-18T14:55:06","slug":"empresario-e-preso-por-dirigir-embriagado-e-discutir-com-policial-em-ribeirao","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/18\/empresario-e-preso-por-dirigir-embriagado-e-discutir-com-policial-em-ribeirao\/","title":{"rendered":"Empres\u00e1rio \u00e9 preso por dirigir embriagado e discutir com policial em Ribeir\u00e3o"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>Um empres\u00e1rio de 44 anos foi preso na noite da \u00faltima quarta-feira (17) em<strong> Ribeir\u00e3o Preto<\/strong> ap\u00f3s ser flagrado dirigindo alcoolizado na <strong>avenida Presidente Castelo Branco<\/strong>. A abordagem da<strong> PMR (Pol\u00edcia Militar Rodovi\u00e1ria) <\/strong>aconteceu por volta das 23h, e o homem chegou a discutir com os agentes.<\/p>\n<p>Segundo o <strong>B.O. (boletim de ocorr\u00eancia)<\/strong>, os policiais estavam fazendo o patrulhamento de rotina quando abordaram o motorista. Ele foi questionado se teria consumido bebida alco\u00f3lica e negou.<\/p>\n<p>Contudo, os agentes pediram que fosse realizado o teste do baf\u00f4metro, resultando na <mark style=\"background-color:#fcb900\" class=\"has-inline-color has-black-color\">concentra\u00e7\u00e3o de 0,42 mg\/l de \u00e1lcool por litro de ar expelido<\/mark>. De acordo com o <strong>CTB (C\u00f3digo de Tr\u00e2nsito Brasileiro)<\/strong>,<mark style=\"background-color:#fcb900\" class=\"has-inline-color has-black-color\"> acima de 0,34 mg\/l de \u00e1lcool por litro de ar expelido \u00e9 considerado crime de tr\u00e2nsito.<\/mark><\/p>\n<p>Por isso, foi dada voz de pris\u00e3o para o motorista. Neste momento, <mark style=\"background-color:#fcb900\" class=\"has-inline-color has-black-color\">o empres\u00e1rio teria se alterado e se recusou a entrar na viatura. O registro afirma que, por conta disso, foi necess\u00e1rio o \u201cuso moderado da for\u00e7a\u201d.<\/mark><\/p>\n<p>No carro do empres\u00e1rio, havia uma mulher, que, segundo os agentes, teria tentado \u201ctumultuar\u201d, segurando um policial durante a discuss\u00e3o.<\/p>\n<p>O motorista foi levado para <strong>CPJ (Central de Pol\u00edcia Judici\u00e1ria) de Ribeir\u00e3o Preto <\/strong>e o caso foi registrado como embriaguez ao volante. O empres\u00e1rio foi solto ap\u00f3s o pagamento de fian\u00e7a de R$ 1,5 mil.<\/p>\n<p>SAIBA MAIS<\/p>\n<p>Moradores de Ribeir\u00e3o denunciam vazamento de \u00e1gua limpa<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do<strong> acidade on<\/strong> no <a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Instagram<\/a> e no <a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do <strong>acidade on<\/strong> no WhatsApp. <a href=\"https:\/\/chat.whatsapp.com\/Bnv2w66ZT4VDyZW3oiZ69n\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: 16\u00a0 99117 7802.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Ludmilla revela regra para cantar no BBB 24; confira<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/empresario-e-preso-por-dirigir-embriagado-e-discutir-com-policial-em-ribeirao\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Um empres\u00e1rio de 44 anos foi preso na noite da \u00faltima quarta-feira (17) em Ribeir\u00e3o Preto ap\u00f3s ser flagrado dirigindo alcoolizado na avenida Presidente Castelo Branco. A abordagem da PMR (Pol\u00edcia Militar Rodovi\u00e1ria) aconteceu por volta das 23h, e o homem chegou a discutir com os agentes. Segundo o B.O. (boletim de ocorr\u00eancia), os &#8230; <a title=\"Empres\u00e1rio \u00e9 preso por dirigir embriagado e discutir com policial em Ribeir\u00e3o\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/18\/empresario-e-preso-por-dirigir-embriagado-e-discutir-com-policial-em-ribeirao\/\" aria-label=\"Leia mais sobre Empres\u00e1rio \u00e9 preso por dirigir embriagado e discutir com policial em Ribeir\u00e3o\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":29450,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[3049,3665,3664,23,1397,134,36,26],"class_list":["post-29449","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-dirigir","tag-discutir","tag-embriagado","tag-empresario","tag-policial","tag-por","tag-preso","tag-ribeirao"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1705589708_policia_militar_1024x576_17072021134619.jpg?fit=1024%2C576&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1705589708_policia_militar_1024x576_17072021134619.jpg?fit=1024%2C576&ssl=1",1024,576,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1705589708_policia_militar_1024x576_17072021134619.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1705589708_policia_militar_1024x576_17072021134619.jpg?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1705589708_policia_militar_1024x576_17072021134619.jpg?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1705589708_policia_militar_1024x576_17072021134619.jpg?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1705589708_policia_militar_1024x576_17072021134619.jpg?fit=1024%2C576&ssl=1",1024,576,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/1705589708_policia_militar_1024x576_17072021134619.jpg?fit=1024%2C576&ssl=1",1024,576,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Um empres\u00e1rio de 44 anos foi preso na noite da \u00faltima quarta-feira (17) em Ribeir\u00e3o Preto ap\u00f3s ser flagrado dirigindo alcoolizado na avenida Presidente Castelo Branco. A abordagem da PMR (Pol\u00edcia Militar Rodovi\u00e1ria) aconteceu por volta das 23h, e o homem chegou a discutir com os agentes. Segundo o B.O. (boletim de ocorr\u00eancia), os&hellip;","jetpack-related-posts":[{"id":67757,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/25\/homem-e-preso-apos-colidir-com-viatura-da-policia-militar-em-ribeirao-preto\/","url_meta":{"origin":29449,"position":0},"title":"Homem \u00e9 preso ap\u00f3s colidir com viatura da Pol\u00edcia Militar em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"25 de Setembro de 2024","format":false,"excerpt":"[ad_1] Um homem foi preso na noite desta quarta-feira (13) em Ribeir\u00e3o Preto ap\u00f3s colidir o carro que dirigia com uma viatura da Pol\u00edcia Militar. O acidente ocorreu em um cruzamento na zona norte da cidade, e, segundo informa\u00e7\u00f5es da PM, o motorista apresentava sinais de embriaguez e tentou fugir\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Policia-Militar-e1717532645165.webp.webp?fit=800%2C450&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Policia-Militar-e1717532645165.webp.webp?fit=800%2C450&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Policia-Militar-e1717532645165.webp.webp?fit=800%2C450&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/Policia-Militar-e1717532645165.webp.webp?fit=800%2C450&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":37115,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/14\/motorista-embriagado-atropela-seis-pessoas-na-regiao-de-ribeirao-preto\/","url_meta":{"origin":29449,"position":1},"title":"Motorista embriagado atropela seis pessoas na regi\u00e3o de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"14 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] Seis pessoas foram atropeladas em um cruzamento no Centro de Taquaritinga, na madrugada de ter\u00e7a-feira (13) durante a tradicional festa de Carnaval da cidade. Al\u00e9m das v\u00edtimas, o carro dirigido por um motorista embriagado, tamb\u00e9m atingiu outro ve\u00edculo que estava estacionado na via. Segundo a ocorr\u00eancia registrada pela Pol\u00edcia\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Capturar-11.jpg?fit=730%2C480&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Capturar-11.jpg?fit=730%2C480&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Capturar-11.jpg?fit=730%2C480&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Capturar-11.jpg?fit=730%2C480&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":54623,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/26\/o-que-se-sabe-sobre-o-caso-do-motorista-embriagado-que-invadiu-posto-com-carro-em-ribeirao\/","url_meta":{"origin":29449,"position":2},"title":"O que se sabe sobre o caso do motorista embriagado que invadiu posto com carro em Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"26 de Junho de 2024","format":false,"excerpt":"[ad_1] O motorista de um carro foi preso por embriaguez ao volante na madrugada desta quarta-feira (26), ap\u00f3s invadir um posto de combust\u00edveis com o ve\u00edculo e arrancar um equipamento de filtro de diesel ao lado de uma das bombas do estabelecimento, na avenida Maur\u00edlio Biagi, zona Sul de Ribeir\u00e3o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-26-at-14.17.47_2024-06-26_17-20-47_jpeg_2024-06-26_17-20-48.webp.webp?fit=1200%2C964&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-26-at-14.17.47_2024-06-26_17-20-47_jpeg_2024-06-26_17-20-48.webp.webp?fit=1200%2C964&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-26-at-14.17.47_2024-06-26_17-20-47_jpeg_2024-06-26_17-20-48.webp.webp?fit=1200%2C964&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-26-at-14.17.47_2024-06-26_17-20-47_jpeg_2024-06-26_17-20-48.webp.webp?fit=1200%2C964&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-26-at-14.17.47_2024-06-26_17-20-47_jpeg_2024-06-26_17-20-48.webp.webp?fit=1200%2C964&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":39499,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/26\/pai-lamenta-falta-de-socorro-para-entregador-vitima-de-acidente-em-ribeirao\/","url_meta":{"origin":29449,"position":3},"title":"Pai lamenta falta de socorro para entregador v\u00edtima de acidente em Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"26 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] O pai do entregador Johny Oliveira Lima da Silva, de 19 anos, v\u00edtima de um acidente envolvendo um motorista embriagado na zona Sul de Ribeir\u00e3o Preto, na madrugada do \u00faltimo domingo (26), lamentou que o condutor do ve\u00edculo que atingiu o filho deixou de prestar socorro. O entregador foi\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/pai-entregador.jpg?fit=1200%2C785&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/pai-entregador.jpg?fit=1200%2C785&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/pai-entregador.jpg?fit=1200%2C785&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/pai-entregador.jpg?fit=1200%2C785&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/pai-entregador.jpg?fit=1200%2C785&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":55450,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/03\/blitz-da-lei-seca-autua-37-motoristas-no-anel-viario-sul-em-ribeirao-preto\/","url_meta":{"origin":29449,"position":4},"title":"Blitz da Lei Seca autua 37 motoristas no Anel Vi\u00e1rio Sul em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"3 de Julho de 2024","format":false,"excerpt":"[ad_1] A blitz da Lei Seca autuou 37 motoristas na rodovia Ant\u00f4nio Duarte Nogueira, o Anel Vi\u00e1rio Sul, em Ribeir\u00e3o Preto, no \u00faltimo final de semana. De acordo com o Detran-SP, 35 motoristas se recusaram a realizar o teste do baf\u00f4metros e duas pessoas foram flagradas dirigindo alcoolizadas. A a\u00e7\u00e3o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/AnyConv.com__anel-viario-sul_2024-07-03_13-31-20.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/AnyConv.com__anel-viario-sul_2024-07-03_13-31-20.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/AnyConv.com__anel-viario-sul_2024-07-03_13-31-20.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/AnyConv.com__anel-viario-sul_2024-07-03_13-31-20.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/AnyConv.com__anel-viario-sul_2024-07-03_13-31-20.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":66490,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/17\/blitz-da-lei-seca-autua-39-motoristas-na-regiao-de-ribeirao-preto\/","url_meta":{"origin":29449,"position":5},"title":"Blitz da Lei Seca autua 39 motoristas na regi\u00e3o de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"17 de Setembro de 2024","format":false,"excerpt":"[ad_1] A blitz da Lei Seca autuou 39 motoristas na avenida Affonso Trigo, em Sert\u00e3ozinho, cidade na regi\u00e3o de Ribeir\u00e3o Preto, no \u00faltimo final de semana. Conforme o Detran-SP, 38 condutores se recusaram a realizar o teste do baf\u00f4metro e um foi pego dirigindo sob a influ\u00eancia de \u00e1lcool. A\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/lei-seca_2024-07-23_15-55-31_jpg_2024-07-23_15-55-31.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/lei-seca_2024-07-23_15-55-31_jpg_2024-07-23_15-55-31.webp.webp?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/lei-seca_2024-07-23_15-55-31_jpg_2024-07-23_15-55-31.webp.webp?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/lei-seca_2024-07-23_15-55-31_jpg_2024-07-23_15-55-31.webp.webp?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/lei-seca_2024-07-23_15-55-31_jpg_2024-07-23_15-55-31.webp.webp?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-7EZ","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/29449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=29449"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/29449\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/29450"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=29449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=29449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=29449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}