{"id":28246,"date":"2024-01-15T11:19:36","date_gmt":"2024-01-15T14:19:36","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/15\/utm_sourcerssutm_mediumrssutm_campaignvalentao-e-preso-apos-perseguir-esposa-que-iria-denunciar-agressao-na-cpj-de-ribeirao-preto-uma-chave-de-roda-usada-no-crime-foi-apreendida\/"},"modified":"2024-01-15T11:19:36","modified_gmt":"2024-01-15T14:19:36","slug":"utm_sourcerssutm_mediumrssutm_campaignvalentao-e-preso-apos-perseguir-esposa-que-iria-denunciar-agressao-na-cpj-de-ribeirao-preto-uma-chave-de-roda-usada-no-crime-foi-apreendida","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/15\/utm_sourcerssutm_mediumrssutm_campaignvalentao-e-preso-apos-perseguir-esposa-que-iria-denunciar-agressao-na-cpj-de-ribeirao-preto-uma-chave-de-roda-usada-no-crime-foi-apreendida\/","title":{"rendered":"Valent\u00e3o \u00e9 preso ap\u00f3s perseguir esposa que iria denunciar agress\u00e3o na CPJ de Ribeir\u00e3o Preto; uma chave de roda usada no crime foi apreendida"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>\u00a0Um valent\u00e3o foi preso por investigadores da Pol\u00edcia Civil defronte a Central de Pol\u00edcia Judici\u00e1ria (CPJ) ap\u00f3s amea\u00e7ar e tentar intimidar sua esposa que denunciava agress\u00e3o na madrugada deste domingo (14\/1), em Ribeir\u00e3o Preto.\u00a0<\/p>\n<p>Segundo apurado com a Pol\u00edcia Civil, a v\u00edtima chegou na Delegacia da rua Duque de Caxias, informando que queria registrar um B.O (boletim de ocorr\u00eancia), pois teria sido agredida e amea\u00e7ada de morte pelo seu esposo \u2013 que estava armado com uma chave de roda, disse ainda, que o autor estaria te esperando do lado de fora em um ve\u00edculo branco.\u00a0<\/p>\n<p>\u00a0De posse das informa\u00e7\u00f5es da v\u00edtima, os investigadores plantonistas da Delegacia, foram at\u00e9 o carro do autor que estava estacionado em local destinado \u00e0 viaturas Policial, e constatou a den\u00fancia da v\u00edtima.\u00a0<\/p>\n<p>Consta no B.O, que o autor estava no interior do ve\u00edculo de posse de uma chave de roda, aguardando a v\u00edtima sair.\u00a0<\/p>\n<p>Ap\u00f3s tomar ci\u00eancia dos fatos, o Delegado plantonista ratificou a voz de pris\u00e3o, baseada nos crimes (viol\u00eancia dom\u00e9stica, les\u00e3o corporal, amea\u00e7a e perseguir). Parab\u00e9ns aos Policiais Civis pela pris\u00e3o deste valent\u00e3o.\u00a0<\/p>\n<figure class=\"is-layout-flex wp-block-gallery-1 wp-block-gallery has-nested-images columns-default is-cropped\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" loading=\"lazy\" width=\"844\" height=\"579\" data-id=\"27640\" src=\"https:\/\/i0.wp.com\/xtudoribeirao.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-10.49.23.jpeg?resize=844%2C579&#038;ssl=1\" alt=\"\" class=\"wp-image-27640\" srcset=\"https:\/\/xtudoribeirao.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-10.49.23.jpeg 844w, https:\/\/xtudoribeirao.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-10.49.23-300x206.jpeg 300w, https:\/\/xtudoribeirao.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-10.49.23-768x527.jpeg 768w, https:\/\/xtudoribeirao.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-10.49.23-750x515.jpeg 750w\" sizes=\"auto, (max-width: 844px) 100vw, 844px\"\/><\/figure>\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" loading=\"lazy\" width=\"779\" height=\"543\" data-id=\"27639\" src=\"https:\/\/i0.wp.com\/xtudoribeirao.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-10.49.23-1.jpeg?resize=779%2C543&#038;ssl=1\" alt=\"\" class=\"wp-image-27639\" srcset=\"https:\/\/xtudoribeirao.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-10.49.23-1.jpeg 779w, https:\/\/xtudoribeirao.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-10.49.23-1-300x209.jpeg 300w, https:\/\/xtudoribeirao.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-10.49.23-1-768x535.jpeg 768w, https:\/\/xtudoribeirao.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-10.49.23-1-750x523.jpeg 750w\" sizes=\"auto, (max-width: 779px) 100vw, 779px\"\/><\/figure>\n<\/figure><\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/xtudoribeirao.com.br\/2024\/01\/15\/valentao-e-preso-apos-perseguir-esposa-que-iria-denunciar-agressao-na-cpj-de-ribeirao-preto-uma-chave-de-roda-usada-no-crime-foi-apreendida\/?utm_source=rss&#038;utm_medium=rss&#038;utm_campaign=valentao-e-preso-apos-perseguir-esposa-que-iria-denunciar-agressao-na-cpj-de-ribeirao-preto-uma-chave-de-roda-usada-no-crime-foi-apreendida\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] \u00a0Um valent\u00e3o foi preso por investigadores da Pol\u00edcia Civil defronte a Central de Pol\u00edcia Judici\u00e1ria (CPJ) ap\u00f3s amea\u00e7ar e tentar intimidar sua esposa que denunciava agress\u00e3o na madrugada deste domingo (14\/1), em Ribeir\u00e3o Preto.\u00a0 Segundo apurado com a Pol\u00edcia Civil, a v\u00edtima chegou na Delegacia da rua Duque de Caxias, informando que queria registrar &#8230; <a title=\"Valent\u00e3o \u00e9 preso ap\u00f3s perseguir esposa que iria denunciar agress\u00e3o na CPJ de Ribeir\u00e3o Preto; uma chave de roda usada no crime foi apreendida\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/15\/utm_sourcerssutm_mediumrssutm_campaignvalentao-e-preso-apos-perseguir-esposa-que-iria-denunciar-agressao-na-cpj-de-ribeirao-preto-uma-chave-de-roda-usada-no-crime-foi-apreendida\/\" aria-label=\"Leia mais sobre Valent\u00e3o \u00e9 preso ap\u00f3s perseguir esposa que iria denunciar agress\u00e3o na CPJ de Ribeir\u00e3o Preto; uma chave de roda usada no crime foi apreendida\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":28247,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[3538,37,3540,997,3539,88,3537,3535,654,3536,3534,36,27,26,2013,85,1495,1255],"class_list":["post-28246","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-agressao","tag-apos","tag-apreendida","tag-chave","tag-cpj","tag-crime","tag-denunciar","tag-esposa","tag-foi","tag-iria","tag-perseguir","tag-preso","tag-preto","tag-ribeirao","tag-roda","tag-uma","tag-usada","tag-valentao"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-10.49.23-1.jpeg?fit=779%2C543&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-10.49.23-1.jpeg?fit=779%2C543&ssl=1",779,543,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-10.49.23-1.jpeg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-10.49.23-1.jpeg?fit=300%2C209&ssl=1",300,209,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-10.49.23-1.jpeg?fit=768%2C535&ssl=1",768,535,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-10.49.23-1.jpeg?fit=779%2C543&ssl=1",779,543,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-10.49.23-1.jpeg?fit=779%2C543&ssl=1",779,543,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-10.49.23-1.jpeg?fit=779%2C543&ssl=1",779,543,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] \u00a0Um valent\u00e3o foi preso por investigadores da Pol\u00edcia Civil defronte a Central de Pol\u00edcia Judici\u00e1ria (CPJ) ap\u00f3s amea\u00e7ar e tentar intimidar sua esposa que denunciava agress\u00e3o na madrugada deste domingo (14\/1), em Ribeir\u00e3o Preto.\u00a0 Segundo apurado com a Pol\u00edcia Civil, a v\u00edtima chegou na Delegacia da rua Duque de Caxias, informando que queria registrar&hellip;","jetpack-related-posts":[{"id":32737,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/26\/utm_sourcerssutm_mediumrssutm_campaignhomem-e-preso-apos-matar-sua-esposa-com-golpes-de-madeira-no-rosto-na-cidade-de-brodowski\/","url_meta":{"origin":28246,"position":0},"title":"Homem \u00e9 preso ap\u00f3s matar sua esposa com golpes de madeira no rosto na cidade de Brodowski \u2013 X Tudo Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"26 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Um valent\u00e3o foi preso pela PM (Pol\u00edcia Militar) ap\u00f3s matar sua esposa com golpes de madeira na tarde desta quinta-feira (25\/1), no Loteamento Parque do S\u00e1bia, na cidade de Brodowski.\u00a0 Segundo informa\u00e7\u00f5es da PM, populares acionaram os PMs atrav\u00e9s do telefone (190) versando sobre uma agress\u00e3o contra uma mulher\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-26-at-10.17.16-3.jpeg?fit=740%2C547&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-26-at-10.17.16-3.jpeg?fit=740%2C547&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-26-at-10.17.16-3.jpeg?fit=740%2C547&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-26-at-10.17.16-3.jpeg?fit=740%2C547&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":37696,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/17\/homem-e-preso-por-bater-em-cao-com-pedaco-de-madeira-em-ribeirao-preto\/","url_meta":{"origin":28246,"position":1},"title":"Homem \u00e9 preso por bater em c\u00e3o com peda\u00e7o de madeira em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"17 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] Um homem de 56 anos foi preso em flagrante na manh\u00e3 deste s\u00e1bado (17), ap\u00f3s bater em um cachorro com um peda\u00e7o de madeira, no bairro Jardim Heitor Rigon, na zona Norte de Ribeir\u00e3o Preto. Segundo o tenente da Pol\u00edcia Militar F\u00e1bio Guidoni, al\u00e9m da agress\u00e3o contra o animal,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/2.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/2.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/2.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/2.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/2.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":14674,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/12\/utm_sourcerssutm_mediumrssutm_campaigntres-homens-sao-presos-apos-tentarem-matar-desafeto-com-golpes-de-chave-de-roda-em-ribeirao-preto\/","url_meta":{"origin":28246,"position":2},"title":"Tr\u00eas homens s\u00e3o presos ap\u00f3s tentarem matar desafeto com golpes de chave de roda em Ribeir\u00e3o Preto \u2013 X Tudo Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"12 de Dezembro de 2023","format":false,"excerpt":"[ad_1] A Pol\u00edcia Militar prendeu tr\u00eas homens, na noite desta segunda-feira (11), na Avenida Santa Luzia, Jardim Sumar\u00e9, zona Sul de Ribeir\u00e3o Preto. Os ausados estariam agredindo um homem que estava ca\u00eddo no ch\u00e3o. Segundo o Boletim de Ocorr\u00eancia, uma viatura da PM fazia rondas pela regi\u00e3o do Jardim Sumar\u00e9\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-12-at-10.02.15.jpeg?fit=1200%2C803&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-12-at-10.02.15.jpeg?fit=1200%2C803&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-12-at-10.02.15.jpeg?fit=1200%2C803&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-12-at-10.02.15.jpeg?fit=1200%2C803&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-12-at-10.02.15.jpeg?fit=1200%2C803&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":9178,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/01\/utm_sourcerssutm_mediumrssutm_campaignvalentao-e-preso-apos-tentar-matar-a-ex-gravida-em-rp\/","url_meta":{"origin":28246,"position":3},"title":"Valent\u00e3o \u00e9 preso ap\u00f3s tentar matar a ex gr\u00e1vida em RP \u2013 X Tudo Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"1 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Um homem foi preso pela Pol\u00edcia Militar na tarde desta sexta-feira (1\/12), ap\u00f3s tentar matar sua ex-mulher gr\u00e1vida de 4 meses a paulada na Favela do SBT, na zona Oeste de Ribeir\u00e3o Preto. Segundo informa\u00e7\u00f5es preliminares da PM, populares acionaram os Policiais versando sobre um fato, onde uma mulher\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/28d53e90-3eab-40b4-a308-082b2c2a22f3.jpeg?fit=1200%2C897&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/28d53e90-3eab-40b4-a308-082b2c2a22f3.jpeg?fit=1200%2C897&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/28d53e90-3eab-40b4-a308-082b2c2a22f3.jpeg?fit=1200%2C897&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/28d53e90-3eab-40b4-a308-082b2c2a22f3.jpeg?fit=1200%2C897&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/28d53e90-3eab-40b4-a308-082b2c2a22f3.jpeg?fit=1200%2C897&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":48340,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/02\/homem-e-preso-acusado-de-matar-esposa-apos-ela-recusar-fazer-almoco-na-regiao-de-ribeirao\/","url_meta":{"origin":28246,"position":4},"title":"Homem \u00e9 preso acusado de matar esposa ap\u00f3s ela recusar fazer almo\u00e7o na regi\u00e3o de Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"2 de Maio de 2024","format":false,"excerpt":"[ad_1] Um homem de 53 anos foi preso suspeito de matar a esposa com uma garrucha nesta quarta-feira (1\u00ba), em um s\u00edtio de Santo Ant\u00f4nio da Alegria, cidade a aproximadamente 90 quil\u00f4metros de Ribeir\u00e3o Preto. Segundo o boletim de ocorr\u00eancia (BO), a v\u00edtima, identificada como Clarice Marciano da Silva, de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-02-at-11.51.13_2024-05-02_15-02-15_jpeg_2024-05-02_15-02-15.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-02-at-11.51.13_2024-05-02_15-02-15_jpeg_2024-05-02_15-02-15.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-02-at-11.51.13_2024-05-02_15-02-15_jpeg_2024-05-02_15-02-15.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-02-at-11.51.13_2024-05-02_15-02-15_jpeg_2024-05-02_15-02-15.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-02-at-11.51.13_2024-05-02_15-02-15_jpeg_2024-05-02_15-02-15.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":52787,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/10\/homem-e-denunciado-apos-espancar-gata-e-filmar-para-a-esposa-na-regiao-de-ribeirao\/","url_meta":{"origin":28246,"position":5},"title":"Homem \u00e9 denunciado ap\u00f3s espancar gata e filmar para a esposa na regi\u00e3o de Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"10 de Junho de 2024","format":false,"excerpt":"[ad_1] A Pol\u00edcia Civil investiga um homem de Franca, cidade na regi\u00e3o de Ribeir\u00e3o Preto, ap\u00f3s um v\u00eddeo em que ele aparece espancando uma gata, de sete meses, circular nas redes sociais \u2013 veja o v\u00eddeo abaixo (imagens fortes). De acordo com o boletim de ocorr\u00eancia (BO), a Guarda Municipal\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-73_2024-06-10_23-23-10_png_2024-06-10_23-23-10.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-73_2024-06-10_23-23-10_png_2024-06-10_23-23-10.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-73_2024-06-10_23-23-10_png_2024-06-10_23-23-10.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-73_2024-06-10_23-23-10_png_2024-06-10_23-23-10.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-73_2024-06-10_23-23-10_png_2024-06-10_23-23-10.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-7lA","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/28246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=28246"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/28246\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/28247"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=28246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=28246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=28246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}