{"id":27349,"date":"2024-01-12T01:28:55","date_gmt":"2024-01-12T04:28:55","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/12\/producao-agricola-deve-recuar\/"},"modified":"2024-01-12T01:28:55","modified_gmt":"2024-01-12T04:28:55","slug":"producao-agricola-deve-recuar","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/12\/producao-agricola-deve-recuar\/","title":{"rendered":"Produ\u00e7\u00e3o agr\u00edcola deve recuar \u00a0"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p><span class=\"TextRun SCXW201771521 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW201771521 BCX0\">A Companhia Nacional de Abastecimento e o Instituto Brasileiro de Geografia e Estat\u00edstica divulgaram nesta qu<\/span><span class=\"NormalTextRun SCXW201771521 BCX0\">ar<\/span><span class=\"NormalTextRun SCXW201771521 BCX0\">ta-feira, <\/span><span class=\"NormalTextRun SCXW201771521 BCX0\">10 de janeiro<\/span><span class=\"NormalTextRun SCXW201771521 BCX0\">, suas proje\u00e7\u00f5es para a safra de gr\u00e3os<\/span><span class=\"NormalTextRun SCXW201771521 BCX0\"> 2023\/24<\/span><span class=\"NormalTextRun SCXW201771521 BCX0\">. Segundo a <\/span><\/span><span class=\"TextRun SCXW201771521 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW201771521 BCX0\">Conab, os produtores brasileiros dever\u00e3o colher <\/span><span class=\"NormalTextRun SCXW201771521 BCX0\">306,37 milh\u00f5es de toneladas, o que corresponde a uma queda de 4,2%, ou 13,5 milh\u00f5es de t a menos, em compara\u00e7\u00e3o com a temporada anterior 2022\/23, que foi de 319,86 milh\u00f5es de t<\/span><span class=\"NormalTextRun SCXW201771521 BCX0\">. <\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW201771521 BCX0\"><span class=\"SCXW201771521 BCX0\">\u00a0<\/span><br class=\"SCXW201771521 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW201771521 BCX0\"><span class=\"SCXW201771521 BCX0\">\u00a0<\/span><br class=\"SCXW201771521 BCX0\"\/><\/span><span class=\"TextRun SCXW201771521 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW201771521 BCX0\">J\u00e1 o <\/span><span class=\"NormalTextRun SCXW201771521 BCX0\">IBGE projeta 306,5 milh\u00f5es de toneladas, recuo de 2,8% em 2024.<\/span><span class=\"NormalTextRun SCXW201771521 BCX0\"> Por\u00e9m, prev\u00ea <\/span><span class=\"NormalTextRun SCXW201771521 BCX0\">recorde de 315,4 milh\u00f5es de <\/span><span class=\"NormalTextRun ContextualSpellingAndGrammarErrorV2Themed SCXW201771521 BCX0\">t<\/span> <span class=\"NormalTextRun ContextualSpellingAndGrammarErrorV2Themed SCXW201771521 BCX0\">em<\/span><span class=\"NormalTextRun SCXW201771521 BCX0\"> 2023, <\/span><span class=\"NormalTextRun SCXW201771521 BCX0\">alta de <\/span><span class=\"NormalTextRun SCXW201771521 BCX0\">19,8%<\/span><span class=\"NormalTextRun SCXW201771521 BCX0\">. <\/span><span class=\"NormalTextRun SCXW201771521 BCX0\">Os n\u00fameros <\/span><span class=\"NormalTextRun SCXW201771521 BCX0\">da Conab <\/span><span class=\"NormalTextRun SCXW201771521 BCX0\">fazem parte do 4\u00ba Levantamento para a safra 2023\/24. Em compara\u00e7\u00e3o com a pesquisa anterior, de dezembro, houve uma queda de 1,9%, ou 5,93 milh\u00f5es de t.<\/span> <\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW201771521 BCX0\"><span class=\"SCXW201771521 BCX0\">\u00a0<\/span><br class=\"SCXW201771521 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW201771521 BCX0\"><span class=\"SCXW201771521 BCX0\">\u00a0<\/span><br class=\"SCXW201771521 BCX0\"\/><\/span><span class=\"TextRun SCXW201771521 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW201771521 BCX0\">Conforme comunicado da Conab, no geral, as condi\u00e7\u00f5es clim\u00e1ticas inst\u00e1veis, com chuvas escassas e mal distribu\u00eddas aliadas a altas temperaturas na regi\u00e3o central do <\/span><span class=\"NormalTextRun SCXW201771521 BCX0\">p<\/span><span class=\"NormalTextRun SCXW201771521 BCX0\">a\u00eds, al\u00e9m de precipita\u00e7\u00f5es volumosas na regi\u00e3o <\/span><span class=\"NormalTextRun SCXW201771521 BCX0\">Sul, provocaram<\/span><span class=\"NormalTextRun SCXW201771521 BCX0\"> e ainda persistem no atraso do plantio da safra, al\u00e9m de influenciarem de maneira negativa no potencial produtivo das lavouras.<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW201771521 BCX0\"><span class=\"SCXW201771521 BCX0\">\u00a0<\/span><br class=\"SCXW201771521 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW201771521 BCX0\"><span class=\"SCXW201771521 BCX0\">\u00a0<\/span><br class=\"SCXW201771521 BCX0\"\/><\/span><span class=\"TextRun SCXW201771521 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW201771521 BCX0\">Em rela\u00e7\u00e3o \u00e0 inten\u00e7\u00e3o de plantio, o levantamento da Conab estima \u00e1rea de 78,78 milh\u00f5es de hectares na safra 2023\/24, com pequeno aumento de 0,3% em compara\u00e7\u00e3o com a safra anterior (78,55 milh\u00f5es de hectares).<\/span> <span class=\"NormalTextRun SCXW201771521 BCX0\">Principal cultura cultivada no <\/span><span class=\"NormalTextRun SCXW201771521 BCX0\">p<\/span><span class=\"NormalTextRun SCXW201771521 BCX0\">a\u00eds, a soja deve apresentar uma produ\u00e7\u00e3o de 155,27 milh\u00f5es de toneladas, representando uma quebra de 4,2% na expectativa, uma vez que as primeiras proje\u00e7\u00f5es apontavam para uma colheita de 162 milh\u00f5es de toneladas. <\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW201771521 BCX0\"><span class=\"SCXW201771521 BCX0\">\u00a0<\/span><br class=\"SCXW201771521 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW201771521 BCX0\"><span class=\"SCXW201771521 BCX0\">\u00a0<\/span><br class=\"SCXW201771521 BCX0\"\/><\/span><span class=\"TextRun SCXW201771521 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW201771521 BCX0\">Em rela\u00e7\u00e3o \u00e0 temporada anterior (154,61 milh\u00f5es de t), a proje\u00e7\u00e3o \u00e9 de pequeno aumento de 0,4%.<\/span> <span class=\"NormalTextRun SCXW201771521 BCX0\">Segundo a Conab, chuvas mal distribu\u00eddas e temperaturas elevadas influenciaram de maneira negativa tanto no plantio como no desenvolvimento das lavouras. As condi\u00e7\u00f5es clim\u00e1ticas tamb\u00e9m foram determinantes para alguns produtores migrarem para outras culturas, contribuindo para a redu\u00e7\u00e3o da \u00e1rea em rela\u00e7\u00e3o ao levantamento divulgado em dezembro.<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW201771521 BCX0\"><span class=\"SCXW201771521 BCX0\">\u00a0<\/span><br class=\"SCXW201771521 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW201771521 BCX0\"><span class=\"SCXW201771521 BCX0\">\u00a0<\/span><br class=\"SCXW201771521 BCX0\"\/><\/span><span class=\"TextRun SCXW201771521 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW201771521 BCX0\">No caso do milho, a produ\u00e7\u00e3o total est\u00e1 estimada em 117,60 milh\u00f5es de toneladas, redu\u00e7\u00e3o de 10,9% em rela\u00e7\u00e3o ao ciclo anterior (131,85 milh\u00f5es de t). A queda \u00e9 <\/span><span class=\"NormalTextRun SCXW201771521 BCX0\">reflexo de uma menor \u00e1rea plantada<\/span><span class=\"NormalTextRun SCXW201771521 BCX0\"> e de uma piora na expectativa de rendimento das lavouras, disse a Conab. A primeira safra do cereal, que representa 20,7% da produ\u00e7\u00e3o, vem passando por situa\u00e7\u00f5es adversas como, elevadas precipita\u00e7\u00f5es nos estados do Sul, baixa pluviosidade acompanhada pelas altas temperaturas no Centro-Oeste.<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW201771521 BCX0\"><span class=\"SCXW201771521 BCX0\">\u00a0<\/span><br class=\"SCXW201771521 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW201771521 BCX0\"><span class=\"SCXW201771521 BCX0\">\u00a0<\/span><br class=\"SCXW201771521 BCX0\"\/><\/span><span class=\"TextRun SCXW201771521 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW201771521 BCX0\">A primeira safra, ou de ver\u00e3o, est\u00e1 projetada em 24,38 milh\u00f5es de t, queda de 10,9% ante o per\u00edodo anterior (27,37 milh\u00f5es de t). A Conab estima a segunda safra do cereal em 91,24 milh\u00f5es de t, tamb\u00e9m queda de 10,9% ante a safra anterior (102,37 milh\u00f5es de t).<\/span> <\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW201771521 BCX0\"><span class=\"SCXW201771521 BCX0\">\u00a0<\/span><br class=\"SCXW201771521 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW201771521 BCX0\"><span class=\"SCXW201771521 BCX0\">\u00a0<\/span><br class=\"SCXW201771521 BCX0\"\/><\/span><span class=\"TextRun SCXW201771521 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW201771521 BCX0\">No casado do algod\u00e3o, \u00e9 esperado um crescimento na \u00e1rea cultivada de 6,2% sobre a safra 2022\/23. Com a semeadura se aproximando de 32% no <\/span><span class=\"NormalTextRun SCXW201771521 BCX0\">p<\/span><span class=\"NormalTextRun SCXW201771521 BCX0\">a\u00eds, de acordo com a Conab, a \u00e1rea estimada em cerca de <\/span><span class=\"NormalTextRun SCXW201771521 BCX0\">1,77 milh\u00e3o<\/span><span class=\"NormalTextRun SCXW201771521 BCX0\"> de hectares poder\u00e1 variar, j\u00e1 que parte da \u00e1rea que deveria ser replantada com soja em Mato Grosso poder\u00e1 ser utilizada com o plantio da fibra. Atualmente a proje\u00e7\u00e3o \u00e9 de uma colheita de 3,10 milh\u00f5es de toneladas de pluma, queda de 2,3% em compara\u00e7\u00e3o com 2022\/23 (3,17 milh\u00f5es de t).<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW201771521 BCX0\"><span class=\"SCXW201771521 BCX0\">\u00a0<\/span><br class=\"SCXW201771521 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW201771521 BCX0\"><span class=\"SCXW201771521 BCX0\">\u00a0<\/span><br class=\"SCXW201771521 BCX0\"\/><\/span><span class=\"TextRun SCXW201771521 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW201771521 BCX0\">Outro importante produto para os brasileiros, o arroz tem uma estimativa de produ\u00e7\u00e3o de 10,76 milh\u00f5es de toneladas, aumento de 7,2% ante 2022\/23 (10,03 milh\u00f5es de t). <\/span><span class=\"NormalTextRun SCXW201771521 BCX0\">P<\/span><span class=\"NormalTextRun SCXW201771521 BCX0\">ara o feij\u00e3o \u00e9 esperada uma estabilidade na produ\u00e7\u00e3o, quando se compara com a safra passada, alcan\u00e7ando colheita de 3,03 milh\u00f5es de toneladas, leve queda de 0,2% ante 2022\/23 (3,04 milh\u00f5es de t). <\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW201771521 BCX0\"><span class=\"SCXW201771521 BCX0\">\u00a0<\/span><br class=\"SCXW201771521 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW201771521 BCX0\"><span class=\"SCXW201771521 BCX0\">\u00a0<\/span><br class=\"SCXW201771521 BCX0\"\/><\/span><span class=\"TextRun SCXW201771521 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW201771521 BCX0\">Por\u00e9m, o plantio da primeira safra da leguminosa caminha para a conclus\u00e3o e vem apresentando <\/span><span class=\"NormalTextRun SCXW201771521 BCX0\">altera\u00e7\u00f5es negativas, por causa da instabilidade do clima, observou<\/span><span class=\"NormalTextRun SCXW201771521 BCX0\"> a estatal.<\/span> <span class=\"NormalTextRun SCXW201771521 BCX0\">Com a colheita encerrada, o trigo registra uma produ\u00e7\u00e3o de 8,1 milh\u00f5es de toneladas. At\u00e9 o in\u00edcio da fase reprodutiva, as condi\u00e7\u00f5es clim\u00e1ticas vinham beneficiando a cultura, com perspectivas de uma safra recorde semelhante \u00e0 de 2022. <\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW201771521 BCX0\"><span class=\"SCXW201771521 BCX0\">\u00a0<\/span><br class=\"SCXW201771521 BCX0\"\/><\/span><\/p>\n<\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/site\/producao-agricola-deve-recuar\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] A Companhia Nacional de Abastecimento e o Instituto Brasileiro de Geografia e Estat\u00edstica divulgaram nesta quarta-feira, 10 de janeiro, suas proje\u00e7\u00f5es para a safra de gr\u00e3os 2023\/24. Segundo a Conab, os produtores brasileiros dever\u00e3o colher 306,37 milh\u00f5es de toneladas, o que corresponde a uma queda de 4,2%, ou 13,5 milh\u00f5es de t a menos, &#8230; <a title=\"Produ\u00e7\u00e3o agr\u00edcola deve recuar \u00a0\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/12\/producao-agricola-deve-recuar\/\" aria-label=\"Leia mais sobre Produ\u00e7\u00e3o agr\u00edcola deve recuar \u00a0\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":27350,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[3421,239,1312,3422],"class_list":["post-27349","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-agricola","tag-deve","tag-producao","tag-recuar"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Safra-Wenderson-Araujo-Trilux-CNA-scaled.jpg?fit=1000%2C591&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Safra-Wenderson-Araujo-Trilux-CNA-scaled.jpg?fit=1000%2C591&ssl=1",1000,591,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Safra-Wenderson-Araujo-Trilux-CNA-scaled.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Safra-Wenderson-Araujo-Trilux-CNA-scaled.jpg?fit=300%2C177&ssl=1",300,177,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Safra-Wenderson-Araujo-Trilux-CNA-scaled.jpg?fit=768%2C454&ssl=1",768,454,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Safra-Wenderson-Araujo-Trilux-CNA-scaled.jpg?fit=1000%2C591&ssl=1",1000,591,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Safra-Wenderson-Araujo-Trilux-CNA-scaled.jpg?fit=1000%2C591&ssl=1",1000,591,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Safra-Wenderson-Araujo-Trilux-CNA-scaled.jpg?fit=1000%2C591&ssl=1",1000,591,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] A Companhia Nacional de Abastecimento e o Instituto Brasileiro de Geografia e Estat\u00edstica divulgaram nesta quarta-feira, 10 de janeiro, suas proje\u00e7\u00f5es para a safra de gr\u00e3os 2023\/24. Segundo a Conab, os produtores brasileiros dever\u00e3o colher 306,37 milh\u00f5es de toneladas, o que corresponde a uma queda de 4,2%, ou 13,5 milh\u00f5es de t a menos,&hellip;","jetpack-related-posts":[{"id":53719,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/19\/aniversario-de-ribeirao-preto-entenda-a-importancia-do-agronegocio-para-a-cidade\/","url_meta":{"origin":27349,"position":0},"title":"Anivers\u00e1rio de Ribeir\u00e3o Preto: Entenda a import\u00e2ncia do agroneg\u00f3cio para a cidade","author":"ismaelcolosi.com.br","date":"19 de Junho de 2024","format":false,"excerpt":"[ad_1] Reconhecida como a \u201cCapital Brasileira do Agroneg\u00f3cio\u201d h\u00e1 20 anos, Ribeir\u00e3o Preto tem papel fundamental para o setor no \u00e2mbito nacional, tornando-se um dos polos mais importantes de agroind\u00fastria do Pa\u00eds devido a produtividade e inova\u00e7\u00e3o. Com a popula\u00e7\u00e3o de 698.642 habitantes e uma \u00e1rea territorial de 650.916 km\u00b2,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/12_2024-06-14_19-51-16_jpg_2024-06-14_19-51-16.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/12_2024-06-14_19-51-16_jpg_2024-06-14_19-51-16.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/12_2024-06-14_19-51-16_jpg_2024-06-14_19-51-16.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/12_2024-06-14_19-51-16_jpg_2024-06-14_19-51-16.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/12_2024-06-14_19-51-16_jpg_2024-06-14_19-51-16.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":71736,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/17\/veja-qual-cidade-da-regiao-de-ribeirao-preto-aparece-em-lista-das-mais-ricas-do-agro\/","url_meta":{"origin":27349,"position":1},"title":"Veja qual cidade da regi\u00e3o de Ribeir\u00e3o Preto aparece em lista das mais ricas do agro","author":"ismaelcolosi.com.br","date":"17 de Outubro de 2024","format":false,"excerpt":"[ad_1] O Minist\u00e9rio da Agricultura e Pecu\u00e1ria divulgou nesta quinta-feira (17) a lista com os 100 munic\u00edpios mais ricos do Brasil no agroneg\u00f3cio. A an\u00e1lise se baseia nos dados da pesquisa anual do IBGE (Instituto Brasileiro de Geografia e Estat\u00edstica) sobre a Produ\u00e7\u00e3o Agr\u00edcola Municipal. A \u00fanica cidade da regi\u00e3o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/ibis-barretos_2024-09-28_16-26-03_jpg_2024-09-28_16-26-03.webp.webp?fit=960%2C637&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/ibis-barretos_2024-09-28_16-26-03_jpg_2024-09-28_16-26-03.webp.webp?fit=960%2C637&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/ibis-barretos_2024-09-28_16-26-03_jpg_2024-09-28_16-26-03.webp.webp?fit=960%2C637&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/ibis-barretos_2024-09-28_16-26-03_jpg_2024-09-28_16-26-03.webp.webp?fit=960%2C637&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":15438,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/13\/volume-de-servicos-recua-06-em-outubro-revela-ibge\/","url_meta":{"origin":27349,"position":2},"title":"Volume de servi\u00e7os recua 0,6% em outubro, revela IBGE \u2013 Folha de Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"13 de Dezembro de 2023","format":false,"excerpt":"[ad_1] O volume de servi\u00e7os no pa\u00eds caiu 0,6% em outubro deste ano, na compara\u00e7\u00e3o com setembro. Essa foi a terceira queda consecutiva do indicador, que acumula perdas de 2,3% em tr\u00eas meses. Os dados s\u00e3o da Pesquisa Mensal de Servi\u00e7os (PMS), divulgada nesta quarta-feira (13), no Rio de Janeiro,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":84966,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/04\/29\/vagas-de-emprego-em-aberto-nos-eua-recuam-em-marco\/","url_meta":{"origin":27349,"position":3},"title":"Vagas de Emprego em Aberto nos EUA Recuam em Mar\u00e7o","author":"ismaelcolosi.com.br","date":"29 de Abril de 2025","format":false,"excerpt":"[ad_1] \r Getty Images\r Contrata\u00e7\u00f5es aumentaram em apenas 41.000, para 5,411 milh\u00f5es\r Acessibilidade \r L\r L\r A-\r A+\r \r \u25d0\r \r \u00a0 As vagas de emprego em aberto nos Estados Unidos ca\u00edram de forma acentuada em mar\u00e7o, mas um decl\u00ednio nas demiss\u00f5es sugeriu que o mercado de trabalho permaneceu em\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/04\/forbes-escritorio-trabalho-emprego-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/04\/forbes-escritorio-trabalho-emprego-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/04\/forbes-escritorio-trabalho-emprego-1200x675.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/04\/forbes-escritorio-trabalho-emprego-1200x675.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/04\/forbes-escritorio-trabalho-emprego-1200x675.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":42609,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/15\/vendas-na-pascoa-devem-ser-recorde\/","url_meta":{"origin":27349,"position":4},"title":"Vendas na P\u00e1scoa devem ser recorde\u00a0","author":"ismaelcolosi.com.br","date":"15 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] 15 de mar\u00e7o de 2024 | 15:0015 de mar\u00e7o de 2024 | 11:07 0O varejo brasileiro deve alcan\u00e7ar um recorde de vendas na P\u00e1scoa deste ano. O volume vendido deve totalizar R$ 3,44 bilh\u00f5es, o que representaria um crescimento de 4,5% em rela\u00e7\u00e3o \u00e0 mesma data do ano passado,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Pascoa-cHO-Marcelo-Camargo-Ag.Br_-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Pascoa-cHO-Marcelo-Camargo-Ag.Br_-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Pascoa-cHO-Marcelo-Camargo-Ag.Br_-scaled.jpg?fit=1000%2C598&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/Pascoa-cHO-Marcelo-Camargo-Ag.Br_-scaled.jpg?fit=1000%2C598&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":86880,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/07\/31\/taxa-de-desemprego-do-brasil-cai-a-58-no-2o-tri-e-vai-ao-menor-nivel-da-serie-renda-e-recorde\/","url_meta":{"origin":27349,"position":5},"title":"Taxa de Desemprego do Brasil Cai a 5,8% no 2\u00ba Tri e Vai Ao Menor N\u00edvel da S\u00e9rie; Renda \u00c9 Recorde","author":"ismaelcolosi.com.br","date":"31 de Julho de 2025","format":false,"excerpt":"[ad_1] \r RUNSTUDIO\/Getty Images\r No mesmo per\u00edodo do ano anterior, a taxa de desemprego foi de 6,9%\r Acessibilidade \r L\r L\r A-\r A+\r \r \u25d0\r \r A taxa de desemprego brasileira recuou mais do que o esperado e foi a 5,8% no segundo trimestre, marcando o resultado mais baixo na\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/07\/money-demissao-desemprego-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/07\/money-demissao-desemprego-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/07\/money-demissao-desemprego-1200x675.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/07\/money-demissao-desemprego-1200x675.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/07\/money-demissao-desemprego-1200x675.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-777","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=27349"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27349\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/27350"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=27349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=27349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=27349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}