{"id":27291,"date":"2024-01-11T22:21:03","date_gmt":"2024-01-12T01:21:03","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/11\/porque-homem-que-comeu-manga-encontrada-no-chao-ficou-em-estado-critico-desenganado\/"},"modified":"2024-01-11T22:21:03","modified_gmt":"2024-01-12T01:21:03","slug":"porque-homem-que-comeu-manga-encontrada-no-chao-ficou-em-estado-critico-desenganado","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/11\/porque-homem-que-comeu-manga-encontrada-no-chao-ficou-em-estado-critico-desenganado\/","title":{"rendered":"Porque homem que comeu manga encontrada no ch\u00e3o ficou em estado cr\u00edtico: \u2018Desenganado\u2019"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div itemprop=\"text\">\n<p>Este caso serve de alerta para milhares de pessoas em todo o Brasil que n\u00e3o resiste ao ver uma fruta madura no ch\u00e3o. Um condutor de caminh\u00e3o, de 53 anos, encontra-se em estado grave ap\u00f3s contrair leptospirose, cujos sintomas se manifestaram ap\u00f3s o consumo de uma manga.<\/p>\n<p>De acordo com informa\u00e7\u00f5es repassadas sobre o caso ele pegou a fruta do ch\u00e3o e a descascou com a boca, sem realizar a devida lavagem. Roberto Luiz expressa gratid\u00e3o por estar vivo, considerando um verdadeiro \u201cmilagre\u201d, pois os m\u00e9dicos inicialmente n\u00e3o tinham confian\u00e7a em sua recupera\u00e7\u00e3o.<\/p><div class='code-block code-block-8' style='margin: 8px auto; text-align: center; display: block; clear: both;'>\n<script>\n  atOptions = {\n    'key' : '66e2e2111ca34da796271819fc334058',\n    'format' : 'iframe',\n    'height' : 250,\n    'width' : 300,\n    'params' : {}\n  };\n<\/script>\n<script src=\"https:\/\/www.highperformanceformat.com\/66e2e2111ca34da796271819fc334058\/invoke.js\"><\/script>\n<\/div>\n\n<p>A leptospirose, resultante da presen\u00e7a de bact\u00e9rias pertencentes ao g\u00eanero Leptospira, comumente \u00e9 transmitida atrav\u00e9s da urina de animais infectados, como roedores, que pode causar severos impactos na sa\u00fade como foi no caso de Roberto.<\/p>\n<p>O condutor ficou em estado cr\u00edtico e precisou submeter-se \u00e0 hemodi\u00e1lise, ele chegou a ser informado que seus \u00f3rg\u00e3os come\u00e7aram a apresentar falhas. \u201cEu estava desenganado\u201d, ressaltou Roberto.<\/p>\n<p>No dia 7 de dezembro, \u00e0s margens da Rodovia Washington Lu\u00eds, durante uma parada na estrada durante sua viagem de volta para Santos, no litoral de S\u00e3o Paulo, ap\u00f3s entregar uma carga no interior paulista, ele consumiu a fruta.<\/p>\n<p>Dois dias depois, j\u00e1 em casa, come\u00e7aram a surgir sintomas como febre, dores musculares e v\u00f4mitos. Em 12 de dezembro, precisou retornar \u00e0 estrada para transportar uma nova carga ao interior do estado, em comboio com outros motoristas.<\/p>\n<p>Ao longo do percurso, sua condi\u00e7\u00e3o se deteriorou, as dores intensificaram-se, e ele come\u00e7ou a vomitar dentro da carreta, nesta ocasi\u00e3o, o motorista n\u00e3o conseguia sequer ficar de p\u00e9 e foi socorrido pelos colegas de profiss\u00e3o.<\/p>\n<p>O homem foi levado para uma unidade de sa\u00fade de Ilha Solteira, localizada no interior do estado paulista, l\u00e1 foi medicado e liberado em seguida. Quando chegou na cidade de Santos, que fica no litoral do estado de S\u00e3o Paulo, no mesmo dia 12 de dezembro, ele voltou a buscar ajuda m\u00e9dica e desta vez foi diagnosticado com dengue.<\/p>\n<p>Contudo, os sintomas pioraram, ele foi achacado com febre alta e dores nos m\u00fasculos. Em 16 de dezembro, j\u00e1 internado na Santa Casa de Santos, a equipe m\u00e9dica repetiu todos os exames diante do agravamento do quadro.<\/p>\n<p>Em meio a isso, um m\u00e9dico indagou se o paciente havia enfrentado uma enchente ou consumido bebidas de latas. Foi nesse momento que ele recordou o incidente com a manga, o que auxiliou na compreens\u00e3o do que poderia ter desencadeado os sintomas.<\/p>\n<p>O diagn\u00f3stico foi demorado por parte dos m\u00e9dicos, e durante o tratamento, o paciente chegou a ouvir previs\u00f5es desanimadoras sobre sua recupera\u00e7\u00e3o: <strong>\u201cTeu f\u00edgado parou, teus rins pararam. Tu quer saber mais o qu\u00ea? Teus \u00f3rg\u00e3os est\u00e3o parando. U\u00e9, cara, n\u00e3o tem o que falar para ti. N\u00e3o tem o que te passar de melhor, n\u00e3o tem mais o que fazer\u201d<\/strong><i>.<\/i><\/p>\n<p>Foi somente no dia 21 de dezembro, que os \u00f3rg\u00e3os de Roberto come\u00e7aram a responder ao tratamento. A recupera\u00e7\u00e3o do motorista surpreendeu a toda equipe m\u00e9dica.<\/p>\n<figure style=\"width: 974px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/fnmais.com\/wp-content\/uploads\/2024\/01\/postiimg-65a09296345515167.jpg?resize=984%2C656&#038;ssl=1\" alt=\"Roberto com a esposa Elizngela e com a filha Morenna Clara no hospital em Santos SP Foto Arquivo pessoal\" width=\"984\" height=\"656\"\/><figcaption class=\"wp-caption-text\">(Roberto com a esposa, Eliz\u00e2ngela, e com a filha, Morenna Clara, no hospital em Santos (SP) \u2014 Foto: Arquivo pessoal)<\/figcaption><\/figure>\n<p>\u00a0<\/p>\n<p>Ele afirmou que colheu muitas mangas no ch\u00e3o, colocou em uma sacola e seguiu a viagem consumindo as frutas, sem se preocupar com a higieniza\u00e7\u00e3o como havia feito por diversas vezes em sua vida.<\/p>\n<\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/fnmais.com\/porque-homem-que-comeu-manga-encontrada-no-chao-ficou-em-estado-critico-desenganado\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Este caso serve de alerta para milhares de pessoas em todo o Brasil que n\u00e3o resiste ao ver uma fruta madura no ch\u00e3o. Um condutor de caminh\u00e3o, de 53 anos, encontra-se em estado grave ap\u00f3s contrair leptospirose, cujos sintomas se manifestaram ap\u00f3s o consumo de uma manga. De acordo com informa\u00e7\u00f5es repassadas sobre o &#8230; <a title=\"Porque homem que comeu manga encontrada no ch\u00e3o ficou em estado cr\u00edtico: \u2018Desenganado\u2019\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/11\/porque-homem-que-comeu-manga-encontrada-no-chao-ficou-em-estado-critico-desenganado\/\" aria-label=\"Read more about Porque homem que comeu manga encontrada no ch\u00e3o ficou em estado cr\u00edtico: \u2018Desenganado\u2019\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":27292,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-27291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a0929889aee3156.jpg?fit=1200%2C628&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a0929889aee3156.jpg?fit=1200%2C628&ssl=1",1200,628,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a0929889aee3156.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a0929889aee3156.jpg?fit=300%2C157&ssl=1",300,157,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a0929889aee3156.jpg?fit=768%2C402&ssl=1",768,402,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a0929889aee3156.jpg?fit=1024%2C536&ssl=1",1024,536,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a0929889aee3156.jpg?fit=1200%2C628&ssl=1",1200,628,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a0929889aee3156.jpg?fit=1200%2C628&ssl=1",1200,628,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Este caso serve de alerta para milhares de pessoas em todo o Brasil que n\u00e3o resiste ao ver uma fruta madura no ch\u00e3o. Um condutor de caminh\u00e3o, de 53 anos, encontra-se em estado grave ap\u00f3s contrair leptospirose, cujos sintomas se manifestaram ap\u00f3s o consumo de uma manga. De acordo com informa\u00e7\u00f5es repassadas sobre o&hellip;","jetpack-related-posts":[{"id":27641,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/12\/defesa-civil-de-ribeirao-alerta-para-os-cuidados-durante-tempestades\/","url_meta":{"origin":27291,"position":0},"title":"Defesa civil de Ribeir\u00e3o alerta para os cuidados durante tempestades","author":"ismaelcolosi.com.br","date":"12 de January de 2024","format":false,"excerpt":"[ad_1] 12 de janeiro de 2024 | 16:14 0Os servi\u00e7os de meteorologia est\u00e3o emitindo alertas para fortes chuvas que podem atingir Ribeir\u00e3o Preto e regi\u00e3o. A passagem de uma frente fria criar\u00e1 condi\u00e7\u00f5es para pancadas de chuvas, al\u00e9m de intensas rajadas de ventos. Entre a tarde de sexta-feira, 12, at\u00e9\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/dicas_defesa_civil_-_foto_fernando_gonzaga-scaled.jpeg?fit=860%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/dicas_defesa_civil_-_foto_fernando_gonzaga-scaled.jpeg?fit=860%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/dicas_defesa_civil_-_foto_fernando_gonzaga-scaled.jpeg?fit=860%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/dicas_defesa_civil_-_foto_fernando_gonzaga-scaled.jpeg?fit=860%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":33378,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/29\/mulher-morre-apos-cair-em-festa-de-aniversario-na-regiao-de-ribeirao-preto\/","url_meta":{"origin":27291,"position":1},"title":"Mulher morre ap\u00f3s cair em festa de anivers\u00e1rio na regi\u00e3o de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"29 de January de 2024","format":false,"excerpt":"[ad_1] Uma mulher de 43 anos morreu na madrugada do \u00faltimo s\u00e1bado (27) ap\u00f3s cair com o rosto no ch\u00e3o em uma festa de anivers\u00e1rio em Santa Rosa de Viterbo, na regi\u00e3o de Ribeir\u00e3o Preto. O caso foi registrado como morte suspeita, sem causa determinante aparente. De acordo com o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/iml-ribeirao-preto.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/iml-ribeirao-preto.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/iml-ribeirao-preto.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/iml-ribeirao-preto.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/iml-ribeirao-preto.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":18401,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/20\/mulher-perde-a-vida-ao-cair-de-roda-gigante-e-momento-da-queda-e-gravado\/","url_meta":{"origin":27291,"position":2},"title":"mulher perde a vida ao cair de roda gigante e momento da queda \u00e9 gravado","author":"ismaelcolosi.com.br","date":"20 de December de 2023","format":false,"excerpt":"[ad_1] Uma mulher de 49 anos acabou perdendo a vida no come\u00e7o desta semana ap\u00f3s brincar em uma roda gigante que fica situada em um restaurante na zona rural de Barbacena, no estado de Minas Gerais.O tr\u00e1gico epis\u00f3dio ocorreu no \u00faltimo domingo (17\/12) e agora est\u00e1 sendo investigado pela pol\u00edcia.\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6582eba5cf7827711.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6582eba5cf7827711.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6582eba5cf7827711.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6582eba5cf7827711.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6582eba5cf7827711.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":48746,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/06\/promotor-de-justica-de-ribeirao-preto-e-suspeito-de-agredir-esposa-gravida\/","url_meta":{"origin":27291,"position":3},"title":"Promotor de Justi\u00e7a de Ribeir\u00e3o Preto \u00e9 suspeito de agredir esposa gr\u00e1vida","author":"ismaelcolosi.com.br","date":"6 de May de 2024","format":false,"excerpt":"[ad_1] O promotor de Justi\u00e7a de Ribeir\u00e3o Preto Wanderley Trindade Junior \u00e9 suspeito de agredir com socos e chutes a mulher com quem vive em uni\u00e3o est\u00e1vel h\u00e1 quatro anos e est\u00e1 gr\u00e1vida de seis meses. O caso ocorreu no s\u00e1bado (4) em um s\u00edtio que fica em Cravinhos, na\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-38_2024-05-06_14-50-35_jpg_2024-05-06_14-50-35.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-38_2024-05-06_14-50-35_jpg_2024-05-06_14-50-35.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-38_2024-05-06_14-50-35_jpg_2024-05-06_14-50-35.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-38_2024-05-06_14-50-35_jpg_2024-05-06_14-50-35.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-38_2024-05-06_14-50-35_jpg_2024-05-06_14-50-35.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":48167,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/01\/homem-fica-em-estado-grave-apos-ser-esfaqueado-em-ribeirao-preto\/","url_meta":{"origin":27291,"position":4},"title":"Homem fica em estado grave ap\u00f3s ser esfaqueado em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"1 de May de 2024","format":false,"excerpt":"[ad_1] Um homem de 20 anos foi internado em estado grave ap\u00f3s ter sido esfaqueado na avenida Caramuru, em Ribeir\u00e3o Preto, na madrugada desta quarta-feira (1\u00ba de maio). Um suspeito foi preso com a arma que teria sido utilizada no crime. O caso aconteceu perto do cruzamento com a rua\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2023-12-09-at-13.55.44.jpeg?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2023-12-09-at-13.55.44.jpeg?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2023-12-09-at-13.55.44.jpeg?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2023-12-09-at-13.55.44.jpeg?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":21821,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/28\/quem-e-o-jovem-que-perdeu-a-vida-de-maneira-cruel-em-uma-das-cidades-mais-badaladas-do-estado-catarinense\/","url_meta":{"origin":27291,"position":5},"title":"Quem \u00e9 o jovem que perdeu a vida de maneira cruel em uma das cidades mais badaladas do estado catarinense","author":"ismaelcolosi.com.br","date":"28 de December de 2023","format":false,"excerpt":"[ad_1] Um indiv\u00edduo de 23 anos, identificado como Gustavo Ernst Martins, perdeu a vida ap\u00f3s ser atacado na regi\u00e3o craniana com um peda\u00e7o de madeira na cidade de Balne\u00e1rio Cambori\u00fa.O munic\u00edpio, localizado no Litoral Norte do estado de Santa Catarina, \u00e9 uma das mais visitadas do estado e famosa por\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658db98c075b67561.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658db98c075b67561.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658db98c075b67561.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658db98c075b67561.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658db98c075b67561.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-76b","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=27291"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27291\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/27292"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=27291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=27291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=27291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}