{"id":27186,"date":"2024-01-11T17:08:33","date_gmt":"2024-01-11T20:08:33","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/11\/guilherme-arantes-passa-por-cirurgia-em-hospital-da-regiao-de-ribeirao-entenda\/"},"modified":"2024-01-11T17:08:33","modified_gmt":"2024-01-11T20:08:33","slug":"guilherme-arantes-passa-por-cirurgia-em-hospital-da-regiao-de-ribeirao-entenda","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/11\/guilherme-arantes-passa-por-cirurgia-em-hospital-da-regiao-de-ribeirao-entenda\/","title":{"rendered":"Guilherme Arantes passa por cirurgia em hospital da regi\u00e3o de Ribeir\u00e3o; Entenda"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p><strong>O cantor e compositor Guilherme Arantes, de 70 anos, realizou uma cirurgia no quadril e permanece internado na Santa casa de Batatais, cidade a 42 quil\u00f4metros de Ribeir\u00e3o Preto<\/strong>.<\/p>\n<p>A informa\u00e7\u00e3o foi confirmada pelo<strong> empres\u00e1rio do cantor <\/strong>ao <strong>portal acidade on<\/strong>, nesta quinta-feira (11). De acordo com o homem, a cirurgia foi realizada na \u00faltima sexta-feira (5).<\/p>\n<p>Guilherme foi submetido a uma <strong>artroplastia total no quadril<\/strong>, procedimento que consiste na substitui\u00e7\u00e3o cir\u00fargica da articula\u00e7\u00e3o lesionada por uma pr\u00f3tese confeccionada de materiais artificiais.<\/p>\n<p><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">A cirurgia \u00e9 a mesma feita pelo presidente <strong>Luiz In\u00e1cio Lula da Silva<\/strong>, em setembro de 2023.<\/mark> A opera\u00e7\u00e3o do artista foi realizada pelo m\u00e9dico Ortopedista e Traumatologista Luiz S\u00e9rgio Marcelino Gomes.<\/p>\n<p>Ainda de acordo com o empres\u00e1rio do artista a opera\u00e7\u00e3o foi bem sucedida e Guilherme est\u00e1 bem. Inclusive,<strong> j\u00e1 come\u00e7ou a realizar as sess\u00f5es de fisioterapia.<\/strong><\/p>\n<blockquote class=\"wp-block-quote is-style-plain\" style=\"font-style:normal;font-weight:700\">\n<p class=\"has-text-align-left\">\u201cEu vim pra c\u00e1 consultar com o Marcelino, j\u00e1 sabendo que eu queria que ele operasse e aqui na Sana Casa. Eu me afei\u00e7oei ao lugar, porque j\u00e1 conhecia. \u00c9 uma dimens\u00e3o de hospital e um cuidado, \u00e9 muito diferenciado\u201d, disse Guilherme Arantes, em coletiva de imprensa.<\/p>\n<\/blockquote>\n<p><strong>O m\u00fasico deve ter alta hospitalar ainda nesta semana<\/strong>, segundo as informa\u00e7\u00f5es do empres\u00e1rio. O procedimento n\u00e3o comprometeu a agenda de shows do cantor, portanto, em mar\u00e7o ele deve volta a se apresentar.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<h4 class=\"wp-block-heading\"><strong><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">FIQUE ON<\/mark><\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do<strong>\u00a0acidade on<\/strong>\u00a0no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do\u00a0<strong>acidade on\u00a0<\/strong>no WhatsApp.<a href=\"https:\/\/chat.whatsapp.com\/DfXwcjKVIddHUT3BvnQuPZ\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a0Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre a Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: (16) 99117 7802.<\/p>\n<p>LEIA MAIS<\/p>\n<p>Rodriguinho debocha de Amanda, \u00faltima vencedora do reality<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/guilherme-arantes-passa-por-cirurgia-em-hospital-da-regiao-de-ribeirao-entenda\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] O cantor e compositor Guilherme Arantes, de 70 anos, realizou uma cirurgia no quadril e permanece internado na Santa casa de Batatais, cidade a 42 quil\u00f4metros de Ribeir\u00e3o Preto. A informa\u00e7\u00e3o foi confirmada pelo empres\u00e1rio do cantor ao portal acidade on, nesta quinta-feira (11). De acordo com o homem, a cirurgia foi realizada na&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":27187,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[1106,1559,33,54,524,631,134,277,26],"class_list":["post-27186","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-arantes","tag-cirurgia","tag-entenda","tag-guilherme","tag-hospital","tag-passa","tag-por","tag-regiao","tag-ribeirao"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/236888485_372172644269665_5078006427887263608_n_version1660685860599.jpg?fit=1423%2C800&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/236888485_372172644269665_5078006427887263608_n_version1660685860599.jpg?fit=1423%2C800&ssl=1",1423,800,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/236888485_372172644269665_5078006427887263608_n_version1660685860599.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/236888485_372172644269665_5078006427887263608_n_version1660685860599.jpg?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/236888485_372172644269665_5078006427887263608_n_version1660685860599.jpg?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/236888485_372172644269665_5078006427887263608_n_version1660685860599.jpg?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/236888485_372172644269665_5078006427887263608_n_version1660685860599.jpg?fit=1423%2C800&ssl=1",1423,800,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/236888485_372172644269665_5078006427887263608_n_version1660685860599.jpg?fit=1423%2C800&ssl=1",1423,800,true],"neve-blog":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/236888485_372172644269665_5078006427887263608_n_version1660685860599.jpg?resize=930%2C620&ssl=1",930,620,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] O cantor e compositor Guilherme Arantes, de 70 anos, realizou uma cirurgia no quadril e permanece internado na Santa casa de Batatais, cidade a 42 quil\u00f4metros de Ribeir\u00e3o Preto. A informa\u00e7\u00e3o foi confirmada pelo empres\u00e1rio do cantor ao portal acidade on, nesta quinta-feira (11). De acordo com o homem, a cirurgia foi realizada na&hellip;&nbsp;","jetpack-related-posts":[{"id":36372,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/09\/show-ira-folk-volta-a-ribeirao-preto-veja-como-comprar-ingressos\/","url_meta":{"origin":27186,"position":0},"title":"Show Ira! Folk volta a Ribeir\u00e3o Preto; Veja como comprar ingressos","author":"ismaelcolosi.com.br","date":"9 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] O show Ira! Folk volta ao Theatro Pedro II, em Ribeir\u00e3o Preto, no dia 30 de agosto, a partir das 20h. Os ingressos est\u00e3o \u00e0 venda pela internet (clique aqui) e os pre\u00e7os variam entre R$ 100 e R$ 320. O Ira! Folk conta com os membros hist\u00f3ricos do\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/ira-folk.jpg?fit=1193%2C663&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/ira-folk.jpg?fit=1193%2C663&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/ira-folk.jpg?fit=1193%2C663&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/ira-folk.jpg?fit=1193%2C663&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/ira-folk.jpg?fit=1193%2C663&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":9010,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/01\/equipe-de-preta-gil-se-pronuncia-apos-cantora-ir-parar-na-uti-e-realizar-cirurgia-delicada\/","url_meta":{"origin":27186,"position":1},"title":"Equipe de Preta Gil se pronuncia ap\u00f3s cantora ir parar na UTI e realizar cirurgia delicada","author":"ismaelcolosi.com.br","date":"1 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Recentemente, chegou a ser anunciado atrav\u00e9s de diversos canais de comunica\u00e7\u00e3o que a cantora Preta Gil est\u00e1 se recuperando ap\u00f3s ter enfrentado uma cirurgia delicada. Neste momento, ela se encontra na UTI (Unidade de Tratamento Intensivo) do Hospital S\u00edrio Liban\u00eas, em S\u00e3o Paulo.E na madrugada desta sexta-feira, dia 1\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6569dbd8405815601.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6569dbd8405815601.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6569dbd8405815601.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6569dbd8405815601.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6569dbd8405815601.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":32778,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/26\/hc-ribeirao-preto-tem-terceiro-caso-de-gemeas-siamesas-unidas-pela-cabeca\/","url_meta":{"origin":27186,"position":2},"title":"HC Ribeir\u00e3o Preto tem terceiro caso de g\u00eameas siamesas unidas pela cabe\u00e7a","author":"ismaelcolosi.com.br","date":"26 de Janeiro de 2024","format":false,"excerpt":"[ad_1] O Hospital das Cl\u00ednicas de Ribeir\u00e3o Preto recebeu h\u00e1 uma semana duas meninas g\u00eameas siamesas que nasceram unidas pela cabe\u00e7a e que devem passar pelo procedimento cir\u00fargico para separa\u00e7\u00e3o. Este \u00e9 o terceiro caso no hospital (veja abaixo). As irm\u00e3s, que s\u00e3o de S\u00e3o Jos\u00e9 dos Campos, nasceram prematuras\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-26-at-11.40.48.jpeg?fit=909%2C864&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-26-at-11.40.48.jpeg?fit=909%2C864&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-26-at-11.40.48.jpeg?fit=909%2C864&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-26-at-11.40.48.jpeg?fit=909%2C864&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":58545,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/31\/hospital-das-clinicas-de-ribeirao-preto-realiza-cirurgia-inedita-com-robo-em-bebe-de-7-meses\/","url_meta":{"origin":27186,"position":3},"title":"Hospital das Cl\u00ednicas de Ribeir\u00e3o Preto realiza cirurgia in\u00e9dita com rob\u00f4 em beb\u00ea de 7 meses","author":"ismaelcolosi.com.br","date":"31 de Julho de 2024","format":false,"excerpt":"[ad_1] O HCRP (Hospital das Cl\u00ednicas de Ribeir\u00e3o Preto) realizou uma cirurgia in\u00e9dita em todo o mundo utilizando um rob\u00f4 para a retirada de 98% do p\u00e2ncreas de um beb\u00ea de sete meses de idade. O procedimento foi necess\u00e1rio, por conta de uma doen\u00e7a rara,chamada hiperinsulinismo cong\u00eanito, que faz com\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-16_2024-07-31_19-18-01_jpg_2024-07-31_19-18-01.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-16_2024-07-31_19-18-01_jpg_2024-07-31_19-18-01.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-16_2024-07-31_19-18-01_jpg_2024-07-31_19-18-01.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-16_2024-07-31_19-18-01_jpg_2024-07-31_19-18-01.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-16_2024-07-31_19-18-01_jpg_2024-07-31_19-18-01.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":47222,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/25\/mae-doa-rim-para-filho-no-1o-transplante-entre-vivos-realizado-no-hc-ribeirao-apos-pandemia\/","url_meta":{"origin":27186,"position":4},"title":"M\u00e3e doa rim para filho no 1\u00ba transplante entre vivos realizado no HC Ribeir\u00e3o ap\u00f3s pandemia","author":"ismaelcolosi.com.br","date":"25 de Abril de 2024","format":false,"excerpt":"[ad_1] O Hospital das Cl\u00ednicas de Ribeir\u00e3o Preto realizou o primeiro transplante entre vivos ap\u00f3s a pandemia. A cirurgia aconteceu na segunda-feira (22) e teve um motivo a mais para comemorar o retorno do procedimento: a doa\u00e7\u00e3o do \u00f3rg\u00e3o foi de uma m\u00e3e para o filho. Marcos Taylor Ferreira, de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/1_2024-04-24_20-55-21_jpg.webp.webp?fit=794%2C473&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/1_2024-04-24_20-55-21_jpg.webp.webp?fit=794%2C473&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/1_2024-04-24_20-55-21_jpg.webp.webp?fit=794%2C473&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/1_2024-04-24_20-55-21_jpg.webp.webp?fit=794%2C473&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":52718,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/10\/hc-rp-e-o-primeiro-hospital-publico-da-america-latina-a-usar-robo-em-cirurgia-de-coluna\/","url_meta":{"origin":27186,"position":5},"title":"HC-RP \u00e9 o primeiro hospital p\u00fablico da Am\u00e9rica Latina a usar rob\u00f4 em cirurgia de coluna","author":"ismaelcolosi.com.br","date":"10 de Junho de 2024","format":false,"excerpt":"[ad_1] O HC-RP (Hospital das Cl\u00ednicas de Ribeir\u00e3o Preto) foi o primeiro hospital p\u00fablico da Am\u00e9rica Latina a realizar uma cirurgia utilizando um rob\u00f4 cir\u00fargico. O procedimento ocorreu na \u00faltima sexta-feira (7) em um paciente de 66 anos com escoliose degenerativa. Ap\u00f3s cinco dias internado, a previs\u00e3o \u00e9 de que\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2_2024-06-10_14-22-29_jpg_2024-06-10_14-22-29.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2_2024-06-10_14-22-29_jpg_2024-06-10_14-22-29.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2_2024-06-10_14-22-29_jpg_2024-06-10_14-22-29.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2_2024-06-10_14-22-29_jpg_2024-06-10_14-22-29.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2_2024-06-10_14-22-29_jpg_2024-06-10_14-22-29.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-74u","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=27186"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27186\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/27187"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=27186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=27186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=27186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}