{"id":27057,"date":"2024-01-11T12:30:38","date_gmt":"2024-01-11T15:30:38","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/11\/serasa-experian-abre-40-vagas-para-areas-de-tecnologia-e-dados\/"},"modified":"2024-01-11T12:30:38","modified_gmt":"2024-01-11T15:30:38","slug":"serasa-experian-abre-40-vagas-para-areas-de-tecnologia-e-dados","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/11\/serasa-experian-abre-40-vagas-para-areas-de-tecnologia-e-dados\/","title":{"rendered":"Serasa Experian abre 40 vagas para \u00e1reas de Tecnologia e Dados"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"\">\n<div class=\"content-infos\">\n<div class=\"texts\">\n<p class=\"author tooltip-comp\"> Da reda\u00e7\u00e3o<span class=\"icon-i\">i<\/span><span class=\"tooltiptext\"> <span class=\"author\"><span>Da reda\u00e7\u00e3o<\/span> <\/span><span class=\"desc\"\/> <\/span><\/p>\n<p>11\/01\/2024 &#8211; 12:15<\/p>\n<\/div>\n<div id=\"share-modal\" class=\"share-modal\"> <button class=\"box-close btn-share\"> <img decoding=\"async\" src=\"https:\/\/istoedinheiro.com.br\/wp-content\/themes\/dinheiro-wp-theme\/assets\/img\/svg\/closeIcon.svg?x46096\" alt=\"Close icon\" class=\"close-btn lazy\"\/> <\/button><\/div>\n<\/p><\/div>\n<p style=\"text-align: left\" align=\"justify\">A Serasa Experian est\u00e1 com processo seletivo aberto 40 vagas de trabalho. As oportunidades s\u00e3o destinadas \u00e0s \u00e1reas de tecnologia e dados, al\u00e9m de posi\u00e7\u00f5es para Vendas, Marketing, Finan\u00e7as, Jur\u00eddico, Produtos e Atendimento. Para se candidatar, interessados podem acessar o <a href=\"https:\/\/www.serasaexperian.com.br\/carreiras\/\" rel=\"nofollow noopener\" target=\"_blank\"><strong>site da empresa<\/strong><\/a>.<\/p>\n<p align=\"justify\"><strong>+ \u2018Enem dos concursos\u2019: o que voc\u00ea precisa saber sobre o Concurso P\u00fablico Nacional Unificado<\/strong><\/p>\n<p style=\"text-align: left\" align=\"justify\">Das vagas dispon\u00edveis, 31 s\u00e3o para o formato h\u00edbrido, 7 para home office e 2 para o modelo presencial. As localidades priorit\u00e1rias s\u00e3o a capital de S\u00e3o Paulo, S\u00e3o Carlos, Blumenau e Bras\u00edlia.<\/p>\n<p style=\"text-align: left\" align=\"justify\">A Serasa Experian oferece uma gama de benef\u00edcios como vale-transporte, vale-refei\u00e7\u00e3o, assist\u00eancia m\u00e9dica e odontol\u00f3gica, seguro de vida, Gympass e Totalpass, canal de suporte 24h para apoio em quest\u00f5es sociais, de sa\u00fade, financeiras e jur\u00eddicas e parceria com cursos de idiomas.<\/p>\n<p align=\"justify\">O programa EmPower, iniciativa global que re\u00fane diversas metodologias de aprimoramento de processos, como Lean, Six Sigma, Kaizen, A3 e Design Thinking faz parte da jornada dos funcion\u00e1rios. A certifica\u00e7\u00e3o Lean Six Sigma, especificamente, \u00e9 oferecida com treinamento e mentoria custeados pela empresa.<\/p>\n<div id=\"txt\">\n<p>Os funcion\u00e1rios da Serasa Experian poder\u00e3o participar dos Hackathons Globais, promovendo a inova\u00e7\u00e3o e desenvolvimento de solu\u00e7\u00f5es criativas para desafios internos e externos. A empresa incentiva o projeto Social Innovation, estimulando a cria\u00e7\u00e3o de solu\u00e7\u00f5es e produtos que impactem positivamente a vida financeira das pessoas.<\/p>\n<\/div>\n<section data-hb-type=\"ads\" name=\"adsMateria\" data-hb-position=\"after-content\" data-hb-provider=\"\">\n<hr\/>\n<\/section>\n<div id=\"share-modal\" class=\"share-modal\"> <button class=\"box-close btn-share\"> <img decoding=\"async\" src=\"https:\/\/istoedinheiro.com.br\/wp-content\/themes\/dinheiro-wp-theme\/assets\/img\/svg\/closeIcon.svg?x46096\" alt=\"Close icon\" class=\"close-btn lazy\"\/> <\/button><\/div>\n<\/p><\/div>\n<p><script>!function(f,b,e,v,n,t,s){if(f.fbq)return;n=f.fbq=function(){n.callMethod?n.callMethod.apply(n,arguments):n.queue.push(arguments)};if(!f._fbq)f._fbq=n;n.push=n;n.loaded=!0;n.version='2.0';n.queue=[];t=b.createElement(e);t.async=!0;t.src=v;s=b.getElementsByTagName(e)[0];s.parentNode.insertBefore(t,s)}(window,document,'script','<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/istoedinheiro.com.br\/serasa-experian-abre-40-vagas-para-areas-de-tecnologia-e-dados\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Da reda\u00e7\u00e3oi Da reda\u00e7\u00e3o 11\/01\/2024 &#8211; 12:15 A Serasa Experian est\u00e1 com processo seletivo aberto 40 vagas de trabalho. As oportunidades s\u00e3o destinadas \u00e0s \u00e1reas de tecnologia e dados, al\u00e9m de posi\u00e7\u00f5es para Vendas, Marketing, Finan\u00e7as, Jur\u00eddico, Produtos e Atendimento. Para se candidatar, interessados podem acessar o site da empresa. + \u2018Enem dos concursos\u2019: &#8230; <a title=\"Serasa Experian abre 40 vagas para \u00e1reas de Tecnologia e Dados\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/11\/serasa-experian-abre-40-vagas-para-areas-de-tecnologia-e-dados\/\" aria-label=\"Leia mais sobre Serasa Experian abre 40 vagas para \u00e1reas de Tecnologia e Dados\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":27058,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-27057","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vagas-de-empregos-em-ribeirao-preto-regiao-brasil"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/serasa-e1704985658345.jpg?fit=640%2C427&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/serasa-e1704985658345.jpg?fit=640%2C427&ssl=1",640,427,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/serasa-e1704985658345.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/serasa-e1704985658345.jpg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/serasa-e1704985658345.jpg?fit=640%2C427&ssl=1",640,427,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/serasa-e1704985658345.jpg?fit=640%2C427&ssl=1",640,427,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/serasa-e1704985658345.jpg?fit=640%2C427&ssl=1",640,427,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/serasa-e1704985658345.jpg?fit=640%2C427&ssl=1",640,427,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Da reda\u00e7\u00e3oi Da reda\u00e7\u00e3o 11\/01\/2024 &#8211; 12:15 A Serasa Experian est\u00e1 com processo seletivo aberto 40 vagas de trabalho. As oportunidades s\u00e3o destinadas \u00e0s \u00e1reas de tecnologia e dados, al\u00e9m de posi\u00e7\u00f5es para Vendas, Marketing, Finan\u00e7as, Jur\u00eddico, Produtos e Atendimento. Para se candidatar, interessados podem acessar o site da empresa. + \u2018Enem dos concursos\u2019:&hellip;","jetpack-related-posts":[{"id":41183,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/06\/serasa-experian-abriu-06-vagas-home-office-para-trabalhar-de-casa-no-setor-de-t-i\/","url_meta":{"origin":27057,"position":0},"title":"Serasa Experian abriu 06 vagas HOME OFFICE para TRABALHAR DE CASA no setor de T.I","author":"ismaelcolosi.com.br","date":"6 de Mar\u00e7o de 2024","format":false,"excerpt":"Home Office Serasa Experian abriu 06 vagas HOME OFFICE para TRABALHAR DE CASA no setor de T.I Home Office CVC Corp anunciou novas vagas HOME OFFICE no Setor de vendas Home Office Banco Sicoob abriu vaga HOME OFFICE par Assistente de Controle e oferece um sal\u00e1rio de R$ 2.156,00 mil\u2026","rel":"","context":"In &quot;Vagas de Emprego Remoto - Home Office&quot;","block_context":{"text":"Vagas de Emprego Remoto - Home Office","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/vagas-de-emprego-para-trabalhar-de-casa-home-office-remoto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/SERASA-761x492.webp?fit=761%2C492&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/SERASA-761x492.webp?fit=761%2C492&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/SERASA-761x492.webp?fit=761%2C492&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/SERASA-761x492.webp?fit=761%2C492&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":41315,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/07\/jovem-aprendiz-home-office-meliuz-abriu-vaga-home-office-para-trabalhar-de-casa-como-aprendiz-de-recursos-humanos\/","url_meta":{"origin":27057,"position":1},"title":"Jovem Aprendiz Home Office: M\u00e9liuz abriu vaga HOME OFFICE para TRABALHAR DE CASA como Aprendiz de Recursos Humanos","author":"ismaelcolosi.com.br","date":"7 de Mar\u00e7o de 2024","format":false,"excerpt":"Home Office Jovem Aprendiz Home Office: M\u00e9liuz abriu vaga HOME OFFICE para TRABALHAR DE CASA como Aprendiz de Recursos Humanos Home Office HOME OFFICE SEM EXPERI\u00caNCIA: HYPERATIVA abre vagas para TRABALHAR DE CASA no cargo de Assistente de Sac Home Office Will Bank abriu vagas HOME OFFICE para Trabalhar de\u2026","rel":"","context":"In &quot;Vagas de Emprego Remoto - Home Office&quot;","block_context":{"text":"Vagas de Emprego Remoto - Home Office","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/vagas-de-emprego-para-trabalhar-de-casa-home-office-remoto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/MELIUZ-761x492.webp?fit=761%2C492&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/MELIUZ-761x492.webp?fit=761%2C492&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/MELIUZ-761x492.webp?fit=761%2C492&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/MELIUZ-761x492.webp?fit=761%2C492&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":22615,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/30\/tentativas-de-fraudes-a-consumidores-passaram-de-837-mil-em-outubro\/","url_meta":{"origin":27057,"position":2},"title":"Tentativas de fraudes a consumidores passaram de 837 mil, em outubro","author":"ismaelcolosi.com.br","date":"30 de Dezembro de 2023","format":false,"excerpt":"[ad_1] 30 de dezembro de 2023 | 12:0029 de dezembro de 2023 | 18:56 0Em outubro, foram contabilizadas 837.419 tentativas de fraude contra consumidores e empresas no Brasil, o que corresponde a uma a cada 3,2 segundos, segundo o Indicador de Tentativas de Fraude da Serasa Experian. Em rela\u00e7\u00e3o a\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1-fraudes-compra_online2411203173-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1-fraudes-compra_online2411203173-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1-fraudes-compra_online2411203173-scaled.jpg?fit=1000%2C598&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1-fraudes-compra_online2411203173-scaled.jpg?fit=1000%2C598&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":41214,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/07\/amazon-anuncia-vagas-home-office-06-horas-dia-e-ainda-fornece-computador-oferece-um-salario-de-r-1280-e-alimentacao-de-r-83600-mil\/","url_meta":{"origin":27057,"position":3},"title":"Amazon anuncia vagas HOME OFFICE 06 Horas dia e ainda Fornece computador: Oferece um Sal\u00e1rio de R$ 1280 e Alimenta\u00e7\u00e3o de R$ 836,00 MIL","author":"ismaelcolosi.com.br","date":"7 de Mar\u00e7o de 2024","format":false,"excerpt":"Home Office Amazon anuncia vagas HOME OFFICE 06 Horas dia e ainda Fornece computador: Oferece um Sal\u00e1rio de R$ 1280 e Alimenta\u00e7\u00e3o de R$ 836,00 MIL Home Office Serasa Experian abriu 06 vagas HOME OFFICE para TRABALHAR DE CASA no setor de T.I Home Office CVC Corp anunciou novas vagas\u2026","rel":"","context":"In &quot;Vagas de Emprego Remoto - Home Office&quot;","block_context":{"text":"Vagas de Emprego Remoto - Home Office","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/vagas-de-emprego-para-trabalhar-de-casa-home-office-remoto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AMAZON-761x492.webp?fit=761%2C492&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AMAZON-761x492.webp?fit=761%2C492&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AMAZON-761x492.webp?fit=761%2C492&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AMAZON-761x492.webp?fit=761%2C492&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":41397,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/07\/unimed-abriu-vagas-home-office-para-trabalhar-de-casa-com-salario-de-r-2-50316-e-va-de-r-80000-para-assistente-de-gestao\/","url_meta":{"origin":27057,"position":4},"title":"Unimed abriu vagas HOME OFFICE para TRABALHAR DE CASA com sal\u00e1rio de R$ 2.503,16 e VA de R$ 800,00 para Assistente de Gest\u00e3o","author":"ismaelcolosi.com.br","date":"7 de Mar\u00e7o de 2024","format":false,"excerpt":"Home Office Unimed abriu vagas HOME OFFICE para TRABALHAR DE CASA com sal\u00e1rio de R$ 2.503,16 e VA de R$ 800,00 para Assistente de Gest\u00e3o Home Office Jovem Aprendiz Home Office: M\u00e9liuz abriu vaga HOME OFFICE para TRABALHAR DE CASA como Aprendiz de Recursos Humanos Home Office HOME OFFICE SEM\u2026","rel":"","context":"In &quot;Vagas de Emprego Remoto - Home Office&quot;","block_context":{"text":"Vagas de Emprego Remoto - Home Office","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/vagas-de-emprego-para-trabalhar-de-casa-home-office-remoto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/UNIMED-1-761x492.webp?fit=761%2C492&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/UNIMED-1-761x492.webp?fit=761%2C492&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/UNIMED-1-761x492.webp?fit=761%2C492&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/UNIMED-1-761x492.webp?fit=761%2C492&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":41559,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/08\/empresa-oferece-notebook-e-fone-de-ouvido-para-voce-trabalhar-de-casa-hi-platform-contrata-para-home-office-analista-de-suporte-jr\/","url_meta":{"origin":27057,"position":5},"title":"Empresa oferece Notebook e fone de ouvido para voc\u00ea trabalhar de Casa! Hi Platform contrata para HOME OFFICE Analista de Suporte Jr","author":"ismaelcolosi.com.br","date":"8 de Mar\u00e7o de 2024","format":false,"excerpt":"Home Office Empresa oferece Notebook e fone de ouvido para voc\u00ea trabalhar de Casa! Hi Platform contrata para HOME OFFICE Analista de Suporte Jr Home Office Unimed abriu vagas HOME OFFICE para TRABALHAR DE CASA com sal\u00e1rio de R$ 2.503,16 e VA de R$ 800,00 para Assistente de Gest\u00e3o Home\u2026","rel":"","context":"In &quot;Vagas de Emprego Remoto - Home Office&quot;","block_context":{"text":"Vagas de Emprego Remoto - Home Office","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/vagas-de-empregos-em-ribeirao-preto-regiao-brasil\/vagas-de-emprego-para-trabalhar-de-casa-home-office-remoto\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/hI-761x492.webp?fit=761%2C492&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/hI-761x492.webp?fit=761%2C492&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/hI-761x492.webp?fit=761%2C492&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/hI-761x492.webp?fit=761%2C492&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-72p","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=27057"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27057\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/27058"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=27057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=27057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=27057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}