{"id":26911,"date":"2024-01-11T02:35:26","date_gmt":"2024-01-11T05:35:26","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/11\/jovem-enviou-mensagens-pedindo-ajuda-a-mae-antes-de-perder-a-vida-de-forma-cruel-pelas-maos-do-marido\/"},"modified":"2024-01-11T02:35:26","modified_gmt":"2024-01-11T05:35:26","slug":"jovem-enviou-mensagens-pedindo-ajuda-a-mae-antes-de-perder-a-vida-de-forma-cruel-pelas-maos-do-marido","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/11\/jovem-enviou-mensagens-pedindo-ajuda-a-mae-antes-de-perder-a-vida-de-forma-cruel-pelas-maos-do-marido\/","title":{"rendered":"Jovem enviou mensagens pedindo ajuda \u00e0 m\u00e3e antes de perder a vida de forma cruel pelas m\u00e3os do marido"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div itemprop=\"text\">\n<p>Merin Izabel Ribeiro Padilha, uma jovem de 24 anos, foi morta em sua resid\u00eancia na cidade de Iva\u00ed, localizada na regi\u00e3o dos Campos Gerais que fica no interior do Paran\u00e1, ap\u00f3s buscar aux\u00edlio de sua m\u00e3e momentos antes do crime.<\/p>\n<p>O esposo dela, Wilhan Rafael Galv\u00e3o, de 27 anos, \u00e9 considerado o principal suspeito do homic\u00eddio. Antes de falecer, a v\u00edtima enviou v\u00e1rias mensagens \u00e0 sua m\u00e3e, expressando temor em rela\u00e7\u00e3o ao companheiro, com quem pretendia dialogar sobre o div\u00f3rcio.<\/p>\n<p>Essas mensagens foram inclu\u00eddas como anexos no inqu\u00e9rito policial. O di\u00e1logo entre as duas teve in\u00edcio \u00e0s 4h40 do s\u00e1bado passado (6). De acordo com a m\u00e3e da v\u00edtima, a jovem tinha a inten\u00e7\u00e3o de solicitar o div\u00f3rcio e mudar-se com a filha de seis anos do casal para outra resid\u00eancia, ap\u00f3s cerca de uma d\u00e9cada de conviv\u00eancia.<\/p>\n<p><strong>\u201cM\u00e3e, ora pra mim a\u00ed. T\u00e1 quase na hora. T\u00f4 com medo da rea\u00e7\u00e3o dele. T\u00f4 com medo do que ele vai tentar fazer. Eu quero ir embora. Reza pra mim e pra [minha] filha\u201d<\/strong><i>,<\/i> pediu Merin.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/fnmais.com\/wp-content\/uploads\/2024\/01\/postiimg-659f50f3d9bb52299.png?w=1200&#038;ssl=1\" alt=\"Jovem enviou mensagens me pedindo ajuda Foto Reproduo\"\/><\/p>\n<p>A jovem relatou sua inten\u00e7\u00e3o de acordar a filha somente quando estivesse prestes a sair, a fim de n\u00e3o a assustar. A m\u00e3e alertou que Wilhan possivelmente impediria Merin de deixar a resid\u00eancia.<\/p>\n<p>Merin ent\u00e3o respondeu a m\u00e3e afirmando que n\u00e3o precisava da permiss\u00e3o do companheiro. A \u00faltima mensagem de Merin foi registrada \u00e0s 5h. \u00c0s 8h23, a m\u00e3e da jovem questionou sobre seu bem-estar, mas a mensagem n\u00e3o foi visualizada.<\/p>\n<p>Thiago Andrade, delegado respons\u00e1vel pelas investiga\u00e7\u00f5es sobre o caso, os familiares e testemunhas que conheciam o casal relataram que Merin vivia um relacionamento abusivo.<\/p>\n<p>De acordo com informa\u00e7\u00f5es da Pol\u00edcia Militar (PM), o homic\u00eddio ocorreu por volta das 7h15. Merin foi alvo de tr\u00eas disparos, sendo dois na cabe\u00e7a e um no peito. As fam\u00edlias de ambos residem em proximidades do local do crime e afirmaram ter ouvido os tiros.<\/p>\n<p>Para assistir ao v\u00eddeo <a href=\"https:\/\/globoplay.globo.com\/v\/12251896\/\" target=\"_blank\" rel=\"nofollow noopener sponsored\">CLIQUE AQUI!<\/a><\/p>\n<p>Segundo a PM, ap\u00f3s o ocorrido, Wilhan evadiu-se de carro. Ainda de acordo com o agente de seguran\u00e7a, o suspeito teria falado com a m\u00e3e que iria atentar contra a pr\u00f3pria vida ap\u00f3s cometer o crime.<\/p>\n<\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/fnmais.com\/jovem-enviou-mensagens-pedindo-ajuda-mae-antes-perder-vida-forma-cruel-pelas-maos-marido\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Merin Izabel Ribeiro Padilha, uma jovem de 24 anos, foi morta em sua resid\u00eancia na cidade de Iva\u00ed, localizada na regi\u00e3o dos Campos Gerais que fica no interior do Paran\u00e1, ap\u00f3s buscar aux\u00edlio de sua m\u00e3e momentos antes do crime. O esposo dela, Wilhan Rafael Galv\u00e3o, de 27 anos, \u00e9 considerado o principal suspeito &#8230; <a title=\"Jovem enviou mensagens pedindo ajuda \u00e0 m\u00e3e antes de perder a vida de forma cruel pelas m\u00e3os do marido\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/11\/jovem-enviou-mensagens-pedindo-ajuda-a-mae-antes-de-perder-a-vida-de-forma-cruel-pelas-maos-do-marido\/\" aria-label=\"Leia mais sobre Jovem enviou mensagens pedindo ajuda \u00e0 m\u00e3e antes de perder a vida de forma cruel pelas m\u00e3os do marido\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":26912,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-26911","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659f50f6630d28719.jpg?fit=1200%2C628&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659f50f6630d28719.jpg?fit=1200%2C628&ssl=1",1200,628,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659f50f6630d28719.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659f50f6630d28719.jpg?fit=300%2C157&ssl=1",300,157,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659f50f6630d28719.jpg?fit=768%2C402&ssl=1",768,402,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659f50f6630d28719.jpg?fit=1024%2C536&ssl=1",1024,536,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659f50f6630d28719.jpg?fit=1200%2C628&ssl=1",1200,628,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659f50f6630d28719.jpg?fit=1200%2C628&ssl=1",1200,628,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Merin Izabel Ribeiro Padilha, uma jovem de 24 anos, foi morta em sua resid\u00eancia na cidade de Iva\u00ed, localizada na regi\u00e3o dos Campos Gerais que fica no interior do Paran\u00e1, ap\u00f3s buscar aux\u00edlio de sua m\u00e3e momentos antes do crime. O esposo dela, Wilhan Rafael Galv\u00e3o, de 27 anos, \u00e9 considerado o principal suspeito&hellip;","jetpack-related-posts":[{"id":8856,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/01\/seu-presente-de-natal-pai-suspeito-de-golpear-filho-com-arma-branca-manda-video-do-crime-para-esposa-e-jovem-suplica-para-nao-ser-esquecido\/","url_meta":{"origin":26911,"position":0},"title":"\u2018Seu presente de Natal!\u2019 Pai suspeito de golpear filho com arma branca manda v\u00eddeo do crime para esposa, e jovem suplica para n\u00e3o ser esquecido","author":"ismaelcolosi.com.br","date":"1 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Um indiv\u00edduo est\u00e1 sendo investigado por supostamente apunhalar seu filho, de 16 anos, e registrar um v\u00eddeo do jovem ferido para envi\u00e1-lo \u00e0 esposa. O incidente ocorreu nesta quarta-feira (29), zona sul de S\u00e3o Paulo.Conforme relatado no boletim de ocorr\u00eancia, a Pol\u00edcia Militar foi chamada e descobriu o adolescente\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-656956fb8a0b98680.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-656956fb8a0b98680.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-656956fb8a0b98680.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-656956fb8a0b98680.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-656956fb8a0b98680.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":29997,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/19\/mulher-cai-em-emboscada-e-atacada-com-cutelo-mas-antes-de-falecer-consegue-apontar-o-autor-do-crime\/","url_meta":{"origin":26911,"position":1},"title":"Mulher cai em emboscada \u00e9 atacada com cutelo, mas antes de falecer consegue apontar o autor do crime","author":"ismaelcolosi.com.br","date":"19 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Uma mulher de 43 anos perdeu a vida ap\u00f3s ser v\u00edtima de uma emboscada com facadas no Alto da Boa Vista, localizado na zona norte do Rio de Janeiro, na sexta-feira (19).Mesmo ap\u00f3s ser conduzida para uma unidade hospitalar, na Barra da Tijuca, zona oeste, e submeter-se a uma\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65ab006590b5f9818.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65ab006590b5f9818.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65ab006590b5f9818.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65ab006590b5f9818.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65ab006590b5f9818.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":8049,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/29\/rapaz-confessa-ter-matado-pai-irmaozinho-de-5-anos-e-madrasta-ele-havia-contado-o-motivo-para-a-mae\/","url_meta":{"origin":26911,"position":2},"title":"Rapaz confessa ter matado pai, irm\u00e3ozinho de 5 anos e madrasta; ele havia contado o motivo para a m\u00e3e","author":"ismaelcolosi.com.br","date":"29 de Novembro de 2023","format":false,"excerpt":"[ad_1] Um jovem acabou confessando ter tirado a vida da madrasta, do pai e do irm\u00e3o. O crime b\u00e1rbaro configurado como triplo homic\u00eddio aconteceu no Bronx, um condado situado em Nova Iorque, nos Estados Unidos.O respons\u00e1vel pelo crime tem 19 anos foi identificado como Jayden Rivera. De acordo com o\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656738650d51d8917.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656738650d51d8917.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656738650d51d8917.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656738650d51d8917.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656738650d51d8917.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":16616,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/15\/pais-de-larissa-manoela-pagaram-mae-de-santo-para-separar-a-filha-de-andre-luiz-afirma-jornalista-que-expoe-prints-das-conversas\/","url_meta":{"origin":26911,"position":3},"title":"Pais de Larissa Manoela pagaram M\u00e3e de Santo para separar a filha de Andr\u00e9 Luiz, afirma jornalista que exp\u00f5e prints das conversas","author":"ismaelcolosi.com.br","date":"15 de Dezembro de 2023","format":false,"excerpt":"[ad_1] A separa\u00e7\u00e3o entre Larissa Manoela e seus pais, Silvana Taques e Gilberto Elias, continua gerando muita pol\u00eamica e uma enorme repercuss\u00f5es nos bastidores da fama.Al\u00e9m das quest\u00f5es financeiras envolvendo a atriz, outro fator que contribuiu para o distanciamento familiar foi o relacionamento da artista com Luiz Andr\u00e9 Frambach.A coluna\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657d07312791d6438.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657d07312791d6438.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657d07312791d6438.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657d07312791d6438.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657d07312791d6438.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":15313,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/13\/mae-passa-por-local-onde-ocorreu-acidente-de-transito-e-descobre-que-a-vitima-fatal-e-o-proprio-filho\/","url_meta":{"origin":26911,"position":4},"title":"M\u00e3e passa por local onde ocorreu acidente de tr\u00e2nsito e descobre que a v\u00edtima fatal \u00e9 o pr\u00f3prio filho","author":"ismaelcolosi.com.br","date":"13 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Este caso triste ganhou uma grande repercuss\u00e3o nas redes sociais e se tornou destaque nos principais portais de not\u00edcias de todo o pa\u00eds.Na noite do \u00faltimo s\u00e1bado (9), um jovem de 18 anos, que n\u00e3o possu\u00eda habilita\u00e7\u00e3o para conduzir motocicletas, faleceu em um acidente no trevo entre as rodovias\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6579ba55e420f9744.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6579ba55e420f9744.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6579ba55e420f9744.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6579ba55e420f9744.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6579ba55e420f9744.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":21821,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/28\/quem-e-o-jovem-que-perdeu-a-vida-de-maneira-cruel-em-uma-das-cidades-mais-badaladas-do-estado-catarinense\/","url_meta":{"origin":26911,"position":5},"title":"Quem \u00e9 o jovem que perdeu a vida de maneira cruel em uma das cidades mais badaladas do estado catarinense","author":"ismaelcolosi.com.br","date":"28 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Um indiv\u00edduo de 23 anos, identificado como Gustavo Ernst Martins, perdeu a vida ap\u00f3s ser atacado na regi\u00e3o craniana com um peda\u00e7o de madeira na cidade de Balne\u00e1rio Cambori\u00fa.O munic\u00edpio, localizado no Litoral Norte do estado de Santa Catarina, \u00e9 uma das mais visitadas do estado e famosa por\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658db98c075b67561.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658db98c075b67561.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658db98c075b67561.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658db98c075b67561.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658db98c075b67561.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-703","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/26911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=26911"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/26911\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/26912"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=26911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=26911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=26911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}