{"id":26797,"date":"2024-01-10T20:08:21","date_gmt":"2024-01-10T23:08:21","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/10\/funtec-convoca-inscritos-para-cursos-de-qualificacao-profissional\/"},"modified":"2024-01-10T20:08:21","modified_gmt":"2024-01-10T23:08:21","slug":"funtec-convoca-inscritos-para-cursos-de-qualificacao-profissional","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/10\/funtec-convoca-inscritos-para-cursos-de-qualificacao-profissional\/","title":{"rendered":"Funtec convoca inscritos para cursos de qualifica\u00e7\u00e3o profissional \u2013 Folha de Ribeir\u00e3o"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>A Funda\u00e7\u00e3o Tecnol\u00f3gica de Ribeir\u00e3o Preto (Funtec) est\u00e1 chamando 140 candidatos, que realizaram as inscri\u00e7\u00f5es no segundo semestre do ano passado, para os seguintes cursos:\u00a0 portaria e recep\u00e7\u00e3o, ingl\u00eas, tecnologia da informa\u00e7\u00e3o e comunica\u00e7\u00e3o.<\/p>\n<p>A funda\u00e7\u00e3o tamb\u00e9m est\u00e1 ligando e enviando e-mail para os interessados. A inscri\u00e7\u00e3o e a garantia da vaga s\u00e3o validadas quando o candidato convocado for pessoalmente na sede da Funtec, levar os documentos.<\/p>\n<p>\u00a0<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"\" src=\"https:\/\/i0.wp.com\/www.ribeiraopreto.sp.gov.br\/portal\/foto\/202401\/funtec_convoca-_foto_divulgacao_25_5.jpg?resize=1188%2C798&#038;ssl=1\" width=\"1188\" height=\"798\"\/><\/p>\n<p>As aulas ter\u00e3o in\u00edcio nos dias 15 e 16 de janeiro, no per\u00edodo noturno, e ser\u00e3o ministradas duas vezes por semana. Cada curso ter\u00e1 a dura\u00e7\u00e3o de tr\u00eas meses.<\/p>\n<p>\u00a0<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"\" src=\"https:\/\/i0.wp.com\/www.ribeiraopreto.sp.gov.br\/portal\/foto\/202401\/funtec_convoca_-_foto_guilherme_sircili_25_3.jpg?resize=1102%2C734&#038;ssl=1\" width=\"1102\" height=\"734\"\/><\/p>\n<p><strong>INSCRI\u00c7\u00d5ES<\/strong><\/p>\n<p>O candidato dever\u00e1 efetuar a sua inscri\u00e7\u00e3o e assim garantir a vaga, indo pessoalmente na sede da Funtec, localizada \u00e0 Rua \u00c1lvares Cabral, 629, Centro, de 2\u00aa a 6\u00aa feira, das 9 \u00e0s 16h30.<\/p>\n<p><strong>Documentos necess\u00e1rios para inscri\u00e7\u00e3o:<\/strong><\/p>\n<p>a) uma fotoc\u00f3pia n\u00edtida da C\u00e9dula de Identidade e o n\u00ba do CPF;<\/p>\n<p>b) uma fotoc\u00f3pia n\u00edtida do Comprovante de Escolaridade;<\/p>\n<p>c) uma fotoc\u00f3pia n\u00edtida do Comprovante de Resid\u00eancia.<\/p>\n<p>Outras Informa\u00e7\u00f5es, de 2\u00aa a 6\u00aa feira, das 09 \u00e0s 16h30.<\/p>\n<p>Fone: (16) 3931-5400<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<\/p><\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/folhaderibeirao.com.br\/2024\/01\/10\/funtec-convoca-inscritos-para-cursos-de-qualificacao-profissional\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] A Funda\u00e7\u00e3o Tecnol\u00f3gica de Ribeir\u00e3o Preto (Funtec) est\u00e1 chamando 140 candidatos, que realizaram as inscri\u00e7\u00f5es no segundo semestre do ano passado, para os seguintes cursos:\u00a0 portaria e recep\u00e7\u00e3o, ingl\u00eas, tecnologia da informa\u00e7\u00e3o e comunica\u00e7\u00e3o. A funda\u00e7\u00e3o tamb\u00e9m est\u00e1 ligando e enviando e-mail para os interessados. A inscri\u00e7\u00e3o e a garantia da vaga s\u00e3o validadas&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":26798,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[1788,213,753,209,3350,71,215,214,26],"class_list":["post-26797","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-convoca","tag-cursos","tag-folha","tag-funtec","tag-inscritos","tag-para","tag-profissional","tag-qualificacao","tag-ribeirao"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/funtec_convoca-_foto_divulgacao_25_5.jpg?fit=1040%2C698&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/funtec_convoca-_foto_divulgacao_25_5.jpg?fit=1040%2C698&ssl=1",1040,698,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/funtec_convoca-_foto_divulgacao_25_5.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/funtec_convoca-_foto_divulgacao_25_5.jpg?fit=300%2C201&ssl=1",300,201,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/funtec_convoca-_foto_divulgacao_25_5.jpg?fit=768%2C515&ssl=1",768,515,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/funtec_convoca-_foto_divulgacao_25_5.jpg?fit=1024%2C687&ssl=1",1024,687,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/funtec_convoca-_foto_divulgacao_25_5.jpg?fit=1040%2C698&ssl=1",1040,698,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/funtec_convoca-_foto_divulgacao_25_5.jpg?fit=1040%2C698&ssl=1",1040,698,true],"neve-blog":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/funtec_convoca-_foto_divulgacao_25_5.jpg?resize=930%2C620&ssl=1",930,620,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] A Funda\u00e7\u00e3o Tecnol\u00f3gica de Ribeir\u00e3o Preto (Funtec) est\u00e1 chamando 140 candidatos, que realizaram as inscri\u00e7\u00f5es no segundo semestre do ano passado, para os seguintes cursos:\u00a0 portaria e recep\u00e7\u00e3o, ingl\u00eas, tecnologia da informa\u00e7\u00e3o e comunica\u00e7\u00e3o. A funda\u00e7\u00e3o tamb\u00e9m est\u00e1 ligando e enviando e-mail para os interessados. A inscri\u00e7\u00e3o e a garantia da vaga s\u00e3o validadas&hellip;&nbsp;","jetpack-related-posts":[{"id":26469,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/10\/a-funtec-comeca-o-ano-com-varias-opcoes-de-qualificacao\/","url_meta":{"origin":26797,"position":0},"title":"A Funtec come\u00e7a o ano com v\u00e1rias op\u00e7\u00f5es de qualifica\u00e7\u00e3o \u2013 Folha de Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"10 de Janeiro de 2024","format":false,"excerpt":"[ad_1] O ano de 2024 come\u00e7a com oportunidades de qualifica\u00e7\u00e3o e aprimoramento profissional. A Funda\u00e7\u00e3o de Forma\u00e7\u00e3o Tecnol\u00f3gica de Ribeir\u00e3o Preto (Funtec), institui\u00e7\u00e3o ligada \u00e0 Prefeitura Municipal, est\u00e1 com 600 vagas abertas para 29 cursos. Os cursos s\u00e3o de gra\u00e7a, inclusive o material de apoio para o ensino e aprendizagem,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/novas_turmas_funtec_-_foto_fernando_gonzaga_4.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/novas_turmas_funtec_-_foto_fernando_gonzaga_4.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/novas_turmas_funtec_-_foto_fernando_gonzaga_4.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/novas_turmas_funtec_-_foto_fernando_gonzaga_4.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/novas_turmas_funtec_-_foto_fernando_gonzaga_4.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":32683,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/26\/funtec-oferece-29-cursos-de-qualificacao\/","url_meta":{"origin":26797,"position":1},"title":"Funtec oferece 29 cursos de qualifica\u00e7\u00e3o","author":"ismaelcolosi.com.br","date":"26 de Janeiro de 2024","format":false,"excerpt":"[ad_1] A Funtec est\u00e1 com as inscri\u00e7\u00f5es abertas para 29 cursos de qualifica\u00e7\u00e3o profissional. Os interessados podem procurar a funda\u00e7\u00e3o, localizada \u00e0 \u00c1lvares Cabral, 629, centro. Durante todo o ano, a Funtec oferece cursos de qualifica\u00e7\u00e3o, com aulas nos per\u00edodos diurno e noturno. A Funtec tem 600 vagas divididas em\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/novo_curso_funtec_foto_guilherme_sircili_1-scaled.jpg?fit=968%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/novo_curso_funtec_foto_guilherme_sircili_1-scaled.jpg?fit=968%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/novo_curso_funtec_foto_guilherme_sircili_1-scaled.jpg?fit=968%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/novo_curso_funtec_foto_guilherme_sircili_1-scaled.jpg?fit=968%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":26341,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/09\/funtec-abre-600-vagas-para-cursos-de-qualificacao\/","url_meta":{"origin":26797,"position":2},"title":"Funtec abre 600 vagas para cursos de qualifica\u00e7\u00e3o","author":"ismaelcolosi.com.br","date":"9 de Janeiro de 2024","format":false,"excerpt":"[ad_1] 9 de janeiro de 2024 | 19:08 0O ano de 2024 come\u00e7a com oportunidades de qualifica\u00e7\u00e3o e aprimoramento profissional. A Funda\u00e7\u00e3o de Forma\u00e7\u00e3o Tecnol\u00f3gica de Ribeir\u00e3o Preto (Funtec), institui\u00e7\u00e3o ligada \u00e0 Prefeitura Municipal, est\u00e1 com 600 vagas abertas para 29 cursos.Os cursos s\u00e3o de gra\u00e7a, inclusive o material de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/funtec_17_02_22_3_foto_fernando_gonzaga-scaled.jpg?fit=970%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/funtec_17_02_22_3_foto_fernando_gonzaga-scaled.jpg?fit=970%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/funtec_17_02_22_3_foto_fernando_gonzaga-scaled.jpg?fit=970%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/funtec_17_02_22_3_foto_fernando_gonzaga-scaled.jpg?fit=970%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":38771,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/21\/funtec-oferece-vagas-para-29-cursos-de-qualificacao-2\/","url_meta":{"origin":26797,"position":3},"title":"Funtec oferece vagas para 29 cursos de qualifica\u00e7\u00e3o","author":"ismaelcolosi.com.br","date":"21 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] A Funtec est\u00e1 com as inscri\u00e7\u00f5es abertas para 29 cursos de qualifica\u00e7\u00e3o profissional. Os interessados podem procurar a funda\u00e7\u00e3o, localizada \u00e0 \u00c1lvares Cabral, 629, centro. Durante todo o ano, a Funtec oferece cursos de qualifica\u00e7\u00e3o, com aulas nos per\u00edodos diurno e noturno.A Funtec tem 600 vagas divididas em 29\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/funtec_17_02_22_3_foto_fernando_gonzaga-scaled.jpg?fit=970%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/funtec_17_02_22_3_foto_fernando_gonzaga-scaled.jpg?fit=970%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/funtec_17_02_22_3_foto_fernando_gonzaga-scaled.jpg?fit=970%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/funtec_17_02_22_3_foto_fernando_gonzaga-scaled.jpg?fit=970%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":36922,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/12\/funtec-oferece-vagas-para-29-cursos-de-qualificacao\/","url_meta":{"origin":26797,"position":4},"title":"Funtec oferece vagas para 29 cursos de qualifica\u00e7\u00e3o","author":"ismaelcolosi.com.br","date":"12 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] 12 de fevereiro de 2024 | 14:0010 de fevereiro de 2024 | 13:51 0A Funtec est\u00e1 com as inscri\u00e7\u00f5es abertas para 29 cursos de qualifica\u00e7\u00e3o profissional. Os interessados podem procurar a funda\u00e7\u00e3o, localizada \u00e0 \u00c1lvares Cabral, 629, centro. Destaque para o curso de Ingl\u00eas que ter\u00e1 in\u00edcio ainda em\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/funtec-scaled.jpg?fit=968%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/funtec-scaled.jpg?fit=968%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/funtec-scaled.jpg?fit=968%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/funtec-scaled.jpg?fit=968%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":3181,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/10\/18\/funtec-abre-vagas-gratuitas-para-seis-cursos-de-qualificacao-profissional-2\/","url_meta":{"origin":26797,"position":5},"title":"Funtec abre vagas gratuitas para seis cursos de qualifica\u00e7\u00e3o profissional","author":"ismaelcolosi.com.br","date":"18 de Outubro de 2023","format":false,"excerpt":"[ad_1] 170 A Funda\u00e7\u00e3o de Forma\u00e7\u00e3o Tecnol\u00f3gica de Ribeir\u00e3o Preto (Funtec), institui\u00e7\u00e3o ligada \u00e0 Prefeitura Municipal, est\u00e1 com 180 vagas abertas para os cursos gratuitos de qualifica\u00e7\u00e3o profissional de Educa\u00e7\u00e3o Financeira pra Empreendedores, Escrita Fiscal, Rotinas em Departamento de Pessoal, Rotinas em Recursos Humanos, Cuidador de Idosos e Cuidador Infantil.\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/cursos_funtec_-_foto_guilherme_sircili.jpg?fit=1200%2C799&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/cursos_funtec_-_foto_guilherme_sircili.jpg?fit=1200%2C799&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/cursos_funtec_-_foto_guilherme_sircili.jpg?fit=1200%2C799&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/cursos_funtec_-_foto_guilherme_sircili.jpg?fit=1200%2C799&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/cursos_funtec_-_foto_guilherme_sircili.jpg?fit=1200%2C799&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-6Yd","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/26797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=26797"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/26797\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/26798"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=26797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=26797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=26797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}