{"id":26164,"date":"2024-01-09T11:25:34","date_gmt":"2024-01-09T14:25:34","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/09\/utm_sourcerssutm_mediumrssutm_campaignmulher-e-presa-tentando-entrar-com-viagra-e-maconha-na-penitenciaria-de-ribeirao-preto\/"},"modified":"2024-01-09T11:25:34","modified_gmt":"2024-01-09T14:25:34","slug":"utm_sourcerssutm_mediumrssutm_campaignmulher-e-presa-tentando-entrar-com-viagra-e-maconha-na-penitenciaria-de-ribeirao-preto","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/09\/utm_sourcerssutm_mediumrssutm_campaignmulher-e-presa-tentando-entrar-com-viagra-e-maconha-na-penitenciaria-de-ribeirao-preto\/","title":{"rendered":"Mulher \u00e9 presa tentando entrar com viagra e maconha na Penitenci\u00e1ria de Ribeir\u00e3o Preto \u2013 X Tudo Ribeir\u00e3o"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>Uma mulher de 36 anos, foi presa pela Pol\u00edcia Penal tentando entrar com comprimidos de viagra e maconha dentro da Penitenci\u00e1ria de Ribeir\u00e3o Preto.<\/p>\n<p>Segundo informa\u00e7\u00f5es da Pol\u00edcia Civil, durante as revistas aos visitantes dos presos da Penitenci\u00e1ria de Ribeir\u00e3o Preto, os Policiais Penais suspeitaram de uma visitante que ao passar pelo scanner constou um objeto estranho na regi\u00e3o anal da acusada. Ao indaga-l\u00e1, ela de pronto confessou que estava tentando entrar com drogas no sistema prisional.\u00a0<\/p>\n<p>De acordo com a Pol\u00edcia, a mulher foi conduzida para uma sala reservada, e tirou um pacote que estava introduzido no seu \u00e2nus. Ao todo foram apreendidos, 14 comprimidos de viagra e uma por\u00e7\u00e3o de maconha.\u00a0<\/p>\n<p>Consta no B.O (boletim de ocorr\u00eancia), que a mulher disse que foi contratada para levar os viagra e a maconha para dentro da Penitenci\u00e1ria.\u00a0<\/p>\n<p>A mulher foi presa em flagrante, e durante a audi\u00eancia de cust\u00f3dia foi liberada para responder o processo em liberdade. O caso segue em investiga\u00e7\u00e3o pela Pol\u00edcia Civil de Ribeir\u00e3o Preto.\u00a0<\/p>\n<\/p><\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/xtudoribeirao.com.br\/2024\/01\/09\/mulher-e-presa-tentando-entrar-com-viagra-e-maconha-na-penitenciaria-de-ribeirao-preto\/?utm_source=rss&#038;utm_medium=rss&#038;utm_campaign=mulher-e-presa-tentando-entrar-com-viagra-e-maconha-na-penitenciaria-de-ribeirao-preto\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Uma mulher de 36 anos, foi presa pela Pol\u00edcia Penal tentando entrar com comprimidos de viagra e maconha dentro da Penitenci\u00e1ria de Ribeir\u00e3o Preto. Segundo informa\u00e7\u00f5es da Pol\u00edcia Civil, durante as revistas aos visitantes dos presos da Penitenci\u00e1ria de Ribeir\u00e3o Preto, os Policiais Penais suspeitaram de uma visitante que ao passar pelo scanner constou &#8230; <a title=\"Mulher \u00e9 presa tentando entrar com viagra e maconha na Penitenci\u00e1ria de Ribeir\u00e3o Preto \u2013 X Tudo Ribeir\u00e3o\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/09\/utm_sourcerssutm_mediumrssutm_campaignmulher-e-presa-tentando-entrar-com-viagra-e-maconha-na-penitenciaria-de-ribeirao-preto\/\" aria-label=\"Leia mais sobre Mulher \u00e9 presa tentando entrar com viagra e maconha na Penitenci\u00e1ria de Ribeir\u00e3o Preto \u2013 X Tudo Ribeir\u00e3o\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":26165,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[327,328,325,329,182,27,26,326,43,3279],"class_list":["post-26164","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-entrar","tag-maconha","tag-mulher","tag-penitenciaria","tag-presa","tag-preto","tag-ribeirao","tag-tentando","tag-tudo","tag-viagra"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-09-at-10.17.14.jpeg?fit=1600%2C1071&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-09-at-10.17.14.jpeg?fit=1600%2C1071&ssl=1",1600,1071,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-09-at-10.17.14.jpeg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-09-at-10.17.14.jpeg?fit=300%2C201&ssl=1",300,201,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-09-at-10.17.14.jpeg?fit=768%2C514&ssl=1",768,514,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-09-at-10.17.14.jpeg?fit=1024%2C685&ssl=1",1024,685,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-09-at-10.17.14.jpeg?fit=1536%2C1028&ssl=1",1536,1028,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-09-at-10.17.14.jpeg?fit=1600%2C1071&ssl=1",1600,1071,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Uma mulher de 36 anos, foi presa pela Pol\u00edcia Penal tentando entrar com comprimidos de viagra e maconha dentro da Penitenci\u00e1ria de Ribeir\u00e3o Preto. Segundo informa\u00e7\u00f5es da Pol\u00edcia Civil, durante as revistas aos visitantes dos presos da Penitenci\u00e1ria de Ribeir\u00e3o Preto, os Policiais Penais suspeitaram de uma visitante que ao passar pelo scanner constou&hellip;","jetpack-related-posts":[{"id":3559,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/19\/utm_sourcerssutm_mediumrssutm_campaignmulher-e-presa-tentando-entrar-com-maconha-na-penitenciaria-de-ribeirao-preto\/","url_meta":{"origin":26164,"position":0},"title":"Mulher \u00e9 presa tentando entrar com maconha na Penitenci\u00e1ria de Ribeir\u00e3o Preto \u2013 X Tudo Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"19 de Novembro de 2023","format":false,"excerpt":"[ad_1] Uma mulher foi presa na manh\u00e3 deste s\u00e1bado (18\/11), tentando entrar com maconha dentro da Penitenci\u00e1ria masculina situada na rodovia Abra\u00e3o Assed, entre Ribeir\u00e3o Preto e Serrana.\u00a0 Segundo informa\u00e7\u00f5es da Pol\u00edcia Civil, durante as revistas aos visitantes dos presos da Penitenci\u00e1ria de Ribeir\u00e3o Preto, os Policiais Penais suspeitaram de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-19-at-01.33.45.jpeg?fit=802%2C714&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-19-at-01.33.45.jpeg?fit=802%2C714&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-19-at-01.33.45.jpeg?fit=802%2C714&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-19-at-01.33.45.jpeg?fit=802%2C714&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":43052,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/19\/mulher-e-presa-tentando-entrar-com-maconha-na-penitenciaria\/","url_meta":{"origin":26164,"position":1},"title":"Mulher \u00e9 presa tentando entrar com maconha na penitenci\u00e1ria","author":"ismaelcolosi.com.br","date":"19 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] Visitante foi flagrada em revista por meio de esc\u00e2ner corporal 19 de mar\u00e7o de 2024 | 7:1018 de mar\u00e7o de 2024 | 17:12 1Por: Adalberto LuqueUma mulher foi presa, neste domingo (17), ao tentar entrar com 70 gramas de maconha escondidas em seu corpo. Ela visitava o companheiro, que\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-18-fev-2024-maconha-penitenciaria-foto-sap.jpg?fit=360%2C232&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":31085,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/20\/utm_sourcerssutm_mediumrssutm_campaignidosa-e-preso-com-maconha-no-anus-tentando-entrar-na-penitenciaria-de-ribeirao-preto\/","url_meta":{"origin":26164,"position":2},"title":"Idosa \u00e9 preso com maconha no \u00e2nus tentando entrar na Penitenci\u00e1ria de Ribeir\u00e3o Preto \u2013 X Tudo Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"20 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Uma idosa de 62 anos foi presa ao tentar entrar com uma por\u00e7\u00e3o de maconha introduzida no \u00e2nus na Penitenci\u00e1ria de Ribeir\u00e3o Preto, as margens da rodovia Abra\u00e3o Assed.\u00a0 Segundo informa\u00e7\u00f5es da Pol\u00edcia, a descoberta da droga foi feita pelos Policiais Penais durante a vistoria no scanner aos visitantes\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/IMG-20181105-WA0000.jpg?fit=620%2C465&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/IMG-20181105-WA0000.jpg?fit=620%2C465&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/IMG-20181105-WA0000.jpg?fit=620%2C465&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":823,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/09\/mulher-e-presa-tentando-entrar-com-drogas-no-anus-na-penitenciaria-de-ribeirao-preto-x-tudo-ribeirao\/","url_meta":{"origin":26164,"position":3},"title":"Mulher \u00e9 presa tentando entrar com drogas no \u00e2nus na Penitenci\u00e1ria de Ribeir\u00e3o Preto \u2013 X Tudo Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"9 de Novembro de 2023","format":false,"excerpt":"[ad_1] Uma mulher foi presa na manh\u00e3 deste domingo (5\/11), tentando entrar com drogas introduzidas no \u00e2nus dentro da Penitenci\u00e1ria de Ribeir\u00e3o Preto. Segundo informa\u00e7\u00f5es da Pol\u00edcia Civil, durante as revistas aos visitantes dos presos da Penitenci\u00e1ria de Ribeir\u00e3o Preto, os Policiais Penais suspeitaram de uma visitante que ao passar\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-05-at-17.18.58.jpeg?fit=672%2C423&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-05-at-17.18.58.jpeg?fit=672%2C423&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-05-at-17.18.58.jpeg?fit=672%2C423&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":24155,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/03\/utm_sourcerssutm_mediumrssutm_campaignvelho-safado-preso-por-abusar-de-duas-criancas-em-matao-morre-apos-passar-mal-na-penitenciaria-de-serra-azul\/","url_meta":{"origin":26164,"position":4},"title":"VELHO SAFADO preso por abusar de duas crian\u00e7as em Mat\u00e3o morre ap\u00f3s passar mal na Penitenci\u00e1ria de Serra Azul \u2013 X Tudo Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"3 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Um velho safado preso ap\u00f3s abusar sexualmente de duas crian\u00e7as no ano de 2017, morreu ap\u00f3s passar mal nas depend\u00eancias da Penitenci\u00e1ria de Serra Azul, onde estava preso.\u00a0 Segundo apurado com a Pol\u00edcia, o velho safado de 69 anos, teria passado mal na Penitenci\u00e1ria de Serra Azul, sendo socorrido\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/cadeia-preso.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/cadeia-preso.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/cadeia-preso.jpeg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/cadeia-preso.jpeg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/cadeia-preso.jpeg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":47864,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/29\/casal-e-preso-com-grande-quantidade-de-maconha-em-carro-na-regiao-de-ribeirao\/","url_meta":{"origin":26164,"position":5},"title":"Casal \u00e9 preso com grande quantidade de maconha em carro na regi\u00e3o de Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"29 de Abril de 2024","format":false,"excerpt":"[ad_1] Um casal foi preso por tr\u00e1fico de drogas ap\u00f3s a pol\u00edcia encontrar 90 quilos de maconha dentro de um carro na tarde deste domingo (29), na rodovia Carlos Tonani (SP-333), em Sert\u00e3ozinho. Um homem conduzia o ve\u00edculo \u2013 um Ford Ka branco \u2013 e uma mulher seguia como passageira,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-29-at-10.06.15-1_2024-04-29_13-50-36_jpeg.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-29-at-10.06.15-1_2024-04-29_13-50-36_jpeg.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-29-at-10.06.15-1_2024-04-29_13-50-36_jpeg.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-29-at-10.06.15-1_2024-04-29_13-50-36_jpeg.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-29-at-10.06.15-1_2024-04-29_13-50-36_jpeg.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-6O0","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/26164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=26164"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/26164\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/26165"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=26164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=26164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=26164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}