{"id":25351,"date":"2024-01-06T22:06:41","date_gmt":"2024-01-07T01:06:41","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/06\/105-anos-do-lar-padre-euclides\/"},"modified":"2024-01-06T22:06:41","modified_gmt":"2024-01-07T01:06:41","slug":"105-anos-do-lar-padre-euclides","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/06\/105-anos-do-lar-padre-euclides\/","title":{"rendered":"105 anos do Lar Padre Euclides\u00a0"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"\">\n<p> <span class=\"entry-meta-item penci-posted-on\"><i class=\"fa fa-clock-o\"\/><time class=\"entry-date published\" datetime=\"2024-01-06T11:00:25-03:00\">6 de janeiro de 2024 | 11:00<\/time><time class=\"updated\" datetime=\"2024-01-05T18:27:55-03:00\">5 de janeiro de 2024 | 18:27<\/time><\/span><\/p>\n<p> <span class=\"penci-social-buttons penci-social-share-footer\"><a href=\"#\" class=\"penci-post-like penci_post-meta_item  single-like-button penci-social-item like\" data-post_id=\"369449\" title=\"Like\" data-like=\"Like\" data-unlike=\"Unlike\"><i class=\"fa fa-thumbs-o-up\"\/><span class=\"penci-share-number\">0<\/span><\/a><i class=\"fa fa-facebook\"\/><a class=\"penci-social-item twitter\" target=\"_blank\" rel=\"noopener\" title=\"\" href=\"https:\/\/twitter.com\/intent\/tweet?text=105%20anos%20do%20Lar%20Padre%20Euclides\u00a0%20-%20https:\/\/www.tribunaribeirao.com.br\/site\/105-anos-do-lar-padre-euclides\/\"><i class=\"fa fa-twitter\"\/><\/a><i class=\"fa fa-whatsapp\"\/><\/span><\/div>\n<div>\n<p><span data-contrast=\"auto\">Uma das institui\u00e7\u00f5es mais tradicionais e respeitadas de Ribeir\u00e3o Preto est\u00e1 em festa. O Lar Padre Euclides, localizado na Avenida Saudade, 1577 \u2013 Campos Eli\u0301seos, comemorou nesta sexta-feira, dia 05 de janeiro, 105 anos de exist\u00eancia. A data foi repleta de atividades que inclu\u00edram muita m\u00fasica, feira de expositores, entretenimento e boa gastronomia.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Fundado no ano de 1919 pelo Padre Euclides Gomes Carneiro, o Lar \u00e9 uma casa de longa perman\u00eancia para idosos que prossegue at\u00e9 os dias atuais, oferecendo moradia, alimenta\u00e7\u00e3o, enfermaria, medicamentos, recrea\u00e7\u00e3o e acima de tudo, carinho e aten\u00e7\u00e3o. A institui\u00e7\u00e3o \u00e9 filantr\u00f3pica.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Muito mais do que o acolhimento, o Lar oferece um cuidado integral, com acesso a atividades l\u00fadicas, educativas, de lazer, cultural, para inserir os idosos com a comunidade.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">O evento foi aberto ao p\u00fablico.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<figure id=\"attachment_369451\" aria-describedby=\"caption-attachment-369451\" style=\"width: 300px\" class=\"wp-caption alignleft\"><img data-recalc-dims=\"1\" decoding=\"async\" alt=\"\" width=\"300\" height=\"195\" srcset=\"https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/01\/2-foto-legenda-lar-300x195.jpeg 300w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/01\/2-foto-legenda-lar-1024x665.jpeg 1024w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/01\/2-foto-legenda-lar-768x499.jpeg 768w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/01\/2-foto-legenda-lar-1536x997.jpeg 1536w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/01\/2-foto-legenda-lar-960x623.jpeg 960w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/01\/2-foto-legenda-lar-616x400.jpeg 616w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/01\/2-foto-legenda-lar-585x380.jpeg 585w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/01\/2-foto-legenda-lar-scaled.jpeg 994w\" src=\"https:\/\/i0.wp.com\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/01\/2-foto-legenda-lar-300x195.jpeg?resize=300%2C195&#038;ssl=1\" data-sizes=\"(max-width: 300px) 100vw, 300px\" class=\"size-medium wp-image-369451 lazyload\"\/><noscript><img data-recalc-dims=\"1\" decoding=\"async\" class=\"size-medium wp-image-369451\" src=\"https:\/\/i0.wp.com\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/01\/2-foto-legenda-lar-300x195.jpeg?resize=300%2C195&#038;ssl=1\" alt=\"\" width=\"300\" height=\"195\" srcset=\"https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/01\/2-foto-legenda-lar-300x195.jpeg 300w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/01\/2-foto-legenda-lar-1024x665.jpeg 1024w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/01\/2-foto-legenda-lar-768x499.jpeg 768w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/01\/2-foto-legenda-lar-1536x997.jpeg 1536w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/01\/2-foto-legenda-lar-960x623.jpeg 960w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/01\/2-foto-legenda-lar-616x400.jpeg 616w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/01\/2-foto-legenda-lar-585x380.jpeg 585w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2024\/01\/2-foto-legenda-lar-scaled.jpeg 994w\" sizes=\"(max-width: 300px) 100vw, 300px\"\/><\/noscript><figcaption id=\"caption-attachment-369451\" class=\"wp-caption-text\">(Max Gall\u00e3o Mesquita)<\/figcaption><\/figure>\n<p><span data-contrast=\"auto\">Neste anivers\u00e1rio de 105 anos do Lar Padre Euclides, Rog\u00e9rio Gomes \u2013 turism\u00f3logo e guia de Turismo, proporcionou aos participantes um tour e atividade de reconhecimento dentro das depend\u00eancias do Lar. Nesta atividade os presentes tiveram a oportunidade de conhecer e vivenciar fatos e hist\u00f3rias da institui\u00e7\u00e3o e do bairro, al\u00e9m da import\u00e2ncia do Lar para nossa cidade em tempos passados e nos dias atuais.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/site\/105-anos-do-lar-padre-euclides\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] 6 de janeiro de 2024 | 11:005 de janeiro de 2024 | 18:27 0 Uma das institui\u00e7\u00f5es mais tradicionais e respeitadas de Ribeir\u00e3o Preto est\u00e1 em festa. O Lar Padre Euclides, localizado na Avenida Saudade, 1577 \u2013 Campos Eli\u0301seos, comemorou nesta sexta-feira, dia 05 de janeiro, 105 anos de exist\u00eancia. A data foi repleta &#8230; <a title=\"105 anos do Lar Padre Euclides\u00a0\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/06\/105-anos-do-lar-padre-euclides\/\" aria-label=\"Leia mais sobre 105 anos do Lar Padre Euclides\u00a0\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":25352,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[84,3143,3005,3006],"class_list":["post-25351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-anos","tag-euclides","tag-lar","tag-padre"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/2-lar-2-scaled.jpeg?fit=936%2C645&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/2-lar-2-scaled.jpeg?fit=936%2C645&ssl=1",936,645,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/2-lar-2-scaled.jpeg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/2-lar-2-scaled.jpeg?fit=300%2C207&ssl=1",300,207,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/2-lar-2-scaled.jpeg?fit=768%2C529&ssl=1",768,529,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/2-lar-2-scaled.jpeg?fit=936%2C645&ssl=1",936,645,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/2-lar-2-scaled.jpeg?fit=936%2C645&ssl=1",936,645,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/2-lar-2-scaled.jpeg?fit=936%2C645&ssl=1",936,645,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] 6 de janeiro de 2024 | 11:005 de janeiro de 2024 | 18:27 0 Uma das institui\u00e7\u00f5es mais tradicionais e respeitadas de Ribeir\u00e3o Preto est\u00e1 em festa. O Lar Padre Euclides, localizado na Avenida Saudade, 1577 \u2013 Campos Eli\u0301seos, comemorou nesta sexta-feira, dia 05 de janeiro, 105 anos de exist\u00eancia. A data foi repleta&hellip;","jetpack-related-posts":[{"id":24498,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/04\/lar-padre-euclides-tera-festa-de-105-anos\/","url_meta":{"origin":25351,"position":0},"title":"Lar Padre Euclides\u00a0ter\u00e1 festa de 105 anos","author":"ismaelcolosi.com.br","date":"4 de Janeiro de 2024","format":false,"excerpt":"[ad_1] 4 de janeiro de 2024 | 14:004 de janeiro de 2024 | 10:52 0Em comemora\u00e7\u00e3o aos 105 anos de idade, o Lar Padre Euclides realiza na pr\u00f3xima sexta-feira, dia 05 de janeiro, um dia repleto de atividades que incluem muita m\u00fasica, feira de expositores, entretenimento e boa gastronomia.\u00a0Fundado no\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/3-_lar_p_euclides_2.jpg?fit=968%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/3-_lar_p_euclides_2.jpg?fit=968%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/3-_lar_p_euclides_2.jpg?fit=968%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/3-_lar_p_euclides_2.jpg?fit=968%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":56292,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/10\/lar-padre-euclides-em-ribeirao-preto-realiza-arraia-com-comidas-tipicas-e-musica-ao-vivo\/","url_meta":{"origin":25351,"position":1},"title":"Lar Padre Euclides em Ribeir\u00e3o Preto realiza \u2018arrai\u00e1\u2019 com comidas t\u00edpicas e m\u00fasica ao vivo","author":"ismaelcolosi.com.br","date":"10 de Julho de 2024","format":false,"excerpt":"[ad_1] O Lar Padre Euclides realiza dois dias de \u201carrai\u00e1\u201d com barracas de comidas e bebidas t\u00edpicas, m\u00fasica ao vivo, apresenta\u00e7\u00e3o de dan\u00e7a, bingo e espa\u00e7o kids. O evento, com entrada gratuita, ser\u00e1 nesta sexta-feira (12) e no s\u00e1bado (13), a partir das 17h. Toda renda arrecadada nas vendas das\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/festa_junina_1024x576_24062020120510.jpg?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/festa_junina_1024x576_24062020120510.jpg?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/festa_junina_1024x576_24062020120510.jpg?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/festa_junina_1024x576_24062020120510.jpg?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":44172,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/26\/semana-santa-confira-a-programacao-das-missas-em-igrejas-de-ribeirao-preto\/","url_meta":{"origin":25351,"position":2},"title":"Semana Santa: Confira a programa\u00e7\u00e3o das missas em igrejas de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"26 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] Igrejas cat\u00f3licas de Ribeir\u00e3o Preto divulgaram a programa\u00e7\u00e3o para a Semana Santa. As celebra\u00e7\u00f5es marcam a trajet\u00f3ria de Jesus Cristo at\u00e9 a crucifica\u00e7\u00e3o e a ressurrei\u00e7\u00e3o. Confira as datas e hor\u00e1rios em sete igrejas de Ribeir\u00e3o: 1. Catedral Metropolitana de S\u00e3o Sebasti\u00e3o Quinta-feira (28) Ceia do Senhor (Lava-p\u00e9s) \u2013\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/20220618_024226476_catedral_sao_1200x675_17062022004910-1.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/20220618_024226476_catedral_sao_1200x675_17062022004910-1.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/20220618_024226476_catedral_sao_1200x675_17062022004910-1.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/20220618_024226476_catedral_sao_1200x675_17062022004910-1.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/20220618_024226476_catedral_sao_1200x675_17062022004910-1.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":43454,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/21\/centro-de-voluntariado-de-ribeirao-abre-inscricoes-para-capacitacao-de-novos-voluntarios\/","url_meta":{"origin":25351,"position":3},"title":"Centro de Voluntariado de Ribeir\u00e3o abre inscri\u00e7\u00f5es para capacita\u00e7\u00e3o de novos volunt\u00e1rios","author":"ismaelcolosi.com.br","date":"21 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] O Centro de Voluntariado de Ribeir\u00e3o Preto (CVRP) est\u00e1 com inscri\u00e7\u00f5es abertas para o 12\u00ba Programa de Capacita\u00e7\u00e3o de Novos Volunt\u00e1rios. Os interessados podem se inscrever pela internet (clique aqui) at\u00e9 o dia 2 de abril. As vagas s\u00e3o limitadas. O programa ser\u00e1 realizado em duas etapas na sede\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/social-assistant-worker-consoling-handicapped-pensioner-patient-touching-hands-scaled.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/social-assistant-worker-consoling-handicapped-pensioner-patient-touching-hands-scaled.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/social-assistant-worker-consoling-handicapped-pensioner-patient-touching-hands-scaled.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/social-assistant-worker-consoling-handicapped-pensioner-patient-touching-hands-scaled.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/social-assistant-worker-consoling-handicapped-pensioner-patient-touching-hands-scaled.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":42456,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/14\/novo-livro-de-assis-soares-e-semiramis-paterno-fala-de-sonho-e-perseveranca\/","url_meta":{"origin":25351,"position":4},"title":"Novo livro de Assis Soares e Sem\u00edramis Paterno fala de sonho e perseveran\u00e7a","author":"ismaelcolosi.com.br","date":"14 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] 14 de mar\u00e7o de 2024 | 16:44 0A girafa que queria voar \u00e9 o novo t\u00edtulo infantil que ser\u00e1 lan\u00e7ado na Biblioteca Padre Euclides. A hist\u00f3ria nasceu de uma troca de ideias entre os dois autores, inspirando um tratamento diferente para as ilustra\u00e7\u00f5es de Sem\u00edramis Paterno. \u201c\u00c9 bom deixarmos\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/download-1.png?fit=674%2C379&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/download-1.png?fit=674%2C379&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/download-1.png?fit=674%2C379&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":15203,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/13\/liberada-obra-na-santo-antoninho\/","url_meta":{"origin":25351,"position":5},"title":"Liberada obra na\u00a0Santo Antoninho\u00a0 &#8211; Jornal Tribuna Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"13 de Dezembro de 2023","format":false,"excerpt":"[ad_1] 13 de dezembro de 2023 | 8:3012 de dezembro de 2023 | 21:22 0Igreja foi constru\u00edda no s\u00e9culo XIX, entre 1892 e 1898, e fundada em 13 de junho de 1903 pelo padre Euclides Carneiro: templo em p\u00e9 mais antigo\u00a0(Alfredo Risk)O Conselho de Preserva\u00e7\u00e3o do Patrim\u00f4nio Cultural (Conppac) de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/igreja-santo-antoninho-scaled.jpg?fit=1000%2C563&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/igreja-santo-antoninho-scaled.jpg?fit=1000%2C563&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/igreja-santo-antoninho-scaled.jpg?fit=1000%2C563&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/igreja-santo-antoninho-scaled.jpg?fit=1000%2C563&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-6AT","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/25351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=25351"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/25351\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/25352"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=25351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=25351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=25351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}