{"id":23081,"date":"2024-01-01T09:02:22","date_gmt":"2024-01-01T12:02:22","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/01\/reoneracao-integral-do-diesel-retorna-nesta-segunda\/"},"modified":"2024-01-01T09:02:22","modified_gmt":"2024-01-01T12:02:22","slug":"reoneracao-integral-do-diesel-retorna-nesta-segunda","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/01\/reoneracao-integral-do-diesel-retorna-nesta-segunda\/","title":{"rendered":"Reonera\u00e7\u00e3o integral do diesel retorna nesta segunda"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"\">\n<p> <span class=\"entry-meta-item penci-posted-on\"><i class=\"fa fa-clock-o\"\/><time class=\"entry-date published\" datetime=\"2024-01-01T09:00:07-03:00\">1 de janeiro de 2024 | 9:00<\/time><time class=\"updated\" datetime=\"2023-12-31T14:35:51-03:00\">31 de dezembro de 2023 | 14:35<\/time><\/span><\/p>\n<p> <span class=\"penci-social-buttons penci-social-share-footer\"><a href=\"#\" class=\"penci-post-like penci_post-meta_item  single-like-button penci-social-item like\" data-post_id=\"368918\" title=\"Like\" data-like=\"Like\" data-unlike=\"Unlike\"><i class=\"fa fa-thumbs-o-up\"\/><span class=\"penci-share-number\">0<\/span><\/a><i class=\"fa fa-facebook\"\/><a class=\"penci-social-item twitter\" target=\"_blank\" rel=\"noopener\" title=\"\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Reonera\u00e7\u00e3o%20integral%20do%20diesel%20retorna%20nesta%20segunda%20-%20https:\/\/www.tribunaribeirao.com.br\/site\/reoneracao-integral-do-diesel-retorna-nesta-segunda\/\"><i class=\"fa fa-twitter\"\/><\/a><i class=\"fa fa-whatsapp\"\/><\/span><\/div>\n<div>\n<p>A partir desta segunda-feira (1\u00ba), o governo federal retoma a cobran\u00e7a integral do PIS\/Cofins sobre o diesel. O imposto estava zerado desde 2021, mas parte do recolhimento foi antecipada j\u00e1 em setembro deste ano. A partir de janeiro de 2024, a arrecada\u00e7\u00e3o volta a ser integral: cerca de R$ 0,35 por litro de diesel.\u00a0<img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/agenciabrasil.ebc.com.br\/ebc.png?w=1200&#038;ssl=1\" class=\"lazyload\"\/><noscript><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/agenciabrasil.ebc.com.br\/ebc.png?w=1200&#038;ssl=1\"\/><\/noscript><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/agenciabrasil.ebc.com.br\/ebc.gif?w=1200&#038;ssl=1\" class=\"lazyload\"\/><noscript><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/agenciabrasil.ebc.com.br\/ebc.gif?w=1200&#038;ssl=1\"\/><\/noscript><\/p>\n<p>No \u00faltimo dia 26, o ministro da Fazenda, Fernando Haddad, afirmou que a reonera\u00e7\u00e3o n\u00e3o deve encarecer o produto para os consumidores que pagam pelo litro nos postos de abastecimento. Segundo ele, o aumento da carga tribut\u00e1ria que incide sobre o diesel ser\u00e1 amenizado pelas redu\u00e7\u00f5es de pre\u00e7o j\u00e1 anunciadas pela Petrobras.<\/p>\n<p>\u201cEsta reonera\u00e7\u00e3o do diesel vai ser feita, mas o impacto [esperado] \u00e9 de pouco mais de R$ 0,30\u201d, disse. Poucas horas antes, a Petrobras havia anunciado um corte de R$ 0,30 no pre\u00e7o do litro do diesel vendido \u00e0s distribuidoras de combust\u00edvel. Segundo a empresa, no ano, a redu\u00e7\u00e3o do pre\u00e7o para as distribuidoras chega a 22,5%.<\/p>\n<p>\u201c[Essa redu\u00e7\u00e3o] mais que compensa a reonera\u00e7\u00e3o [que entrar\u00e1 em vigor em] 1\u00ba de janeiro\u201d, assegurou Haddad, garantindo n\u00e3o haver raz\u00f5es para alta do pre\u00e7o com a volta da cobran\u00e7a dos impostos federais. \u201cPelo contr\u00e1rio: deveria haver uma pequena redu\u00e7\u00e3o [do pre\u00e7o final].\u201d<\/p>\n<p>\u201c\u00c9 para todo mundo ficar atento: quando vier um argumento de aumento de pre\u00e7o, n\u00e3o tem nada a ver. Estamos em um pa\u00eds de livre-mercado; os pre\u00e7os n\u00e3o s\u00e3o tabelados. Mas, no que diz respeito aos pre\u00e7os da Petrobras, neste m\u00eas de dezembro, o pre\u00e7o [do diesel] caiu mais que a reonera\u00e7\u00e3o de 1\u00ba janeiro.\u201d<\/p>\n<\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/site\/reoneracao-integral-do-diesel-retorna-nesta-segunda\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] 1 de janeiro de 2024 | 9:0031 de dezembro de 2023 | 14:35 0 A partir desta segunda-feira (1\u00ba), o governo federal retoma a cobran\u00e7a integral do PIS\/Cofins sobre o diesel. O imposto estava zerado desde 2021, mas parte do recolhimento foi antecipada j\u00e1 em setembro deste ano. A partir de janeiro de 2024, &#8230; <a title=\"Reonera\u00e7\u00e3o integral do diesel retorna nesta segunda\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/01\/reoneracao-integral-do-diesel-retorna-nesta-segunda\/\" aria-label=\"Leia mais sobre Reonera\u00e7\u00e3o integral do diesel retorna nesta segunda\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":23082,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[1865,2882,207,2881,2883,839],"class_list":["post-23081","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-diesel","tag-integral","tag-nesta","tag-reoneracao","tag-retorna","tag-segunda"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/8b462844-1f08-4a05-b377-fe2b0fe7ef1d-scaled.jpg?fit=1000%2C598&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/8b462844-1f08-4a05-b377-fe2b0fe7ef1d-scaled.jpg?fit=1000%2C598&ssl=1",1000,598,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/8b462844-1f08-4a05-b377-fe2b0fe7ef1d-scaled.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/8b462844-1f08-4a05-b377-fe2b0fe7ef1d-scaled.jpg?fit=300%2C179&ssl=1",300,179,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/8b462844-1f08-4a05-b377-fe2b0fe7ef1d-scaled.jpg?fit=768%2C459&ssl=1",768,459,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/8b462844-1f08-4a05-b377-fe2b0fe7ef1d-scaled.jpg?fit=1000%2C598&ssl=1",1000,598,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/8b462844-1f08-4a05-b377-fe2b0fe7ef1d-scaled.jpg?fit=1000%2C598&ssl=1",1000,598,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/8b462844-1f08-4a05-b377-fe2b0fe7ef1d-scaled.jpg?fit=1000%2C598&ssl=1",1000,598,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] 1 de janeiro de 2024 | 9:0031 de dezembro de 2023 | 14:35 0 A partir desta segunda-feira (1\u00ba), o governo federal retoma a cobran\u00e7a integral do PIS\/Cofins sobre o diesel. O imposto estava zerado desde 2021, mas parte do recolhimento foi antecipada j\u00e1 em setembro deste ano. A partir de janeiro de 2024,&hellip;","jetpack-related-posts":[{"id":30180,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/20\/desoneracao-da-folha-gera-ruido\/","url_meta":{"origin":23081,"position":0},"title":"Desonera\u00e7\u00e3o da folha gera ru\u00eddo \u00a0","author":"ismaelcolosi.com.br","date":"20 de Janeiro de 2024","format":false,"excerpt":"[ad_1] 20 de janeiro de 2024 | 15:0020 de janeiro de 2024 | 9:58 0O presidente do Senado, Rodrigo Pacheco, afirmou nesta sexta-feira, 19 de janeiro, que a desonera\u00e7\u00e3o da folha de pagamentos valer\u00e1 e que a medida provis\u00f3ria (MP) que retoma impostos sobre sal\u00e1rios ser\u00e1 revogada. \u201cH\u00e1 o compromisso\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Desonera-Marcelo-Camargo-Ag.Br_-scaled.jpg?fit=1000%2C603&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Desonera-Marcelo-Camargo-Ag.Br_-scaled.jpg?fit=1000%2C603&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Desonera-Marcelo-Camargo-Ag.Br_-scaled.jpg?fit=1000%2C603&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Desonera-Marcelo-Camargo-Ag.Br_-scaled.jpg?fit=1000%2C603&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":32650,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/25\/abrasmercado-tem-deflacao-de-422\/","url_meta":{"origin":23081,"position":1},"title":"Abrasmercado tem defla\u00e7\u00e3o de 4,22% \u00a0","author":"ismaelcolosi.com.br","date":"25 de Janeiro de 2024","format":false,"excerpt":"[ad_1] A Abrasmercado \u2013 indicador que mede a varia\u00e7\u00e3o de pre\u00e7os nos supermercados \u2013, cesta composta por 35 produtos de largo consumo, dentre eles alimentos, bebidas, carnes, produtos de limpeza, itens de higiene e beleza, fechou o ano passado com defla\u00e7\u00e3o de 4,22% em doze meses, maior queda anual registrada\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Abras-Acu-Alfredo-Risk-scaled.jpg?fit=860%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Abras-Acu-Alfredo-Risk-scaled.jpg?fit=860%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Abras-Acu-Alfredo-Risk-scaled.jpg?fit=860%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Abras-Acu-Alfredo-Risk-scaled.jpg?fit=860%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":66291,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/16\/dinheiro-esquecido-uma-unica-pessoa-tem-r-112-milhoes-a-sacar-veja-como-resgatar\/","url_meta":{"origin":23081,"position":2},"title":"&#8216;Dinheiro esquecido&#8217;: uma \u00fanica pessoa tem R$ 11,2 milh\u00f5es a sacar; veja como resgatar","author":"ismaelcolosi.com.br","date":"16 de Setembro de 2024","format":false,"excerpt":"[ad_1] Uma \u00fanica pessoa tem R$ 11,2 milh\u00f5es \u201cesquecidos\u201d dispon\u00edveis para saque no Sistema de Valores a Receber (SVR), ferramenta do Banco Central que mostra recursos deixados por clientes em contas banc\u00e1rias, cons\u00f3rcios ou outras institui\u00e7\u00f5es Essa \u00e9 a maior cifra dispon\u00edvel para resgate entre pessoas f\u00edsicas. J\u00e1 entre pessoas\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/real_moeda_dinheiro_mcajr_2904223671.webp.webp?fit=1024%2C768&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/real_moeda_dinheiro_mcajr_2904223671.webp.webp?fit=1024%2C768&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/real_moeda_dinheiro_mcajr_2904223671.webp.webp?fit=1024%2C768&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/real_moeda_dinheiro_mcajr_2904223671.webp.webp?fit=1024%2C768&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":51233,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/24\/classificados-de-empregos-vagas-de-empregos-em-ribeirao-preto-sp-veja-agora-8\/","url_meta":{"origin":23081,"position":3},"title":"Classificados de empregos: vagas de empregos em Ribeir\u00e3o Preto-SP, veja agora","author":"ismaelcolosi.com.br","date":"24 de Maio de 2024","format":false,"excerpt":"Promotora de Vendas Ribeir\u00e3o Preto - SP Presencial Per\u00edodo Integral 1 Posi\u00e7\u00e3o Efetivo \u2013 CLT 24 mai Desenhista Cadista Ribeir\u00e3o Preto - SP Presencial Per\u00edodo Integral 1 Posi\u00e7\u00e3o Efetivo \u2013 CLT 20 mai Recepcionista Ribeir\u00e3o Preto - SP Presencial Per\u00edodo Integral 1 Posi\u00e7\u00e3o Efetivo \u2013 CLT 15 mai Consultor de\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":50098,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/14\/classificados-de-empregos-vagas-de-empregos-em-ribeirao-preto-sp-veja-agora-7\/","url_meta":{"origin":23081,"position":4},"title":"Classificados de empregos: vagas de empregos em Ribeir\u00e3o Preto-SP, veja agora","author":"ismaelcolosi.com.br","date":"14 de Maio de 2024","format":false,"excerpt":"Analista Cont\u00e1bil Ribeir\u00e3o Preto - SP Presencial Per\u00edodo Integral 1 Posi\u00e7\u00e3o Efetivo \u2013 CLT 14 mai Auxiliar de Projetos (Desenhos) Ribeir\u00e3o Preto - SP Presencial Per\u00edodo Integral 1 Posi\u00e7\u00e3o Efetivo \u2013 CLT 14 mai Vendedor Interno Ribeir\u00e3o Preto - SP Presencial Per\u00edodo Integral 1 Posi\u00e7\u00e3o Efetivo \u2013 CLT 13 mai\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":53135,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/13\/classificados-de-empregos-vagas-de-empregos-em-ribeirao-preto-sp-veja-agora-10\/","url_meta":{"origin":23081,"position":5},"title":"Classificados de empregos: vagas de empregos em Ribeir\u00e3o Preto-SP, veja agora","author":"ismaelcolosi.com.br","date":"13 de Junho de 2024","format":false,"excerpt":"Vendedor Interno Ribeir\u00e3o Preto - SP Presencial Per\u00edodo Integral 1 Posi\u00e7\u00e3o Efetivo \u2013 CLT 13 jun Analista de Banco de Dados Ribeir\u00e3o Preto - SP Presencial Per\u00edodo Integral 1 Posi\u00e7\u00e3o Efetivo \u2013 CLT 12 jun Analista de RH Ribeir\u00e3o Preto - SP Presencial Per\u00edodo Integral 1 Posi\u00e7\u00e3o Efetivo \u2013 CLT\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-60h","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=23081"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23081\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/23082"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=23081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=23081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=23081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}