{"id":23072,"date":"2024-01-01T08:15:49","date_gmt":"2024-01-01T11:15:49","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/01\/caixa-e-bb-devem-crescer-mais-que-rivais-em-2024\/"},"modified":"2024-01-01T08:15:49","modified_gmt":"2024-01-01T11:15:49","slug":"caixa-e-bb-devem-crescer-mais-que-rivais-em-2024","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/01\/caixa-e-bb-devem-crescer-mais-que-rivais-em-2024\/","title":{"rendered":"Caixa e BB devem crescer mais que rivais em 2024"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"Corpo\">Os bancos p\u00fablicos devem continuar a crescer mais forte que os pares privados em 2024, de acordo com as previs\u00f5es de mercado Banco do Brasil e Caixa Econ\u00f4mica Federal (CEF), que sustentaram um aumento de dois d\u00edgitos nas carteiras de cr\u00e9dito ao longo de 2023, devem manter uma expans\u00e3o mais forte gra\u00e7as ao perfil dos neg\u00f3cios em que atuam e do maior conservadorismo dos pares do setor privado.<\/p>\n<p>Nos nove primeiros meses do ano, a carteira da Caixa cresceu 11,4% em rela\u00e7\u00e3o ao mesmo per\u00edodo de 2022, batendo em R$ 1,091 trilh\u00e3o. No BB, a expans\u00e3o foi de 10%, para R$ 1,066 trilh\u00e3o. A t\u00edtulo de compara\u00e7\u00e3o, o Ita\u00fa Unibanco, que tamb\u00e9m tem mais de R$ 1 trilh\u00e3o em opera\u00e7\u00f5es, cresceu 5,7% no mesmo intervalo.<\/p>\n<p>\u201cAcredito que no primeiro semestre, o \u2018WO\u2019 deve continuar, pelo menos em linhas direcionadas, e o mercado deve vir com mais parcim\u00f4nia [que n\u00f3s]\u201d, afirma o vice-presidente de Finan\u00e7as e Controladoria da Caixa, Marcos Brasiliano. Foi uma modalidade direcionada, o cr\u00e9dito imobili\u00e1rio, que garantiu a \u201clargada\u201d do banco em 2023, com crescimento de 14,6% at\u00e9 setembro.<\/p>\n<p>O vice-presidente de Controles Internos e Gest\u00e3o de Riscos do BB, Felipe Prince, diz que o mercado tende a crescer mais no pr\u00f3ximo ano, ainda que de forma mais t\u00edmida que no per\u00edodo da pandemia. O banco, segundo ele, se beneficia por ter mantido o apetite de risco ao longo do \u00faltimo ano.<\/p>\n<p>\u201cO que fizemos foi selecionar os mercados com melhor retorno ajustado ao risco\u201d, afirma o executivo. Com capital aberto, o BB deve divulgar apenas em fevereiro as expectativas de crescimento da carteira em 2024. Entretanto, tem sinalizado que pode crescer um d\u00edgito porcentual alto ou dois d\u00edgitos baixos em rela\u00e7\u00e3o a 2023.<\/p>\n<p><b>Fatores<\/b><\/p>\n<p>A manuten\u00e7\u00e3o do apetite de Caixa e BB ao longo do ano vem de alguns fatores. Primeiro, os dois bancos t\u00eam como principais carteiras dois mercados que t\u00eam garantias e inadimpl\u00eancia mais baixa, o imobili\u00e1rio e o agr\u00edcola. Nos bancos privados, h\u00e1 uma maior presen\u00e7a de linhas de financiamento ao consumo, que t\u00eam maior risco.<\/p>\n<p>Matheus Amaral, analista do Inter, afirma que a lideran\u00e7a dos dois bancos nessas linhas ajuda a explicar porque eles mantiveram o apetite enquanto os bancos privados restringiram as torneiras.<\/p>\n<p>O BB tem mais da metade do mercado no cr\u00e9dito agr\u00edcola, que tem crescido junto com a produ\u00e7\u00e3o rural no Pa\u00eds. A Caixa det\u00e9m quase 70% do cr\u00e9dito imobili\u00e1rio, uma lideran\u00e7a que tem aumentado desde o ano passado. \u201c\u00c9 mais uma quest\u00e3o de o mercado desacelerar e esses bancos manterem o ritmo de concess\u00e3o\u201d, diz.<\/p>\n<p>No come\u00e7o do ano, o mercado esperava que os dois bancos crescessem de forma mais acelerada em 2023 ap\u00f3s a troca de governo, dado que o presidente Luiz In\u00e1cio Lula da Silva \u00e9 favor\u00e1vel \u00e0 expans\u00e3o da presen\u00e7a das institui\u00e7\u00f5es p\u00fablicas no mercado de cr\u00e9dito. O vice-presidente e analista s\u00eanior da Moody\u2019s, Alexandre Albuquerque, afirma que a expans\u00e3o encontra bases t\u00e9cnicas no balan\u00e7o dos bancos.<\/p>\n<p>\u201cOs bancos p\u00fablicos est\u00e3o em uma posi\u00e7\u00e3o melhor em rela\u00e7\u00e3o a capital, que continua a ser acima dos pares privados, e esse \u00e9 um fator que auxilia nesse crescimento\u201d, diz ele. Outro ponto positivo, segundo ele, \u00e9 o acesso a fontes de financiamento baratas \u2013 a poupan\u00e7a, no caso da Caixa, e dep\u00f3sitos \u00e0 vista e judiciais, no do BB.<\/p>\n<p><b>Uns foram, os dois ficaram<\/b><\/p>\n<p>Brasiliano, da Caixa, afirma que em momentos de juro alto, os bancos privados tendem a reduzir as concess\u00f5es em carteiras como a do cr\u00e9dito imobili\u00e1rio, que tem um prazo longo e margens mais baixas. \u201cA carteira cresce nesse patamar acima de dois d\u00edgitos muito mais pela aus\u00eancia do mercado competindo nessas duas linhas que fazemos bastante [habita\u00e7\u00e3o e infraestrutura]. Fazemos praticamente 100% do or\u00e7amento do FGTS\u201d, afirma.<\/p>\n<p>Prince, do BB, diz que o banco n\u00e3o mudou a estrat\u00e9gia de concess\u00e3o de cr\u00e9dito neste ano. \u201cConcentramos o crescimento em linhas mais rent\u00e1veis, com melhor retorno ajustado ao risco e que estavam crescendo, n\u00e3o \u00e9 contrac\u00edclico\u201d, afirma o executivo<\/p>\n<p>Al\u00e9m do cr\u00e9dito rural, a institui\u00e7\u00e3o observou crescimento pr\u00f3ximo a dois d\u00edgitos em linhas n\u00e3o direcionadas, como o consignado, que subiu 8,9% em setembro em rela\u00e7\u00e3o ao mesmo per\u00edodo do ano passado. O vice de Controles e Riscos diz que o banco conseguiu ganhar espa\u00e7o no consignado para benefici\u00e1rios do INSS diante do menor custo de opera\u00e7\u00e3o.<\/p>\n<p>Com as redu\u00e7\u00f5es no teto de juros da modalidade pelo governo, os bancos privados reduziram as concess\u00f5es do produto, alegando que as taxas n\u00e3o cobrem os custos. No caso do BB, a origina\u00e7\u00e3o \u00e9 feita majoritariamente atrav\u00e9s da rede pr\u00f3pria, sem correspondentes, que formam um fator de custo importante para os rivais. \u201cEstruturalmente, o nosso consignado INSS \u00e9 menos custoso que os dos outros bancos\u201d, afirma Prince.<\/p>\n<\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/site\/caixa-e-bb-devem-crescer-mais-que-rivais-em-2024\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Os bancos p\u00fablicos devem continuar a crescer mais forte que os pares privados em 2024, de acordo com as previs\u00f5es de mercado Banco do Brasil e Caixa Econ\u00f4mica Federal (CEF), que sustentaram um aumento de dois d\u00edgitos nas carteiras de cr\u00e9dito ao longo de 2023, devem manter uma expans\u00e3o mais forte gra\u00e7as ao perfil &#8230; <a title=\"Caixa e BB devem crescer mais que rivais em 2024\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/01\/caixa-e-bb-devem-crescer-mais-que-rivais-em-2024\/\" aria-label=\"Leia mais sobre Caixa e BB devem crescer mais que rivais em 2024\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":23073,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[669,1314,977,276,2880],"class_list":["post-23072","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-caixa","tag-crescer","tag-devem","tag-mais","tag-rivais"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Banco-Central-1024x683-1-scaled.jpg?fit=967%2C645&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Banco-Central-1024x683-1-scaled.jpg?fit=967%2C645&ssl=1",967,645,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Banco-Central-1024x683-1-scaled.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Banco-Central-1024x683-1-scaled.jpg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Banco-Central-1024x683-1-scaled.jpg?fit=768%2C512&ssl=1",768,512,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Banco-Central-1024x683-1-scaled.jpg?fit=967%2C645&ssl=1",967,645,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Banco-Central-1024x683-1-scaled.jpg?fit=967%2C645&ssl=1",967,645,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Banco-Central-1024x683-1-scaled.jpg?fit=967%2C645&ssl=1",967,645,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Os bancos p\u00fablicos devem continuar a crescer mais forte que os pares privados em 2024, de acordo com as previs\u00f5es de mercado Banco do Brasil e Caixa Econ\u00f4mica Federal (CEF), que sustentaram um aumento de dois d\u00edgitos nas carteiras de cr\u00e9dito ao longo de 2023, devem manter uma expans\u00e3o mais forte gra\u00e7as ao perfil&hellip;","jetpack-related-posts":[{"id":80469,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/12\/26\/a-educacao-abre-portas-sou-exemplo-disso\/","url_meta":{"origin":23072,"position":0},"title":"\u201cA educa\u00e7\u00e3o abre portas, sou exemplo disso&#8221;","author":"ismaelcolosi.com.br","date":"26 de Dezembro de 2024","format":false,"excerpt":"[ad_1] \r Divulga\u00e7\u00e3o\r Den\u00edsio Liberato, primeiro l\u00edder da BB Asset de origem africana, est\u00e1 na\u00a0lista Forbes Melhores CEOs de 2024\r \u00a0 Acessibilidade \r L\r L\r A-\r A+\r \r \u25d0\r \r \u00a0 A BB Asset, empresa de gest\u00e3o de recursos do Banco do Brasil, \u00e9 uma gigante. Administra R$ 1,7 trilh\u00e3o\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/denisio-liberato-forbess-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/denisio-liberato-forbess-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/denisio-liberato-forbess-1200x675.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/denisio-liberato-forbess-1200x675.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/denisio-liberato-forbess-1200x675.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":32411,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/25\/banco-do-brasil-renegocia-r-2-bilhoes-em-dividas-do-fies\/","url_meta":{"origin":23072,"position":1},"title":"Banco do Brasil renegocia R$ 2 bilh\u00f5es em d\u00edvidas do Fies","author":"ismaelcolosi.com.br","date":"25 de Janeiro de 2024","format":false,"excerpt":"[ad_1] 24 de janeiro de 2024 | 16:3024 de janeiro de 2024 | 11:12 0O Banco do Brasil (BB) renegociou R$ 2 bilh\u00f5es em d\u00edvidas do Fies, o programa de financiamento estudantil para o ensino superior do governo federal, desde o in\u00edcio das repactua\u00e7\u00f5es, em novembro do ano passado. Segundo\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/07836b48-7a60-4701-af3c-efcca017bacf-scaled.jpg?fit=967%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/07836b48-7a60-4701-af3c-efcca017bacf-scaled.jpg?fit=967%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/07836b48-7a60-4701-af3c-efcca017bacf-scaled.jpg?fit=967%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/07836b48-7a60-4701-af3c-efcca017bacf-scaled.jpg?fit=967%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":37302,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/15\/abono-salarial-comeca-a-ser-pago-nesta-quinta\/","url_meta":{"origin":23072,"position":2},"title":"Abono salarial come\u00e7a a ser pago nesta quinta","author":"ismaelcolosi.com.br","date":"15 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] 15 de fevereiro de 2024 | 12:0015 de fevereiro de 2024 | 12:23 0Cerca de 24 milh\u00f5es de pessoas que trabalharam com carteira assinada em 2022 podem consultar o valor do abono salarial do Programa de Integra\u00e7\u00e3o Social (PIS) e do Programa de Forma\u00e7\u00e3o do Patrim\u00f4nio do Servidor P\u00fablico\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Abono-Agencia-Brasil-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Abono-Agencia-Brasil-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Abono-Agencia-Brasil-scaled.jpg?fit=1000%2C598&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Abono-Agencia-Brasil-scaled.jpg?fit=1000%2C598&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":33940,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/31\/desemprego-brasil-tem-menor-taxa-media-desde-2014\/","url_meta":{"origin":23072,"position":3},"title":"Desemprego: Brasil tem menor taxa m\u00e9dia desde 2014","author":"ismaelcolosi.com.br","date":"31 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Getty ImagesSomente no 4\u00ba trimestre, o n\u00famero de desempregados recuou 2,8% em rela\u00e7\u00e3o ao 3\u00ba trimestre, chegando a 8,082 milh\u00f5es de pessoas O Brasil encerrou 2023 com uma taxa m\u00e9dia de desemprego de 7,8%, a menor em quase 10 anos, depois de um resultado melhor que o esperado no\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/carreira-contratar-brasil-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/carreira-contratar-brasil-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/carreira-contratar-brasil-1024x683.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/carreira-contratar-brasil-1024x683.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":32932,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/26\/pix-deve-chegar-a-40-dos-pagamentos-online-ate-2026-e-empatar-com-cartao\/","url_meta":{"origin":23072,"position":4},"title":"Pix deve chegar a 40% dos pagamentos online at\u00e9 2026 e empatar com cart\u00e3o","author":"ismaelcolosi.com.br","date":"26 de Janeiro de 2024","format":false,"excerpt":"[ad_1] O Pix deve atingir 40% do mercado brasileiro de pagamentos at\u00e9 2026, projeta a empresa de pagamentos Ebanx. Com uma movimenta\u00e7\u00e3o financeira anual pr\u00f3xima a US$ 200 bilh\u00f5es (o equivalente a R$ 985,5 bilh\u00f5es), o sistema de pagamentos instant\u00e2neos deve empatar com os cart\u00f5es de cr\u00e9dito no posto de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/shutterstock_1919177990_pix-1140x694-1-scaled.jpg?fit=1000%2C609&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/shutterstock_1919177990_pix-1140x694-1-scaled.jpg?fit=1000%2C609&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/shutterstock_1919177990_pix-1140x694-1-scaled.jpg?fit=1000%2C609&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/shutterstock_1919177990_pix-1140x694-1-scaled.jpg?fit=1000%2C609&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":8956,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/01\/estao-confirmadas-as-datas-de-pagamento\/","url_meta":{"origin":23072,"position":5},"title":"est\u00e3o confirmadas as datas de pagamento?","author":"ismaelcolosi.com.br","date":"1 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Muitas pessoas t\u00eam questionado sobre o pagamento do abono salarial do PIS\/Pasep para aqueles que trabalharam em 2022, especialmente agora, que o governo finalizou os pagamentos referentes ao ano-base 2021. Uma coisa j\u00e1 \u00e9 certa, vai ter pagamento em 2024, referente ao ano base 2022. Cr\u00e9ditos: Ag\u00eancia Brasil\/ArquivoPIS\/Pasep 2024:\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/pis-pasep-r-1-bilhao-ainda-nao-foi-sacado-saiba-como-receber.png?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/pis-pasep-r-1-bilhao-ainda-nao-foi-sacado-saiba-como-receber.png?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/pis-pasep-r-1-bilhao-ainda-nao-foi-sacado-saiba-como-receber.png?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/pis-pasep-r-1-bilhao-ainda-nao-foi-sacado-saiba-como-receber.png?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/pis-pasep-r-1-bilhao-ainda-nao-foi-sacado-saiba-como-receber.png?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-608","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=23072"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23072\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/23073"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=23072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=23072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=23072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}