{"id":22864,"date":"2023-12-31T10:46:01","date_gmt":"2023-12-31T13:46:01","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/31\/abracos-gratis-voluntarios-distribuem-abracos-no-calcadao-de-ribeirao-preto\/"},"modified":"2023-12-31T10:46:01","modified_gmt":"2023-12-31T13:46:01","slug":"abracos-gratis-voluntarios-distribuem-abracos-no-calcadao-de-ribeirao-preto","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/31\/abracos-gratis-voluntarios-distribuem-abracos-no-calcadao-de-ribeirao-preto\/","title":{"rendered":"\u2018Abra\u00e7os gr\u00e1tis\u2019: Volunt\u00e1rios distribuem abra\u00e7os no Cal\u00e7ad\u00e3o de Ribeir\u00e3o Preto"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_104\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p>Quem passou pelo <strong>Cal\u00e7ad\u00e3o <\/strong>de <strong>Ribeir\u00e3o Preto<\/strong> no \u00faltimo s\u00e1bado (30) pode ter ganhado um abra\u00e7o \u201cgratuito\u201d do pedagogo Alexandre Ruder e dos seus amigos Rita e Matheus. <mark style=\"background-color:#fcb900\" class=\"has-inline-color has-black-color\">A a\u00e7\u00e3o \u00e9 inspirada no \u201c<em>Free hugs<\/em>\u201d, que come\u00e7ou na <strong>Austr\u00e1lia<\/strong> no in\u00edcio dos anos 2000.<\/mark><\/p>\n<p>Alexandre come\u00e7ou a a\u00e7\u00e3o em 2007 durante o <strong>Jo\u00e3o Rock<\/strong> e desde ent\u00e3o coleciona hist\u00f3ria de centenas de abra\u00e7os distribu\u00eddos. \u201cA recep\u00e7\u00e3o \u00e9 o que mais move a gente\u201d, afirma o pedagogo.<\/p>\n<p>Ao<strong> acidade on Ribeir\u00e3o<\/strong>, Alexandre diz que sempre v\u00ea pessoas se emocionando, porque muitas vezes est\u00e3o longe da fam\u00edlia ou passando por momentos dif\u00edceis.  <\/p>\n<p>\u201cSer\u00e1 que ainda \u00e9 v\u00e1lido?\u201d, questiona. \u201cMas \u00e9 sempre muito engra\u00e7ado, porque nunca voc\u00ea sabe quem voc\u00ea vai abra\u00e7ar\u201d, completa.<\/p>\n<p>\u201c\u00c0s vezes, a pessoa n\u00e3o precisa falar nada. Ela s\u00f3 quer o abra\u00e7o\u201d, relata Alexandre. Para ele, isso transforma os abra\u00e7os mais especiais, porque s\u00e3o espont\u00e2neos e nunca s\u00e3o banalizados.<\/p>\n<p>\u201cO que mais motiva \u00e9 saber que sou o instrumento de algo maior. Mas, mesmo sem saber, somos os maiores beneficiados\u201d, afirma.<\/p>\n<h4 class=\"wp-block-heading\"><strong>VEJA AS FOTOS<\/strong><\/h4>\n<blockquote class=\"instagram-media\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/C1hIDf5ur9T\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"\/>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Veja como fica o tempo em Ribeir\u00e3o no \u00faltimo dia de 2023 e na hora da virada<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do <strong>acidade on <\/strong>no <a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Instagram<\/a> e no<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"> Facebook.<\/a><\/p>\n<p>Receba not\u00edcias do<strong> acidade on <\/strong>no WhatsApp. <a href=\"https:\/\/chat.whatsapp.com\/Bnv2w66ZT4VDyZW3oiZ69n\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre a Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: (16) 99117 7802.<\/p>\n<p>LEIA MAIS<\/p>\n<p>Bolo de aveia sem gl\u00faten da Ana Maria Braga; veja como fazer<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/abracos-gratis-voluntarios-distribuem-abracos-no-calcadao-de-ribeirao-preto\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Quem passou pelo Cal\u00e7ad\u00e3o de Ribeir\u00e3o Preto no \u00faltimo s\u00e1bado (30) pode ter ganhado um abra\u00e7o \u201cgratuito\u201d do pedagogo Alexandre Ruder e dos seus amigos Rita e Matheus. A a\u00e7\u00e3o \u00e9 inspirada no \u201cFree hugs\u201d, que come\u00e7ou na Austr\u00e1lia no in\u00edcio dos anos 2000. Alexandre come\u00e7ou a a\u00e7\u00e3o em 2007 durante o Jo\u00e3o Rock &#8230; <a title=\"\u2018Abra\u00e7os gr\u00e1tis\u2019: Volunt\u00e1rios distribuem abra\u00e7os no Cal\u00e7ad\u00e3o de Ribeir\u00e3o Preto\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/31\/abracos-gratis-voluntarios-distribuem-abracos-no-calcadao-de-ribeirao-preto\/\" aria-label=\"Leia mais sobre \u2018Abra\u00e7os gr\u00e1tis\u2019: Volunt\u00e1rios distribuem abra\u00e7os no Cal\u00e7ad\u00e3o de Ribeir\u00e3o Preto\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":22865,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[2858,2275,2861,2859,27,26,2860],"class_list":["post-22864","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-abracos","tag-calcadao","tag-distribuem","tag-gratis","tag-preto","tag-ribeirao","tag-voluntarios"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/abracos-gratis.jpeg?fit=1600%2C1066&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/abracos-gratis.jpeg?fit=1600%2C1066&ssl=1",1600,1066,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/abracos-gratis.jpeg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/abracos-gratis.jpeg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/abracos-gratis.jpeg?fit=768%2C512&ssl=1",768,512,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/abracos-gratis.jpeg?fit=1024%2C682&ssl=1",1024,682,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/abracos-gratis.jpeg?fit=1536%2C1023&ssl=1",1536,1023,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/abracos-gratis.jpeg?fit=1600%2C1066&ssl=1",1600,1066,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Quem passou pelo Cal\u00e7ad\u00e3o de Ribeir\u00e3o Preto no \u00faltimo s\u00e1bado (30) pode ter ganhado um abra\u00e7o \u201cgratuito\u201d do pedagogo Alexandre Ruder e dos seus amigos Rita e Matheus. A a\u00e7\u00e3o \u00e9 inspirada no \u201cFree hugs\u201d, que come\u00e7ou na Austr\u00e1lia no in\u00edcio dos anos 2000. Alexandre come\u00e7ou a a\u00e7\u00e3o em 2007 durante o Jo\u00e3o Rock&hellip;","jetpack-related-posts":[{"id":22976,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/31\/saiba-quem-sao-os-escritores-que-vendem-livros-nas-ruas-de-ribeirao-preto\/","url_meta":{"origin":22864,"position":0},"title":"Saiba quem s\u00e3o os escritores que vendem livros nas ruas de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"31 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Quem j\u00e1 passou pelas ruas do Jardim Paulista, na zona Leste, ou parou em algum bar do Centro de Ribeir\u00e3o Preto, pode j\u00e1 ter sido abordado por escritores vendendo seus livros. Entre eles, est\u00e1 o dentista aposentado Cavalheiro Verardo, que decidiu vender livros nas ruas de Ribeir\u00e3o Preto h\u00e1\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/vinicius-e-cavalheiro.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/vinicius-e-cavalheiro.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/vinicius-e-cavalheiro.jpeg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/vinicius-e-cavalheiro.jpeg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/vinicius-e-cavalheiro.jpeg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":22947,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/31\/corredor-da-regiao-de-ribeirao-termina-a-sao-silvestre-entre-os-25-primeiros\/","url_meta":{"origin":22864,"position":1},"title":"Corredor da regi\u00e3o de Ribeir\u00e3o termina a S\u00e3o Silvestre entre os 25 primeiros","author":"ismaelcolosi.com.br","date":"31 de Dezembro de 2023","format":false,"excerpt":"[ad_1] O corredor Walace Evangelista, de S\u00e3o Joaquim da Barra, na regi\u00e3o de Ribeir\u00e3o Preto, terminou a corrida da S\u00e3o Silvestre, em S\u00e3o Paulo, na 25\u00aa coloca\u00e7\u00e3o. A prova reuniu mais de 35 mil competidores na manh\u00e3 deste domingo (31) \u2013 a elite masculina \u00e9 composta por 75 atletas profissionais.\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/walace-evangelista.jpg?fit=859%2C720&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/walace-evangelista.jpg?fit=859%2C720&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/walace-evangelista.jpg?fit=859%2C720&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/walace-evangelista.jpg?fit=859%2C720&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":22926,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/31\/2024-e-ano-de-eleicoes-municipais-veja-as-principais-datas-da-disputa\/","url_meta":{"origin":22864,"position":2},"title":"2024 \u00e9 ano de elei\u00e7\u00f5es municipais; Veja as principais datas da disputa","author":"ismaelcolosi.com.br","date":"31 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Em 2024, os mais de 470 mil eleitores de Ribeir\u00e3o Preto v\u00e3o eleger o novo prefeito, o vice e 22 vereadores. Por isso, o acidade on Ribeir\u00e3o Preto separou as principais datas do calend\u00e1rio eleitoral do novo ano para voc\u00ea decidir como ser\u00e1 o futuro da cidade. As elei\u00e7\u00f5es\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/urna-eletronica.jpg?fit=1170%2C700&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/urna-eletronica.jpg?fit=1170%2C700&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/urna-eletronica.jpg?fit=1170%2C700&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/urna-eletronica.jpg?fit=1170%2C700&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/urna-eletronica.jpg?fit=1170%2C700&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":8235,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/29\/tudo-o-que-voce-precisa-saber-sobre-o-natal-no-centro-de-ribeirao-preto\/","url_meta":{"origin":22864,"position":3},"title":"Tudo o que voc\u00ea precisa saber sobre o Natal no Centro de Ribeir\u00e3o Preto\u00a0","author":"ismaelcolosi.com.br","date":"29 de Novembro de 2023","format":false,"excerpt":"[ad_1] O primeiro final de semana do m\u00eas de dezembro marca o in\u00edcio das celebra\u00e7\u00f5es natalinas realizadas no Centro de Ribeir\u00e3o Preto. \u00a0 O acidadeon preparou uma programa\u00e7\u00e3o do que voc\u00ea precisa saber para aproveitar o Natal e os eventos comemorativos no Cal\u00e7ad\u00e3o e regi\u00e3o.\u00a0 HOR\u00c1RIO DE FUNCIONAMENTO\u00a0 A Acirp\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/whatsapp_image_2022-12-06_at_09_32_39.jpe","width":350,"height":200,"srcset":"https:\/\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/whatsapp_image_2022-12-06_at_09_32_39.jpe 1x, https:\/\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/whatsapp_image_2022-12-06_at_09_32_39.jpe 1.5x, https:\/\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/whatsapp_image_2022-12-06_at_09_32_39.jpe 2x, https:\/\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/whatsapp_image_2022-12-06_at_09_32_39.jpe 3x"},"classes":[]},{"id":46982,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/16\/ladroes-furtam-mais-de-r-7-mil-em-mercadorias-de-loja-no-calcadao-de-ribeirao\/","url_meta":{"origin":22864,"position":4},"title":"Ladr\u00f5es furtam mais de R$ 7 mil em mercadorias de loja no Cal\u00e7ad\u00e3o de Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"16 de Abril de 2024","format":false,"excerpt":"[ad_1] Uma loja de varejo foi alvo de furto na madrugada desta segunda-feira (15), no Cal\u00e7ad\u00e3o da rua General Os\u00f3rio, no Centro de Ribeir\u00e3o Preto. Segundo o gerente da Pernambucanas informou \u00e0 pol\u00edcia no boletim de ocorr\u00eancia (BO), dois criminosos vestindo moletons e com m\u00e1scaras entraram na loja pelo estacionamento,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/cpj_1024x576_21012021092745.jpg?fit=1024%2C575&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/cpj_1024x576_21012021092745.jpg?fit=1024%2C575&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/cpj_1024x576_21012021092745.jpg?fit=1024%2C575&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/cpj_1024x576_21012021092745.jpg?fit=1024%2C575&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":6123,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/24\/festival-potencias-pretas-traz-show-de-alessandro-machado\/","url_meta":{"origin":22864,"position":5},"title":"Festival Pot\u00eancias Pretas traz show de Alessandro Machado","author":"ismaelcolosi.com.br","date":"24 de Novembro de 2023","format":false,"excerpt":"[ad_1] 24 de novembro de 2023 | 16:0024 de novembro de 2023 | 9:39 0Come\u00e7ou na \u00faltima ter\u00e7a-feira, 21 de novembro, a 2\u00aa edi\u00e7\u00e3o do \u201cFestival Pot\u00eancias Pretas\u201d, na Biblioteca Sinh\u00e1 Junqueira, em Ribeir\u00e3o Preto, na rua Duque de Caxias n\u00ba 547, Centro. A entrada \u00e9 aberta e gratuita. A\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/machado-1.jpg?fit=720%2C715&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/machado-1.jpg?fit=720%2C715&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/machado-1.jpg?fit=720%2C715&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/machado-1.jpg?fit=720%2C715&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-5WM","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/22864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=22864"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/22864\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/22865"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=22864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=22864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=22864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}