{"id":21854,"date":"2023-12-28T16:56:24","date_gmt":"2023-12-28T19:56:24","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/28\/bancos-nao-abrem-em-ribeirao-preto-nesta-sexta-feira-entenda-1\/"},"modified":"2023-12-28T16:56:24","modified_gmt":"2023-12-28T19:56:24","slug":"bancos-nao-abrem-em-ribeirao-preto-nesta-sexta-feira-entenda-1","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/28\/bancos-nao-abrem-em-ribeirao-preto-nesta-sexta-feira-entenda-1\/","title":{"rendered":"Bancos n\u00e3o abrem em Ribeir\u00e3o Preto nesta sexta-feira; Entenda"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>As ag\u00eancias banc\u00e1rias de <strong>Ribeir\u00e3o Preto<\/strong> \u2013 e de todo o pa\u00eds \u2013 estar\u00e3o <strong>fechadas para atendimento presencial ao p\u00fablico<\/strong>, nesta sexta-feira (29), de acordo com as informa\u00e7\u00f5es da <strong>Febraban (Federa\u00e7\u00e3o Brasileira de Bancos)<\/strong>.<\/p>\n<p>De acordo com o \u00f3rg\u00e3o, quem precisar utilizar os servi\u00e7os de transa\u00e7\u00f5es financeiras durante este final de semana, <strong>deve optar pelos meios eletr\u00f4nicos de atendimento banc\u00e1rio<\/strong>, como mobile e internet banking, caixas eletr\u00f4nicos, banco por telefone e correspondentes.<\/p>\n<p><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">No munic\u00edpio, os bancos voltam a funcionar normalmente para atendimento presencial ao p\u00fablico na <strong>ter\u00e7a-feira, dia 2 de janeiro de 2024.<\/strong><\/mark><\/p>\n<h4 class=\"wp-block-heading\"><strong>Como fica a situa\u00e7\u00e3o dos boletos?<\/strong><\/h4>\n<p>Os boletos que vencem nesta sexta-feira (29), no final de semana e no dia 1\u00ba de janeiro, poder\u00e3o ser pagos <strong>sem acr\u00e9scimo de juros<\/strong>, at\u00e9 o dia 2 de janeiro, uma vez que os tributos <strong>j\u00e1 est\u00e3o com as datas ajustadas ao calend\u00e1rio de feriados<\/strong>, sejam federais, estaduais ou municipais.<\/p>\n<p>\u201cMesmo durante feriados, os canais digitais e caixas eletr\u00f4nicos est\u00e3o dispon\u00edveis e oferecem praticamente a totalidade das transa\u00e7\u00f5es financeiras do sistema banc\u00e1rio\u201d, disse o diretor-adjunto de Servi\u00e7os da Febraban, Walter Tadeu de Faria.<\/p>\n<p>Os clientes tamb\u00e9m podem agendar os pagamentos das contas de consumo ou pag\u00e1-las (as que t\u00eam c\u00f3digo de barras) nos pr\u00f3prios caixas autom\u00e1ticos.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Vai passar a virada no litoral de SP? Veja as praias impr\u00f3prias para banho<\/p>\n<h4 class=\"wp-block-heading\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-orange-color\">FIQUE ON<\/mark><\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do\u00a0<strong>acidade on\u00a0<\/strong>no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook.<\/a><\/p>\n<p>Receba not\u00edcias do<strong>\u00a0acidade on<\/strong>\u00a0no WhatsApp.<a href=\"https:\/\/chat.whatsapp.com\/Bnv2w66ZT4VDyZW3oiZ69n\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a0Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre a Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: (16) 99117 7802.<\/p>\n<p>LEIA MAIS<\/p>\n<p><a href=\"https:\/\/www.tudoep.com\/tudo-receitas\/noticias\/NOT,0,0,1869079,sorvete-de-uva-com-dois-ingredientes-da-ana-maria-braga.aspx\" target=\"_blank\" rel=\"noreferrer noopener\">Sorvete de uva com dois ingredientes da Ana Maria Braga<\/a><\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/bancos-nao-abrem-em-ribeirao-preto-nesta-sexta-feira-entenda-1\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] As ag\u00eancias banc\u00e1rias de Ribeir\u00e3o Preto \u2013 e de todo o pa\u00eds \u2013 estar\u00e3o fechadas para atendimento presencial ao p\u00fablico, nesta sexta-feira (29), de acordo com as informa\u00e7\u00f5es da Febraban (Federa\u00e7\u00e3o Brasileira de Bancos). De acordo com o \u00f3rg\u00e3o, quem precisar utilizar os servi\u00e7os de transa\u00e7\u00f5es financeiras durante este final de semana, deve optar &#8230; <a title=\"Bancos n\u00e3o abrem em Ribeir\u00e3o Preto nesta sexta-feira; Entenda\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/28\/bancos-nao-abrem-em-ribeirao-preto-nesta-sexta-feira-entenda-1\/\" aria-label=\"Leia mais sobre Bancos n\u00e3o abrem em Ribeir\u00e3o Preto nesta sexta-feira; Entenda\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":21855,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[2761,388,33,678,207,27,26,1160],"class_list":["post-21854","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-abrem","tag-bancos","tag-entenda","tag-nao","tag-nesta","tag-preto","tag-ribeirao","tag-sextafeira"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/bancos_voltam_1024x576_15022021111254.jpg?fit=1024%2C576&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/bancos_voltam_1024x576_15022021111254.jpg?fit=1024%2C576&ssl=1",1024,576,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/bancos_voltam_1024x576_15022021111254.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/bancos_voltam_1024x576_15022021111254.jpg?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/bancos_voltam_1024x576_15022021111254.jpg?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/bancos_voltam_1024x576_15022021111254.jpg?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/bancos_voltam_1024x576_15022021111254.jpg?fit=1024%2C576&ssl=1",1024,576,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/bancos_voltam_1024x576_15022021111254.jpg?fit=1024%2C576&ssl=1",1024,576,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] As ag\u00eancias banc\u00e1rias de Ribeir\u00e3o Preto \u2013 e de todo o pa\u00eds \u2013 estar\u00e3o fechadas para atendimento presencial ao p\u00fablico, nesta sexta-feira (29), de acordo com as informa\u00e7\u00f5es da Febraban (Federa\u00e7\u00e3o Brasileira de Bancos). De acordo com o \u00f3rg\u00e3o, quem precisar utilizar os servi\u00e7os de transa\u00e7\u00f5es financeiras durante este final de semana, deve optar&hellip;","jetpack-related-posts":[{"id":44324,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/27\/agencias-bancarias-fecham-na-sexta\/","url_meta":{"origin":21854,"position":0},"title":"Ag\u00eancias banc\u00e1rias\u00a0fecham na sexta\u00a0 &#8211; Jornal Tribuna Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"27 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] 27 de mar\u00e7o de 2024 | 11:0027 de mar\u00e7o de 2024 | 9:26 0 N\u00e3o haver\u00e1 expediente nas ag\u00eancias banc\u00e1rias nesta Sexta-Feira da Paix\u00e3o, 29 de mar\u00e7o, e os servi\u00e7os presenciais em bancos s\u00f3 ser\u00e1 retomado na segunda-feira, dia 1\u00ba de abril, depois da Semana Santa, de acordo com\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/8dca8fb3-8370-4332-ae6a-04c1ca913ef8.jpg?fit=800%2C533&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/8dca8fb3-8370-4332-ae6a-04c1ca913ef8.jpg?fit=800%2C533&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/8dca8fb3-8370-4332-ae6a-04c1ca913ef8.jpg?fit=800%2C533&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/8dca8fb3-8370-4332-ae6a-04c1ca913ef8.jpg?fit=800%2C533&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":1746,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/13\/veja-os-horarios-dos-shoppings-comercio-e-bancos-de-ribeirao-nos-proximos-feriados-de-novembro\/","url_meta":{"origin":21854,"position":1},"title":"Veja os hor\u00e1rios dos shoppings, com\u00e9rcio e bancos de Ribeir\u00e3o nos pr\u00f3ximos feriados de novembro","author":"ismaelcolosi.com.br","date":"13 de Novembro de 2023","format":false,"excerpt":"[ad_1] Foram divulgados, nesta segunda-feira (13), os hor\u00e1rios de funcionamento de shoppings, com\u00e9rcios e bancos em Ribeir\u00e3o Preto, durante os feriados da Proclama\u00e7\u00e3o da Rep\u00fablica, celebrado na quarta-feira (15), e no Dia da Consci\u00eancia Negra, na pr\u00f3xima segunda-feira (20). A abertura do com\u00e9rcio de Ribeir\u00e3o Preto ser\u00e1 facultativa, de acordo\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/comercio_calcadao_1024x576_13022021101609.jpg?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/comercio_calcadao_1024x576_13022021101609.jpg?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/comercio_calcadao_1024x576_13022021101609.jpg?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/comercio_calcadao_1024x576_13022021101609.jpg?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":22192,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/29\/mercadao-de-ribeirao-tem-horario-especial-neste-final-de-semana-veja-como-fica\/","url_meta":{"origin":21854,"position":2},"title":"Mercad\u00e3o de Ribeir\u00e3o tem hor\u00e1rio especial neste final de semana; Veja como fica","author":"ismaelcolosi.com.br","date":"29 de Dezembro de 2023","format":false,"excerpt":"[ad_1] O Mercad\u00e3o Central de Ribeir\u00e3o Preto informou que, devido \u00e0s celebra\u00e7\u00f5es de ano novo, o hor\u00e1rio de atendimento ao p\u00fablico foi alterado neste \u00faltimo final de semana de 2023. Um dos mais movimentados pontos de com\u00e9rcio da cidade, o mercad\u00e3o est\u00e1 localizado no quadril\u00e1tero entre as ruas S\u00e3o Sebasti\u00e3o,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/2019_27_09_aniversario_mercadao_alexandre_de_azevedo_097.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/2019_27_09_aniversario_mercadao_alexandre_de_azevedo_097.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/2019_27_09_aniversario_mercadao_alexandre_de_azevedo_097.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/2019_27_09_aniversario_mercadao_alexandre_de_azevedo_097.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/2019_27_09_aniversario_mercadao_alexandre_de_azevedo_097.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":66286,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/16\/correios-abrem-inscricoes-para-o-pdv-2024-edital-de-concurso-sai-neste-mes\/","url_meta":{"origin":21854,"position":3},"title":"Correios abrem inscri\u00e7\u00f5es para o PDV 2024; Edital de concurso sai neste m\u00eas","author":"ismaelcolosi.com.br","date":"16 de Setembro de 2024","format":false,"excerpt":"[ad_1] Come\u00e7ou nesta segunda-feira (16), o per\u00edodo de inscri\u00e7\u00e3o para o Programa de Desligamento Volunt\u00e1rio (PDV 2024) dos Correios. O programa proposto prev\u00ea que os empregados eleg\u00edveis que vierem a ser desligados tenham direito a um incentivo financeiro, de car\u00e1ter indenizat\u00f3rio. Os funcion\u00e1rios interessados em participar do programa devem se\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1111707-mac_edit_12031807463.webp.webp?fit=1170%2C700&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1111707-mac_edit_12031807463.webp.webp?fit=1170%2C700&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1111707-mac_edit_12031807463.webp.webp?fit=1170%2C700&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1111707-mac_edit_12031807463.webp.webp?fit=1170%2C700&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/1111707-mac_edit_12031807463.webp.webp?fit=1170%2C700&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":37246,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/15\/prazo-para-pagar-taxa-do-concurso-nacional-unificado-termina-nesta-sexta\/","url_meta":{"origin":21854,"position":4},"title":"Prazo para pagar taxa do Concurso Nacional Unificado termina nesta sexta","author":"ismaelcolosi.com.br","date":"15 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] 14 de fevereiro de 2024 | 14:0014 de fevereiro de 2024 | 11:42 0Os candidatos ao Concurso P\u00fablico Nacional Unificado que ainda n\u00e3o pagaram a taxa de inscri\u00e7\u00e3o t\u00eam at\u00e9 sexta-feira (16) para quitarem a Guia de Recolhimento da Uni\u00e3o (GRU). O pagamento, no valor de R$ 90 para\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/48bed575-a298-4721-a099-5c82fdec3996.jpg?fit=900%2C600&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/48bed575-a298-4721-a099-5c82fdec3996.jpg?fit=900%2C600&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/48bed575-a298-4721-a099-5c82fdec3996.jpg?fit=900%2C600&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/48bed575-a298-4721-a099-5c82fdec3996.jpg?fit=900%2C600&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":51613,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/29\/corpus-christi-confira-o-que-abre-e-fecha-no-feriado-em-ribeirao-preto\/","url_meta":{"origin":21854,"position":5},"title":"Corpus Christi: Confira o que abre e fecha no feriado em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"29 de Maio de 2024","format":false,"excerpt":"[ad_1] O Corpus Christi \u00e9 comemorado sempre em uma quinta-feira, 60 dias ap\u00f3s a celebra\u00e7\u00e3o da P\u00e1scoa. Em Ribeir\u00e3o Preto, a data crist\u00e3 \u00e9 considerada feriado nesta quinta-feira (30) e a sexta-feira (31), ponto facultativo. Com o feriado prolongado, shoppings, com\u00e9rcio de rua e servi\u00e7os p\u00fablicos podem ter os hor\u00e1rios\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/VejaoqueabreeoquefechaemRibeiroPretonoferiadodestasegunda_Tamanho_2_image.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/VejaoqueabreeoquefechaemRibeiroPretonoferiadodestasegunda_Tamanho_2_image.jpg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/VejaoqueabreeoquefechaemRibeiroPretonoferiadodestasegunda_Tamanho_2_image.jpg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/VejaoqueabreeoquefechaemRibeiroPretonoferiadodestasegunda_Tamanho_2_image.jpg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/VejaoqueabreeoquefechaemRibeiroPretonoferiadodestasegunda_Tamanho_2_image.jpg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-5Gu","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=21854"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21854\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/21855"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=21854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=21854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=21854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}