{"id":21419,"date":"2023-12-27T18:13:37","date_gmt":"2023-12-27T21:13:37","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/27\/instagram-tera-inteligencia-artificial-inedita-para-os-stories-entenda\/"},"modified":"2023-12-27T18:13:37","modified_gmt":"2023-12-27T21:13:37","slug":"instagram-tera-inteligencia-artificial-inedita-para-os-stories-entenda","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/27\/instagram-tera-inteligencia-artificial-inedita-para-os-stories-entenda\/","title":{"rendered":"Instagram ter\u00e1 intelig\u00eancia artificial in\u00e9dita para os Stories; entenda"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<div id=\"attachment_2328429\" class=\"wp-caption alignnone\">\n<div class=\"d-flex justify-content-center\" data-attachment-id=\"2328429\">\n<div class=\"position-relative d-inline-block\"><img data-recalc-dims=\"1\" data-portal-copyright=\"Depositphotos\/rafapress\" fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-2328429\" src=\"https:\/\/i0.wp.com\/catracalivre.com.br\/wp-content\/uploads\/2023\/12\/depositphotos-493060672-xl-scaled-e1702603421989.jpg?resize=1200%2C718&#038;ssl=1\" alt=\"Instagram ter\u00e1 ferramenta para criar fundo em fotos nos Stories\" width=\"1200\" height=\"718\" srcset=\"https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/12\/depositphotos-493060672-xl-scaled-e1702603421989.jpg 2560w, https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/12\/depositphotos-493060672-xl-scaled-e1702603421989-450x269.jpg 450w, https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/12\/depositphotos-493060672-xl-scaled-e1702603421989-768x459.jpg 768w\" sizes=\"(max-width: 2560px) 100vw, 2560px\"\/><\/p>\n<p>Cr\u00e9ditos: Depositphotos\/rafapress<\/p>\n<\/div>\n<\/div>\n<p><span class=\"post-imagem__legenda\">Instagram ter\u00e1 ferramenta para criar fundo em fotos nos Stories<\/span><\/p>\n<\/div>\n<p>Tem novidade chegando! O Instagram acaba de lan\u00e7ar uma ferramenta de <a href=\"https:\/\/catracalivre.com.br\/educacao\/inteligencia-artificial-educacao\/\" target=\"_blank\" rel=\"noopener\">Intelig\u00eancia Artificial (IA)<\/a> que amplia as possibilidades de edi\u00e7\u00e3o de <a href=\"https:\/\/catracalivre.com.br\/entretenimento\/5-series-recem-lancadas-para-assistir-na-netflix-ainda-em-2023\/\" target=\"_blank\" rel=\"noopener\">imagens<\/a>.<\/p>\n<p>A <a href=\"https:\/\/catracalivre.com.br\/entretenimento\/ative-este-botao-e-voce-tera-legendas-automaticas-em-videos-no-instagram\/\" target=\"_blank\" rel=\"noopener\">funcionalidade<\/a>, revelada recentemente, permite que seus usu\u00e1rios alterem o fundo de suas fotos e gerem novos cen\u00e1rios a partir de instru\u00e7\u00f5es de texto. Por enquanto, apenas os usu\u00e1rios nos Estados Unidos ter\u00e3o acesso a essa novidade.<\/p>\n<p>A nova ferramenta de edi\u00e7\u00e3o chega como uma alternativa inovadora para aqueles que desejam adicionar mais criatividade e personaliza\u00e7\u00e3o \u00e0s suas fotos na <a href=\"https:\/\/catracalivre.com.br\/entretenimento\/veja-como-rever-todos-os-stories-que-voce-ja-postou-no-instagram\/\" target=\"_blank\" rel=\"noopener\">rede social<\/a>.<\/p>\n<h2>Como funciona a nova ferramenta de IA do Instagram?<\/h2>\n<p>Para utilizar a nova funcionalidade, o usu\u00e1rio deve acessar um novo bot\u00e3o dispon\u00edvel no menu de op\u00e7\u00f5es ao criar um novo Story. O bot\u00e3o fica ao lado das <a href=\"https:\/\/catracalivre.com.br\/entretenimento\/passo-a-passo-simples-para-apagar-e-organizar-figurinhas-no-whatsapp\/\" target=\"_blank\" rel=\"noopener\">figurinhas<\/a> e do editor de texto.<\/p>\n<p>Ao clicar nele, a IA ir\u00e1 remover o fundo original da imagem e abrir\u00e1 um campo de texto para possibilitar que o usu\u00e1rio descreva o novo fundo.<\/p>\n<p>O resultado das edi\u00e7\u00f5es poder\u00e1 ir para os Stories, o que provoca ainda mais engajamento com os seguidores.<\/p>\n<div id=\"attachment_2328428\" class=\"wp-caption alignnone\">\n<div class=\"d-flex justify-content-center\" data-attachment-id=\"2328428\">\n<div class=\"position-relative d-inline-block\"><img data-recalc-dims=\"1\" data-portal-copyright=\"divulga\u00e7\u00e3o\/Instagram\" decoding=\"async\" class=\"size-full wp-image-2328428\" src=\"https:\/\/i0.wp.com\/catracalivre.com.br\/wp-content\/uploads\/2023\/12\/fotos-catraca-2023-12-14t221525571.png?resize=1200%2C660&#038;ssl=1\" alt=\"Como funcionaria a nova ferramenta de IA?\" width=\"1200\" height=\"660\" srcset=\"https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/12\/fotos-catraca-2023-12-14t221525571.png 1200w, https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/12\/fotos-catraca-2023-12-14t221525571-450x248.png 450w, https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/12\/fotos-catraca-2023-12-14t221525571-768x422.png 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\"\/><\/p>\n<p>Cr\u00e9ditos: divulga\u00e7\u00e3o\/Instagram<\/p>\n<\/div>\n<\/div>\n<p><span class=\"post-imagem__legenda\">Como funcionaria a nova ferramenta de IA?<\/span><\/p>\n<\/div>\n<h2>Existe alguma limita\u00e7\u00e3o na cria\u00e7\u00e3o dos cen\u00e1rios?<\/h2>\n<p>Na rede social, os usu\u00e1rios ter\u00e3o total liberdade para descrever e criar o cen\u00e1rio que desejar, basta usar a criatividade.<\/p>\n<p>E tem mais! Ao criar um novo fundo para as fotos, uma marca\u00e7\u00e3o ser\u00e1 inclu\u00edda nos Stories convidando os seguidores a experimentarem o novo recurso, o que acaba promovendo ainda mais a intera\u00e7\u00e3o na plataforma.<\/p>\n<p>A nova ferramenta de IA do Instagram s\u00f3 est\u00e1 dispon\u00edvel para os usu\u00e1rios nos Estados Unidos. At\u00e9 o momento, a empresa n\u00e3o revelou quando pretende expandir o lan\u00e7amento do recurso para outros pa\u00edses, o que deixa os demais usu\u00e1rios em expectativa.<\/p>\n<\/div>\n<p><script>\n\t\t! function(f, b, e, v, n, t, s) {\n\t\t\tif (f.fbq) return;\n\t\t\tn = f.fbq = function() {\n\t\t\t\tn.callMethod ?\n\t\t\t\t\tn.callMethod.apply(n, arguments) : n.queue.push(arguments)\n\t\t\t};\n\t\t\tif (!f._fbq) f._fbq = n;\n\t\t\tn.push = n;\n\t\t\tn.loaded = !0;\n\t\t\tn.version = '2.0';\n\t\t\tn.queue = [];\n\t\t\tt = b.createElement(e);\n\t\t\tt.async = !0;\n\t\t\tt.src = v;\n\t\t\ts = b.getElementsByTagName(e)[0];\n\t\t\ts.parentNode.insertBefore(t, s)\n\t\t}(window, document, 'script',\n\t\t\t'https:\/\/connect.facebook.net\/en_US\/fbevents.js');\n\t\tfbq('init', '338315473262380');\n\t\tfbq('track', 'PageView');\n\t<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/catracalivre.com.br\/entretenimento\/instagram-tera-inteligencia-artificial-para-criar-fundo-em-fotos-nos-stories\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Cr\u00e9ditos: Depositphotos\/rafapress Instagram ter\u00e1 ferramenta para criar fundo em fotos nos Stories Tem novidade chegando! O Instagram acaba de lan\u00e7ar uma ferramenta de Intelig\u00eancia Artificial (IA) que amplia as possibilidades de edi\u00e7\u00e3o de imagens. A funcionalidade, revelada recentemente, permite que seus usu\u00e1rios alterem o fundo de suas fotos e gerem novos cen\u00e1rios a partir &#8230; <a title=\"Instagram ter\u00e1 intelig\u00eancia artificial in\u00e9dita para os Stories; entenda\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/27\/instagram-tera-inteligencia-artificial-inedita-para-os-stories-entenda\/\" aria-label=\"Leia mais sobre Instagram ter\u00e1 intelig\u00eancia artificial in\u00e9dita para os Stories; entenda\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":21420,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-21419","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-variedades"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/depositphotos-493060672-xl-scaled-e1702603421989.jpg?fit=1200%2C638&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/depositphotos-493060672-xl-scaled-e1702603421989.jpg?fit=1200%2C638&ssl=1",1200,638,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/depositphotos-493060672-xl-scaled-e1702603421989.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/depositphotos-493060672-xl-scaled-e1702603421989.jpg?fit=300%2C160&ssl=1",300,160,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/depositphotos-493060672-xl-scaled-e1702603421989.jpg?fit=768%2C408&ssl=1",768,408,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/depositphotos-493060672-xl-scaled-e1702603421989.jpg?fit=1024%2C544&ssl=1",1024,544,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/depositphotos-493060672-xl-scaled-e1702603421989.jpg?fit=1200%2C638&ssl=1",1200,638,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/depositphotos-493060672-xl-scaled-e1702603421989.jpg?fit=1200%2C638&ssl=1",1200,638,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Cr\u00e9ditos: Depositphotos\/rafapress Instagram ter\u00e1 ferramenta para criar fundo em fotos nos Stories Tem novidade chegando! O Instagram acaba de lan\u00e7ar uma ferramenta de Intelig\u00eancia Artificial (IA) que amplia as possibilidades de edi\u00e7\u00e3o de imagens. A funcionalidade, revelada recentemente, permite que seus usu\u00e1rios alterem o fundo de suas fotos e gerem novos cen\u00e1rios a partir&hellip;","jetpack-related-posts":[{"id":6031,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/24\/5-habitos-que-podem-prejudicar-sua-saude-financeira\/","url_meta":{"origin":21419,"position":0},"title":"5 h\u00e1bitos que podem prejudicar sua sa\u00fade financeira","author":"ismaelcolosi.com.br","date":"24 de Novembro de 2023","format":false,"excerpt":"[ad_1] A sa\u00fade financeira \u00e9 a capacidade de administrar bem o seu dinheiro, atender \u00e0s suas necessidades, realizar seus sonhos e lidar com imprevistos. Ter uma boa sa\u00fade financeira \u00e9 essencial para ter uma vida mais tranquila, feliz e equilibrada. Cr\u00e9ditos: iSTock5 h\u00e1bitos que podem prejudicar sua sa\u00fade financeira H\u00e1bitos\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/saude-financeira-2.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/saude-financeira-2.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/saude-financeira-2.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/saude-financeira-2.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/saude-financeira-2.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":27538,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/12\/luana-piovani-defende-motivo-de-ter-traido-rodrigo-santoro\/","url_meta":{"origin":21419,"position":1},"title":"Luana Piovani defende motivo de ter tra\u00eddo Rodrigo Santoro","author":"ismaelcolosi.com.br","date":"12 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Um dos temas mais temidos de separa\u00e7\u00e3o de casais, a trai\u00e7\u00e3o, foi debatido muito abertamente pela atriz Luana Piovani sobre seu motivo de ter tra\u00eddo Rodrigo Santoro enquanto namoravam.\u201cEu tra\u00ed e falei: \u2018n\u00e3o te quero mais. Sabe por qu\u00ea? Porque sou fiel aos meus princ\u00edpios. Eu tra\u00ed porque o\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a155aa9e2714617.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a155aa9e2714617.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a155aa9e2714617.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a155aa9e2714617.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65a155aa9e2714617.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":6323,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/25\/caso-do-pai-que-tirou-a-vida-do-proprio-filho-apos-visitar-neta-pode-ter-reviravolta-na-motivacao-detalhes-sao-expostos\/","url_meta":{"origin":21419,"position":2},"title":"Caso do pai que tirou a vida do pr\u00f3prio filho ap\u00f3s visitar neta pode ter reviravolta na motiva\u00e7\u00e3o; detalhes s\u00e3o expostos","author":"ismaelcolosi.com.br","date":"25 de Novembro de 2023","format":false,"excerpt":"[ad_1] Nesta \u00faltima quinta-feira, dia 23 de novembro, um pai foi preso ap\u00f3s ter tirado a vida do pr\u00f3prio filho, na regi\u00e3o de Ibi\u00fana, no interior de S\u00e3o Paulo.E diante de toda a situa\u00e7\u00e3o, a poss\u00edvel causa pra o crime b\u00e1rbaro acabou sendo exposta, pois aparentemente a morte teria sido\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656223055a9a15109.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656223055a9a15109.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656223055a9a15109.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656223055a9a15109.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-656223055a9a15109.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":46099,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/09\/posso-ter-dois-empregos-de-carteira-assinada-aprenda-mais\/","url_meta":{"origin":21419,"position":3},"title":"Posso ter dois empregos de carteira assinada? Aprenda mais!","author":"ismaelcolosi.com.br","date":"9 de Abril de 2024","format":false,"excerpt":"[ad_1] Muitos profissionais t\u00eam d\u00favidas sobre ter dois empregos com carteira assinada, afinal, pode ser uma oportunidade de exercer atividades em mais de uma empresa para ganhar mais experi\u00eancia, al\u00e9m de aumentar a renda mensal. Por isso, a jornada dupla de trabalho tem se tornado uma op\u00e7\u00e3o cada vez mais\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/posso-ter-dois-empregos-de-carteira-assinada.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/posso-ter-dois-empregos-de-carteira-assinada.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/posso-ter-dois-empregos-de-carteira-assinada.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/posso-ter-dois-empregos-de-carteira-assinada.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/posso-ter-dois-empregos-de-carteira-assinada.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":39692,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/27\/usp-ribeirao-ainda-precisa-de-voluntarios-para-pesquisas-com-ayahuasca\/","url_meta":{"origin":21419,"position":4},"title":"USP Ribeir\u00e3o ainda precisa de volunt\u00e1rios para pesquisas com ayahuasca","author":"ismaelcolosi.com.br","date":"27 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] A Faculdade de Medicina de Ribeir\u00e3o Preto (FMRP) da USP (Universidade de S\u00e3o Paulo) ainda est\u00e1 em busca de volunt\u00e1rios para cinco pesquisas sobre a ayahuasca, bebida preparada a partir de duas plantas amaz\u00f4nicas, a Psychotria viridis (chacrona), e a Banisteriosis caapi (cip\u00f3 jagube). Os pesquisadores tamb\u00e9m buscam volunt\u00e1rios\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/santo_daime_1024x576_16092021114557.jpg?fit=1024%2C575&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/santo_daime_1024x576_16092021114557.jpg?fit=1024%2C575&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/santo_daime_1024x576_16092021114557.jpg?fit=1024%2C575&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/santo_daime_1024x576_16092021114557.jpg?fit=1024%2C575&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":4238,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/21\/jovem-que-teria-sido-dado-como-morto-aparece-vivo-apos-sua-familia-ter-realizado-o-velorio\/","url_meta":{"origin":21419,"position":5},"title":"Jovem que teria sido dado como morto aparece vivo ap\u00f3s sua fam\u00edlia ter realizado o vel\u00f3rio","author":"ismaelcolosi.com.br","date":"21 de Novembro de 2023","format":false,"excerpt":"[ad_1] Uma situa\u00e7\u00e3o muito inesperada aconteceu na regi\u00e3o de Passo Fundo, no Rio Grande do Sul, ap\u00f3s um homem, identificado previamente como falecido, ter enviado um v\u00eddeo para sua fam\u00edlia, dizendo que estava bem.E diante do ocorrido, a Pol\u00edcia Civil, precisou realizar uma ocorr\u00eancia, visto que o jovem, supostamente morto,\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655c5cd67a87b6459.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655c5cd67a87b6459.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655c5cd67a87b6459.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655c5cd67a87b6459.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655c5cd67a87b6459.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-5zt","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=21419"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21419\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/21420"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=21419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=21419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=21419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}