{"id":21100,"date":"2023-12-27T06:11:25","date_gmt":"2023-12-27T09:11:25","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/27\/air-europa-oferece-stopover-gratuito-em-madri-veja-como-funciona\/"},"modified":"2023-12-27T06:11:25","modified_gmt":"2023-12-27T09:11:25","slug":"air-europa-oferece-stopover-gratuito-em-madri-veja-como-funciona","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/27\/air-europa-oferece-stopover-gratuito-em-madri-veja-como-funciona\/","title":{"rendered":"Air Europa oferece stopover gratuito em Madri; veja como funciona"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>Dois destinos numa mesma viagem! A Air Europa oferece programa de stopover gratuito em Madri (Espanha), permitindo aos brasileiros que possam voar at\u00e9 outra cidade europeia, saindo do Brasil, e fazendo uma parada de alguns dias na <a href=\"https:\/\/catracalivre.com.br\/viagem-livre\/roteiro-2-dias-em-madri\/\" target=\"_blank\" rel=\"noopener\">capital espanhola<\/a>.<\/p>\n<p>O recurso tamb\u00e9m pode ser utilizado na viagem de volta do Brasil.<\/p>\n<div id=\"attachment_2174875\" class=\"wp-caption aligncenter\">\n<div class=\"d-flex justify-content-center\" data-attachment-id=\"2174875\">\n<div class=\"position-relative d-inline-block\"><img data-recalc-dims=\"1\" data-portal-copyright=\"Divulga\u00e7\u00e3o\/Syldavia\" fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-2174875 size-large\" src=\"https:\/\/i0.wp.com\/catracalivre.com.br\/wp-content\/uploads\/2021\/08\/espanha-libera-entrada-de-brasileiros-vacinados-910x606.jpg?resize=910%2C606&#038;ssl=1\" alt=\"Stopover da Air Europa permite conhecer Madri de forma gratuita\" width=\"910\" height=\"606\" srcset=\"https:\/\/catracalivre.com.br\/wp-content\/uploads\/2021\/08\/espanha-libera-entrada-de-brasileiros-vacinados-910x606.jpg 910w, https:\/\/catracalivre.com.br\/wp-content\/uploads\/2021\/08\/espanha-libera-entrada-de-brasileiros-vacinados-450x299.jpg 450w, https:\/\/catracalivre.com.br\/wp-content\/uploads\/2021\/08\/espanha-libera-entrada-de-brasileiros-vacinados-768x511.jpg 768w\" sizes=\"(max-width: 910px) 100vw, 910px\"\/><\/p>\n<p>Cr\u00e9ditos: Divulga\u00e7\u00e3o\/Syldavia<\/p>\n<\/div>\n<\/div>\n<p><span class=\"post-imagem__legenda\">Stopover da Air Europa permite conhecer Madri de forma gratuita<\/span><\/p>\n<\/div>\n<p>O stopover pode ser adquirido durante a compra da passagem ainda no Brasil.<\/p>\n<p>Ao fazer a reserva de um voo da companhia, os passageiros podem escolher a op\u00e7\u00e3o no momento da compra. Dessa forma, eles t\u00eam a oportunidade de permanecer na cidade por at\u00e9 tr\u00eas noites antes de continuar a sua jornada.<\/p>\n<p>Algumas das cidades mais buscadas pelos passageiros s\u00e3o Barcelona (Espanha), Roma (It\u00e1lia), Frankfurt (Alemanha), Amsterd\u00e3 (Holanda), Londres (Inglaterra) e Porto (Portugal).<\/p>\n<p>A Air Europa tamb\u00e9m permite que os passageiros possam parar em outros destinos, a um pre\u00e7o de US$ 100 cada.<\/p>\n<p>Os interessados em adquirir as passagens podem compr\u00e1-las pelo site da Air Europa.<\/p>\n<h2>Voos da Air Europa para o Brasil<\/h2>\n<p>No Brasil, a Air Europa opera com voos di\u00e1rios saindo do aeroporto de Guarulhos (S\u00e3o Paulo) at\u00e9 Madri, e com duas frequ\u00eancias semanais decolando do aeroporto de Salvador, tamb\u00e9m em dire\u00e7\u00e3o \u00e0 capital espanhola.<\/p>\n<p>\u201cO stopover \u00e9 uma forma de os passageiros conhecerem dois destinos, pagando apenas por um. Nesses casos, geralmente, os viajantes ficam em torno de dois a tr\u00eas dias em Madri e depois continuam a viagem\u201d, destaca o diretor-geral da Air Europa, Gonzalo Romero.<\/p>\n<p>Tamb\u00e9m \u00e9 poss\u00edvel fazer a parada na volta da viagem, j\u00e1 que todos os voos que saem ou t\u00eam como destino o Brasil fazem conex\u00f5es com a capital espanhola.<\/p>\n<\/div>\n<p><script>\n\t\t! function(f, b, e, v, n, t, s) {\n\t\t\tif (f.fbq) return;\n\t\t\tn = f.fbq = function() {\n\t\t\t\tn.callMethod ?\n\t\t\t\t\tn.callMethod.apply(n, arguments) : n.queue.push(arguments)\n\t\t\t};\n\t\t\tif (!f._fbq) f._fbq = n;\n\t\t\tn.push = n;\n\t\t\tn.loaded = !0;\n\t\t\tn.version = '2.0';\n\t\t\tn.queue = [];\n\t\t\tt = b.createElement(e);\n\t\t\tt.async = !0;\n\t\t\tt.src = v;\n\t\t\ts = b.getElementsByTagName(e)[0];\n\t\t\ts.parentNode.insertBefore(t, s)\n\t\t}(window, document, 'script',\n\t\t\t'https:\/\/connect.facebook.net\/en_US\/fbevents.js');\n\t\tfbq('init', '338315473262380');\n\t\tfbq('track', 'PageView');\n\t<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/catracalivre.com.br\/viagem-livre\/air-europa-oferece-stopover-gratuito-em-madri-veja-como-funciona\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Dois destinos numa mesma viagem! A Air Europa oferece programa de stopover gratuito em Madri (Espanha), permitindo aos brasileiros que possam voar at\u00e9 outra cidade europeia, saindo do Brasil, e fazendo uma parada de alguns dias na capital espanhola. O recurso tamb\u00e9m pode ser utilizado na viagem de volta do Brasil. Cr\u00e9ditos: Divulga\u00e7\u00e3o\/Syldavia Stopover &#8230; <a title=\"Air Europa oferece stopover gratuito em Madri; veja como funciona\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/27\/air-europa-oferece-stopover-gratuito-em-madri-veja-como-funciona\/\" aria-label=\"Leia mais sobre Air Europa oferece stopover gratuito em Madri; veja como funciona\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":21101,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-21100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-variedades"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/madri-stopover-air-europa-scaled.jpg?fit=1200%2C638&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/madri-stopover-air-europa-scaled.jpg?fit=1200%2C638&ssl=1",1200,638,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/madri-stopover-air-europa-scaled.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/madri-stopover-air-europa-scaled.jpg?fit=300%2C160&ssl=1",300,160,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/madri-stopover-air-europa-scaled.jpg?fit=768%2C408&ssl=1",768,408,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/madri-stopover-air-europa-scaled.jpg?fit=1024%2C544&ssl=1",1024,544,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/madri-stopover-air-europa-scaled.jpg?fit=1200%2C638&ssl=1",1200,638,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/madri-stopover-air-europa-scaled.jpg?fit=1200%2C638&ssl=1",1200,638,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Dois destinos numa mesma viagem! A Air Europa oferece programa de stopover gratuito em Madri (Espanha), permitindo aos brasileiros que possam voar at\u00e9 outra cidade europeia, saindo do Brasil, e fazendo uma parada de alguns dias na capital espanhola. O recurso tamb\u00e9m pode ser utilizado na viagem de volta do Brasil. Cr\u00e9ditos: Divulga\u00e7\u00e3o\/Syldavia Stopover&hellip;","jetpack-related-posts":[{"id":12887,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/08\/7-passeios-totalmente-gratuitos-para-fazer-em-buenos-aires\/","url_meta":{"origin":21100,"position":0},"title":"7 passeios totalmente gratuitos para fazer em Buenos Aires","author":"ismaelcolosi.com.br","date":"8 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Que Buenos Aires foi o destino internacional favorito dos brasileiros este ano, n\u00e3o \u00e9 novidade para ningu\u00e9m. O que n\u00e3o falta na internet s\u00e3o postagens nas redes sociais e reportagens com dicas do que fazer, onde comer e o que comprar na capital da Argentina. O principal motivo? A\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/buenos-aires-tango.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/buenos-aires-tango.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/buenos-aires-tango.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/buenos-aires-tango.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/buenos-aires-tango.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":20296,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/24\/flybondi-tem-passagens-para-buenos-aires-a-partir-de-r-455\/","url_meta":{"origin":21100,"position":1},"title":"Flybondi tem passagens para Buenos Aires a partir de R$ 455","author":"ismaelcolosi.com.br","date":"24 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Que tal aproveitar o fim de semana para programar a pr\u00f3xima viagem? A companhia low cost Flybondi lan\u00e7ou uma promo\u00e7\u00e3o especial de passagens a\u00e9reas para destinos na Argentina com 25% de desconto, a partir de R$ 455. A oferta vale para compras efetuadas entre 24 de dezembro e 1\u00ba\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/regras-para-entrar-na-argetina.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/regras-para-entrar-na-argetina.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/regras-para-entrar-na-argetina.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/regras-para-entrar-na-argetina.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/regras-para-entrar-na-argetina.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":66854,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/09\/19\/ribeirao-preto-recebe-pre-estreia-de-madre-documentario-sobre-freira-presa-na-ditadura\/","url_meta":{"origin":21100,"position":2},"title":"Ribeir\u00e3o Preto recebe pr\u00e9-estreia de &#8216;Madre&#8217;, document\u00e1rio sobre freira presa na ditadura","author":"ismaelcolosi.com.br","date":"19 de Setembro de 2024","format":false,"excerpt":"[ad_1] A Biblioteca Sinh\u00e1 Junqueira, em Ribeir\u00e3o Preto, segue com a Mostra Liter\u00e1ria: escrita, cinema & gastronomia. A programa\u00e7\u00e3o inclui a pr\u00e9-estreia do document\u00e1rio \u201cMadre\u201c, que conta a hist\u00f3ria de Maurina Borges, uma freira que foi presa em Ribeir\u00e3o Preto, torturada e banida do Brasil durante a ditadura militar. No\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/madre-maurina-1_2024-09-19_19-06-20_jpg_2024-09-19_19-06-20.webp.webp?fit=1200%2C653&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/madre-maurina-1_2024-09-19_19-06-20_jpg_2024-09-19_19-06-20.webp.webp?fit=1200%2C653&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/madre-maurina-1_2024-09-19_19-06-20_jpg_2024-09-19_19-06-20.webp.webp?fit=1200%2C653&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/madre-maurina-1_2024-09-19_19-06-20_jpg_2024-09-19_19-06-20.webp.webp?fit=1200%2C653&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/09\/madre-maurina-1_2024-09-19_19-06-20_jpg_2024-09-19_19-06-20.webp.webp?fit=1200%2C653&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":43937,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/24\/documentario-sobre-madre-maurina-ganha-circuito-estadual\/","url_meta":{"origin":21100,"position":3},"title":"Document\u00e1rio sobre Madre Maurina ganha circuito estadual\u00a0","author":"ismaelcolosi.com.br","date":"24 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] Este ano, o Brasil tem uma data emblem\u00e1tica: 31 de mar\u00e7o, quando ser\u00e3o lembrados os 60 anos do Golpe Militar de 1964 e tudo o que isso acarretou para o Pa\u00eds. Momento prop\u00edcio para se rever parte dessa hist\u00f3ria nefasta, resgatar epis\u00f3dios e tamb\u00e9m personagens que foram v\u00edtimas inocentes\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/2-Madre-Maurina-scaled.jpg?fit=762%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/2-Madre-Maurina-scaled.jpg?fit=762%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/2-Madre-Maurina-scaled.jpg?fit=762%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/2-Madre-Maurina-scaled.jpg?fit=762%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":31167,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/21\/top-10-destinos-internacionais-mais-visitados-pelos-brasileiros\/","url_meta":{"origin":21100,"position":4},"title":"Top 10 destinos internacionais mais visitados pelos brasileiros","author":"ismaelcolosi.com.br","date":"21 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Nos \u00faltimos anos, os brasileiros t\u00eam expandido cada vez mais seus horizontes ao decidir para onde ir\u00e3o em suas f\u00e9rias. O gosto pela aventura, a busca por novas culturas e experi\u00eancias, a melhoria do poder de compra, a facilidade de acesso a informa\u00e7\u00f5es e a crescente conectividade a\u00e9rea contribu\u00edram\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/viagens-internacionais.png?fit=600%2C384&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/viagens-internacionais.png?fit=600%2C384&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/viagens-internacionais.png?fit=600%2C384&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":2432,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/15\/gol-faz-promocao-relampago-com-passagens-a-partir-de-r-133\/","url_meta":{"origin":21100,"position":5},"title":"Gol faz promo\u00e7\u00e3o rel\u00e2mpago com passagens a partir de R$ 133","author":"ismaelcolosi.com.br","date":"15 de Novembro de 2023","format":false,"excerpt":"[ad_1] Aproveite o feriado para programar sua pr\u00f3xima viagem! A Gol Linhas A\u00e9reas est\u00e1 com uma promo\u00e7\u00e3o rel\u00e2mpago de passagens para destinos nacionais com pre\u00e7os a partir de R$ 133, 72 \u2013o trecho j\u00e1 com a taxa de embarque inclusa. A oferta \u00e9 valida somente para bilhetes emitidos at\u00e9 as\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-1695544972.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-1695544972.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-1695544972.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-1695544972.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/istock-1695544972.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-5uk","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=21100"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21100\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/21101"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=21100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=21100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=21100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}