{"id":20943,"date":"2023-12-26T20:03:06","date_gmt":"2023-12-26T23:03:06","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/26\/prefeitura-de-ribeirao-preto-abre-inscricoes-para-o-carnaval-2024\/"},"modified":"2023-12-26T20:03:06","modified_gmt":"2023-12-26T23:03:06","slug":"prefeitura-de-ribeirao-preto-abre-inscricoes-para-o-carnaval-2024","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/26\/prefeitura-de-ribeirao-preto-abre-inscricoes-para-o-carnaval-2024\/","title":{"rendered":"Prefeitura de Ribeir\u00e3o Preto abre inscri\u00e7\u00f5es para o Carnaval 2024"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p><strong>A Prefeitura de Ribeir\u00e3o Preto abriu cadastro para os grupos de Carnaval interessados em realizar suas atividades durante a folia de 2024, entre os dias 10 e 13 de fevereiro, em espa\u00e7os p\u00fablicos<\/strong>.<\/p>\n<p>Os organizadores respons\u00e1veis pelas escolas de samba, blocos, afox\u00e9s, maracatus, grupos art\u00edsticos e culturais t\u00eam <strong>at\u00e9 o dia 9 de janeiro de 2024, \u00e0s 23h59<\/strong>, para realizarem a <a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLScK7DXP3hzMcTzRIVLX0-S5tOlS3kbXn2qgIeLLpMxlAw6xrA\/viewform\" target=\"_blank\" rel=\"noreferrer noopener\">inscri\u00e7\u00e3o on-line (clique aqui).<\/a><\/p>\n<p>A Secretaria da Cultura e Turismo ressalta que o cadastramento \u00e9 importante para que a Comiss\u00e3o T\u00e9cnica analise e verifique a viabilidade da manifesta\u00e7\u00e3o perante a legisla\u00e7\u00e3o vigente, al\u00e9m do planejamento da log\u00edstica de apoio \u00e0s a\u00e7\u00f5es ou ocupa\u00e7\u00f5es.<\/p>\n<p>Mais informa\u00e7\u00f5es sobre o cadastramento tamb\u00e9m podem ser obtidas na Secretaria da Cultura e Turismo pelo WhatsApp (16) 98109-2477.<\/p>\n<h4 class=\"wp-block-heading\"><strong>Documenta\u00e7\u00e3o necess\u00e1ria<\/strong><\/h4>\n<p>Para pessoa f\u00edsica, \u00e9 necess\u00e1rio anexar arquivo em PDF, nos campos espec\u00edficos do formul\u00e1rio, com os seguintes documentos: <strong>documento de identidade (RG), Cadastro de Pessoa F\u00edsica (CPF) e comprovante de resid\u00eancia atual.<\/strong><\/p>\n<p>J\u00e1 para pessoa jur\u00eddica, \u00e9 preciso arquivos em PDF, nos campos espec\u00edficos do formul\u00e1rio, dos seguintes documentos: estatuto ou contrato social; Ata de elei\u00e7\u00e3o de sua diretoria (se for o caso); Cadastro Nacional de Pessoas Jur\u00eddicas (CNPJ); Comprovante de endere\u00e7o atual e documentos do representante legal (RG e CPF).<\/p>\n<p>SAIBA MAIS<br \/>Biquini Cavad\u00e3o faz show em Ribeir\u00e3o Preto; Veja como comprar ingressos<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do\u00a0<strong>acidade on<\/strong>\u00a0no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram\u00a0<\/a>e no<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a0Facebook.<\/a><\/p>\n<p>Receba not\u00edcias do\u00a0<strong>acidade on\u00a0<\/strong>no WhatsApp.\u00a0<a href=\"https:\/\/chat.whatsapp.com\/Bnv2w66ZT4VDyZW3oiZ69n\" target=\"_blank\" rel=\"noreferrer noopener\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp:\u00a0<strong>(16) 99117 7802.<\/strong><\/p>\n<p>VEJA TAMB\u00c9M<br \/>Qual roupa usar? Veja o significado das cores na festa de Ano-Novo<\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/lazer-e-cultura\/prefeitura-de-ribeirao-preto-abre-inscricoes-para-o-carnaval-2024\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] A Prefeitura de Ribeir\u00e3o Preto abriu cadastro para os grupos de Carnaval interessados em realizar suas atividades durante a folia de 2024, entre os dias 10 e 13 de fevereiro, em espa\u00e7os p\u00fablicos. Os organizadores respons\u00e1veis pelas escolas de samba, blocos, afox\u00e9s, maracatus, grupos art\u00edsticos e culturais t\u00eam at\u00e9 o dia 9 de janeiro&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":20944,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[210,2688,566,71,244,27,26],"class_list":["post-20943","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-abre","tag-carnaval","tag-inscricoes","tag-para","tag-prefeitura","tag-preto","tag-ribeirao"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/mask-1155808_1280.jpg?fit=1280%2C853&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/mask-1155808_1280.jpg?fit=1280%2C853&ssl=1",1280,853,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/mask-1155808_1280.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/mask-1155808_1280.jpg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/mask-1155808_1280.jpg?fit=768%2C512&ssl=1",768,512,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/mask-1155808_1280.jpg?fit=1024%2C682&ssl=1",1024,682,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/mask-1155808_1280.jpg?fit=1280%2C853&ssl=1",1280,853,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/mask-1155808_1280.jpg?fit=1280%2C853&ssl=1",1280,853,true],"neve-blog":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/mask-1155808_1280.jpg?resize=930%2C620&ssl=1",930,620,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] A Prefeitura de Ribeir\u00e3o Preto abriu cadastro para os grupos de Carnaval interessados em realizar suas atividades durante a folia de 2024, entre os dias 10 e 13 de fevereiro, em espa\u00e7os p\u00fablicos. Os organizadores respons\u00e1veis pelas escolas de samba, blocos, afox\u00e9s, maracatus, grupos art\u00edsticos e culturais t\u00eam at\u00e9 o dia 9 de janeiro&hellip;&nbsp;","jetpack-related-posts":[{"id":21187,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/27\/secretaria-da-cultura-abre-cadastro-para-grupos-carnavalescos\/","url_meta":{"origin":20943,"position":0},"title":"Secretaria da Cultura abre cadastro para Grupos Carnavalescos","author":"ismaelcolosi.com.br","date":"27 de Dezembro de 2023","format":false,"excerpt":"[ad_1] 27 de dezembro de 2023 | 10:0026 de dezembro de 2023 | 19:38 0Est\u00e1 aberto o cadastro para a convoca\u00e7\u00e3o dos grupos de manifesta\u00e7\u00f5es carnavalescas interessados em realizar suas atividades durante o Carnaval de 2024, entre os dias 10 e 13 de fevereiro, em espa\u00e7os p\u00fablicos de Ribeir\u00e3o Preto.O\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/close-up-na-decoracao-do-cotillon-1536x1024-1-scaled.jpg?fit=967%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/close-up-na-decoracao-do-cotillon-1536x1024-1-scaled.jpg?fit=967%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/close-up-na-decoracao-do-cotillon-1536x1024-1-scaled.jpg?fit=967%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/close-up-na-decoracao-do-cotillon-1536x1024-1-scaled.jpg?fit=967%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":29122,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/17\/reuniao-define-detalhes-do-carnaval-2024\/","url_meta":{"origin":20943,"position":1},"title":"Reuni\u00e3o define detalhes do Carnaval 2024 \u2013 Folha de Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"17 de Janeiro de 2024","format":false,"excerpt":"[ad_1] A Prefeitura de Ribeir\u00e3o Preto deu o pontap\u00e9 inicial para a organiza\u00e7\u00e3o do Carnaval 2024. Uma primeira reuni\u00e3o coordenada pela Secretaria da Cultura e Turismo, foi realizada ontem, dia 15 de janeiro, pela manh\u00e3 no Pal\u00e1cio Rio Branco, entre os \u00f3rg\u00e3os municipais envolvidos no evento, a pol\u00edcia militar, o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/reuniao_carnaval_2.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/reuniao_carnaval_2.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/reuniao_carnaval_2.jpeg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/reuniao_carnaval_2.jpeg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/reuniao_carnaval_2.jpeg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":34496,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/02\/prefeitura-na-regiao-de-ribeirao-preto-tem-concurso-publico-com-salarios-de-r-5-mil\/","url_meta":{"origin":20943,"position":2},"title":"Prefeitura na regi\u00e3o de Ribeir\u00e3o Preto tem concurso p\u00fablico com sal\u00e1rios de R$ 5 mil","author":"ismaelcolosi.com.br","date":"2 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] A Prefeitura de Serrana, na regi\u00e3o de Ribeir\u00e3o Preto, abriu concurso p\u00fablico para tr\u00eas cargos de n\u00edvel m\u00e9dio, t\u00e9cnico e superior com sal\u00e1rios entre R$ 2.259,15 e R$ 5.891,90. As inscri\u00e7\u00f5es devem ser realizadas pela internet, no site da RBO Concursos (clique aqui), no per\u00edodo entre 5 de fevereiro\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/concurso-publico-13.jpg?fit=1200%2C801&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/concurso-publico-13.jpg?fit=1200%2C801&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/concurso-publico-13.jpg?fit=1200%2C801&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/concurso-publico-13.jpg?fit=1200%2C801&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/concurso-publico-13.jpg?fit=1200%2C801&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":35504,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/06\/confira-a-programacao-de-carnaval-em-shoppings-de-ribeirao-preto-e-franca\/","url_meta":{"origin":20943,"position":3},"title":"Confira a programa\u00e7\u00e3o de Carnaval em shoppings de Ribeir\u00e3o Preto e Franca","author":"ismaelcolosi.com.br","date":"6 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] Faltando poucos dias para o Carnaval, dois dos quatro shoppings de Ribeir\u00e3o Preto e o de Franca divulgaram as programa\u00e7\u00f5es para comemorar a data. As atividades culturais oferecidas pelos centros de compras s\u00e3o para toda fam\u00edlia e v\u00e3o desde oficinas, matin\u00eas at\u00e9 desfile de fantasias (veja abaixo). Shopping Iguatemi\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-6-1.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-6-1.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-6-1.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-6-1.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-6-1.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":35590,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/06\/hospital-santa-lydia-abre-processo-seletivo-em-ribeirao-preto-veja-as-vagas\/","url_meta":{"origin":20943,"position":4},"title":"Hospital Santa Lydia abre processo seletivo em Ribeir\u00e3o Preto; Veja as vagas","author":"ismaelcolosi.com.br","date":"6 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] A Funda\u00e7\u00e3o Hospital Santa Lydia de Ribeir\u00e3o Preto abriu um processo seletivo emergencial com quatro vagas de n\u00edvel m\u00e9dio e t\u00e9cnico com sal\u00e1rios que variam de R$ 1,4 mil e R$ 2,3 mil. As inscri\u00e7\u00f5es come\u00e7aram nesta ter\u00e7a-feira (6) e devem ser realizadas at\u00e9 as 16h do dia 15\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/hospital_santa_1200x675_10022022125527.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/hospital_santa_1200x675_10022022125527.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/hospital_santa_1200x675_10022022125527.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/hospital_santa_1200x675_10022022125527.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/hospital_santa_1200x675_10022022125527.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":37033,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/13\/ainda-nao-acabou-ribeirao-tem-mais-dois-blocos-de-carnaval-veja-quando\/","url_meta":{"origin":20943,"position":5},"title":"Ainda n\u00e3o acabou! Ribeir\u00e3o t\u00eam mais dois blocos de Carnaval; Veja quando","author":"ismaelcolosi.com.br","date":"13 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] O Carnaval em Ribeir\u00e3o Preto ainda n\u00e3o acabou de acordo com a programa\u00e7\u00e3o de atra\u00e7\u00f5es divulgadas pela Secretaria de Cultura de Ribeir\u00e3o Preto, no dia 5 de fevereiro. Entre os dias 8 e 13 de fevereiro, a cidade teve mais de 25 blocos de rua que fizeram a alegria\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/bloco-carnaval.webp.webp?fit=1024%2C768&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/bloco-carnaval.webp.webp?fit=1024%2C768&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/bloco-carnaval.webp.webp?fit=1024%2C768&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/bloco-carnaval.webp.webp?fit=1024%2C768&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-5rN","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/20943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=20943"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/20943\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/20944"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=20943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=20943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=20943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}