{"id":20223,"date":"2023-12-24T16:07:48","date_gmt":"2023-12-24T19:07:48","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/24\/grave-colisao-na-br-101-deixa-vitimas-fatais-entre-elas-uma-adolescente-de-apenas-13-anos\/"},"modified":"2023-12-24T16:07:48","modified_gmt":"2023-12-24T19:07:48","slug":"grave-colisao-na-br-101-deixa-vitimas-fatais-entre-elas-uma-adolescente-de-apenas-13-anos","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/24\/grave-colisao-na-br-101-deixa-vitimas-fatais-entre-elas-uma-adolescente-de-apenas-13-anos\/","title":{"rendered":"Grave colis\u00e3o na BR-101 deixa v\u00edtimas fatais, entre elas, uma adolescente de apenas 13 anos"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div itemprop=\"text\">\n<p>Um grave acidente, ocorrido na Rodovia do Contorno, na BR-101, que atravesa as cidades da Serra e Cariacica, na Grande Vit\u00f3ria, no Esp\u00edrito Santo, ocasionou a morte de tr\u00eas pessoas, incluindo uma adolescente de 13 anos. A situa\u00e7\u00e3o ainda deixou quatro pessoas feridas.<\/p>\n<p>O incidente aconteceu neste \u00faltimo domingo, dia 24 de dezembro, na v\u00e9spera de Natal. Entre as v\u00edtimas fatais est\u00e3o Ana Karoliny, de 13 anos, e dois homens, Thieres Celestino Sodr\u00e9, de 33 anos, e Jackson Barreto Ferreira, de 35 anos.<\/p>\n<p>Ana era acompanhada pela m\u00e3e e pela irm\u00e3 de apenas 6 anos dentro do ve\u00edculo. Os sobreviventes, incluindo uma crian\u00e7a de seis anos, foram encaminhados aos hospitais locais e se encontram em um estado de sa\u00fade est\u00e1vel.<\/p>\n<p>O acidente envolveu um Renault Sandero, que estava seguindo no sentido Cariacica-Serra, pr\u00f3ximo ao km 277, quando colidiu com um poste e capotou \u00e0s margens da via. Thiago estava dirigingo o ve\u00edculo.<\/p>\n<p>A PRF (Pol\u00edcia Rodovi\u00e1ria Federal) foi acionada, para atender a ocorr\u00eancia e idenfiticou que o carro estava com excesso de lota\u00e7\u00e3o, transportando sete pessoas, algo que pode ter influenciado no acidente.<\/p>\n<p>Imagens da PRF indicaram que o ve\u00edculo perdeu o controle enquanto estava na curva, chegou a girar na rodovia, e colidiu com o poste e capotou, assim caindo em um barranco.<\/p>\n<p>Devido ao grave acidente, a Pol\u00edcia Civil foi acionada e dever\u00e1 investigar quais foram as causas que levaram a toda a trag\u00e9dia que tirou a vida de 3 pessoas.<\/p>\n<\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/fnmais.com\/grave-colisao-na-br-101-deixa-vitimas-fatais-entre-elas-adolescente-apenas-13-anos\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Um grave acidente, ocorrido na Rodovia do Contorno, na BR-101, que atravesa as cidades da Serra e Cariacica, na Grande Vit\u00f3ria, no Esp\u00edrito Santo, ocasionou a morte de tr\u00eas pessoas, incluindo uma adolescente de 13 anos. A situa\u00e7\u00e3o ainda deixou quatro pessoas feridas. O incidente aconteceu neste \u00faltimo domingo, dia 24 de dezembro, na&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":20224,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-20223","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65886190b6bfd2223.jpg?fit=1200%2C628&ssl=1",1200,628,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65886190b6bfd2223.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65886190b6bfd2223.jpg?fit=300%2C157&ssl=1",300,157,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65886190b6bfd2223.jpg?fit=768%2C402&ssl=1",768,402,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65886190b6bfd2223.jpg?fit=1024%2C536&ssl=1",1024,536,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65886190b6bfd2223.jpg?fit=1200%2C628&ssl=1",1200,628,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65886190b6bfd2223.jpg?fit=1200%2C628&ssl=1",1200,628,true],"neve-blog":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65886190b6bfd2223.jpg?resize=930%2C620&ssl=1",930,620,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Um grave acidente, ocorrido na Rodovia do Contorno, na BR-101, que atravesa as cidades da Serra e Cariacica, na Grande Vit\u00f3ria, no Esp\u00edrito Santo, ocasionou a morte de tr\u00eas pessoas, incluindo uma adolescente de 13 anos. A situa\u00e7\u00e3o ainda deixou quatro pessoas feridas. O incidente aconteceu neste \u00faltimo domingo, dia 24 de dezembro, na&hellip;&nbsp;","jetpack-related-posts":[{"id":20218,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/24\/pai-mae-e-namorado-da-filha-morrem-em-acidente-na-br-101-a-caminho-da-bahia-vitimas-sao-identificadas\/","url_meta":{"origin":20223,"position":0},"title":"Pai, m\u00e3e e namorado da filha morrem em acidente na BR-101 a caminho da Bahia; v\u00edtimas s\u00e3o identificadas","author":"ismaelcolosi.com.br","date":"24 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Tr\u00eas pessoas acabaram perdendo a vida nesta fim de semana ap\u00f3s serem v\u00edtimas de um grave acidente de tr\u00e2nsito. O fato ocorreu no Km 55 da BR 101, que fica em Concei\u00e7\u00e3o da Barra, no Norte do Esp\u00edrito Santo.O acidente foi registrado por volta das 20h15 do \u00faltimo s\u00e1bado\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65886faa2606a5047.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65886faa2606a5047.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65886faa2606a5047.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65886faa2606a5047.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65886faa2606a5047.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":7059,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/27\/pericia-e-acionada-para-investigar-acidente-entre-carro-e-caminhao-que-deixou-duas-vitimas-fatais-e-acaba-tendo-o-veiculo-atingido-na-br-101\/","url_meta":{"origin":20223,"position":1},"title":"Per\u00edcia \u00e9 acionada para investigar acidente entre carro e caminh\u00e3o que deixou duas v\u00edtimas fatais e acaba tendo o ve\u00edculo atingido na BR-101","author":"ismaelcolosi.com.br","date":"27 de Novembro de 2023","format":false,"excerpt":"[ad_1] Na noite deste \u00faltimo domingo, dia 26 de novembro, duas pessoas morreram ap\u00f3s uma batida entre um caminh\u00e3o e um carro. O caso aconteceu na BR-101, na cidade de Mascote, na Bahia.De acordo com informa\u00e7\u00f5es fornecidas pela Pol\u00edcia Militar (PM), as duas v\u00edtimas fatais, que n\u00e3o estavam com os\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6564ac444c11c5401.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6564ac444c11c5401.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6564ac444c11c5401.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6564ac444c11c5401.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6564ac444c11c5401.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":20546,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/25\/quem-e-a-familia-que-perdeu-a-vida-em-acidente-de-carro-a-caminho-de-brasilia-identidades-sao-divulgadas\/","url_meta":{"origin":20223,"position":2},"title":"Quem \u00e9 a fam\u00edlia que perdeu a vida em acidente de carro a caminho de Bras\u00edlia; identidades s\u00e3o divulgadas","author":"ismaelcolosi.com.br","date":"25 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Um grave acidente acabou resultando na morte de quatro pessoas de uma mesma fam\u00edlia no \u00faltimo final de semana na BR-020. As v\u00edtimas eram um homem, a esposa e os dois filhos pequenos, que n\u00e3o resistiram aos ferimentos.O acidente ocorreu em um trecho da cidade de Correntina, que fica\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6589fa0401c742453.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6589fa0401c742453.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6589fa0401c742453.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6589fa0401c742453.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6589fa0401c742453.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":27105,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/11\/numero-de-vitimas-fatais-entre-acidente-em-onibus-na-bahia-sobe-para-25\/","url_meta":{"origin":20223,"position":3},"title":"N\u00famero de v\u00edtimas fatais entre acidente em \u00f4nibus na Bahia sobe para 25","author":"ismaelcolosi.com.br","date":"11 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Foi a \u00f3bito mais uma v\u00edtima do grave acidente entre um \u00f4nibus de turismo e um caminh\u00e3o de carga. At\u00e9 a atualiza\u00e7\u00e3o anterior, o n\u00famero de v\u00edtimas fatais registrados na trag\u00e9dia era de 24 e agora foi para 25 com a morte de Maria da Concei\u00e7\u00e3o Fernandes, de 33\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659ffaac9057f9969.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659ffaac9057f9969.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659ffaac9057f9969.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659ffaac9057f9969.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659ffaac9057f9969.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":9227,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/01\/quem-sao-as-vitimas-fatais-do-grave-acidente-que-deixou-um-cenario-apocaliptico-na-pr-445\/","url_meta":{"origin":20223,"position":4},"title":"Quem s\u00e3o as v\u00edtimas fatais do grave acidente que deixou um cen\u00e1rio apocal\u00edptico na PR-445","author":"ismaelcolosi.com.br","date":"1 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Um terr\u00edvel acidente terminou em uma grande trag\u00e9dia ao deixar v\u00edtimas fatais e um cen\u00e1rio apocal\u00edptico na rodovia PR-445, entre os munic\u00edpios de Mau\u00e1 da Serra e Tamarana, ambos localizados no interior do estado do Paran\u00e1.De acordo com as informa\u00e7\u00f5es repassadas pela Pol\u00edcia Rodovi\u00e1ria Estadual (PRE), a colis\u00e3o envolveu\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-656a4c1d32d277356.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-656a4c1d32d277356.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-656a4c1d32d277356.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-656a4c1d32d277356.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-656a4c1d32d277356.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":19590,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/22\/quem-sao-as-vitimas-fatais-do-acidente-com-ambulancia\/","url_meta":{"origin":20223,"position":5},"title":"quem s\u00e3o as v\u00edtimas fatais do acidente com ambul\u00e2ncia","author":"ismaelcolosi.com.br","date":"22 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Um acidente grave deixou v\u00e1rias v\u00edtimas fatais na tarde da \u00faltima quinta-feira (21\/12). O tr\u00e1gico epis\u00f3dio ocorreu na BR-040, pr\u00f3ximo a Santos Dumont, na Zona da Mata mineira, em uma curva do km 736 da rodovia.O acidente envolveu uma carreta e uma ambul\u00e2ncia. No total, 5 pessoas faleceram na\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6585f368a27225526.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6585f368a27225526.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6585f368a27225526.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6585f368a27225526.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6585f368a27225526.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-5gb","jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65886190b6bfd2223.jpg?fit=1200%2C628&ssl=1","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/20223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=20223"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/20223\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/20224"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=20223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=20223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=20223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}