{"id":20192,"date":"2023-12-24T14:11:47","date_gmt":"2023-12-24T17:11:47","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/24\/cantor-e-pastor-davi-passamani-tenta-tirar-a-propria-vida-e-deixa-carta-de-despedida-apos-acusacao\/"},"modified":"2023-12-24T14:11:47","modified_gmt":"2023-12-24T17:11:47","slug":"cantor-e-pastor-davi-passamani-tenta-tirar-a-propria-vida-e-deixa-carta-de-despedida-apos-acusacao","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/24\/cantor-e-pastor-davi-passamani-tenta-tirar-a-propria-vida-e-deixa-carta-de-despedida-apos-acusacao\/","title":{"rendered":"cantor e pastor Davi Passamani tenta tirar a pr\u00f3pria vida e deixa carta de despedida ap\u00f3s acusa\u00e7\u00e3o"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div itemprop=\"text\">\n<p>O pastor Davi Passamani, recentemente envolvido em um Boletim de Ocorr\u00eancia por acusa\u00e7\u00f5es de importuna\u00e7\u00e3o sexual, teria tentadotirar a pr\u00f3pria vida, de acordo com relatos divulgados.<\/p>\n<p>E antes do ato, ele teria publicado uma carta aberta dentro de um grupo da igreja no WhatsApp, sendo acompanhada de um v\u00eddeo que sugere uma despedida.<\/p>\n<p>O texto da carta teria sido escrito dentro de um hotel, onde o pastor escolheu se isolar ap\u00f3s ter enfrentado todo o esc\u00e2ndalo. A fam\u00edlia teria sa\u00eddo em busca dele ap\u00f3s ter se deparado com a publica\u00e7\u00e3o.<\/p>\n<p>E por enquanto, n\u00e3o h\u00e1 grandes informa\u00e7\u00f5es sobre o seu estado de sa\u00fade, mas fontes ligadas \u00e0 igreja Casa indicam que ele teria tentado tirar a pr\u00f3pria vida.<\/p>\n<p>Na publica\u00e7\u00e3o, o pastor expressa profundos confltios internos e ang\u00fastias, reconhecendo que estava perdendo a batalha contra si mesmo. Ele menciona tentativas de mostrar alegrias e diz que aqueles que se mantiveram pr\u00f3ximo dele perceberam sua tristeza.<\/p>\n<p><em>\u201cHoje eu escrevo uma das cartas mais dif\u00edceis de se escrever. Hoje eu deixo a r\u00e9dea da minha vida, por ter tentado tanto percebi que jamais conseguiria vencer. Hoje estou perdendo para mim, eu feri a mim e somente a mim, o maior advers\u00e1rio da minha vida foi o que eu perdi.\u201d<\/em>, declarou diante do ocorrido.<\/p>\n<p>Com isso, Passamani compartilhou o seu sofrimento interno e chegou at\u00e9 mesmo a mencionar o seu \u00faltimo abra\u00e7o com sua fam\u00edlia, destacando a import\u00e2ncia de seus filhos e o amor que recebeu de sua m\u00e3e.<\/p>\n<\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/fnmais.com\/urgente-cantor-pastor-davi-passamani-tenta-tirar-propria-vida-deixa-carta-despedida-apos-acusacao\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] O pastor Davi Passamani, recentemente envolvido em um Boletim de Ocorr\u00eancia por acusa\u00e7\u00f5es de importuna\u00e7\u00e3o sexual, teria tentadotirar a pr\u00f3pria vida, de acordo com relatos divulgados. E antes do ato, ele teria publicado uma carta aberta dentro de um grupo da igreja no WhatsApp, sendo acompanhada de um v\u00eddeo que sugere uma despedida. O&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":20193,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-20192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65885d5a3b4435194.jpg?fit=1200%2C628&ssl=1",1200,628,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65885d5a3b4435194.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65885d5a3b4435194.jpg?fit=300%2C157&ssl=1",300,157,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65885d5a3b4435194.jpg?fit=768%2C402&ssl=1",768,402,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65885d5a3b4435194.jpg?fit=1024%2C536&ssl=1",1024,536,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65885d5a3b4435194.jpg?fit=1200%2C628&ssl=1",1200,628,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65885d5a3b4435194.jpg?fit=1200%2C628&ssl=1",1200,628,true],"neve-blog":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65885d5a3b4435194.jpg?resize=930%2C620&ssl=1",930,620,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] O pastor Davi Passamani, recentemente envolvido em um Boletim de Ocorr\u00eancia por acusa\u00e7\u00f5es de importuna\u00e7\u00e3o sexual, teria tentadotirar a pr\u00f3pria vida, de acordo com relatos divulgados. E antes do ato, ele teria publicado uma carta aberta dentro de um grupo da igreja no WhatsApp, sendo acompanhada de um v\u00eddeo que sugere uma despedida. O&hellip;&nbsp;","jetpack-related-posts":[{"id":19690,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/22\/pastor-davi-passamani-e-alvo-de-nova-denuncia-por-importunacao-sexual\/","url_meta":{"origin":20192,"position":0},"title":"Pastor Davi Passamani \u00e9 alvo de nova den\u00fancia por importuna\u00e7\u00e3o sexual","author":"ismaelcolosi.com.br","date":"22 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Nesta sexta-feira (22\/12), o nome do pastor Davi Vieira Passamani voltou a figurar no notici\u00e1rio. Isso porque o religioso foi acusado de importuna\u00e7\u00e3o sexual pela segunda vez. A primeira denuncia aconteceu em 2020, feita por outra mulher.A denunciante procurou a pol\u00edcia na quarta-feira (20\/12) e denunciou o epis\u00f3dio, que\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65863a3d7f4bf1130.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65863a3d7f4bf1130.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65863a3d7f4bf1130.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65863a3d7f4bf1130.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65863a3d7f4bf1130.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":26180,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/09\/pastor-guia-de-turismo-e-musico-estao-entre-os-mortos-em-acidente-com-onibus-na-bahia-que-deixou-mais-de-20-vitimas-fatais\/","url_meta":{"origin":20192,"position":1},"title":"Pastor, guia de turismo e m\u00fasico est\u00e3o entre os mortos em acidente com \u00f4nibus na Bahia que deixou mais de 20 v\u00edtimas fatais","author":"ismaelcolosi.com.br","date":"9 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Nesta \u00faltima noite de domingo, dia 7 de janeiro, a Bahia ficou de luto ap\u00f3s um acidente fatal envolvendo um micro-\u00f4nibus e um caminh\u00e3o na BR-324, em S\u00e3o Jos\u00e9 do Jacu\u00edpe. E entre as vinte e quatro v\u00edtimas fatais, est\u00e3o um pastor evang\u00e9lico, uma guia de turismo e um\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659d6303b2e382917.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659d6303b2e382917.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659d6303b2e382917.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659d6303b2e382917.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659d6303b2e382917.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":12335,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/07\/famoso-pastor-e-preso-nos-eua-acusado-de-furto-e-teve-fianca-fixada-em-r-430-mil-para-deixar-a-cadeia-diz-site\/","url_meta":{"origin":20192,"position":2},"title":"Famoso pastor \u00e9 preso nos EUA acusado de furto e teve fian\u00e7a fixada em R$ 430 mil para deixar a cadeia, diz site","author":"ismaelcolosi.com.br","date":"7 de Dezembro de 2023","format":false,"excerpt":"[ad_1] As atividades cotidianas da fam\u00edlia Poncio continuam sendo assunto na internet. Conforme relatado pelo perfil Gossip do Dia, Saulo Poncio foi detido na cidade de Orlando, que fica no estado da Fl\u00f3rida, nos Estados Unidos, no \u00faltimo 4 de novembro.Entretanto, somente nas ultimas horas \u00e9 que a not\u00edcia veio\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657246c3ad5166361.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657246c3ad5166361.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657246c3ad5166361.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657246c3ad5166361.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-657246c3ad5166361.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":12327,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/07\/ximbinha-afirma-que-pastora-influenciou-decisao-de-joelma-em-encerrar-a-banda\/","url_meta":{"origin":20192,"position":3},"title":"Ximbinha afirma que pastora influenciou decis\u00e3o de Joelma em encerrar a banda","author":"ismaelcolosi.com.br","date":"7 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Ximbinha esteve no podcast Saladacast e voltou a falar sobre o fim da parceria, e do casamento, com Joelma. Durante a entrevista, Ximbinha afirmou que houve influ\u00eancia de uma lideran\u00e7a religiosa em sua separa\u00e7\u00e3o.Sem dizer o nome de quem seria a pastora, Ximbinha afirmou que havia uma pastora influenciando\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65724b5f328df6016.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65724b5f328df6016.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65724b5f328df6016.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65724b5f328df6016.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65724b5f328df6016.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":39774,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/28\/pec-que-amplia-isencao-para-igrejas-avanca-na-camara\/","url_meta":{"origin":20192,"position":4},"title":"PEC que amplia isen\u00e7\u00e3o para igrejas avan\u00e7a na C\u00e2mara","author":"ismaelcolosi.com.br","date":"28 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] Uma comiss\u00e3o especial da C\u00e2mara dos Deputados aprovou nesta ter\u00e7a, 27, parecer de uma Proposta de Emenda \u00e0 Constitui\u00e7\u00e3o (PEC) que amplia a imunidade tribut\u00e1ria de entidades religiosas. De acordo com o relator, deputado Dr. Fernando M\u00e1ximo (Uni\u00e3o Brasil-RO), o texto final foi acertado com o governo do presidente\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/27022024-lula1760.jpg?fit=754%2C458&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/27022024-lula1760.jpg?fit=754%2C458&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/27022024-lula1760.jpg?fit=754%2C458&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/27022024-lula1760.jpg?fit=754%2C458&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":4482,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/21\/apos-ser-flagrado-com-amante-pastor-toma-atitude-drastica-contra-ex-esposa\/","url_meta":{"origin":20192,"position":5},"title":"Ap\u00f3s ser flagrado com amante, pastor toma atitude dr\u00e1stica contra ex-esposa","author":"ismaelcolosi.com.br","date":"21 de Novembro de 2023","format":false,"excerpt":"[ad_1] A viol\u00eancia dom\u00e9stica \u00e9 um problema global que atravessa fronteiras culturais, sociais e econ\u00f4micas, afetando pessoas independentemente de idade, g\u00eanero ou status social.Ela se manifesta de diversas formas, desde agress\u00f5es f\u00edsicas at\u00e9 abusos emocionais, deixando cicatrizes profundas n\u00e3o apenas na v\u00edtima direta, mas tamb\u00e9m em fam\u00edlias e comunidades. Este\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655cd57ac969a3560.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655cd57ac969a3560.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655cd57ac969a3560.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655cd57ac969a3560.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-655cd57ac969a3560.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-5fG","jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-65885d5a3b4435194.jpg?fit=1200%2C628&ssl=1","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/20192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=20192"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/20192\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/20193"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=20192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=20192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=20192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}