{"id":20144,"date":"2023-12-24T11:47:52","date_gmt":"2023-12-24T14:47:52","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/24\/casal-e-duas-criancas-perderm-a-vida-em-acidente-entre-carro-e-caminhao-no-interior-de-minas-gerais\/"},"modified":"2023-12-24T11:47:52","modified_gmt":"2023-12-24T14:47:52","slug":"casal-e-duas-criancas-perderm-a-vida-em-acidente-entre-carro-e-caminhao-no-interior-de-minas-gerais","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/24\/casal-e-duas-criancas-perderm-a-vida-em-acidente-entre-carro-e-caminhao-no-interior-de-minas-gerais\/","title":{"rendered":"Casal e duas crian\u00e7as perderm a vida em acidente entre carro e caminh\u00e3o no interior de Minas Gerais"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div itemprop=\"text\">\n<p>Neste \u00faltimo s\u00e1bado (23), a rodovia BR-251, foi o cen\u00e1rio de uma trag\u00e9dia que ceifou quatro vidas, entre as v\u00edtimas fatais est\u00e3o duas crian\u00e7as.<\/p>\n<p>De acordo com as primeiras informa\u00e7\u00f5es repassadas pelas autoridades respons\u00e1veis por atenderem a ocorr\u00eancia, um carro de passeio, modelo Prisma, colidiu com um caminh\u00e3o tanque, na altura do munic\u00edpio de Rubelita, localizado no interior do estado de Minas Gerais, no KM 336.<\/p>\n<p>Segundo as informa\u00e7\u00f5es dos socorristas do Corpo de Bombeiros, a bordo do carro estavam cinco pessoas, a fam\u00edlia havia partido da cidade de Montes Claros com destino a Salinas, ambas no interior do estado mineiro.<\/p>\n<p>Na altura do KM 36, o carro colidiu lateralmente contra o caminh\u00e3o, apenas o motorista do carro sobreviveu a colis\u00e3o.<\/p>\n<p>Ainda segundo as informa\u00e7\u00f5es coletadas junto as autoridades, um homem de 36 anos, uma mulher de 34 anos, e dois meninos, de 2 e 9 anos, faleceram no local do acidente.<\/p>\n<p>A viol\u00eancia do impacto deixou o carro completamente destru\u00eddo, as v\u00edtimas ficaram presas as ferragens e os socorristas do Corpo de Bombeiros precisaram utilizar a t\u00e9cnica de desencarceramento para retirar os corpos do casal e das crian\u00e7as.<\/p>\n<p>O motorista do ve\u00edculo foi socorrido e encaminhado para uma unidade de sa\u00fade mais pr\u00f3xima. O condutor do caminh\u00e3o que n\u00e3o estava carregado teve les\u00f5es leves, recebeu os primeiros socorros e foi liberado em seguida.<\/p>\n<p>De acordo com testemunhas, chovia no momento do acidente. Os agentes da per\u00edcia forense foram acionados para realizarem o trabalho necess\u00e1rio para que os corpos fossem removidos para o Instituto M\u00e9dico Legal (IML), mais pr\u00f3ximo.<\/p>\n<\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/fnmais.com\/tragedia-na-br-251-casal-duas-criancas-perderm-vida-em-acidente-entre-carro-caminhao-no-interior-minas-gerais\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Neste \u00faltimo s\u00e1bado (23), a rodovia BR-251, foi o cen\u00e1rio de uma trag\u00e9dia que ceifou quatro vidas, entre as v\u00edtimas fatais est\u00e3o duas crian\u00e7as. De acordo com as primeiras informa\u00e7\u00f5es repassadas pelas autoridades respons\u00e1veis por atenderem a ocorr\u00eancia, um carro de passeio, modelo Prisma, colidiu com um caminh\u00e3o tanque, na altura do munic\u00edpio de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":20145,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-20144","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658842bdc9d1a1233.jpg?fit=1200%2C628&ssl=1",1200,628,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658842bdc9d1a1233.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658842bdc9d1a1233.jpg?fit=300%2C157&ssl=1",300,157,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658842bdc9d1a1233.jpg?fit=768%2C402&ssl=1",768,402,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658842bdc9d1a1233.jpg?fit=1024%2C536&ssl=1",1024,536,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658842bdc9d1a1233.jpg?fit=1200%2C628&ssl=1",1200,628,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658842bdc9d1a1233.jpg?fit=1200%2C628&ssl=1",1200,628,true],"neve-blog":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658842bdc9d1a1233.jpg?resize=930%2C620&ssl=1",930,620,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Neste \u00faltimo s\u00e1bado (23), a rodovia BR-251, foi o cen\u00e1rio de uma trag\u00e9dia que ceifou quatro vidas, entre as v\u00edtimas fatais est\u00e3o duas crian\u00e7as. De acordo com as primeiras informa\u00e7\u00f5es repassadas pelas autoridades respons\u00e1veis por atenderem a ocorr\u00eancia, um carro de passeio, modelo Prisma, colidiu com um caminh\u00e3o tanque, na altura do munic\u00edpio de&hellip;&nbsp;","jetpack-related-posts":[{"id":31550,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/22\/carro-bate-em-carreta-destroi-familia-pai-mae-e-bebe-perderam-a-vida-crianca-foi-ejetada-do-carro\/","url_meta":{"origin":20144,"position":0},"title":"Carro bate em carreta, destr\u00f3i fam\u00edlia, pai, m\u00e3e e beb\u00ea perderam a vida, crian\u00e7a foi ejetada do carro","author":"ismaelcolosi.com.br","date":"22 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Uma colis\u00e3o frontal entre um carro e uma carreta destruiu uma fam\u00edlia, o acidente teve como cen\u00e1rio a rodovia BR-25 e aconteceu na tarde deste domingo (21). No final da tarde deste \u00faltimo domingo, um tr\u00e1gico acidente na BR-251, pr\u00f3ximo a localidade de Curral de Dentro, que fica no\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65aeb8e91dccd9738.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65aeb8e91dccd9738.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65aeb8e91dccd9738.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65aeb8e91dccd9738.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-65aeb8e91dccd9738.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":25998,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/08\/tragedia-na-pr-317-caminhao-sem-freios-atinge-varios-carros-deixa-vitimas-fatais-entre-elas-uma-crianca-alem-de-varios-feridos\/","url_meta":{"origin":20144,"position":1},"title":"Trag\u00e9dia na PR-317: Caminh\u00e3o sem freios atinge v\u00e1rios carros deixa v\u00edtimas fatais entre elas uma crian\u00e7a, al\u00e9m de v\u00e1rios feridos","author":"ismaelcolosi.com.br","date":"8 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Na tarde desta segunda-feira (8), um grave acidente envolvendo um caminh\u00e3o e tr\u00eas carros provocou uma verdadeira trag\u00e9dia que teve como cen\u00e1rio a rodovia BR-317.De acordo com as informa\u00e7\u00f5es repassadas pelos agentes da Pol\u00edcia Rodovi\u00e1ria Estadual (PRE), em virtude do acidente duas mulheres e uma crian\u00e7a perderam a vida\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659c95959f11b9036.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659c95959f11b9036.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659c95959f11b9036.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659c95959f11b9036.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659c95959f11b9036.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":6319,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/25\/acidente-entre-carro-e-caminhao-deixa-vitimas-fatais-na-pr-340-e-interdita-rodovia\/","url_meta":{"origin":20144,"position":2},"title":"Acidente entre carro e caminh\u00e3o deixa v\u00edtimas fatais na PR-340 e interdita rodovia","author":"ismaelcolosi.com.br","date":"25 de Novembro de 2023","format":false,"excerpt":"[ad_1] Na PR-340, na regi\u00e3o de Tel\u00eamaco Borba, no Paran\u00e1, chegou a ser noticiado atrav\u00e9s de diversos canais de comunica\u00e7\u00e3o que um tr\u00e1gico acidente tirou a vida de tr\u00eas pessoas.Segundo informa\u00e7\u00f5es da PRF (Pol\u00edcia Rodovi\u00e1ria Federal), a batida teria sido frontal e ocorrida no per\u00edodo da manh\u00e3 desta segunda-feira, dia\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-65622352dd48d2379.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-65622352dd48d2379.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-65622352dd48d2379.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-65622352dd48d2379.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-65622352dd48d2379.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":50754,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/18\/suspeito-de-causar-acidente-com-caminhao-na-regiao-de-ribeirao-vai-responder-por-fuga\/","url_meta":{"origin":20144,"position":3},"title":"Suspeito de causar acidente com caminh\u00e3o na regi\u00e3o de Ribeir\u00e3o vai responder por fuga","author":"ismaelcolosi.com.br","date":"18 de Maio de 2024","format":false,"excerpt":"[ad_1] O motorista do carro suspeito de ter colidido com um caminh\u00e3o-tanque carregado de etanol na rodovia Candido Portinari, em Batatais, na manh\u00e3 deste s\u00e1bado (18), foi indiciado pela Pol\u00edcia Civil por ter fugido do local do acidente. O caminh\u00e3o pegou fogo e provocou a interdi\u00e7\u00e3o da rodovia. O homem\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/rodovia-candido-portinari_2024-05-18_22-14-58_jpeg_2024-05-18_22-14-58.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/rodovia-candido-portinari_2024-05-18_22-14-58_jpeg_2024-05-18_22-14-58.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/rodovia-candido-portinari_2024-05-18_22-14-58_jpeg_2024-05-18_22-14-58.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/rodovia-candido-portinari_2024-05-18_22-14-58_jpeg_2024-05-18_22-14-58.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/rodovia-candido-portinari_2024-05-18_22-14-58_jpeg_2024-05-18_22-14-58.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":28518,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/16\/casal-de-idosos-morre-apos-colidir-com-caminhao-estacionado-na-regiao-de-ribeirao-veja-o-video\/","url_meta":{"origin":20144,"position":4},"title":"Casal de idosos morre ap\u00f3s colidir com caminh\u00e3o estacionado na regi\u00e3o de Ribeir\u00e3o; Veja o v\u00eddeo","author":"ismaelcolosi.com.br","date":"16 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Dois idosos morreram ap\u00f3s colidir com um caminh\u00e3o que estava estacionado em um posto de combust\u00edvel, na tarde deste domingo (14), em Sert\u00e3ozinho, cidade na regi\u00e3o de Ribeir\u00e3o Preto. O acidente aconteceu por volta das 15h22 e foi registrado por uma c\u00e2mera de seguran\u00e7a (veja o v\u00eddeo abaixo). Nas\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-17.34.55.jpeg?fit=750%2C424&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-17.34.55.jpeg?fit=750%2C424&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-17.34.55.jpeg?fit=750%2C424&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-17.34.55.jpeg?fit=750%2C424&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":10774,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/05\/video-flagra-momento-em-que-carro-e-caminhao-colidem-em-uma-das-ruas-de-recife-e-deixou-vitimas-fatais\/","url_meta":{"origin":20144,"position":5},"title":"V\u00eddeo flagra momento em que carro e caminh\u00e3o colidem em uma das ruas de Recife e deixou v\u00edtimas fatais","author":"ismaelcolosi.com.br","date":"5 de Dezembro de 2023","format":false,"excerpt":"[ad_1] As imagens de uma c\u00e2mera de vigil\u00e2ncia capturaram o exato momento que aconteceu uma colis\u00e3o entre um autom\u00f3vel e um caminh\u00e3o de coleta vinculado \u00e0 prefeitura do Recife, na madrugada desta segunda-feira (4), \u00a0na Zona Oeste, da capital de Pernambuco.O acidente resultou na fatalidade dos ocupantes do carro de\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-656ea5ae3ff9b1024.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-656ea5ae3ff9b1024.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-656ea5ae3ff9b1024.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-656ea5ae3ff9b1024.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-656ea5ae3ff9b1024.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-5eU","jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658842bdc9d1a1233.jpg?fit=1200%2C628&ssl=1","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/20144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=20144"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/20144\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/20145"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=20144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=20144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=20144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}