{"id":19654,"date":"2023-12-22T21:18:39","date_gmt":"2023-12-23T00:18:39","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/22\/em-lua-de-mel-larissa-manoela-e-vitima-de-crime-e-detalhes-sao-expostos\/"},"modified":"2023-12-22T21:18:39","modified_gmt":"2023-12-23T00:18:39","slug":"em-lua-de-mel-larissa-manoela-e-vitima-de-crime-e-detalhes-sao-expostos","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/22\/em-lua-de-mel-larissa-manoela-e-vitima-de-crime-e-detalhes-sao-expostos\/","title":{"rendered":"Em lua de mel, Larissa Manoela \u00e9 v\u00edtima de crime e detalhes s\u00e3o expostos"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div itemprop=\"text\">\n<p>A atriz Larissa Manoela est\u00e1 vivendo seus dias de lua de mel com o marido em uma viagem rom\u00e2ntica. A artista, de 22 anos, se casou em segredo no in\u00edcio desta semana e deixou os f\u00e3s surpresos com a novidade.<\/p>\n<p>Mas enquanto est\u00e1 em lua de mel, Larissa tem sido v\u00edtima de golpistas nas redes sociais. \u00c9 que a imagem da celebridade est\u00e1 sendo usada de forma ilegal para promover um joguinho em uma p\u00e1gina na internet.<\/p>\n<p>Na publica\u00e7\u00e3o que se refere \u00e0 Larissa, os golpistas utilizam o nome da famosa como se ela estivesse jogando um dos joguinhos do momento para faturar na internet. <strong>\u201cGente, e eu que fiz a minha grana todinha para a minha lua de mel com o Andr\u00e9 no Subway Surf?\u201d<\/strong>, diz um trecho da postagem junto com uma motangem de fotos da artista.<\/p>\n<p>Na publica\u00e7\u00e3o, os criminosos ainda fizeram refer\u00eancia \u00e0 briga de Larissa Manoela com os pais, Gilberto Elias e Silvana Taques, com quem a famosa rompeu rela\u00e7\u00f5es h\u00e1 alguns meses devido a quest\u00f5es financeiras.<\/p>\n<div class=\"code-block code-block-9\" style=\"margin: 8px auto; text-align: center; display: block; clear: both;\">\n<p><span style=\"font-size: xx-small;\"><b>PUBLICIDADE<\/b><\/span><\/p>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a href=\"https:\/\/breeze.bet\/?c=1&amp;utm_source=fbs\" imageanchor=\"1\" style=\"margin-left: 1em; margin-right: 1em;\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" border=\"0\" data-original-height=\"250\" data-original-width=\"300\" height=\"250\" src=\"https:\/\/i0.wp.com\/blogger.googleusercontent.com\/img\/b\/R29vZ2xl\/AVvXsEhHMStsQpenim-wcfJXHMndm0o0P6BrbXYcb_zvAoVvLcdQw8AP_XKlfa98ltKcznGeZ-LpsBl2FxLCp8WOYwgFSB3cRFm5w-61F-0aTWm387IgHB-GZMFhX20JbEzho8NVK1flhSUYOat_fFInLDqTMO3djGgM3zf7gMkbu8Ut7Zlm-7-ZYF292G63voBG\/s1600\/at%C3%A9%20X2500.png?resize=300%2C250&#038;ssl=1\" width=\"300\"\/><\/a><\/div>\n<\/div>\n<p><strong>\u201cMeu pais ainda n\u00e3o liberaram a minha conta e eu tive que fazer os meus corres por fora\u201d<\/strong>, diz a p\u00e1gina. Vale lembrar que n\u00e3o foi apenas o nome de Larissa que foi alvo de a\u00e7\u00e3o como essas. Diversos outros famosos tiveram imagens usadas sem consentimento para promover itens na internet.<\/p>\n<p>At\u00e9 o momento, Larissa n\u00e3o se manifestou sobre o uso indevido de sua imagem.<\/p>\n<\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/fnmais.com\/em-lua-mel-larissa-manoela-vitima-crime-detalhes-sao-expostos\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] A atriz Larissa Manoela est\u00e1 vivendo seus dias de lua de mel com o marido em uma viagem rom\u00e2ntica. A artista, de 22 anos, se casou em segredo no in\u00edcio desta semana e deixou os f\u00e3s surpresos com a novidade. Mas enquanto est\u00e1 em lua de mel, Larissa tem sido v\u00edtima de golpistas nas&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":19655,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-19654","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658624a12d0b53049.jpg?fit=1200%2C628&ssl=1",1200,628,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658624a12d0b53049.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658624a12d0b53049.jpg?fit=300%2C157&ssl=1",300,157,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658624a12d0b53049.jpg?fit=768%2C402&ssl=1",768,402,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658624a12d0b53049.jpg?fit=1024%2C536&ssl=1",1024,536,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658624a12d0b53049.jpg?fit=1200%2C628&ssl=1",1200,628,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658624a12d0b53049.jpg?fit=1200%2C628&ssl=1",1200,628,true],"neve-blog":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658624a12d0b53049.jpg?resize=930%2C620&ssl=1",930,620,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] A atriz Larissa Manoela est\u00e1 vivendo seus dias de lua de mel com o marido em uma viagem rom\u00e2ntica. A artista, de 22 anos, se casou em segredo no in\u00edcio desta semana e deixou os f\u00e3s surpresos com a novidade. Mas enquanto est\u00e1 em lua de mel, Larissa tem sido v\u00edtima de golpistas nas&hellip;&nbsp;","jetpack-related-posts":[{"id":17594,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/18\/larissa-manoela-se-casou-escondido-sem-avisar-ninguem-fotos\/","url_meta":{"origin":19654,"position":0},"title":"Larissa Manoela se casou escondido, sem avisar ningu\u00e9m; fotos","author":"ismaelcolosi.com.br","date":"18 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Nesta segunda-feira, dia 18 de dezembro, a famosa atriz Larissa Manoela chamou aten\u00e7\u00e3o de seus f\u00e3s ao compartilhar a not\u00edcia de seu casamento com o ator Andr\u00e9 Luiz Frambach. A cerim\u00f4nia foi exposta ap\u00f3s a artista ter compartilhado alguma fotos.O casamento secreto teria acontecido neste domingo, dia 17 de\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6580a2eb636541890.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6580a2eb636541890.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6580a2eb636541890.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6580a2eb636541890.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6580a2eb636541890.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":26795,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/10\/recem-casada-larissa-manoela-faz-cliques-ousados-em-dia-de-praia-com-o-marido\/","url_meta":{"origin":19654,"position":1},"title":"Rec\u00e9m casada, Larissa Manoela faz cliques ousados em dia de praia com o marido","author":"ismaelcolosi.com.br","date":"10 de Janeiro de 2024","format":false,"excerpt":"[ad_1] O ver\u00e3o t\u00e1 mais do que on no Rio de Janeiro. Conhecida pela cidade dos 40 \u00baC, a cidade maravilhosa n\u00e3o decepciona quando o quesito \u00e9 fornecer aquele belo dia de sol \u00e0 beira mar.V\u00e1rios artistas tem aproveitado os dias quentes na capital para renovar as marquinhas e aproveitar\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659ed4436707a3304.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659ed4436707a3304.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659ed4436707a3304.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659ed4436707a3304.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-659ed4436707a3304.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":55927,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/08\/gosto-de-estar-em-movimento-e-sou-movida-por-desafios-diz-larissa-manoela\/","url_meta":{"origin":19654,"position":2},"title":"\u201cGosto de estar em movimento e sou movida por desafios&#8221;, diz Larissa Manoela","author":"ismaelcolosi.com.br","date":"8 de Julho de 2024","format":false,"excerpt":"[ad_1] Al\u00e9m de atriz, Larissa Manoela \u00e9 uma das comunicadoras mais influentes do pa\u00eds Acessibilidade L L A- A+ \u25d0 A atriz e cantora paranaense Larissa Manoela estreou nos palcos aos 8 anos, em uma montagem de \u201cA Novi\u00e7a Rebelde\u201d. Passados 15 anos, a artista estreia em abril, no Rio\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/1720441743_Larissa-Manoela.-Foto-Jorge-Bispo-1024x683.png?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/1720441743_Larissa-Manoela.-Foto-Jorge-Bispo-1024x683.png?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/1720441743_Larissa-Manoela.-Foto-Jorge-Bispo-1024x683.png?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/1720441743_Larissa-Manoela.-Foto-Jorge-Bispo-1024x683.png?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":55847,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/06\/gosto-sempre-de-estar-em-movimento-e-sou-movida-por-desafios-diz-larissa-manoela\/","url_meta":{"origin":19654,"position":3},"title":"\u201cGosto sempre de estar em movimento e sou movida por desafios&#8221;, diz Larissa Manoela","author":"ismaelcolosi.com.br","date":"6 de Julho de 2024","format":false,"excerpt":"[ad_1] Al\u00e9m de atriz, Larissa Manoela \u00e9 uma das comunicadoras mais influentes do pa\u00eds Acessibilidade L L A- A+ \u25d0 A atriz e cantora paranaense Larissa Manoela estreou nos palcos aos 8 anos, em uma montagem de \u201cA Novi\u00e7a Rebelde\u201d. Passados 15 anos, a artista estreia em abril, no Rio\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Larissa-Manoela.-Foto-Jorge-Bispo-1024x683.png?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Larissa-Manoela.-Foto-Jorge-Bispo-1024x683.png?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Larissa-Manoela.-Foto-Jorge-Bispo-1024x683.png?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Larissa-Manoela.-Foto-Jorge-Bispo-1024x683.png?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":17930,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/19\/cunhada-de-larissa-manoela-faz-declaracao-apos-casamento-me-acabo-de-chorar\/","url_meta":{"origin":19654,"position":4},"title":"Cunhada de Larissa Manoela faz declara\u00e7\u00e3o ap\u00f3s casamento: \u201cMe acabo de chorar\u201d","author":"ismaelcolosi.com.br","date":"19 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Al\u00e9m de reafirmarem mais ainda o noivado ap\u00f3s o epis\u00f3dio envolvendo a fam\u00edlia de Larissa Manoela, o casal resolveu trocar as alian\u00e7as em uma cerim\u00f4nia \u2018secreta\u2019.Ningu\u00e9m ficou sabendo quando e como seria o casamento dos dois. Eles surpreenderam o p\u00fablico com fotos registradas do momento, ao aparecerem oficialmente casados.As\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6581b37cf2b533632.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6581b37cf2b533632.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6581b37cf2b533632.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6581b37cf2b533632.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-6581b37cf2b533632.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":7096,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/27\/larissa-manoela-conta-momento-em-que-consulta-os-astros-para-entender-relacionamento\/","url_meta":{"origin":19654,"position":5},"title":"Larissa Manoela conta momento em que consulta os astros para entender relacionamento","author":"ismaelcolosi.com.br","date":"27 de Novembro de 2023","format":false,"excerpt":"[ad_1] Existem v\u00e1rias maneiras de se manter no controle da situa\u00e7\u00e3o. Uma delas, \u00e9 atrav\u00e9s dos astros. Muitas pessoas recorrem a astrologia para conseguir informa\u00e7\u00f5es valiosas sobre sua vida.Larissa Manoela foi uma das que recorreu a astrologia para manter o controle. Mas isso apenas na fic\u00e7\u00e3o. A atriz contou como\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6564d5b5ed2d43347.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6564d5b5ed2d43347.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6564d5b5ed2d43347.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6564d5b5ed2d43347.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/postimg-6564d5b5ed2d43347.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-570","jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/postimg-658624a12d0b53049.jpg?fit=1200%2C628&ssl=1","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/19654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=19654"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/19654\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/19655"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=19654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=19654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=19654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}