{"id":18220,"date":"2023-12-19T23:55:46","date_gmt":"2023-12-20T02:55:46","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/19\/theatro-pedro-ii-em-ribeirao-preto-recebe-concerto-com-entrada-gratuita\/"},"modified":"2023-12-19T23:55:46","modified_gmt":"2023-12-20T02:55:46","slug":"theatro-pedro-ii-em-ribeirao-preto-recebe-concerto-com-entrada-gratuita","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/19\/theatro-pedro-ii-em-ribeirao-preto-recebe-concerto-com-entrada-gratuita\/","title":{"rendered":"Theatro Pedro II, em Ribeir\u00e3o Preto, recebe concerto com entrada gratuita"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_104\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p><strong>Em seu \u00faltimo concerto do ano, a USP Filarm\u00f4nica de apresenta, nesta quarta-feira (20), \u00e0s 20 horas, no Theatro Pedro II, no Centro de Ribeir\u00e3o Preto.<\/strong> A entrada \u00e9 gratuita e n\u00e3o precisa retirar os ingressos com anteced\u00eancia.<\/p>\n<p>O evento tem apoio da Pr\u00f3-Reitoria de Gradua\u00e7\u00e3o da USP, que far\u00e1 a entrega dos pr\u00eamios aos estudantes de gradua\u00e7\u00e3o do Departamento de M\u00fasica da FFFCLRP-USP.<\/p>\n<p><strong>Em seu 187\u00b0 concerto, a orquestra ser\u00e1 regida pelo maestro Rubens Russomanno Ricciardi<\/strong>, com participa\u00e7\u00f5es do pianista solista ChristianYukiYokosawa, da soprano solista Gabriela Vian e da mezzo-soprano Ester Sonievski.<\/p>\n<p>No repert\u00f3rio, a USP Filarm\u00f4nica traz as obras <em>Abertura<\/em> da \u00f3pera <em>Le nozzedi Figaro, <\/em>de Wolfgang Amadeus Mozart, <em>Stille Nacht, heilige Nacht<\/em> (Noite Feliz), de Conrad Franz Xaver Gruber e <em>Concerto n\u00ba 3 para piano e orquestra em D\u00f3 menor, <\/em>com seus tr\u00eas movimentos, de Ludwig van Beethoven.<\/p>\n<h4 class=\"wp-block-heading\"><strong>SERVI\u00c7O<\/strong><\/h4>\n<p><strong>USP Filarm\u00f4nica \u2013 Theatro Pedro II<\/strong><br \/>Data: 20\/12 (quarta-feira)<br \/>Hor\u00e1rio: 20h<br \/>Local: Theatro Pedro II<br \/>Rua \u00c1lvares Cabral, 370 \u2013 Centro<\/p>\n<p>VEJA TAMB\u00c9M<br \/>Ribeir\u00e3o Preto est\u00e1 sobre um vulc\u00e3o adormecido? Veja a explica\u00e7\u00e3o<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do<strong>\u00a0acidade on\u00a0<\/strong>no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do\u00a0<strong>acidade on\u00a0<\/strong>no WhatsApp.\u00a0<a href=\"https:\/\/chat.whatsapp.com\/Bnv2w66ZT4VDyZW3oiZ69n\" target=\"_blank\" rel=\"noreferrer noopener\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp:\u00a0<strong>16 99117 7802.<\/strong><\/p>\n<p>LEIA MAIS<br \/><a href=\"https:\/\/www.tudoep.com\/tudo-valor\/NOT,0,0,1868791,como-jogar-na-mega-da-virada-on-line.aspx\" target=\"_blank\" rel=\"noreferrer noopener\">Como jogar na Mega da Virada on-line?<\/a><\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/lazer-e-cultura\/theatro-pedro-ii-em-ribeirao-preto-recebe-concerto-com-entrada-gratuita\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Em seu \u00faltimo concerto do ano, a USP Filarm\u00f4nica de apresenta, nesta quarta-feira (20), \u00e0s 20 horas, no Theatro Pedro II, no Centro de Ribeir\u00e3o Preto. A entrada \u00e9 gratuita e n\u00e3o precisa retirar os ingressos com anteced\u00eancia. O evento tem apoio da Pr\u00f3-Reitoria de Gradua\u00e7\u00e3o da USP, que far\u00e1 a entrega dos pr\u00eamios &#8230; <a title=\"Theatro Pedro II, em Ribeir\u00e3o Preto, recebe concerto com entrada gratuita\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/19\/theatro-pedro-ii-em-ribeirao-preto-recebe-concerto-com-entrada-gratuita\/\" aria-label=\"Leia mais sobre Theatro Pedro II, em Ribeir\u00e3o Preto, recebe concerto com entrada gratuita\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":18221,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[287,509,343,58,27,407,26,57],"class_list":["post-18220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-concerto","tag-entrada","tag-gratuita","tag-pedro","tag-preto","tag-recebe","tag-ribeirao","tag-theatro"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-19-at-11.16.15.jpeg?fit=1600%2C900&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-19-at-11.16.15.jpeg?fit=1600%2C900&ssl=1",1600,900,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-19-at-11.16.15.jpeg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-19-at-11.16.15.jpeg?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-19-at-11.16.15.jpeg?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-19-at-11.16.15.jpeg?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-19-at-11.16.15.jpeg?fit=1536%2C864&ssl=1",1536,864,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-19-at-11.16.15.jpeg?fit=1600%2C900&ssl=1",1600,900,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Em seu \u00faltimo concerto do ano, a USP Filarm\u00f4nica de apresenta, nesta quarta-feira (20), \u00e0s 20 horas, no Theatro Pedro II, no Centro de Ribeir\u00e3o Preto. A entrada \u00e9 gratuita e n\u00e3o precisa retirar os ingressos com anteced\u00eancia. O evento tem apoio da Pr\u00f3-Reitoria de Gradua\u00e7\u00e3o da USP, que far\u00e1 a entrega dos pr\u00eamios&hellip;","jetpack-related-posts":[{"id":74099,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/29\/usp-filarmonica-apresenta-repertorio-brasileiro\/","url_meta":{"origin":18220,"position":0},"title":"USP Filarm\u00f4nica apresenta repert\u00f3rio brasileiro","author":"ismaelcolosi.com.br","date":"29 de Outubro de 2024","format":false,"excerpt":"[ad_1] A USP Filarm\u00f4nica, sob a reg\u00eancia do maestro convidado Lucas Eduardo da Silva Galon, realiza um concerto gratuito de repert\u00f3rio brasileiro na pr\u00f3xima ter\u00e7a-feira, dia 29 de outubro, \u00e0s 20h, no Theatro Pedro II. A apresenta\u00e7\u00e3o contar\u00e1 com a participa\u00e7\u00e3o dos solistas Raquel Paulin (soprano), Juliana Taino (mezzo-soprano) e\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Lucas-Eduardo-da-Silva-Galon-divulgacao-scaled.jpg?fit=752%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Lucas-Eduardo-da-Silva-Galon-divulgacao-scaled.jpg?fit=752%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Lucas-Eduardo-da-Silva-Galon-divulgacao-scaled.jpg?fit=752%2C500&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Lucas-Eduardo-da-Silva-Galon-divulgacao-scaled.jpg?fit=752%2C500&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":51407,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/27\/usp-filarmonica-de-ribeirao-apresenta-concerto-em-homenagem-a-jornalista-erica-amendola\/","url_meta":{"origin":18220,"position":1},"title":"USP Filarm\u00f4nica de Ribeir\u00e3o apresenta concerto em homenagem a jornalista \u00c9rica Am\u00eandola","author":"ismaelcolosi.com.br","date":"27 de Maio de 2024","format":false,"excerpt":"[ad_1] A USP Filarm\u00f4nica de Ribeir\u00e3o Preto realiza, nesta ter\u00e7a-feira (28), uma homenagem \u00e0 jornalista e apresentadora, \u00c9rica Am\u00eandola, que morreu em 30 de abril durante tratamento de um c\u00e2ncer. A apresenta\u00e7\u00e3o ser\u00e1 \u00e0s 20h, no Theatro Pedro II, no Centro da cidade. O concerto pela \u201cS\u00e9rie Concertos USP\u201d tem\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/ERICA-AMENDOLA-2_2024-04-30_17-05-40_jpg.webp.webp?fit=1200%2C841&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/ERICA-AMENDOLA-2_2024-04-30_17-05-40_jpg.webp.webp?fit=1200%2C841&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/ERICA-AMENDOLA-2_2024-04-30_17-05-40_jpg.webp.webp?fit=1200%2C841&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/ERICA-AMENDOLA-2_2024-04-30_17-05-40_jpg.webp.webp?fit=1200%2C841&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/ERICA-AMENDOLA-2_2024-04-30_17-05-40_jpg.webp.webp?fit=1200%2C841&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":6963,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/27\/filarmonica-da-usp-tem-concerto-gratuito-de-compositores-negros-no-theatro-pedro-ii\/","url_meta":{"origin":18220,"position":2},"title":"Filarm\u00f4nica da USP tem concerto gratuito de compositores negros no Theatro Pedro II","author":"ismaelcolosi.com.br","date":"27 de Novembro de 2023","format":false,"excerpt":"[ad_1] O Theatro Pedro II, no Centro de Ribeir\u00e3o Preto, ir\u00e1 receber, nesta ter\u00e7a-feira (28), a Filarm\u00f4nica da USP com obras de compositores negros pela s\u00e9rie Concertos USP. A entrada \u00e9 gratuita. \u00a0 Este ser\u00e1 o 185\u00b0 concerto da Filarm\u00f4nica. A reg\u00eancia ser\u00e1 do maestro Rubens Russomanno Ricciardi e tamb\u00e9m\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-27-at-08.34.25.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-27-at-08.34.25.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-27-at-08.34.25.jpeg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-27-at-08.34.25.jpeg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-27-at-08.34.25.jpeg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":41451,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/08\/solistas-da-usp-filarmonica-apresentam-concerto-especial-nesta-sexta-em-ribeirao\/","url_meta":{"origin":18220,"position":3},"title":"Solistas da USP Filarm\u00f4nica apresentam concerto especial nesta sexta em Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"8 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] Nesta sexta-feira (8), o Ensemble Mentemanuque \u2013 Solistas da USP Filarm\u00f4nica, sob dire\u00e7\u00e3o do maestro Rubens Russomanno Ricciardi, apresentam um concerto especial com repert\u00f3rio do per\u00edodo colonial brasileiro, que inclui obras dos s\u00e9culos 17 e 18. A apresenta\u00e7\u00e3o acontecer\u00e1 \u00e0s 20h, no Audit\u00f3rio da Faculdade de Direito de Ribeir\u00e3o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/MAESTRO.jpg?fit=1200%2C706&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/MAESTRO.jpg?fit=1200%2C706&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/MAESTRO.jpg?fit=1200%2C706&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/MAESTRO.jpg?fit=1200%2C706&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/MAESTRO.jpg?fit=1200%2C706&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":3043,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/07\/sinfonica-de-ribeirao-coro-e-solistas-apresentam-opera-carmen\/","url_meta":{"origin":18220,"position":4},"title":"Sinf\u00f4nica de Ribeir\u00e3o, coro e solistas apresentam \u00f3pera Carmen","author":"ismaelcolosi.com.br","date":"7 de Novembro de 2023","format":false,"excerpt":"[ad_1] 71 Grande produ\u00e7\u00e3o da Orquestra Sinf\u00f4nica de Ribeir\u00e3o Preto, com coro e solistas, a \u00f3pera Carmen, estreia com duas r\u00e9citas em Ribeir\u00e3o Preto, dias 10 e 11 de novembro no Theatro Pedro II, e uma apresenta\u00e7\u00e3o, dia 12 no Teatro Municipal de Batatais. A reg\u00eancia ser\u00e1 de Reginaldo Nascimento,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/91530b8d9947d62da4c75fb32a32172blow-1.jpeg?fit=800%2C537&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/91530b8d9947d62da4c75fb32a32172blow-1.jpeg?fit=800%2C537&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/91530b8d9947d62da4c75fb32a32172blow-1.jpeg?fit=800%2C537&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/91530b8d9947d62da4c75fb32a32172blow-1.jpeg?fit=800%2C537&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":74194,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/30\/alma-fara-tributo-a-beethoven-em-rp\/","url_meta":{"origin":18220,"position":5},"title":"Alma far\u00e1 tributo a\u00a0Beethoven em RP\u00a0","author":"ismaelcolosi.com.br","date":"30 de Outubro de 2024","format":false,"excerpt":"[ad_1] Para comemorar dez anos de atividade, a Alma de Ribeir\u00e3o Preto preparou um espet\u00e1culo para homenagear o compositor alem\u00e3o Ludwig van Beethoven Para comemorar dez anos de atividade, a Academia Livre de M\u00fasica e Artes (Alma) de Ribeir\u00e3o Preto preparou um espet\u00e1culo para homenagear o compositor alem\u00e3o Ludwig van\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Alma-Bee-Divulgacao-scaled.jpg?fit=750%2C500&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Alma-Bee-Divulgacao-scaled.jpg?fit=750%2C500&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Alma-Bee-Divulgacao-scaled.jpg?fit=750%2C500&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/Alma-Bee-Divulgacao-scaled.jpg?fit=750%2C500&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-4JS","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/18220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=18220"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/18220\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/18221"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=18220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=18220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=18220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}