{"id":17934,"date":"2023-12-19T12:49:10","date_gmt":"2023-12-19T15:49:10","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/19\/rayssa-leal-conquista-prata-no-mundial-de-skate-street-no-japao\/"},"modified":"2023-12-19T12:49:10","modified_gmt":"2023-12-19T15:49:10","slug":"rayssa-leal-conquista-prata-no-mundial-de-skate-street-no-japao","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/19\/rayssa-leal-conquista-prata-no-mundial-de-skate-street-no-japao\/","title":{"rendered":"Rayssa Leal conquista prata no Mundial de skate street no Jap\u00e3o \u2013 Folha de Ribeir\u00e3o"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>A brasileira Rayssa Leal ficou com o vice-campeonato no Mundial de skate street, disputado em T\u00f3quio (Jap\u00e3o). A maranhense de 15 anos dividiu o p\u00f3dio da final, realizada na madrugada deste domingo (17), pelo hor\u00e1rio de Bras\u00edlia, com as anfitri\u00e3s Yumeka Odo (ouro) e Momiji Nishiya (bronze).<img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/agenciabrasil.ebc.com.br\/ebc.png?w=1200&#038;ssl=1\"\/><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/agenciabrasil.ebc.com.br\/ebc.gif?w=1200&#038;ssl=1\"\/><\/p>\n<p>Fadinha obteve 261.90 na somat\u00f3ria dos pontos da melhor volta (foram duas, de 45 segundos cada) e das duas manobras mais bem avaliadas (em cinco tentativas). Em uma delas, Rayssa recebeu 90.91 de nota e colocou press\u00e3o em Yumeka, principal advers\u00e1ria. A japonesa, por\u00e9m, na reta final, conseguiu um 94.80, ultrapassando a brasileira e assegurando o ouro.<\/p>\n<p>A prata em T\u00f3quio encerra uma temporada vitoriosa de Rayssa. Em mar\u00e7o, a maranhense disputou o Mundial de Sharjah (Emirados \u00c1rabes Unidos), referente a 2022, e ficou com o t\u00edtulo. No in\u00edcio de dezembro, em S\u00e3o Paulo, ela foi bicampe\u00e3 do Super Crown (super coroa, na tradu\u00e7\u00e3o literal) do Street League Skateboarding (SLS), principal circuito mundial da modalidade.<\/p>\n<p>A final masculina do Mundial de T\u00f3quio tamb\u00e9m foi dominada pelos anfitri\u00f5es. Os tr\u00eas lugares do p\u00f3dio foram ocupados pelos japoneses. A vit\u00f3ria foi de Sora Shirai, com Kairi Netsuke ficando com a prata e Yuto Horigome levando o bronze. O paulista Gabryel Aguilar foi o brasileiro que chegou mais longe, parando na semifinal.<\/p>\n<h2>Jogos de Paris<\/h2>\n<p>O Mundial faz parte da primeira fase de classifica\u00e7\u00e3o \u00e0 Olimp\u00edada de Paris, na Fran\u00e7a. A \u00faltima competi\u00e7\u00e3o deste per\u00edodo ser\u00e1 a etapa de Dubai, nos Emirados \u00c1rabes Unidos, do circuito da World Skate, federa\u00e7ao internacional da modalidade, em mar\u00e7o.<\/p>\n<p>Os 44 primeiros do ranking avan\u00e7am \u00e0 pr\u00f3xima fase, com limite de seis skatistas por pa\u00eds em cada g\u00eanero. Eles ter\u00e3o mais duas etapas para somar pontos: Xangai, na China, em maio; e Budapeste, na Hungria, em junho.<\/p>\n<p>O skate street em Paris ter\u00e1 44 atletas \u2013 22 no masculino e 22 no feminino. Cada pa\u00eds pode classificar, no m\u00e1ximo, tr\u00eas skatistas no masculino e tr\u00eas no feminino. Entre as mulheres, as brasileiras mais bem colocadas s\u00e3o Rayssa (segunda), P\u00e2mela Rosa (s\u00e9tima) e Gabi Mazetto (11\u00aa). Entre os homens, os destaques s\u00e3o Kelvin Hoefler (quarto), Giovanni Vianna (d\u00e9cimo) e Felipe Gustavo (19\u00ba).<\/p>\n<\/p><\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/folhaderibeirao.com.br\/2023\/12\/19\/rayssa-leal-conquista-prata-no-mundial-de-skate-street-no-japao\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] A brasileira Rayssa Leal ficou com o vice-campeonato no Mundial de skate street, disputado em T\u00f3quio (Jap\u00e3o). A maranhense de 15 anos dividiu o p\u00f3dio da final, realizada na madrugada deste domingo (17), pelo hor\u00e1rio de Bras\u00edlia, com as anfitri\u00e3s Yumeka Odo (ouro) e Momiji Nishiya (bronze). Fadinha obteve 261.90 na somat\u00f3ria dos pontos&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":17935,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[317,753,2389,2386,1811,694,2385,26,2387,2388],"class_list":["post-17934","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-conquista","tag-folha","tag-japao","tag-leal","tag-mundial","tag-prata","tag-rayssa","tag-ribeirao","tag-skate","tag-street"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1703000952_ebc.png?fit=1%2C1&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1703000952_ebc.png?fit=1%2C1&ssl=1",1,1,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1703000952_ebc.png?resize=1%2C1&ssl=1",1,1,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1703000952_ebc.png?fit=1%2C1&ssl=1",1,1,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1703000952_ebc.png?fit=1%2C1&ssl=1",1,1,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1703000952_ebc.png?fit=1%2C1&ssl=1",1,1,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1703000952_ebc.png?fit=1%2C1&ssl=1",1,1,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1703000952_ebc.png?fit=1%2C1&ssl=1",1,1,true],"neve-blog":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1703000952_ebc.png?resize=1%2C1&ssl=1",1,1,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] A brasileira Rayssa Leal ficou com o vice-campeonato no Mundial de skate street, disputado em T\u00f3quio (Jap\u00e3o). A maranhense de 15 anos dividiu o p\u00f3dio da final, realizada na madrugada deste domingo (17), pelo hor\u00e1rio de Bras\u00edlia, com as anfitri\u00e3s Yumeka Odo (ouro) e Momiji Nishiya (bronze). Fadinha obteve 261.90 na somat\u00f3ria dos pontos&hellip;&nbsp;","jetpack-related-posts":[{"id":79443,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/12\/16\/rayssa-leal-conquista-tricampeonato-mundial-de-skate-street-com-vitoria-emocionante\/","url_meta":{"origin":17934,"position":0},"title":"Rayssa Leal conquista tricampeonato mundial de skate street com vit\u00f3ria emocionante","author":"ismaelcolosi.com.br","date":"16 de Dezembro de 2024","format":false,"excerpt":"[ad_1] A skatista brasileira Rayssa Leal, conhecida como \u201cFadinha\u201d, fez hist\u00f3ria ao conquistar seu terceiro t\u00edtulo mundial de skate street neste domingo (15). A vit\u00f3ria veio com uma performance impec\u00e1vel na etapa final do campeonato, realizada nos Estados Unidos, em que Rayssa executou uma manobra decisiva nos \u00faltimos segundos, garantindo\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/rayssa_leal_tri.webp.webp?fit=1170%2C700&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/rayssa_leal_tri.webp.webp?fit=1170%2C700&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/rayssa_leal_tri.webp.webp?fit=1170%2C700&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/rayssa_leal_tri.webp.webp?fit=1170%2C700&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/rayssa_leal_tri.webp.webp?fit=1170%2C700&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":17224,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/17\/fifa-anuncia-novo-mundial-de-clubes-entre-junho-e-julho-de-2025-entenda\/","url_meta":{"origin":17934,"position":1},"title":"Fifa anuncia novo Mundial de Clubes entre junho e julho de 2025; Entenda","author":"ismaelcolosi.com.br","date":"17 de Dezembro de 2023","format":false,"excerpt":"[ad_1] O Conselho da Federa\u00e7\u00e3o Internacional de Futebol (Fifa) se reuniu neste domingo (17), em Jeddah, na Ar\u00e1bia Saudita, e definiu os detalhes do novo Mundial de Clubes da entidade, que ter\u00e1 a edi\u00e7\u00e3o inicial em 2025. O torneio, que reunir\u00e1 32 equipes, ser\u00e1 disputado nos Estados Unidos entre 15\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/partida_do_1200x675_22062022150950.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/partida_do_1200x675_22062022150950.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/partida_do_1200x675_22062022150950.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/partida_do_1200x675_22062022150950.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/partida_do_1200x675_22062022150950.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":84173,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/04\/01\/o-que-medalhistas-ensinam-sobre-sucesso\/","url_meta":{"origin":17934,"position":2},"title":"o Que Medalhistas Ensinam sobre Sucesso","author":"ismaelcolosi.com.br","date":"1 de Abril de 2025","format":false,"excerpt":"[ad_1] \r Getty Images\r Rebeca Andrade, Rayssa Leal e Bia Souza s\u00e3o algumas das medalhistas que fizeram hist\u00f3ria em Paris 2024\r Acessibilidade \r L\r L\r A-\r A+\r \r \u25d0\r \r \u00a0 O impacto das mulheres no esporte nunca foi t\u00e3o grande \u2013 e os n\u00fameros comprovam isso. Segundo um relat\u00f3rio\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/04\/forbes-capa-mulheres-no-esporte-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/04\/forbes-capa-mulheres-no-esporte-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/04\/forbes-capa-mulheres-no-esporte-1200x675.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/04\/forbes-capa-mulheres-no-esporte-1200x675.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/04\/forbes-capa-mulheres-no-esporte-1200x675.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":59775,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/12\/veja-cinco-pistas-de-skate-gratuitas-em-ribeirao-preto\/","url_meta":{"origin":17934,"position":3},"title":"Veja cinco pistas de skate gratuitas em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"12 de Agosto de 2024","format":false,"excerpt":"[ad_1] Em 2013, o skate foi considerado o segundo esporte mais praticado do Pa\u00eds. E desde a estreia do esporte nos Jogos de T\u00f3quio, em 2021, vem se tornando cada vez mais popular. O Brasil ocupa o segundo lugar de pa\u00edses com mais medalhas no esporte, com cinco, sendo tr\u00eas\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/pista-skate-maurilio_2024-08-12_16-22-21_jpeg_2024-08-12_16-22-21.webp.webp?fit=1118%2C624&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/pista-skate-maurilio_2024-08-12_16-22-21_jpeg_2024-08-12_16-22-21.webp.webp?fit=1118%2C624&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/pista-skate-maurilio_2024-08-12_16-22-21_jpeg_2024-08-12_16-22-21.webp.webp?fit=1118%2C624&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/pista-skate-maurilio_2024-08-12_16-22-21_jpeg_2024-08-12_16-22-21.webp.webp?fit=1118%2C624&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/pista-skate-maurilio_2024-08-12_16-22-21_jpeg_2024-08-12_16-22-21.webp.webp?fit=1118%2C624&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":12184,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/07\/vila-plural-recebe-warley-santana-neste-sabado\/","url_meta":{"origin":17934,"position":4},"title":"Vila Plural recebe Warley Santana neste s\u00e1bado","author":"ismaelcolosi.com.br","date":"7 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Neste s\u00e1bado (09\/12) \u00e0s 18h, o Vila Plural, o primeiro hub de entretenimento criativo do pa\u00eds, recebe Warley Santana. No encontro, que ser\u00e1 gratuito, o artista compartilhar\u00e1 os bastidores de sua carreira e contar suas realiza\u00e7\u00f5es na interpreta\u00e7\u00e3o e ventriloquia. Conhecido por sua incr\u00edvel versatilidade, Warley Santana \u00e9 muito\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/warley-santana-01.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/warley-santana-01.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/warley-santana-01.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/warley-santana-01.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/warley-santana-01.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":59082,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/06\/atletas-tem-carreira-paralela-para-se-manter\/","url_meta":{"origin":17934,"position":5},"title":"atletas t\u00eam carreira paralela para se manter","author":"ismaelcolosi.com.br","date":"6 de Agosto de 2024","format":false,"excerpt":"[ad_1] \u00a0 Acessibilidade L L A- A+ \u25d0 \u00a0 Os atletas que ganham medalhas nas Olimp\u00edadas s\u00e3o frequentemente recompensados com pr\u00eamios em dinheiro que variam dependendo do pa\u00eds. Esses pagamentos, por\u00e9m, n\u00e3o chegam para a maioria dos participantes. Aqueles que deixam a competi\u00e7\u00e3o sem pisar no p\u00f3dio frequentemente precisam de\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Robbie-Manson-rebeca-andrade-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Robbie-Manson-rebeca-andrade-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Robbie-Manson-rebeca-andrade-1024x683.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Robbie-Manson-rebeca-andrade-1024x683.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-4Fg","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/17934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=17934"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/17934\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/17935"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=17934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=17934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=17934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}