{"id":17901,"date":"2023-12-19T11:21:33","date_gmt":"2023-12-19T14:21:33","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/19\/nove-de-julho-prefeitura-aguarda-resposta-da-rual\/"},"modified":"2023-12-19T11:21:33","modified_gmt":"2023-12-19T14:21:33","slug":"nove-de-julho-prefeitura-aguarda-resposta-da-rual","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/19\/nove-de-julho-prefeitura-aguarda-resposta-da-rual\/","title":{"rendered":"Nove de Julho: Prefeitura aguarda resposta da Rual\u00a0"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"post-367763\">\n<header class=\"entry-header penci-entry-header penci-title-center\">\n<p> <span class=\"entry-meta-item penci-posted-on\"><i class=\"fa fa-clock-o\"\/><time class=\"entry-date published\" datetime=\"2023-12-19T11:00:56-03:00\">19 de dezembro de 2023 | 11:00<\/time><time class=\"updated\" datetime=\"2023-12-19T09:04:51-03:00\">19 de dezembro de 2023 | 9:04<\/time><\/span><\/p>\n<p> <span class=\"penci-social-buttons penci-social-share-footer\"><a href=\"#\" class=\"penci-post-like penci_post-meta_item  single-like-button penci-social-item like\" data-post_id=\"367763\" title=\"Like\" data-like=\"Like\" data-unlike=\"Unlike\"><i class=\"fa fa-thumbs-o-up\"\/><span class=\"penci-share-number\">0<\/span><\/a><i class=\"fa fa-facebook\"\/><a class=\"penci-social-item twitter\" target=\"_blank\" rel=\"noopener\" title=\"\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Nove%20de%20Julho:%20Prefeitura%20aguarda%20resposta%20da%20Rual\u00a0%20-%20https:\/\/www.tribunaribeirao.com.br\/site\/nove-de-julho-prefeitura-aguarda-resposta-da-rual\/\"><i class=\"fa fa-twitter\"\/><\/a><i class=\"fa fa-whatsapp\"\/><\/span><\/header>\n<div class=\"penci-entry-content entry-content\">\n<p><span class=\"TextRun SCXW2350302 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW2350302 BCX0\">A empresa <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW2350302 BCX0\">Rual<\/span><span class=\"NormalTextRun SCXW2350302 BCX0\"> Constru\u00e7\u00f5es e Com\u00e9rcio S.A, segunda colocada na licita\u00e7\u00e3o para obras de revitaliza\u00e7\u00e3o, restaura\u00e7\u00e3o e constru\u00e7\u00e3o de corredor de \u00f4nibus na <\/span><span class=\"NormalTextRun SCXW2350302 BCX0\">avenida<\/span><span class=\"NormalTextRun SCXW2350302 BCX0\"> Nove de Julho, tem at\u00e9 esta quinta-feira, 21 de dezembro, para responder \u00e0 prefeitura de Ribeir\u00e3o Preto se aceitar\u00e1 ou n\u00e3o concluir os trabalhos. <\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW2350302 BCX0\"><span class=\"SCXW2350302 BCX0\">\u00a0<\/span><br class=\"SCXW2350302 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW2350302 BCX0\"><span class=\"SCXW2350302 BCX0\">\u00a0<\/span><br class=\"SCXW2350302 BCX0\"\/><\/span><span class=\"TextRun SCXW2350302 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW2350302 BCX0\">Legalmente, ap\u00f3s ser notificada, a empresa tem o prazo de cinco dias \u00fateis para dar a resposta, conforme estabelecido no processo de licita\u00e7\u00e3o.\u00a0 A notifica\u00e7\u00e3o ocorreu na sexta-feira (15). No certame, a <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW2350302 BCX0\">Rual<\/span><span class=\"NormalTextRun SCXW2350302 BCX0\"> Constru\u00e7\u00f5es ficou em segundo lugar ao oferecer R$ 32.756.792,80 contra os R$ 31.132.101,77 ofertados pela Construtora Metropolitana, vencedora do processo <\/span><span class=\"NormalTextRun SCXW2350302 BCX0\">l<\/span><span class=\"NormalTextRun SCXW2350302 BCX0\">icitat\u00f3rio. <\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW2350302 BCX0\"><span class=\"SCXW2350302 BCX0\">\u00a0<\/span><br class=\"SCXW2350302 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW2350302 BCX0\"><span class=\"SCXW2350302 BCX0\">\u00a0<\/span><br class=\"SCXW2350302 BCX0\"\/><\/span><span class=\"TextRun SCXW2350302 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW2350302 BCX0\">Caso a empresa n\u00e3o aceite assumir as obras, a prefeitura ter\u00e1 que abrir uma nova licita\u00e7\u00e3o, o que levar\u00e1 pelo menos 90 dias para ser conclu\u00edda. Ou seja, neste caso, a obra s\u00f3 dever\u00e1 ser reiniciada em abril do pr\u00f3ximo ano. Fontes ouvidas <\/span><span class=\"NormalTextRun SCXW2350302 BCX0\">pelo Tribuna<\/span><span class=\"NormalTextRun SCXW2350302 BCX0\"> afirmaram que existem alguns empecilhos que dificultam a entrada da segunda colocada na hist\u00f3ria. <\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW2350302 BCX0\"><span class=\"SCXW2350302 BCX0\">\u00a0<\/span><br class=\"SCXW2350302 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW2350302 BCX0\"><span class=\"SCXW2350302 BCX0\">\u00a0<\/span><br class=\"SCXW2350302 BCX0\"\/><\/span><span class=\"TextRun SCXW2350302 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW2350302 BCX0\">A primeira \u00e9 o valor que receber\u00e1 que corresponder\u00e1 ao remanescente do contrato de R$ 28.614.425,83. Segundo estas fontes, mesmo com a corre\u00e7\u00e3o das planilhas or\u00e7ament\u00e1rias que est\u00e3o sendo feitas, o valor seria inferior ao oferecido pela empresa quando da licita\u00e7\u00e3o. Outro empecilho \u00e9 o desgaste que a empresa enfrentaria devido aos problemas que as obras causaram. Entre eles, a morte de um oper\u00e1rio no canteiro de obras no dia 16 de agosto.<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW2350302 BCX0\"><span class=\"SCXW2350302 BCX0\">\u00a0<\/span><br class=\"SCXW2350302 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW2350302 BCX0\"><span class=\"SCXW2350302 BCX0\">\u00a0<\/span><br class=\"SCXW2350302 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW2350302 BCX0\"><br class=\"SCXW2350302 BCX0\"\/><\/span><\/p>\n<\/div>\n<footer class=\"penci-entry-footer\"\/><\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/site\/nove-de-julho-prefeitura-aguarda-resposta-da-rual\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] 19 de dezembro de 2023 | 11:0019 de dezembro de 2023 | 9:04 0 A empresa Rual Constru\u00e7\u00f5es e Com\u00e9rcio S.A, segunda colocada na licita\u00e7\u00e3o para obras de revitaliza\u00e7\u00e3o, restaura\u00e7\u00e3o e constru\u00e7\u00e3o de corredor de \u00f4nibus na avenida Nove de Julho, tem at\u00e9 esta quinta-feira, 21 de dezembro, para responder \u00e0 prefeitura de Ribeir\u00e3o &#8230; <a title=\"Nove de Julho: Prefeitura aguarda resposta da Rual\u00a0\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/19\/nove-de-julho-prefeitura-aguarda-resposta-da-rual\/\" aria-label=\"Leia mais sobre Nove de Julho: Prefeitura aguarda resposta da Rual\u00a0\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":17902,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[1690,1229,1228,244,2376,2377],"class_list":["post-17901","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-aguarda","tag-julho","tag-nove","tag-prefeitura","tag-resposta","tag-rual"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/NoveRP-Alfredo-Risk-scaled.jpg?fit=1000%2C538&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/NoveRP-Alfredo-Risk-scaled.jpg?fit=1000%2C538&ssl=1",1000,538,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/NoveRP-Alfredo-Risk-scaled.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/NoveRP-Alfredo-Risk-scaled.jpg?fit=300%2C161&ssl=1",300,161,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/NoveRP-Alfredo-Risk-scaled.jpg?fit=768%2C413&ssl=1",768,413,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/NoveRP-Alfredo-Risk-scaled.jpg?fit=1000%2C538&ssl=1",1000,538,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/NoveRP-Alfredo-Risk-scaled.jpg?fit=1000%2C538&ssl=1",1000,538,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/NoveRP-Alfredo-Risk-scaled.jpg?fit=1000%2C538&ssl=1",1000,538,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] 19 de dezembro de 2023 | 11:0019 de dezembro de 2023 | 9:04 0 A empresa Rual Constru\u00e7\u00f5es e Com\u00e9rcio S.A, segunda colocada na licita\u00e7\u00e3o para obras de revitaliza\u00e7\u00e3o, restaura\u00e7\u00e3o e constru\u00e7\u00e3o de corredor de \u00f4nibus na avenida Nove de Julho, tem at\u00e9 esta quinta-feira, 21 de dezembro, para responder \u00e0 prefeitura de Ribeir\u00e3o&hellip;","jetpack-related-posts":[{"id":16657,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/16\/nove-de-julho-prefeitura-notifica-oficialmente-construtora-responsavel\/","url_meta":{"origin":17901,"position":0},"title":"Nove de Julho: Prefeitura notifica oficialmente construtora respons\u00e1vel","author":"ismaelcolosi.com.br","date":"16 de Dezembro de 2023","format":false,"excerpt":"[ad_1] 15 de dezembro de 2023 | 15:4615 de dezembro de 2023 | 16:28 0A secretaria municipal de Obras P\u00fablicas de Ribeir\u00e3o Preto anunciou, nesta sexta-feira, 15 de dezembro, que notificou oficialmente a construtora Metropolitana, sobre a multa que ser\u00e1 aplicada \u00e0 empresa no valor de R$ 2.861.442,58, A multa\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/NoveRP-Alfredo-Risk-Arquivo-1-scaled.jpg?fit=1000%2C523&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/NoveRP-Alfredo-Risk-Arquivo-1-scaled.jpg?fit=1000%2C523&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/NoveRP-Alfredo-Risk-Arquivo-1-scaled.jpg?fit=1000%2C523&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/NoveRP-Alfredo-Risk-Arquivo-1-scaled.jpg?fit=1000%2C523&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":12561,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/08\/prefeitura-limpara-canteiro-central-da-nove-de-julho\/","url_meta":{"origin":17901,"position":1},"title":"Prefeitura limpar\u00e1 canteiro central da Nove de Julho","author":"ismaelcolosi.com.br","date":"8 de Dezembro de 2023","format":false,"excerpt":"[ad_1] 8 de dezembro de 2023 | 8:307 de dezembro de 2023 | 19:47 0O secret\u00e1rio municipal de Obras P\u00fablicas, Pedro Luiz Pegoraro, afirmou que na pr\u00f3xima quinta-feira, 13 de dezembro, a prefeitura de Ribeir\u00e3o Preto iniciar\u00e1 os trabalhos de limpeza e desobstru\u00e7\u00e3o das cal\u00e7adas e do canteiro central da\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/nove-2-scaled.jpg?fit=1000%2C521&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/nove-2-scaled.jpg?fit=1000%2C521&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/nove-2-scaled.jpg?fit=1000%2C521&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/nove-2-scaled.jpg?fit=1000%2C521&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":16495,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/15\/empresa-e-multada-apos-atraso-nas-obras-da-avenida-nove-de-julho\/","url_meta":{"origin":17901,"position":2},"title":"Empresa \u00e9 multada ap\u00f3s atraso nas obras da avenida Nove de Julho","author":"ismaelcolosi.com.br","date":"15 de Dezembro de 2023","format":false,"excerpt":"[ad_1] A Prefeitura de Ribeir\u00e3o Preto informou nesta sexta-feira (15) que multou em R$ 2.861.442,58 a construtora Metropolitana, ap\u00f3s o munic\u00edpio ter rompido o contrato com a empresa para revitaliza\u00e7\u00e3o da avenida Nove de Julho. O acordo foi rescindido por conta do atraso nas obras, j\u00e1 que a Metropolitana realizou\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702673439_WhatsApp-Image-2023-12-05-at-11.04.13.jpeg?fit=1200%2C764&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702673439_WhatsApp-Image-2023-12-05-at-11.04.13.jpeg?fit=1200%2C764&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702673439_WhatsApp-Image-2023-12-05-at-11.04.13.jpeg?fit=1200%2C764&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702673439_WhatsApp-Image-2023-12-05-at-11.04.13.jpeg?fit=1200%2C764&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702673439_WhatsApp-Image-2023-12-05-at-11.04.13.jpeg?fit=1200%2C764&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":18395,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/20\/prefeitura-de-ribeirao-preto-vai-fazer-nova-licitacao-para-obra-da-nove-de-julho\/","url_meta":{"origin":17901,"position":3},"title":"Prefeitura de Ribeir\u00e3o Preto vai fazer nova licita\u00e7\u00e3o para obra da Nove de Julho","author":"ismaelcolosi.com.br","date":"20 de Dezembro de 2023","format":false,"excerpt":"[ad_1] A Prefeitura de Ribeir\u00e3o Preto vai precisar fazer uma nova licita\u00e7\u00e3o para concluir a obra da avenida Nove de Julho, na regi\u00e3o central da cidade. A Construtora Metropolitana, que venceu a primeira licita\u00e7\u00e3o j\u00e1 foi, inclusive, multada pela Prefeitura de Ribeir\u00e3o Preto por n\u00e3o respeitar o cronograma \u2013 contrato\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-20-at-10.47.41.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-20-at-10.47.41.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-20-at-10.47.41.jpeg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-20-at-10.47.41.jpeg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-20-at-10.47.41.jpeg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":23946,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/03\/guarda-civil-diz-ser-inviavel-base-na-nove-de-julho\/","url_meta":{"origin":17901,"position":4},"title":"Guarda Civil diz ser invi\u00e1vel base na Nove de Julho\u00a0","author":"ismaelcolosi.com.br","date":"3 de Janeiro de 2024","format":false,"excerpt":"[ad_1] A Guarda Civil Metropolitana (GCM) de Ribeir\u00e3o Preto afirmou ser invi\u00e1vel instalar uma base da corpora\u00e7\u00e3o na Avenida Nove de Julho, zona Sul da cidade, como deseja o Conselho de Preserva\u00e7\u00e3o do Patrim\u00f4nio Cultural (Conppac) de Ribeir\u00e3o Preto. A reposta foi dada no dia 18 de dezembro, por meio\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/2-nove-de-julho-risk-2-scaled.jpg?fit=967%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/2-nove-de-julho-risk-2-scaled.jpg?fit=967%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/2-nove-de-julho-risk-2-scaled.jpg?fit=967%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/2-nove-de-julho-risk-2-scaled.jpg?fit=967%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2300,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/15\/nove-de-julho-segunda-colocada-pode-assumir-obras\/","url_meta":{"origin":17901,"position":5},"title":"Nove de Julho: segunda colocada pode assumir obras \u00a0","author":"ismaelcolosi.com.br","date":"15 de Novembro de 2023","format":false,"excerpt":"[ad_1] 15 de novembro de 2023 | 9:0314 de novembro de 2023 | 19:28 0Levantamento do Tribuna junto a fontes ligadas ao governo Duarte Nogueira (PSDB) indica que a prefeitura de Ribeir\u00e3o Preto tem um \u201cPlano B\u201d para as obras de revitaliza\u00e7\u00e3o, restauro e constru\u00e7\u00e3o de corredor de \u00f4nibus na\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/nove-scaled.jpg?fit=1000%2C560&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/nove-scaled.jpg?fit=1000%2C560&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/nove-scaled.jpg?fit=1000%2C560&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/nove-scaled.jpg?fit=1000%2C560&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-4EJ","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/17901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=17901"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/17901\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/17902"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=17901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=17901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=17901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}