{"id":16596,"date":"2023-12-15T22:04:12","date_gmt":"2023-12-16T01:04:12","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/15\/prestadora-da-usp-nao-paga-13o-dos-funcionarios-e-pede-rescisao-amigavel\/"},"modified":"2023-12-15T22:04:12","modified_gmt":"2023-12-16T01:04:12","slug":"prestadora-da-usp-nao-paga-13o-dos-funcionarios-e-pede-rescisao-amigavel","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/15\/prestadora-da-usp-nao-paga-13o-dos-funcionarios-e-pede-rescisao-amigavel\/","title":{"rendered":"Prestadora da USP n\u00e3o paga 13\u00ba dos funcion\u00e1rios e pede rescis\u00e3o amig\u00e1vel"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"\">\n<h2 class=\"penci-post-subtitle\">Empresa alegou dificuldades financeiras e n\u00e3o saldou benef\u00edcios de funcion\u00e1rios que prestam servi\u00e7os de fiscaliza\u00e7\u00e3o das portarias de edif\u00edcios no Campus da universidade<\/h2>\n<p> <span class=\"entry-meta-item penci-posted-on\"><i class=\"fa fa-clock-o\"\/><time class=\"entry-date published\" datetime=\"2023-12-15T16:51:46-03:00\">15 de dezembro de 2023 | 16:51<\/time><time class=\"updated\" datetime=\"2023-12-15T16:53:12-03:00\">15 de dezembro de 2023 | 16:53<\/time><\/span><\/p>\n<p> <span class=\"penci-social-buttons penci-social-share-footer\"><a href=\"#\" class=\"penci-post-like penci_post-meta_item  single-like-button penci-social-item like\" data-post_id=\"367467\" title=\"Like\" data-like=\"Like\" data-unlike=\"Unlike\"><i class=\"fa fa-thumbs-o-up\"\/><span class=\"penci-share-number\">2<\/span><\/a><i class=\"fa fa-facebook\"\/><a class=\"penci-social-item twitter\" target=\"_blank\" rel=\"noopener\" title=\"\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Prestadora%20da%20USP%20n\u00e3o%20paga%2013\u00ba%20dos%20funcion\u00e1rios%20e%20pede%20rescis\u00e3o%20amig\u00e1vel%20-%20https:\/\/www.tribunaribeirao.com.br\/site\/prestadora-da-usp-nao-paga-13o-dos-funcionarios-e-pede-rescisao-amigavel\/\"><i class=\"fa fa-twitter\"\/><\/a><i class=\"fa fa-whatsapp\"\/><\/span><\/div>\n<div>\n<p>Por: Adalberto Luque<\/p>\n<p>Os funcion\u00e1rios de uma empresa terceirizada, que presta servi\u00e7o de portaria em v\u00e1rios edif\u00edcios do Campus da Universidade de S\u00e3o Paulo (USP) em Ribeir\u00e3o Preto, divulgou um comunicado informando que n\u00e3o vai conseguir efetuar o pagamento do 13\u00ba sal\u00e1rio, vale transporte, vale refei\u00e7\u00e3o e demais obriga\u00e7\u00f5es de seus funcion\u00e1rios.<\/p>\n<p>A empresa alegou dificuldades financeiras e que n\u00e3o conseguiu linha de cr\u00e9dito para saldar as verbas salariais dos trabalhadores alocados nos postos. \u201cPara que n\u00e3o haja ainda mais preju\u00edzos para o contratante e colaboradores informamos que n\u00e3o iremos conseguir honrar nossos compromissos adotando para tanto as medidas emergenciais necess\u00e1rias. Diante do exposto, requeremos a rescis\u00e3o amig\u00e1vel do contrato na forma de praxe\u201d, informou em of\u00edcio a Masterserv Servi\u00e7os Avan\u00e7ados Eireli, respons\u00e1vel pela terceiriza\u00e7\u00e3o.<\/p>\n<p>A empresa prop\u00f5e que o cr\u00e9dito das notas de novembro de 2023, ainda n\u00e3o liquidadas, seja repassado diretamente em favor dos funcion\u00e1rios. E encerra pedindo a aplica\u00e7\u00e3o da menor penalidade em desfavor da empresa.<\/p>\n<p>A empresa tem sede em S\u00e3o Paulo e o propriet\u00e1rio, Leone Lafaiete Carlin, informou por e-mail que ele tem total empatia pelo momento vivido por seus colaboradores. \u201cN\u00e3o houve nenhuma rescis\u00e3o de contrato, desta forma esperamos manifesta\u00e7\u00e3o do \u00f3rg\u00e3o quanto aos pedidos. Eu tentei de v\u00e1rias formas manter a regularidade da empresa, contudo meus colaboradores dificultaram muito a continuidade do servi\u00e7o, certo que a lei e pro colaborador, contudo n\u00e3o houve qualquer tipo de negocia\u00e7\u00e3o com esta empresa no sentido de mantermos os postos [sic]\u201d, explicou em e-mail.<\/p>\n<figure id=\"attachment_367469\" aria-describedby=\"caption-attachment-367469\" style=\"width: 968px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" decoding=\"async\" alt=\"\" width=\"968\" height=\"645\" srcset=\"https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2023\/12\/00-15-dez-2023-terceirizada-usp-calote-02-foto-alfredo-risk-scaled.jpg 968w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2023\/12\/00-15-dez-2023-terceirizada-usp-calote-02-foto-alfredo-risk-300x200.jpg 300w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2023\/12\/00-15-dez-2023-terceirizada-usp-calote-02-foto-alfredo-risk-1024x682.jpg 1024w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2023\/12\/00-15-dez-2023-terceirizada-usp-calote-02-foto-alfredo-risk-768x512.jpg 768w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2023\/12\/00-15-dez-2023-terceirizada-usp-calote-02-foto-alfredo-risk-1536x1023.jpg 1536w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2023\/12\/00-15-dez-2023-terceirizada-usp-calote-02-foto-alfredo-risk-480x320.jpg 480w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2023\/12\/00-15-dez-2023-terceirizada-usp-calote-02-foto-alfredo-risk-280x186.jpg 280w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2023\/12\/00-15-dez-2023-terceirizada-usp-calote-02-foto-alfredo-risk-960x640.jpg 960w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2023\/12\/00-15-dez-2023-terceirizada-usp-calote-02-foto-alfredo-risk-600x400.jpg 600w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2023\/12\/00-15-dez-2023-terceirizada-usp-calote-02-foto-alfredo-risk-585x390.jpg 585w\" src=\"https:\/\/i0.wp.com\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2023\/12\/00-15-dez-2023-terceirizada-usp-calote-02-foto-alfredo-risk-scaled.jpg?resize=968%2C645&#038;ssl=1\" data-sizes=\"(max-width: 968px) 100vw, 968px\" class=\"size-full wp-image-367469 lazyload\"\/><noscript><img data-recalc-dims=\"1\" decoding=\"async\" class=\"size-full wp-image-367469\" src=\"https:\/\/i0.wp.com\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2023\/12\/00-15-dez-2023-terceirizada-usp-calote-02-foto-alfredo-risk-scaled.jpg?resize=968%2C645&#038;ssl=1\" alt=\"\" width=\"968\" height=\"645\" srcset=\"https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2023\/12\/00-15-dez-2023-terceirizada-usp-calote-02-foto-alfredo-risk-scaled.jpg 968w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2023\/12\/00-15-dez-2023-terceirizada-usp-calote-02-foto-alfredo-risk-300x200.jpg 300w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2023\/12\/00-15-dez-2023-terceirizada-usp-calote-02-foto-alfredo-risk-1024x682.jpg 1024w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2023\/12\/00-15-dez-2023-terceirizada-usp-calote-02-foto-alfredo-risk-768x512.jpg 768w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2023\/12\/00-15-dez-2023-terceirizada-usp-calote-02-foto-alfredo-risk-1536x1023.jpg 1536w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2023\/12\/00-15-dez-2023-terceirizada-usp-calote-02-foto-alfredo-risk-480x320.jpg 480w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2023\/12\/00-15-dez-2023-terceirizada-usp-calote-02-foto-alfredo-risk-280x186.jpg 280w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2023\/12\/00-15-dez-2023-terceirizada-usp-calote-02-foto-alfredo-risk-960x640.jpg 960w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2023\/12\/00-15-dez-2023-terceirizada-usp-calote-02-foto-alfredo-risk-600x400.jpg 600w, https:\/\/www.tribunaribeirao.com.br\/site\/wp-content\/uploads\/2023\/12\/00-15-dez-2023-terceirizada-usp-calote-02-foto-alfredo-risk-585x390.jpg 585w\" sizes=\"(max-width: 968px) 100vw, 968px\"\/><\/noscript><figcaption id=\"caption-attachment-367469\" class=\"wp-caption-text\">Campus da USP de Ribeir\u00e3o Preto informou que est\u00e1 tratando do assunto com urg\u00eancia e vai solicitar autoriza\u00e7\u00e3o para pagar funcion\u00e1rios diretamente, por ter quest\u00f5es sociais envolvidas (Foto: Alfredo Risk)<\/figcaption><\/figure>\n<p><span style=\"color: #008000\"><em><strong>Nota oficial<\/strong><\/em><\/span><\/p>\n<p>A assessoria de comunica\u00e7\u00e3o do Campus da USP Ribeir\u00e3o Preto divulgou nota a respeito do problema. Leia na \u00edntegra, a seguir.<\/p>\n<p><em>\u201cNo \u00faltimo dia 14 de dezembro de 2023, a Masterserv Servi\u00e7os Avan\u00e7ados Eireli, empresa respons\u00e1vel pelos servi\u00e7os de controle, opera\u00e7\u00e3o e fiscaliza\u00e7\u00e3o das portarias dos edif\u00edcios localizados no Campus da USP em Ribeir\u00e3o Preto, solicitou \u00e0 Universidade a rescis\u00e3o de seu contrato de presta\u00e7\u00e3o de servi\u00e7os vigente, alegando dificuldades financeiras.\u201d<\/em><\/p>\n<p><em>\u201cAp\u00f3s o recebimento da notifica\u00e7\u00e3o, a Prefeitura do Campus de Ribeir\u00e3o Preto imediatamente deu in\u00edcio aos procedimentos legais necess\u00e1rios para encerrar o contrato e, considerando a relev\u00e2ncia das quest\u00f5es sociais envolvidas nesse processo, solicitar a autoriza\u00e7\u00e3o dos \u00f3rg\u00e3os centrais da Universidade para efetuar o pagamento direto aos funcion\u00e1rios da Masterserv, limitado aos valores referentes \u00e0s faturas pendentes de novembro de 2023, as quais est\u00e3o retidas.\u201d<\/em><\/p>\n<p><em>\u201cNo que se refere aos servi\u00e7os de opera\u00e7\u00e3o e fiscaliza\u00e7\u00e3o das portarias dos edif\u00edcios no Campus local, a Prefeitura busca a melhor e mais r\u00e1pida solu\u00e7\u00e3o na presta\u00e7\u00e3o desses servi\u00e7os, visando a minimiza\u00e7\u00e3o dos transtornos aos usu\u00e1rios, mantendo a qualidade e a efici\u00eancia esperadas\u201d<\/em>, conclui a nota.<\/p>\n<\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/site\/prestadora-da-usp-nao-paga-13o-dos-funcionarios-e-pede-rescisao-amigavel\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Empresa alegou dificuldades financeiras e n\u00e3o saldou benef\u00edcios de funcion\u00e1rios que prestam servi\u00e7os de fiscaliza\u00e7\u00e3o das portarias de edif\u00edcios no Campus da universidade 15 de dezembro de 2023 | 16:5115 de dezembro de 2023 | 16:53 2 Por: Adalberto Luque Os funcion\u00e1rios de uma empresa terceirizada, que presta servi\u00e7o de portaria em v\u00e1rios edif\u00edcios &#8230; <a title=\"Prestadora da USP n\u00e3o paga 13\u00ba dos funcion\u00e1rios e pede rescis\u00e3o amig\u00e1vel\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/15\/prestadora-da-usp-nao-paga-13o-dos-funcionarios-e-pede-rescisao-amigavel\/\" aria-label=\"Leia mais sobre Prestadora da USP n\u00e3o paga 13\u00ba dos funcion\u00e1rios e pede rescis\u00e3o amig\u00e1vel\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":16597,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[2243,2246,470,2244,678,2242,21,2241,2245,872],"class_list":["post-16596","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-13o","tag-amigavel","tag-dos","tag-funcionarios","tag-nao","tag-paga","tag-pede","tag-prestadora","tag-rescisao","tag-usp"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/00-15-dez-2023-terceirizada-usp-calote-01-foto-alfredo-risk-scaled.jpg?fit=968%2C645&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/00-15-dez-2023-terceirizada-usp-calote-01-foto-alfredo-risk-scaled.jpg?fit=968%2C645&ssl=1",968,645,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/00-15-dez-2023-terceirizada-usp-calote-01-foto-alfredo-risk-scaled.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/00-15-dez-2023-terceirizada-usp-calote-01-foto-alfredo-risk-scaled.jpg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/00-15-dez-2023-terceirizada-usp-calote-01-foto-alfredo-risk-scaled.jpg?fit=768%2C512&ssl=1",768,512,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/00-15-dez-2023-terceirizada-usp-calote-01-foto-alfredo-risk-scaled.jpg?fit=968%2C645&ssl=1",968,645,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/00-15-dez-2023-terceirizada-usp-calote-01-foto-alfredo-risk-scaled.jpg?fit=968%2C645&ssl=1",968,645,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/00-15-dez-2023-terceirizada-usp-calote-01-foto-alfredo-risk-scaled.jpg?fit=968%2C645&ssl=1",968,645,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Empresa alegou dificuldades financeiras e n\u00e3o saldou benef\u00edcios de funcion\u00e1rios que prestam servi\u00e7os de fiscaliza\u00e7\u00e3o das portarias de edif\u00edcios no Campus da universidade 15 de dezembro de 2023 | 16:5115 de dezembro de 2023 | 16:53 2 Por: Adalberto Luque Os funcion\u00e1rios de uma empresa terceirizada, que presta servi\u00e7o de portaria em v\u00e1rios edif\u00edcios&hellip;","jetpack-related-posts":[{"id":52992,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/12\/posso-pedir-demissao-nas-ferias-entenda-o-que-diz-a-lei\/","url_meta":{"origin":16596,"position":0},"title":"Posso pedir demiss\u00e3o nas f\u00e9rias? Entenda o que diz a lei","author":"ismaelcolosi.com.br","date":"12 de Junho de 2024","format":false,"excerpt":"[ad_1] A decis\u00e3o de pedir demiss\u00e3o deve ser feita com planejamento e organiza\u00e7\u00e3o para que o funcion\u00e1rio n\u00e3o saia prejudicado. Para isso, deve ser feito da maneira mais adequada poss\u00edvel, conhecendo os seus direitos e o que a legisla\u00e7\u00e3o trabalhista determina sobre o assunto. Ent\u00e3o, o funcion\u00e1rio pode\u00a0pedir demiss\u00e3o\u00a0durante as\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Posso-pedir-demissao-nas-ferias-.png?fit=1200%2C627&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Posso-pedir-demissao-nas-ferias-.png?fit=1200%2C627&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Posso-pedir-demissao-nas-ferias-.png?fit=1200%2C627&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Posso-pedir-demissao-nas-ferias-.png?fit=1200%2C627&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Posso-pedir-demissao-nas-ferias-.png?fit=1200%2C627&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":55751,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/05\/pedir-demissao-na-experiencia-paga-multa-entenda-a-lei\/","url_meta":{"origin":16596,"position":1},"title":"Pedir demiss\u00e3o na experi\u00eancia paga multa? Entenda a lei","author":"ismaelcolosi.com.br","date":"5 de Julho de 2024","format":false,"excerpt":"[ad_1] Quando nos perguntamos se pedir demiss\u00e3o na experi\u00eancia paga multa, a resposta \u00e9 \u201cdepende\u201d. O per\u00edodo de adapta\u00e7\u00e3o \u00e9 crucial para voc\u00ea entender se voc\u00ea se encaixa na fun\u00e7\u00e3o e combina com a cultura organizacional da empresa. Em alguns casos, tamb\u00e9m serve para voc\u00ea entender que aquela n\u00e3o \u00e9\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Pedir-demissao-na-experiencia-paga-multa.png?fit=1200%2C627&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Pedir-demissao-na-experiencia-paga-multa.png?fit=1200%2C627&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Pedir-demissao-na-experiencia-paga-multa.png?fit=1200%2C627&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Pedir-demissao-na-experiencia-paga-multa.png?fit=1200%2C627&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Pedir-demissao-na-experiencia-paga-multa.png?fit=1200%2C627&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":11154,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/05\/deficit-ameaca-272-dos-municipios\/","url_meta":{"origin":16596,"position":2},"title":"D\u00e9ficit amea\u00e7a 27,2% dos munic\u00edpios \u00a0","author":"ismaelcolosi.com.br","date":"5 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Mais de 28,6% das prefeituras brasileiras afirmaram que atrasariam o pagamento da primeira parcela do d\u00e9cimo terceiro sal\u00e1rio aos funcion\u00e1rios, que deveria ocorrer at\u00e9 a \u00faltima quinta-feira, 30 de novembro. Isso representa 1.246 administra\u00e7\u00f5es municipais que participaram da pesquisa da Confedera\u00e7\u00e3o Nacional de Munic\u00edpios (CNM). O tradicional estudo elaborado\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/ContasCNM-Marcelo-Camargo-Ag.Br_-scaled.jpg?fit=968%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/ContasCNM-Marcelo-Camargo-Ag.Br_-scaled.jpg?fit=968%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/ContasCNM-Marcelo-Camargo-Ag.Br_-scaled.jpg?fit=968%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/ContasCNM-Marcelo-Camargo-Ag.Br_-scaled.jpg?fit=968%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":60889,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/19\/quer-estudar-na-usp-ribeirao-preto-inscricoes-da-fuvest-comecam-hoje\/","url_meta":{"origin":16596,"position":3},"title":"Quer estudar na USP Ribeir\u00e3o Preto? Inscri\u00e7\u00f5es da Fuvest come\u00e7am hoje","author":"ismaelcolosi.com.br","date":"19 de Agosto de 2024","format":false,"excerpt":"[ad_1] Come\u00e7am \u00e0s 12h desta segunda-feira (19) as inscri\u00e7\u00f5es para Fuvest, vestibular que d\u00e1 acesso \u00e0 USP (Universidade de S\u00e3o Paulo). Ao todo, s\u00e3o 8.147 vagas disponibilizadas no vestibular, sendo 4.888 de ampla concorr\u00eancia, 2.053 reservadas para estudantes de escolas p\u00fablicas e 1.206 vagas para estudantes de escolas p\u00fablicas PPI\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/20170216_00_campus_ribeirao1.webp.webp?fit=800%2C420&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/20170216_00_campus_ribeirao1.webp.webp?fit=800%2C420&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/20170216_00_campus_ribeirao1.webp.webp?fit=800%2C420&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/20170216_00_campus_ribeirao1.webp.webp?fit=800%2C420&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":37569,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/16\/nike-cortara-2-da-forca-de-trabalho-para-reduzir-custos\/","url_meta":{"origin":16596,"position":4},"title":"Nike cortar\u00e1 2% da for\u00e7a de trabalho para reduzir custos","author":"ismaelcolosi.com.br","date":"16 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] Floren\u00e7a Lo\/ReutersA Nike tinha cerca de 83.700 funcion\u00e1rios at\u00e9 31 de maio de 2023 A Nike cortar\u00e1 cerca de 2% de sua for\u00e7a de trabalho total, ou mais de 1.600 empregos, disse a gigante do vestu\u00e1rio esportivo na noite de quinta-feira (15), visando reduzir despesas \u00e0 medida que a\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Carreira_Nike-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Carreira_Nike-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Carreira_Nike-1024x683.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Carreira_Nike-1024x683.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":18044,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/19\/concessionaria-conclui-passarela-em-bonfim\/","url_meta":{"origin":16596,"position":5},"title":"Concession\u00e1ria conclui passarela em Bonfim","author":"ismaelcolosi.com.br","date":"19 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Dispositivo foi constru\u00eddo sobre rodovia que liga Ribeir\u00e3o Preto ao distrito e consumiu R$ 1,8 milh\u00e3o 19 de dezembro de 2023 | 16:01 2Por: Adalberto LuqueA passarela de pedestres, constru\u00edda na Rodovia Jos\u00e9 Fregonesi (SP-328), entre Ribeir\u00e3o Preto e o distrito de Bonfim Paulista, foi conclu\u00edda e liberada nesta\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/00-19-dez-2023-passarela-bonfim-01-foto-arteris-scaled.jpg?fit=1000%2C563&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/00-19-dez-2023-passarela-bonfim-01-foto-arteris-scaled.jpg?fit=1000%2C563&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/00-19-dez-2023-passarela-bonfim-01-foto-arteris-scaled.jpg?fit=1000%2C563&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/00-19-dez-2023-passarela-bonfim-01-foto-arteris-scaled.jpg?fit=1000%2C563&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-4jG","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=16596"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16596\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/16597"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=16596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=16596"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=16596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}