{"id":15594,"date":"2023-12-13T23:03:17","date_gmt":"2023-12-14T02:03:17","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/13\/homem-e-preso-transportando-k-9-em-rodovia-na-regiao-de-ribeirao\/"},"modified":"2023-12-13T23:03:17","modified_gmt":"2023-12-14T02:03:17","slug":"homem-e-preso-transportando-k-9-em-rodovia-na-regiao-de-ribeirao","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/13\/homem-e-preso-transportando-k-9-em-rodovia-na-regiao-de-ribeirao\/","title":{"rendered":"Homem \u00e9 preso transportando K-9 em rodovia na regi\u00e3o de Ribeir\u00e3o"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>Um homem foi preso na \u00faltima ter\u00e7a-feira (12), na Rodovia At\u00edlio Balbo, pr\u00f3ximo a <strong>Sert\u00e3ozinho<\/strong>, cidade na regi\u00e3o de <strong>Ribeir\u00e3o Preto<\/strong>, transportando um quilo da droga <strong>K-9<\/strong>.<\/p>\n<p><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">O consumo da subst\u00e2ncia vem crescendo no <strong>Brasil <\/strong>e ficou conhecida por \u201c<strong>transformar os usu\u00e1rios em zumbis<\/strong>\u201d.<\/mark><\/p>\n<p>De acordo com o sargento da <strong>Pol\u00edcia Rodovi\u00e1ria<\/strong> Ricardo Alexandre Malavolta, a droga foi localizada durante uma <strong>abordagem de rotina<\/strong>, pr\u00f3ximo ao ped\u00e1gio da cidade. Ainda segundo o sargento,<strong> essa seria a primeira apreens\u00e3o do entorpecente na regi\u00e3o<\/strong>.<\/p>\n<blockquote class=\"wp-block-quote\">\n<p class=\"has-text-align-left\">\u201cA respeito do nervosismo do motorista e da passageira, na revista veicular, foi localizado quatro pacotes da K9. Essa droga estava em baixo do banco do motorista. Foi localizado [a droga] e dado voz de pris\u00e3o ao condutor\u201d, disse Malavolta, em entrevista a <em>EPTV<\/em>.<\/p>\n<\/blockquote>\n<p>O condutor do ve\u00edculo chegou a confessar para a pol\u00edcia, que receberia <strong>R$ 1 mil <\/strong>para pegar a droga e levar para <strong>Jaboticabal<\/strong>, na regi\u00e3o de <strong>Ribeir\u00e3o Preto<\/strong>. <\/p>\n<p>Tamb\u00e9m foram encontrados R$ 123 em dinheiro, R$ 240 em cheques e dois celulares. As duas pessoas envolvidas foram levadas para a<strong> CPJ<\/strong> (Central de Pol\u00edcia Judici\u00e1ria). <strong>O homem foi preso em flagrante e encaminhado para a cadeia de Prad\u00f3polis.<\/strong><\/p>\n<h4 class=\"wp-block-heading\"><strong>O que a droga causa no organismo?<\/strong><\/h4>\n<p>A chegada da droga na regi\u00e3o chamou a aten\u00e7\u00e3o das autoridades de sa\u00fade. A<strong> K-9<\/strong> \u00e9 uma subst\u00e2ncia sint\u00e9tica que possui efeitos parecidos com o da maconha, contudo, em <strong><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">uma propor\u00e7\u00e3o muito mais potente, capaz de levar o usu\u00e1rio a morte.<\/mark><\/strong><\/p>\n<p>\u201cEla \u00e9 uma droga nova. Ela \u00e9 sintetizada em laborat\u00f3rio, ent\u00e3o ela tem uma estrutura qu\u00edmica bem definida. Ela n\u00e3o \u00e9 uma mistura de compostos, como por exemplo, a maconha, que \u00e9 uma planta e possui diversos compostos juntos\u201d, explicou Daniel Junqueira Dorta, professor de Qu\u00edmica da <strong>USP (Universidade de S\u00e3o Paulo)<\/strong> de <strong>Ribeir\u00e3o Preto<\/strong>.<\/p>\n<p>Ainda de acordo com Daniel, o entorpecente tem efeito muito potente e r\u00e1pido no organismo de quem utiliza.<\/p>\n<p>\u201cEla causa uma depend\u00eancia muito severa e muito r\u00e1pida no organismo e pode ter diversos efeitos muito graves, desde uma paranoia, uma ansiedade, alucina\u00e7\u00f5es. At\u00e9 efeitos mais graves, como uma fal\u00eancia renal e em \u00faltimos casos, a morte\u201d. <em>(com informa\u00e7\u00f5es da EPTV)<\/em><\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Quatro pessoas s\u00e3o presas suspeitas de furtarem R$ 50 mil em roupas de shopping da zona Sul de Ribeir\u00e3o<\/p>\n<h4 class=\"wp-block-heading\"><strong><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">FIQUE ON \u00a0<\/mark><\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do<strong>\u00a0acidade on<\/strong>\u00a0no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram\u00a0<\/a>e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook.<\/a><\/p>\n<p>Receba not\u00edcias do\u00a0<strong>acidade on\u00a0<\/strong>no WhatsApp.\u00a0<a href=\"https:\/\/chat.whatsapp.com\/Bnv2w66ZT4VDyZW3oiZ69n\" target=\"_blank\" rel=\"noreferrer noopener\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp:\u00a0<strong>16 99117 7802.<\/strong><\/p>\n<p>LEIA MAIS<\/p>\n<p><a href=\"https:\/\/www.tudoep.com\/tudo-noticias\/tudo-noticias\/brasil-e-mundo\/NOT,0,0,1868725,janeiro-de-2024-tera-onda-de-calor.aspx\" target=\"_blank\" rel=\"noreferrer noopener\">Janeiro de 2024 ter\u00e1 onda de calor?<\/a><\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/homem-e-preso-transportando-k-9-em-rodovia-na-regiao-de-ribeirao\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Um homem foi preso na \u00faltima ter\u00e7a-feira (12), na Rodovia At\u00edlio Balbo, pr\u00f3ximo a Sert\u00e3ozinho, cidade na regi\u00e3o de Ribeir\u00e3o Preto, transportando um quilo da droga K-9. O consumo da subst\u00e2ncia vem crescendo no Brasil e ficou conhecida por \u201ctransformar os usu\u00e1rios em zumbis\u201d. De acordo com o sargento da Pol\u00edcia Rodovi\u00e1ria Ricardo Alexandre &#8230; <a title=\"Homem \u00e9 preso transportando K-9 em rodovia na regi\u00e3o de Ribeir\u00e3o\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/13\/homem-e-preso-transportando-k-9-em-rodovia-na-regiao-de-ribeirao\/\" aria-label=\"Leia mais sobre Homem \u00e9 preso transportando K-9 em rodovia na regi\u00e3o de Ribeir\u00e3o\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":15595,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[59,36,277,26,80,2135],"class_list":["post-15594","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-homem","tag-preso","tag-regiao","tag-ribeirao","tag-rodovia","tag-transportando"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23.png?fit=1200%2C675&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23.png?fit=1200%2C675&ssl=1",1200,675,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23.png?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23.png?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23.png?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23.png?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23.png?fit=1200%2C675&ssl=1",1200,675,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-23.png?fit=1200%2C675&ssl=1",1200,675,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Um homem foi preso na \u00faltima ter\u00e7a-feira (12), na Rodovia At\u00edlio Balbo, pr\u00f3ximo a Sert\u00e3ozinho, cidade na regi\u00e3o de Ribeir\u00e3o Preto, transportando um quilo da droga K-9. O consumo da subst\u00e2ncia vem crescendo no Brasil e ficou conhecida por \u201ctransformar os usu\u00e1rios em zumbis\u201d. De acordo com o sargento da Pol\u00edcia Rodovi\u00e1ria Ricardo Alexandre&hellip;","jetpack-related-posts":[{"id":41746,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/11\/motorista-e-preso-por-trafico-no-anel-viario-sul\/","url_meta":{"origin":15594,"position":0},"title":"Motorista \u00e9 preso por tr\u00e1fico no Anel Vi\u00e1rio Sul","author":"ismaelcolosi.com.br","date":"11 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] Condutor teria tentado fugir de viatura, mas acabou surpreendido com mais de mil por\u00e7\u00f5es de coca\u00edna 11 de mar\u00e7o de 2024 | 7:1110 de mar\u00e7o de 2024 | 21:32 1Um homem foi preso, na noite deste s\u00e1bado (9), por tr\u00e1fico de drogas. Ele foi detido ap\u00f3s uma persegui\u00e7\u00e3o na\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-traficante-preso-foto-pmrv.jpg?fit=598%2C596&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-traficante-preso-foto-pmrv.jpg?fit=598%2C596&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-11-mar-2024-traficante-preso-foto-pmrv.jpg?fit=598%2C596&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":43972,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/25\/grupo-e-preso-transportando-cocaina-em-compartimento-de-caminhonete\/","url_meta":{"origin":15594,"position":1},"title":"Grupo \u00e9 preso transportando coca\u00edna em compartimento de caminhonete","author":"ismaelcolosi.com.br","date":"25 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] Fundo falso foi localizado com apoio de c\u00e3o de faro; um homem e tr\u00eas mulheres foram presos e encaminhados \u00e0 PF 25 de mar\u00e7o de 2024 | 7:1124 de mar\u00e7o de 2024 | 20:07 1 Por: Adalberto Luque Um grupo de quatro pessoas foi preso neste domingo (24) por\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-25-mar-2024-apreensao-maconha-01-foto-baep.jpg?fit=1200%2C822&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-25-mar-2024-apreensao-maconha-01-foto-baep.jpg?fit=1200%2C822&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-25-mar-2024-apreensao-maconha-01-foto-baep.jpg?fit=1200%2C822&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-25-mar-2024-apreensao-maconha-01-foto-baep.jpg?fit=1200%2C822&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-25-mar-2024-apreensao-maconha-01-foto-baep.jpg?fit=1200%2C822&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":15223,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/13\/homem-e-preso-em-rodovia-com-droga-zumbi\/","url_meta":{"origin":15594,"position":2},"title":"Homem \u00e9 preso em rodovia com \u201cdroga zumbi\u201d","author":"ismaelcolosi.com.br","date":"13 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Suspeito transportava quatro pacotes com droga potente quando foi abordado 13 de dezembro de 2023 | 9:22 0Por: Adalberto LuqueUm homem foi preso, na noite desta ter\u00e7a-feira (12), ao ser flagrado transportando a subst\u00e2ncia K9, tamb\u00e9m conhecida por \u201cdroga zumbi\u201d, pelo efeito devastador que causa aos usu\u00e1rios. Ele seguia\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/00-13-dez-2023-apreensao-pedagio-01-foto-pmrv-scaled.jpg?fit=1000%2C562&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/00-13-dez-2023-apreensao-pedagio-01-foto-pmrv-scaled.jpg?fit=1000%2C562&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/00-13-dez-2023-apreensao-pedagio-01-foto-pmrv-scaled.jpg?fit=1000%2C562&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/00-13-dez-2023-apreensao-pedagio-01-foto-pmrv-scaled.jpg?fit=1000%2C562&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":35081,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/05\/menor-e-preso-com-drogas-na-zona-leste\/","url_meta":{"origin":15594,"position":3},"title":"Menor \u00e9 preso com drogas na zona Leste","author":"ismaelcolosi.com.br","date":"5 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] Jovem estava vendendo entorpecentes e foi surpreendido por agentes da GCM 5 de fevereiro de 2024 | 9:06 2Por: Adalberto LuqueUm adolescente foi apreendido, na manh\u00e3 deste domingo (04). Foi flagrado vendendo drogas na R. Benedito Jacinto de Souza, pr\u00f3xima ao Centro de Esportes Unificado (CEU) das Artes, no\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/00-05-fev-2024-gcm-00-foto-divulgacao-scaled.jpg?fit=586%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/00-05-fev-2024-gcm-00-foto-divulgacao-scaled.jpg?fit=586%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/00-05-fev-2024-gcm-00-foto-divulgacao-scaled.jpg?fit=586%2C645&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":32047,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/24\/policia-prende-um-dos-grandes-do-trafico-em-rp\/","url_meta":{"origin":15594,"position":4},"title":"Pol\u00edcia prende um dos grandes do tr\u00e1fico em RP","author":"ismaelcolosi.com.br","date":"24 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Homem foi detido com comparsa durante a\u00e7\u00e3o onde centenas de pinos de coca\u00edna e tijolos de maconha foram apreendidos 23 de janeiro de 2024 | 15:4823 de janeiro de 2024 | 17:24 2Por: Adalberto LuqueDois homens foram presos, na manh\u00e3 desta ter\u00e7a-feira (23), ap\u00f3s uma opera\u00e7\u00e3o realizada pela Delegacia\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/00-23-jan-2024-prisao-dise-01-foto-divulgacao.jpg?fit=756%2C422&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/00-23-jan-2024-prisao-dise-01-foto-divulgacao.jpg?fit=756%2C422&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/00-23-jan-2024-prisao-dise-01-foto-divulgacao.jpg?fit=756%2C422&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/00-23-jan-2024-prisao-dise-01-foto-divulgacao.jpg?fit=756%2C422&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":36322,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/09\/k-9-localiza-droga-enterrada-em-terreno-da-zona-norte\/","url_meta":{"origin":15594,"position":5},"title":"K-9 localiza droga enterrada em terreno da zona Norte","author":"ismaelcolosi.com.br","date":"9 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] Tonel escondia tijolos de maconha e centenas de por\u00e7\u00f5es de drogas 9 de fevereiro de 2024 | 9:05 0Por: Adalberto LuqueA fuga de um homem levou equipes da Guarda Civil Metropolitana (GCM) de Ribeir\u00e3o Preto a encontrarem uma grande quantidade de drogas, na tarde desta quinta-feira (08). Os entorpecentes\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/00-09-fev-2024-apreensao-gcm-01-foto-max-gallao-mesquita-scaled.jpg?fit=1000%2C562&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/00-09-fev-2024-apreensao-gcm-01-foto-max-gallao-mesquita-scaled.jpg?fit=1000%2C562&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/00-09-fev-2024-apreensao-gcm-01-foto-max-gallao-mesquita-scaled.jpg?fit=1000%2C562&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/00-09-fev-2024-apreensao-gcm-01-foto-max-gallao-mesquita-scaled.jpg?fit=1000%2C562&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-43w","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/15594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=15594"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/15594\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/15595"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=15594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=15594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=15594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}