{"id":15102,"date":"2023-12-13T02:41:49","date_gmt":"2023-12-13T05:41:49","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/13\/inscricoes-para-fatec-vao-ate-segunda-feira\/"},"modified":"2023-12-13T02:41:49","modified_gmt":"2023-12-13T05:41:49","slug":"inscricoes-para-fatec-vao-ate-segunda-feira","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/13\/inscricoes-para-fatec-vao-ate-segunda-feira\/","title":{"rendered":"Inscri\u00e7\u00f5es para Fatec v\u00e3o at\u00e9 segunda-feira\u00a0"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"post-366982\">\n<header class=\"entry-header penci-entry-header penci-title-center\">\n<p> <span class=\"entry-meta-item penci-posted-on\"><i class=\"fa fa-clock-o\"\/><time class=\"entry-date published\" datetime=\"2023-12-12T16:00:11-03:00\">12 de dezembro de 2023 | 16:00<\/time><time class=\"updated\" datetime=\"2023-12-12T09:48:44-03:00\">12 de dezembro de 2023 | 9:48<\/time><\/span><\/p>\n<p> <span class=\"penci-social-buttons penci-social-share-footer\"><a href=\"#\" class=\"penci-post-like penci_post-meta_item  single-like-button penci-social-item like\" data-post_id=\"366982\" title=\"Like\" data-like=\"Like\" data-unlike=\"Unlike\"><i class=\"fa fa-thumbs-o-up\"\/><span class=\"penci-share-number\">0<\/span><\/a><i class=\"fa fa-facebook\"\/><a class=\"penci-social-item twitter\" target=\"_blank\" rel=\"noopener\" title=\"\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Inscri\u00e7\u00f5es%20para%20Fatec%20v\u00e3o%20at\u00e9%20segunda-feira\u00a0%20-%20https:\/\/www.tribunaribeirao.com.br\/site\/inscricoes-para-fatec-vao-ate-segunda-feira\/\"><i class=\"fa fa-twitter\"\/><\/a><i class=\"fa fa-whatsapp\"\/><\/span><\/header>\n<div class=\"penci-entry-content entry-content\">\n<p><span class=\"TextRun SCXW248019745 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW248019745 BCX0\">As inscri\u00e7\u00f5es para o processo seletivo das Faculdades de Tecnologia (<\/span><span class=\"NormalTextRun SCXW248019745 BCX0\">Fatecs<\/span><span class=\"NormalTextRun SCXW248019745 BCX0\">) do Estado de S\u00e3o Paulo foram prorrogadas at\u00e9 a pr\u00f3xima <\/span><span class=\"NormalTextRun SCXW248019745 BCX0\">segunda-feir<\/span><span class=\"NormalTextRun SCXW248019745 BCX0\">a,<\/span><span class=\"NormalTextRun SCXW248019745 BCX0\">18 de dezembro,<\/span><span class=\"NormalTextRun SCXW248019745 BCX0\"> e devem ser feitas, exclusivamente, pelo site www.vestibularfatec.com.br. No \u00faltimo dia, o prazo encerra-se \u00e0s 15 horas. <\/span><span class=\"NormalTextRun SCXW248019745 BCX0\">O valor da taxa \u00e9 de R$ 84.<\/span><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW248019745 BCX0\"><span class=\"SCXW248019745 BCX0\">\u00a0<\/span><br class=\"SCXW248019745 BCX0\"\/><\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW248019745 BCX0\"><span class=\"SCXW248019745 BCX0\">\u00a0<\/span><br class=\"SCXW248019745 BCX0\"\/><\/span><span class=\"TextRun SCXW248019745 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW248019745 BCX0\">A prova ser\u00e1 aplicada <\/span><span class=\"NormalTextRun SCXW248019745 BCX0\">em <\/span><span class=\"NormalTextRun SCXW248019745 BCX0\">7<\/span><span class=\"NormalTextRun SCXW248019745 BCX0\"> de janeiro de 2024.<\/span> <span class=\"NormalTextRun SCXW248019745 BCX0\">Para o primeiro semestre do pr\u00f3ximo ano, as <\/span><span class=\"NormalTextRun SCXW248019745 BCX0\">Fatecs<\/span><span class=\"NormalTextRun SCXW248019745 BCX0\"> oferecem 19.445 vagas para as unidades de todo o Estado de S\u00e3o Paulo. Deste total, 14.581 s\u00e3o destinadas ao <\/span><span class=\"NormalTextRun SCXW248019745 BCX0\">v<\/span><span class=\"NormalTextRun SCXW248019745 BCX0\">estibular e 4.864 vagas ao Prov\u00e3o Paulista Seriado.<\/span> <\/span><span class=\"LineBreakBlob BlobObject DragDrop SCXW248019745 BCX0\"><span class=\"SCXW248019745 BCX0\">\u00a0<\/span><br class=\"SCXW248019745 BCX0\"\/><\/span><\/p>\n<\/div>\n<footer class=\"penci-entry-footer\"\/><\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/site\/inscricoes-para-fatec-vao-ate-segunda-feira\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] 12 de dezembro de 2023 | 16:0012 de dezembro de 2023 | 9:48 0 As inscri\u00e7\u00f5es para o processo seletivo das Faculdades de Tecnologia (Fatecs) do Estado de S\u00e3o Paulo foram prorrogadas at\u00e9 a pr\u00f3xima segunda-feira,18 de dezembro, e devem ser feitas, exclusivamente, pelo site www.vestibularfatec.com.br. No \u00faltimo dia, o prazo encerra-se \u00e0s 15&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":15103,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[103,2064,566,71,208,1258],"class_list":["post-15102","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-ate","tag-fatec","tag-inscricoes","tag-para","tag-segundafeira","tag-vao"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/imagem-27.jpg?fit=675%2C450&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/imagem-27.jpg?fit=675%2C450&ssl=1",675,450,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/imagem-27.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/imagem-27.jpg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/imagem-27.jpg?fit=675%2C450&ssl=1",675,450,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/imagem-27.jpg?fit=675%2C450&ssl=1",675,450,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/imagem-27.jpg?fit=675%2C450&ssl=1",675,450,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/imagem-27.jpg?fit=675%2C450&ssl=1",675,450,true],"neve-blog":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/imagem-27.jpg?resize=675%2C450&ssl=1",675,450,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] 12 de dezembro de 2023 | 16:0012 de dezembro de 2023 | 9:48 0 As inscri\u00e7\u00f5es para o processo seletivo das Faculdades de Tecnologia (Fatecs) do Estado de S\u00e3o Paulo foram prorrogadas at\u00e9 a pr\u00f3xima segunda-feira,18 de dezembro, e devem ser feitas, exclusivamente, pelo site www.vestibularfatec.com.br. No \u00faltimo dia, o prazo encerra-se \u00e0s 15&hellip;&nbsp;","jetpack-related-posts":[{"id":10424,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/04\/fatec-itu-oferece-vagas-em-cursos-superiores-gratuitos\/","url_meta":{"origin":15102,"position":0},"title":"Fatec Itu oferece vagas em cursos superiores gratuitos","author":"ismaelcolosi.com.br","date":"4 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Com inscri\u00e7\u00f5es abertas at\u00e9 12 de dezembro, \u00e0s 15h, o vestibular \u00e9 uma oportunidade imperd\u00edvel para ingressar em uma das institui\u00e7\u00f5es de ensino de destaque na regi\u00e3o.Cr\u00e9ditos: Divulga\u00e7\u00e3oFatec Itu oferece vagas em cursos superiores gratuitosA Fatec oferece uma variedade de cursos superiores reconhecidos pela qualidade de ensino e pelo\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/cursos-gratuitos-fatec-itu.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/cursos-gratuitos-fatec-itu.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/cursos-gratuitos-fatec-itu.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/cursos-gratuitos-fatec-itu.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/cursos-gratuitos-fatec-itu.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":58245,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/29\/fatec-abre-processo-seletivo-para-faculdade-em-ribeirao-preto\/","url_meta":{"origin":15102,"position":1},"title":"Fatec abre processo seletivo para faculdade em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"29 de Julho de 2024","format":false,"excerpt":"[ad_1] A Fatec (Faculdade de Tecnologia) de Ribeir\u00e3o Preto est\u00e1 com inscri\u00e7\u00f5es abertas para o processo seletivo que contratar\u00e1 um auxiliar de docente para \u00e1rea de mec\u00e2nica. O sal\u00e1rio \u00e9 de R$ 2.964,87 para jornada de trabalho de 40h semanais. As inscri\u00e7\u00f5es podem ser feitas at\u00e9 o dia 7 de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-8_2024-07-29_18-10-00_jpg_2024-07-29_18-10-00.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-8_2024-07-29_18-10-00_jpg_2024-07-29_18-10-00.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-8_2024-07-29_18-10-00_jpg_2024-07-29_18-10-00.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-8_2024-07-29_18-10-00_jpg_2024-07-29_18-10-00.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-8_2024-07-29_18-10-00_jpg_2024-07-29_18-10-00.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":14294,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/11\/fatecs-oferecem-vagas-em-mais-de-90-cursos-gratuitos\/","url_meta":{"origin":15102,"position":2},"title":"Fatecs oferecem vagas em mais de 90 cursos gratuitos","author":"ismaelcolosi.com.br","date":"11 de Dezembro de 2023","format":false,"excerpt":"[ad_1] As inscri\u00e7\u00f5es para o processo seletivo das Faculdades de Tecnologia do Estado (Fatecs) est\u00e3o abertas at\u00e9 12 de dezembro. S\u00e3o, ao todo, 19.445 vagas em mais de 90 op\u00e7\u00f5es de cursos gratuitos na \u00e1rea de tecnologia. Desse total, 14.581 s\u00e3o destinadas ao Vestibular das Faculdades de Tecnologia e 4.864\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/fatec-scaled.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/fatec-scaled.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/fatec-scaled.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/fatec-scaled.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/fatec-scaled.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":770,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/09\/foram-prorrogadas-as-inscricoes-para-o-vestibulinho-das-etecs\/","url_meta":{"origin":15102,"position":3},"title":"Foram prorrogadas as inscri\u00e7\u00f5es para o vestibulinho das Etecs","author":"ismaelcolosi.com.br","date":"9 de Novembro de 2023","format":false,"excerpt":"[ad_1] 8 de novembro de 2023 | 18:008 de novembro de 2023 | 16:19 0No dia 10 de dezembro, candidatos fazem a prova do Vestibulinho das Escolas T\u00e9cnicas Estaduais (Etecs), que d\u00e1 acesso a mais de 91 mil vagas para ensino p\u00fablico gratuito. O interessado em aproveitar a oportunidade deve\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/1-etec-alfredo-risk-scaled.jpg?fit=1000%2C462&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/1-etec-alfredo-risk-scaled.jpg?fit=1000%2C462&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/1-etec-alfredo-risk-scaled.jpg?fit=1000%2C462&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/1-etec-alfredo-risk-scaled.jpg?fit=1000%2C462&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":55336,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/02\/prefeitura-no-interior-de-sp-reabre-inscricoes-para-concurso-publico-com-62-vagas\/","url_meta":{"origin":15102,"position":4},"title":"Prefeitura no interior de SP reabre inscri\u00e7\u00f5es para concurso p\u00fablico com 62 vagas","author":"ismaelcolosi.com.br","date":"2 de Julho de 2024","format":false,"excerpt":"[ad_1] A Prefeitura de Vista Alegre do Alto, no interior de S\u00e3o Paulo, reabriu as inscri\u00e7\u00f5es de concurso p\u00fablico com 62 vagas e sal\u00e1rios de at\u00e9 R$ 6 mil. As vagas s\u00e3o de n\u00edvel m\u00e9dio, t\u00e9cnico e superior. A inscri\u00e7\u00e3o deve ser realizada no per\u00edodo entre 10h do dia 12\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/prova-concurso-publico-3.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/prova-concurso-publico-3.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/prova-concurso-publico-3.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/prova-concurso-publico-3.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/prova-concurso-publico-3.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1628,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/13\/inscricoes-para-concurso-da-prefeitura-de-rp-comecam-hoje-dia-13\/","url_meta":{"origin":15102,"position":5},"title":"Inscri\u00e7\u00f5es para concurso da Prefeitura de RP come\u00e7am hoje, dia 13","author":"ismaelcolosi.com.br","date":"13 de Novembro de 2023","format":false,"excerpt":"[ad_1] 13 de novembro de 2023 | 14:0013 de novembro de 2023 | 11:30 0Come\u00e7a nesta segunda-feira, 13 de novembro, o per\u00edodo de inscri\u00e7\u00f5es para o concurso p\u00fablico da prefeitura de Ribeir\u00e3o Preto que oferece nove vagas em diferentes \u00e1reas de atua\u00e7\u00e3o. As oportunidades s\u00e3o para cirurgi\u00e3o dentista (2), educador\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/concurso-scaled.jpeg?fit=968%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/concurso-scaled.jpeg?fit=968%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/concurso-scaled.jpeg?fit=968%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/concurso-scaled.jpeg?fit=968%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-3VA","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/15102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=15102"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/15102\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/15103"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=15102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=15102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=15102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}