{"id":14900,"date":"2023-12-12T17:58:18","date_gmt":"2023-12-12T20:58:18","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/12\/motociclista-morre-apos-bater-em-carro-e-ser-atropelado-por-caminhonete-em-ribeirao\/"},"modified":"2023-12-12T17:58:18","modified_gmt":"2023-12-12T20:58:18","slug":"motociclista-morre-apos-bater-em-carro-e-ser-atropelado-por-caminhonete-em-ribeirao","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/12\/motociclista-morre-apos-bater-em-carro-e-ser-atropelado-por-caminhonete-em-ribeirao\/","title":{"rendered":"Motociclista morre ap\u00f3s bater em carro e ser atropelado por caminhonete em Ribeir\u00e3o"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_104\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p>Um <strong>motociclista morreu<\/strong>, na tarde desta ter\u00e7a-feira (12), ap\u00f3s se envolver em um acidente na avenida Alfredo Ravaneli, na zona Leste de <strong>Ribeir\u00e3o Preto<\/strong>.<\/p>\n<p>De acordo com a apura\u00e7\u00e3o da <em>EPTV<\/em>, o homem, de 35 anos, <mark style=\"background-color:#fcb900\" class=\"has-inline-color\">pilotava a moto quando bateu na traseira de um ve\u00edculo que seguia no mesmo sentido e se preparava pra fazer o retorno.<\/mark><\/p>\n<p>Com o impacto, o motociclista caiu e <strong>foi atropelado por uma caminhonete<\/strong> que tamb\u00e9m seguia pela avenida. <\/p>\n<p>Equipes do <strong>Samu <\/strong>e da <strong>Pol\u00edcia Militar<\/strong> foram acionadas, contudo, o motociclista morreu no local.<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do acidade on no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>.<\/p>\n<p>Receba not\u00edcias do acidade on no WhatsApp.\u00a0<a href=\"https:\/\/chat.whatsapp.com\/Bnv2w66ZT4VDyZW3oiZ69n\" target=\"_blank\" rel=\"noreferrer noopener\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre a Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: (16) 99117 7802.<\/p>\n<p>LEIA MAIS<\/p>\n<p><a href=\"https:\/\/www.tudoep.com\/tudo-valor\/NOT,0,0,1868698,governo-prorroga-desenrola-brasil-ate-marco-de-2024.aspx\" target=\"_blank\" rel=\"noreferrer noopener\">Governo prorroga Desenrola Brasil at\u00e9 mar\u00e7o de 2024<\/a><\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/motociclista-morre-apos-bater-em-carro-e-ser-atropelado-por-caminhonete-em-ribeirao\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Um motociclista morreu, na tarde desta ter\u00e7a-feira (12), ap\u00f3s se envolver em um acidente na avenida Alfredo Ravaneli, na zona Leste de Ribeir\u00e3o Preto. De acordo com a apura\u00e7\u00e3o da EPTV, o homem, de 35 anos, pilotava a moto quando bateu na traseira de um ve\u00edculo que seguia no mesmo sentido e se preparava &#8230; <a title=\"Motociclista morre ap\u00f3s bater em carro e ser atropelado por caminhonete em Ribeir\u00e3o\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/12\/motociclista-morre-apos-bater-em-carro-e-ser-atropelado-por-caminhonete-em-ribeirao\/\" aria-label=\"Leia mais sobre Motociclista morre ap\u00f3s bater em carro e ser atropelado por caminhonete em Ribeir\u00e3o\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":14901,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[37,867,661,2035,295,271,904,134,26,845],"class_list":["post-14900","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-apos","tag-atropelado","tag-bater","tag-caminhonete","tag-carro","tag-morre","tag-motociclista","tag-por","tag-ribeirao","tag-ser"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-16.png?fit=1200%2C675&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-16.png?fit=1200%2C675&ssl=1",1200,675,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-16.png?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-16.png?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-16.png?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-16.png?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-16.png?fit=1200%2C675&ssl=1",1200,675,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-16.png?fit=1200%2C675&ssl=1",1200,675,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Um motociclista morreu, na tarde desta ter\u00e7a-feira (12), ap\u00f3s se envolver em um acidente na avenida Alfredo Ravaneli, na zona Leste de Ribeir\u00e3o Preto. De acordo com a apura\u00e7\u00e3o da EPTV, o homem, de 35 anos, pilotava a moto quando bateu na traseira de um ve\u00edculo que seguia no mesmo sentido e se preparava&hellip;","jetpack-related-posts":[{"id":41600,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/09\/motociclista-morre-apos-bater-em-onibus-e-ser-arrastado-por-caminhonete-na-regiao-de-ribeirao\/","url_meta":{"origin":14900,"position":0},"title":"Motociclista morre ap\u00f3s bater em \u00f4nibus e ser arrastado por caminhonete na regi\u00e3o de Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"9 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] Na noite desta sexta-feira (8), um motociclista de 47 anos morreu depois de se envolver em um acidente com um \u00f4nibus e uma caminhonete, na rodovia Doutor William Amin (SP-385), entre Miguel\u00f3polis e Ituverava, na regi\u00e3o de Ribeir\u00e3o Preto. De acordo com o motorista do \u00f4nibus, ele seguia pela\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__MOTOCICLISTA.webp.webp?fit=1200%2C750&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__MOTOCICLISTA.webp.webp?fit=1200%2C750&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__MOTOCICLISTA.webp.webp?fit=1200%2C750&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__MOTOCICLISTA.webp.webp?fit=1200%2C750&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/AnyConv.com__MOTOCICLISTA.webp.webp?fit=1200%2C750&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":15062,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/13\/motociclista-morre-em-acidente-na-zona-leste\/","url_meta":{"origin":14900,"position":1},"title":"Motociclista morre em acidente na zona Leste","author":"ismaelcolosi.com.br","date":"13 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Colis\u00e3o ocorreu pr\u00f3ximo ao Parque dos Servidores e v\u00edtima foi atropelada ao tentar desviar de outro carro e cair 12 de dezembro de 2023 | 16:38 3Por: Adalberto LuqueUm homem morreu, no in\u00edcio da tarde desta sexta-feira (12), ap\u00f3s se envolver em um acidente de tr\u00e2nsito, na Avenida Alfredo\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/00-12-dez-2023-motociclista-morto-03-foto-max-gallao-mesquita-scaled.jpg?fit=1000%2C629&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/00-12-dez-2023-motociclista-morto-03-foto-max-gallao-mesquita-scaled.jpg?fit=1000%2C629&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/00-12-dez-2023-motociclista-morto-03-foto-max-gallao-mesquita-scaled.jpg?fit=1000%2C629&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/00-12-dez-2023-motociclista-morto-03-foto-max-gallao-mesquita-scaled.jpg?fit=1000%2C629&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":49729,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/13\/motociclista-de-42-anos-morre-apos-bater-moto-e-ser-atropelado-na-rodovia-anhanguera\/","url_meta":{"origin":14900,"position":2},"title":"Motociclista de 42 anos morre ap\u00f3s bater moto e ser atropelado na rodovia Anhanguera","author":"ismaelcolosi.com.br","date":"13 de Maio de 2024","format":false,"excerpt":"[ad_1] Um motociclista de 42 anos morreu na no in\u00edcio da noite deste domingo (12), depois de bater a moto na traseira de um carro, cair e ser atropelado por outros ve\u00edculos na rodovia Anhanguera (SP-330), em Jardin\u00f3polis, na regi\u00e3o de Ribeir\u00e3o Preto. Segundo o boletim de ocorr\u00eancia (BO), a\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/20220809_065618844_policia_rodoviaria_1200x675_21062022083038.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/20220809_065618844_policia_rodoviaria_1200x675_21062022083038.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/20220809_065618844_policia_rodoviaria_1200x675_21062022083038.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/20220809_065618844_policia_rodoviaria_1200x675_21062022083038.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/20220809_065618844_policia_rodoviaria_1200x675_21062022083038.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":72946,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/10\/24\/motociclista-morre-em-acidente-na-francisco-junqueira-em-ribeirao\/","url_meta":{"origin":14900,"position":3},"title":"Motociclista morre em acidente na Francisco Junqueira em Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"24 de Outubro de 2024","format":false,"excerpt":"[ad_1] Uma motociclista de 37 anos morreu em um acidente na manh\u00e3 desta quinta-feira (24), na avenida Francisco Junqueira, em Ribeir\u00e3o Preto. Segundo as primeiras informa\u00e7\u00f5es, a v\u00edtima teria ca\u00eddo na via ap\u00f3s uma batida com um carro. Na sequ\u00eancia, um caminh\u00e3o teria atropelado a motociclista. O Samu foi acionado,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ACIDENTE_2024-10-24_11-27-08_jpg_2024-10-24_11-27-09.webp.webp?fit=1200%2C811&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ACIDENTE_2024-10-24_11-27-08_jpg_2024-10-24_11-27-09.webp.webp?fit=1200%2C811&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ACIDENTE_2024-10-24_11-27-08_jpg_2024-10-24_11-27-09.webp.webp?fit=1200%2C811&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ACIDENTE_2024-10-24_11-27-08_jpg_2024-10-24_11-27-09.webp.webp?fit=1200%2C811&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/10\/ACIDENTE_2024-10-24_11-27-08_jpg_2024-10-24_11-27-09.webp.webp?fit=1200%2C811&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":52262,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/05\/motociclista-morre-apos-acidente-na-regiao-de-ribeirao-preto-motorista-fugiu\/","url_meta":{"origin":14900,"position":4},"title":"Motociclista morre ap\u00f3s acidente na regi\u00e3o de Ribeir\u00e3o Preto; Motorista fugiu","author":"ismaelcolosi.com.br","date":"5 de Junho de 2024","format":false,"excerpt":"[ad_1] O motociclista Joel Alves da Silva, de 28 anos, morreu na noite de ter\u00e7a-feira (4), depois de permanecer internado por quatro dias em decorr\u00eancia de um acidente em Serrana, na regi\u00e3o de Ribeir\u00e3o Preto. Na ocasi\u00e3o, o motorista da caminhonete que bateu contra a moto fugiu sem prestar socorro.\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-10-1.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-10-1.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-10-1.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-10-1.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-10-1.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":49798,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/05\/13\/motociclista-morre-em-acidente-na-anhanguera\/","url_meta":{"origin":14900,"position":5},"title":"Motociclista morre em acidente na Anhanguera","author":"ismaelcolosi.com.br","date":"13 de Maio de 2024","format":false,"excerpt":"[ad_1] Ap\u00f3s bater com sua moto, v\u00edtima caiu e foi atropelada por v\u00e1rios ve\u00edculos 13 de maio de 202413 Compartilhar2 Por: Adalberto Luque Um homem de 41 anos morreu, na noite deste domingo (12), depois de se envolver em um acidente com sua moto. Ele seguia pela Rodovia Anhanguera (SP-330),\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/dupla_anhanguera-scaled-1.jpeg?fit=700%2C524&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/dupla_anhanguera-scaled-1.jpeg?fit=700%2C524&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/dupla_anhanguera-scaled-1.jpeg?fit=700%2C524&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/05\/dupla_anhanguera-scaled-1.jpeg?fit=700%2C524&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-3Sk","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=14900"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14900\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/14901"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=14900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=14900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=14900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}