{"id":14083,"date":"2023-12-11T17:35:04","date_gmt":"2023-12-11T20:35:04","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/11\/motociclista-morre-apos-acidente-em-rodovia-na-regiao-de-ribeirao\/"},"modified":"2023-12-11T17:35:04","modified_gmt":"2023-12-11T20:35:04","slug":"motociclista-morre-apos-acidente-em-rodovia-na-regiao-de-ribeirao","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/11\/motociclista-morre-apos-acidente-em-rodovia-na-regiao-de-ribeirao\/","title":{"rendered":"Motociclista morre ap\u00f3s acidente em rodovia na regi\u00e3o de Ribeir\u00e3o"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_104\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p>Um homem <strong>morreu <\/strong>em um acidente envolvendo uma <strong>van <\/strong>e uma <strong>motocicleta<\/strong>, na rodovia <strong>Deputado Cunha Bueno (SP-253)<\/strong>, em <strong>Luiz Ant\u00f4nio<\/strong>, cidade na regi\u00e3o de <strong>Ribeir\u00e3o Preto<\/strong>, no \u00faltimo s\u00e1bado (9).<\/p>\n<p>De acordo com as informa\u00e7\u00f5es do<strong> boletim de ocorr\u00eancia (BO)<\/strong>, o condutor da motocicleta, de 34 anos, <strong>n\u00e3o resistiu aos ferimentos e faleceu no local da colis\u00e3o<\/strong>, pr\u00f3ximo ao<strong> km 160<\/strong>. O acidente teria ocorrido durante a <strong>ultrapassagem de um caminh\u00e3o<\/strong>.<\/p>\n<p>Conforme o registro da ocorr\u00eancia, a van seguia pela via no sentido Luiz Ant\u00f4nio \u2013 Prad\u00f3polis, quando o motociclista, que estava <mark style=\"background-color:#fcb900\" class=\"has-inline-color\">atr\u00e1s de um caminh\u00e3o que seguia no sentido contr\u00e1rio do local<\/mark>, <strong>tentou ultrapassar o ve\u00edculo.<\/strong><\/p>\n<p>A <strong>Pol\u00edcia Militar Rodovi\u00e1ria<\/strong> e <strong>Pol\u00edcia Cient\u00edfica<\/strong> foram acionadas e estiveram no local. O motorista da van foi socorrido com ferimentos leves e encaminhado para um Pronto Socorro de Luiz Ant\u00f4nio.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Sobrinho \u00e9 suspeito de matar tio a pauladas durante briga em Ribeir\u00e3o<\/p>\n<h4 class=\"wp-block-heading\"><strong><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">FIQUE ON \u00a0<\/mark><\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do<strong>\u00a0acidade on<\/strong>\u00a0no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook.<\/a><\/p>\n<p>Receba not\u00edcias do<strong>\u00a0acidade on\u00a0<\/strong>no WhatsApp.\u00a0<a href=\"https:\/\/chat.whatsapp.com\/Bnv2w66ZT4VDyZW3oiZ69n\" target=\"_blank\" rel=\"noreferrer noopener\">Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre a Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: (16) 99117 7802.<\/p>\n<p>LEIA MAIS<\/p>\n<p><a href=\"https:\/\/www.tudoep.com\/tudo-receitas\/NOT,0,0,1868566,salada-de-macarrao-confira-como-fazer-essa-receita.aspx\" target=\"_blank\" rel=\"noreferrer noopener\">Salada de macarr\u00e3o: confira como fazer essa receita<\/a><\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/cotidiano\/motociclista-morre-apos-acidente-em-rodovia-na-regiao-de-ribeirao\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Um homem morreu em um acidente envolvendo uma van e uma motocicleta, na rodovia Deputado Cunha Bueno (SP-253), em Luiz Ant\u00f4nio, cidade na regi\u00e3o de Ribeir\u00e3o Preto, no \u00faltimo s\u00e1bado (9). De acordo com as informa\u00e7\u00f5es do boletim de ocorr\u00eancia (BO), o condutor da motocicleta, de 34 anos, n\u00e3o resistiu aos ferimentos e faleceu &#8230; <a title=\"Motociclista morre ap\u00f3s acidente em rodovia na regi\u00e3o de Ribeir\u00e3o\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/11\/motociclista-morre-apos-acidente-em-rodovia-na-regiao-de-ribeirao\/\" aria-label=\"Leia mais sobre Motociclista morre ap\u00f3s acidente em rodovia na regi\u00e3o de Ribeir\u00e3o\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":14084,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[74,37,271,904,277,26,80],"class_list":["post-14083","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-acidente","tag-apos","tag-morre","tag-motociclista","tag-regiao","tag-ribeirao","tag-rodovia"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/giroflex_policia_1024x576_23032020103807.jpg?fit=1024%2C576&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/giroflex_policia_1024x576_23032020103807.jpg?fit=1024%2C576&ssl=1",1024,576,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/giroflex_policia_1024x576_23032020103807.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/giroflex_policia_1024x576_23032020103807.jpg?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/giroflex_policia_1024x576_23032020103807.jpg?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/giroflex_policia_1024x576_23032020103807.jpg?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/giroflex_policia_1024x576_23032020103807.jpg?fit=1024%2C576&ssl=1",1024,576,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/giroflex_policia_1024x576_23032020103807.jpg?fit=1024%2C576&ssl=1",1024,576,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Um homem morreu em um acidente envolvendo uma van e uma motocicleta, na rodovia Deputado Cunha Bueno (SP-253), em Luiz Ant\u00f4nio, cidade na regi\u00e3o de Ribeir\u00e3o Preto, no \u00faltimo s\u00e1bado (9). De acordo com as informa\u00e7\u00f5es do boletim de ocorr\u00eancia (BO), o condutor da motocicleta, de 34 anos, n\u00e3o resistiu aos ferimentos e faleceu&hellip;","jetpack-related-posts":[{"id":58923,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/04\/motociclista-morre-e-mulher-fica-ferida-apos-acidente-em-rodovia-na-regiao-de-ribeirao-preto\/","url_meta":{"origin":14083,"position":0},"title":"Motociclista morre e mulher fica ferida ap\u00f3s acidente em rodovia na regi\u00e3o de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"4 de Agosto de 2024","format":false,"excerpt":"[ad_1] Um homem morreu e uma mulher ficou ferida ap\u00f3s um acidente na rodovia Carlos Tonani (SP-333), pr\u00f3ximo ao quil\u00f4metro 97, em Sert\u00e3ozinho, cidade na regi\u00e3o de Ribeir\u00e3o Preto, na noite deste s\u00e1bado (3). De acordo com o boletim de ocorr\u00eancia (BO), William Yudy Matayoshi Da Silva, de 28 anos,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-04T113336.227_2024-08-04_14-33-41_png_2024-08-04_14-33-41.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-04T113336.227_2024-08-04_14-33-41_png_2024-08-04_14-33-41.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-04T113336.227_2024-08-04_14-33-41_png_2024-08-04_14-33-41.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-04T113336.227_2024-08-04_14-33-41_png_2024-08-04_14-33-41.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-04T113336.227_2024-08-04_14-33-41_png_2024-08-04_14-33-41.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":60828,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/18\/motociclista-morre-apos-colisao-com-caminhao-em-rodovia-na-regiao-de-ribeirao\/","url_meta":{"origin":14083,"position":1},"title":"Motociclista morre ap\u00f3s colis\u00e3o com caminh\u00e3o em rodovia na regi\u00e3o de Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"18 de Agosto de 2024","format":false,"excerpt":"[ad_1] Mat\u00e9ria atualizada \u00e0s 18h15, do dia 18 de agosto de 2024 Um motociclista morreu ap\u00f3s se envolver em um acidente na rodovia At\u00edlio Balbo (SP-265), em Sert\u00e3ozinho, cidade na regi\u00e3o de Ribeir\u00e3o Preto, na tarde deste domingo (18). De acordo com as primeiras informa\u00e7\u00f5es, o acidente aconteceu pr\u00f3ximo ao\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-18-at-18.09.14_2024-08-18_21-12-08_jpeg_2024-08-18_21-12-10-scaled.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-18-at-18.09.14_2024-08-18_21-12-08_jpeg_2024-08-18_21-12-10-scaled.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-18-at-18.09.14_2024-08-18_21-12-08_jpeg_2024-08-18_21-12-10-scaled.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-18-at-18.09.14_2024-08-18_21-12-08_jpeg_2024-08-18_21-12-10-scaled.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-18-at-18.09.14_2024-08-18_21-12-08_jpeg_2024-08-18_21-12-10-scaled.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":25223,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/06\/utm_sourcerssutm_mediumrssutm_campaignmotociclista-morre-apos-atropelar-duas-capivaras-entre-serrana-e-serra-azul\/","url_meta":{"origin":14083,"position":2},"title":"Motociclista morre ap\u00f3s atropelar duas capivaras entre Serrana e Serra Azul \u2013 X Tudo Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"6 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Um motociclista de 42 anos morreu ap\u00f3s atropelar duas capivaras na madrugada deste s\u00e1bado (6\/1), na rodovia Abra\u00e3o Assed, entre as cidades de Serrana e Serra Azul.\u00a0 Segundo apurado com a PMR (Pol\u00edcia Militar Rodovi\u00e1ria), por volta das 02h55 usu\u00e1rios da rodovia acionaram os PMs versando sobre um grave\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-09.28.58.jpeg?fit=1200%2C901&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-09.28.58.jpeg?fit=1200%2C901&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-09.28.58.jpeg?fit=1200%2C901&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-09.28.58.jpeg?fit=1200%2C901&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-06-at-09.28.58.jpeg?fit=1200%2C901&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":58936,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/08\/04\/identificada-motociclista-que-morreu-em-acidente-na-zona-sul-de-ribeirao-preto\/","url_meta":{"origin":14083,"position":3},"title":"Identificada motociclista que morreu em acidente na zona Sul de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"4 de Agosto de 2024","format":false,"excerpt":"[ad_1] Foi identificada como Isa Kely Cristina Mota a mulher de 31 anos que morreu ap\u00f3s um acidente de tr\u00e2nsito no Anel Vi\u00e1rio Sul (rodovia Ant\u00f4nio Duarte Nogueira, SP-322), em Ribeir\u00e3o Preto, neste s\u00e1bado (3). De acordo com as informa\u00e7\u00f5es da Secretaria de Seguran\u00e7a P\u00fablica (SSP) do Estado de S\u00e3o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-04T163219.987_2024-08-04_19-32-27_png_2024-08-04_19-32-27.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-04T163219.987_2024-08-04_19-32-27_png_2024-08-04_19-32-27.webp.webp?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-04T163219.987_2024-08-04_19-32-27_png_2024-08-04_19-32-27.webp.webp?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-04T163219.987_2024-08-04_19-32-27_png_2024-08-04_19-32-27.webp.webp?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/08\/Copia-de-Copia-de-TAMANHO-EXATO-PARA-FOTOS-NO-SISTEMA-NOVO-2024-08-04T163219.987_2024-08-04_19-32-27_png_2024-08-04_19-32-27.webp.webp?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":24263,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/03\/utm_sourcerssutm_mediumrssutm_campaignmotociclista-morre-na-rod-anhanguera-em-rp\/","url_meta":{"origin":14083,"position":4},"title":"Motociclista morre na Rod. Anhanguera em RP \u2013 X Tudo Ribeir\u00e3o","author":"ismaelcolosi.com.br","date":"3 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Uma motociclista ainda sem identifica\u00e7\u00e3o morreu ap\u00f3s se envolver em um acidente de tr\u00e2nsito na rodovia Anhanguera, na noite desta quarta-feira (3\/1), em Ribeir\u00e3o Preto. Segundo informa\u00e7\u00f5es da Pol\u00edcia Militar Rodovi\u00e1ria, a v\u00edtima transitava com sua motocicleta no sentido Ribeir\u00e3o Preto \u2013 Cravinhos, quando pr\u00f3ximo do pontilh\u00e3o da Thomaz\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/acdc21c7-e5c7-4f91-a7d9-e399da8013f6.jpeg?fit=1200%2C728&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/acdc21c7-e5c7-4f91-a7d9-e399da8013f6.jpeg?fit=1200%2C728&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/acdc21c7-e5c7-4f91-a7d9-e399da8013f6.jpeg?fit=1200%2C728&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/acdc21c7-e5c7-4f91-a7d9-e399da8013f6.jpeg?fit=1200%2C728&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/acdc21c7-e5c7-4f91-a7d9-e399da8013f6.jpeg?fit=1200%2C728&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":78228,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/12\/03\/mais-um-morto-em-acidente-na-anhanguera\/","url_meta":{"origin":14083,"position":5},"title":"Mais um morto em acidente na Anhanguera","author":"ismaelcolosi.com.br","date":"3 de Dezembro de 2024","format":false,"excerpt":"[ad_1] Por: Adalberto Luque Uma pessoa morreu e duas ficaram feridas ap\u00f3s uma colis\u00e3o traseira, no in\u00edcio da manh\u00e3 desta ter\u00e7a-feira (3). O acidente ocorreu na Rodovia Anhanguera (SP-330), km 257, em Santa Rita do Passa Quatro, regi\u00e3o metropolitana. Um caminh\u00e3o Mercedes Benz 1113 estava parado no acostamento, na pista\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/03dez2024-acidentesantarita-scaled.jpg?fit=800%2C450&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/03dez2024-acidentesantarita-scaled.jpg?fit=800%2C450&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/03dez2024-acidentesantarita-scaled.jpg?fit=800%2C450&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/03dez2024-acidentesantarita-scaled.jpg?fit=800%2C450&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-3F9","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=14083"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14083\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/14084"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=14083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=14083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=14083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}