{"id":13915,"date":"2023-12-11T13:22:00","date_gmt":"2023-12-11T16:22:00","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/11\/vendas-de-produtos-organicos-no-pais-crescem-30\/"},"modified":"2023-12-11T13:22:00","modified_gmt":"2023-12-11T16:22:00","slug":"vendas-de-produtos-organicos-no-pais-crescem-30","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/11\/vendas-de-produtos-organicos-no-pais-crescem-30\/","title":{"rendered":"Vendas de produtos org\u00e2nicos no pa\u00eds crescem 30%"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"\">\n<p> <span class=\"entry-meta-item penci-posted-on\"><i class=\"fa fa-clock-o\"\/><time class=\"entry-date published\" datetime=\"2023-12-11T13:00:44-03:00\">11 de dezembro de 2023 | 13:00<\/time><time class=\"updated\" datetime=\"2023-12-11T11:02:51-03:00\">11 de dezembro de 2023 | 11:02<\/time><\/span><\/p>\n<p> <span class=\"penci-social-buttons penci-social-share-footer\"><a href=\"#\" class=\"penci-post-like penci_post-meta_item  single-like-button penci-social-item like\" data-post_id=\"366867\" title=\"Like\" data-like=\"Like\" data-unlike=\"Unlike\"><i class=\"fa fa-thumbs-o-up\"\/><span class=\"penci-share-number\">0<\/span><\/a><i class=\"fa fa-facebook\"\/><a class=\"penci-social-item twitter\" target=\"_blank\" rel=\"noopener\" title=\"\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Vendas%20de%20produtos%20org\u00e2nicos%20no%20pa\u00eds%20crescem%2030%20-%20https:\/\/www.tribunaribeirao.com.br\/site\/vendas-de-produtos-organicos-no-pais-crescem-30\/\"><i class=\"fa fa-twitter\"\/><\/a><i class=\"fa fa-whatsapp\"\/><\/span><\/div>\n<div>\n<p>Uma pesquisa feita por cientistas da Universidade Federal do Rio Grande do Sul (UFRGS) e da Universidade Tecnol\u00f3gica Federal do Paran\u00e1 (UTFPR) mostrou que, apesar de o Brasil ser vasto em terras cultiv\u00e1veis e ter um dos principais mercados agr\u00edcolas do mundo, incluindo o de produtos org\u00e2nicos, ainda h\u00e1 falhas no levantamento de dados referente ao cultivo de org\u00e2nicos no pa\u00eds. A pesquisa foi publicada no \u00faltimo dia 24 na revista cient\u00edfica\u00a0<em>Desenvolvimento e Meio Ambiente<\/em>.<img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/agenciabrasil.ebc.com.br\/ebc.png?w=1200&#038;ssl=1\" class=\"lazyload\"\/><noscript><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/agenciabrasil.ebc.com.br\/ebc.png?w=1200&#038;ssl=1\"\/><\/noscript><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/agenciabrasil.ebc.com.br\/ebc.gif?w=1200&#038;ssl=1\" class=\"lazyload\"\/><noscript><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/agenciabrasil.ebc.com.br\/ebc.gif?w=1200&#038;ssl=1\"\/><\/noscript><\/p>\n<p>A pesquisa se baseou em dados do Censo Agropecu\u00e1rio de 2017 do Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE), do Cadastro Nacional de Produtores Org\u00e2nicos (CNPO), realizado pelo Minist\u00e9rio da Agricultura, Pecu\u00e1ria e Abastecimento (Mapa), e informa\u00e7\u00f5es sobre\u00a0consumo de pesquisas da Associa\u00e7\u00e3o de Promo\u00e7\u00e3o dos Org\u00e2nicos (Organis) e do Servi\u00e7o de Apoio \u00e0s Micro e Pequenas Empresas (Sebrae).<\/p>\n<p>Segundo os dados, entre 2003 e 2017, as vendas de produtos org\u00e2nicos no pa\u00eds aumentaram quatro vezes. No ano de 2020, tiveram expans\u00e3o de 30%, com o movimento de R$ 5,8 bilh\u00f5es. H\u00e1 ainda 953 certifica\u00e7\u00f5es de org\u00e2nicos para produtos importados, de um total de 23 pa\u00edses, segundo dados do Mapa. S\u00e3o alimentos provenientes de esp\u00e9cies caracter\u00edsticas de outros pa\u00edses (como amaranto, quinoa, damasco, azeite de oliva).\u00a0A pesquisa tamb\u00e9m revelou que houve aumento de 75% no cadastro de produtores de org\u00e2nicos no pa\u00eds em quatro anos (2017 a 2022).<\/p>\n<p>De acordo com a pesquisa, 1,28% das \u00e1reas de cultivo \u00e9 referente\u00a0a propriedades com agricultura org\u00e2nica e, dessas, 30% est\u00e3o no Sudeste do pa\u00eds. Estimativas apontam que esse tipo de cultivo ocupa 0,6% das \u00e1reas agr\u00edcolas do pa\u00eds, com predom\u00ednio da produ\u00e7\u00e3o vegetal em 36.689 estabelecimentos. Os outros 17.612 estabelecimentos dedicam-se \u00e0 produ\u00e7\u00e3o animal, enquanto uma parcela menor de 10.389 estabelecimentos t\u00eam produ\u00e7\u00e3o animal e produ\u00e7\u00e3o vegetal org\u00e2nicas.<\/p>\n<\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/site\/vendas-de-produtos-organicos-no-pais-crescem-30\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] 11 de dezembro de 2023 | 13:0011 de dezembro de 2023 | 11:02 0 Uma pesquisa feita por cientistas da Universidade Federal do Rio Grande do Sul (UFRGS) e da Universidade Tecnol\u00f3gica Federal do Paran\u00e1 (UTFPR) mostrou que, apesar de o Brasil ser vasto em terras cultiv\u00e1veis e ter um dos principais mercados agr\u00edcolas &#8230; <a title=\"Vendas de produtos org\u00e2nicos no pa\u00eds crescem 30%\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/11\/vendas-de-produtos-organicos-no-pais-crescem-30\/\" aria-label=\"Leia mais sobre Vendas de produtos org\u00e2nicos no pa\u00eds crescem 30%\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":13916,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[1375,1956,709,1484,105],"class_list":["post-13915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-crescem","tag-organicos","tag-pais","tag-produtos","tag-vendas"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/suja.jpg?fit=800%2C600&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/suja.jpg?fit=800%2C600&ssl=1",800,600,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/suja.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/suja.jpg?fit=300%2C225&ssl=1",300,225,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/suja.jpg?fit=768%2C576&ssl=1",768,576,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/suja.jpg?fit=800%2C600&ssl=1",800,600,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/suja.jpg?fit=800%2C600&ssl=1",800,600,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/suja.jpg?fit=800%2C600&ssl=1",800,600,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] 11 de dezembro de 2023 | 13:0011 de dezembro de 2023 | 11:02 0 Uma pesquisa feita por cientistas da Universidade Federal do Rio Grande do Sul (UFRGS) e da Universidade Tecnol\u00f3gica Federal do Paran\u00e1 (UTFPR) mostrou que, apesar de o Brasil ser vasto em terras cultiv\u00e1veis e ter um dos principais mercados agr\u00edcolas&hellip;","jetpack-related-posts":[{"id":14142,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/11\/caminhao-tanque-tomba-em-rodovia-na-regiao-de-ribeirao-e-mobiliza-helicoptero-aguia\/","url_meta":{"origin":13915,"position":0},"title":"Caminh\u00e3o tanque tomba em rodovia na regi\u00e3o de Ribeir\u00e3o e mobiliza helic\u00f3ptero \u00c1guia","author":"ismaelcolosi.com.br","date":"11 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Um caminh\u00e3o tanque tombou na rodovia Altino Arantes (SP-351), pr\u00f3ximo \u00e0 cidade de Altin\u00f3polis, na regi\u00e3o de Ribeir\u00e3o Preto, no final da tarde desta segunda-feira (11). De acordo com as primeiras informa\u00e7\u00f5es obtidas pelo Corpo de Bombeiros, houve vazamento de combust\u00edvel na pista. Ainda segundo o \u00f3rg\u00e3o, uma v\u00edtima\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-10-01-at-15.55.52.jpeg?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-10-01-at-15.55.52.jpeg?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-10-01-at-15.55.52.jpeg?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-10-01-at-15.55.52.jpeg?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":77178,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/21\/amazon-anuncia-65-mil-vagas-temporarias-no-brasil-para-black-friday-e-final-de-ano\/","url_meta":{"origin":13915,"position":1},"title":"Amazon anuncia 6,5 mil vagas tempor\u00e1rias no Brasil para Black Friday e final de ano","author":"ismaelcolosi.com.br","date":"21 de Novembro de 2024","format":false,"excerpt":"[ad_1] Da Reutersi Da Reuters 21\/11\/2024 - 17:06 A Amazon anunciou nesta quinta-feira, 21, que vai contratar 6,5 mil funcion\u00e1rios tempor\u00e1rios no Brasil para refor\u00e7ar suas opera\u00e7\u00f5es para a temporada de vendas do per\u00edodo da Black Friday, no final deste m\u00eas, um crescimento de 8% em rela\u00e7\u00e3o a 2023.+ Black\u2026","rel":"","context":"In &quot;Empregos - Classificados&quot;","block_context":{"text":"Empregos - Classificados","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/empregos-classificados-vagas-trabalho\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/53895454b9185a3795189e601a0fec869058c8ba.jpg?fit=768%2C511&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/53895454b9185a3795189e601a0fec869058c8ba.jpg?fit=768%2C511&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/53895454b9185a3795189e601a0fec869058c8ba.jpg?fit=768%2C511&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/53895454b9185a3795189e601a0fec869058c8ba.jpg?fit=768%2C511&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":34776,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/03\/producao-industrial-cresce-02-em-2023\/","url_meta":{"origin":13915,"position":2},"title":"Produ\u00e7\u00e3o industrial cresce 0,2% em 2023\u00a0","author":"ismaelcolosi.com.br","date":"3 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] 3 de fevereiro de 2024 | 13:002 de fevereiro de 2024 | 21:02 0A produ\u00e7\u00e3o industrial do pa\u00eds teve alta de 1,1% em dezembro, sendo o quinto m\u00eas seguido com resultado positivo. Assim, a ind\u00fastria brasileira fecha 2023 com alta de 0,2%. No ano anterior, o resultado tinha sido\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Indus-Washington-Alves-Reuters-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Indus-Washington-Alves-Reuters-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Indus-Washington-Alves-Reuters-scaled.jpg?fit=1000%2C598&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/Indus-Washington-Alves-Reuters-scaled.jpg?fit=1000%2C598&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":26198,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/09\/vendas-do-comercio-de-rp-crescem-3-em-dezembro\/","url_meta":{"origin":13915,"position":3},"title":"Vendas no com\u00e9rcio de RP crescem 3% em dezembro","author":"ismaelcolosi.com.br","date":"9 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Em dezembro de 2023, as vendas no Com\u00e9rcio de Ribeir\u00e3o Preto cresceram 3% em rela\u00e7\u00e3o ao mesmo per\u00edodo do ano passado. Quando a compara\u00e7\u00e3o \u00e9 feita com o m\u00eas anterior (novembro de 2023, que teve varia\u00e7\u00e3o negativa de -2,5%), a alta \u00e9 de 6,5% nas vendas, pr\u00f3xima da proje\u00e7\u00e3o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/caged_3003_-_foto_guilherme_sircili-scaled.jpg?fit=970%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/caged_3003_-_foto_guilherme_sircili-scaled.jpg?fit=970%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/caged_3003_-_foto_guilherme_sircili-scaled.jpg?fit=970%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/caged_3003_-_foto_guilherme_sircili-scaled.jpg?fit=970%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":20660,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/26\/brasil-e-o-4o-pais-com-mais-viciados-em-smartphones\/","url_meta":{"origin":13915,"position":4},"title":"Brasil \u00e9 o 4\u00ba pa\u00eds com mais viciados em smartphones\u00a0","author":"ismaelcolosi.com.br","date":"26 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Pa\u00eds fica atr\u00e1s somente da Mal\u00e1sia, Ar\u00e1bia Saudita e China revela estudo de universidade canadense\u00a0 26 de dezembro de 2023 | 8:0025 de dezembro de 2023 | 11:50 0Estudo divulgado pela plataforma de descontos online CupomValido.com.br com dados da Universidade McGill revela que o Brasil \u00e9 o quarto pa\u00eds\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/2-vicio-celular.jpg?fit=935%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/2-vicio-celular.jpg?fit=935%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/2-vicio-celular.jpg?fit=935%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/2-vicio-celular.jpg?fit=935%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":28830,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/16\/moagem-de-cana-cresce-1876\/","url_meta":{"origin":13915,"position":5},"title":"Moagem de cana cresce 18,76% \u00a0","author":"ismaelcolosi.com.br","date":"16 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Na safra 2023\/24, a moagem atingiu 644,14 milh\u00f5es, ante 542,39 milh\u00f5es de toneladas registradas no mesmo per\u00edodo no ciclo 2022\/23 \u2013 avan\u00e7o de 18,76%\u00a0 16 de janeiro de 2024 | 18:0016 de janeiro de 2024 | 9:39 0A moagem de cana-de-a\u00e7\u00facar na segunda quinzena de dezembro registrou crescimento de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Cana-Divulgacao-scaled.jpg?fit=967%2C645&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Cana-Divulgacao-scaled.jpg?fit=967%2C645&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Cana-Divulgacao-scaled.jpg?fit=967%2C645&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Cana-Divulgacao-scaled.jpg?fit=967%2C645&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-3Cr","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=13915"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13915\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/13916"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=13915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=13915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=13915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}